{"id":100066,"date":"2025-05-12T11:20:58","date_gmt":"2025-05-12T09:20:58","guid":{"rendered":"https:\/\/visit.valueservice.cloud\/oggetto\/ristorante-mex-indo-2\/"},"modified":"2025-05-12T20:21:59","modified_gmt":"2025-05-12T18:21:59","slug":"ristorante-mex-indo","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/ristorante-mex-indo\/","title":{"rendered":"Ristorante Mex Indo"},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":100067,"template":"","categories":[854,823],"tags":[],"aggr":[],"area":[],"kind":[18720],"zona":[],"class_list":["post-100066","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-essen","category-mangiare","kind-ristorante-de"],"acf":{"buttons":false,"hero_type":"images","video_youtube_url":"","video_vimeo_url":"","size":"full","hero_title":"Ristorante Mex Indo","hero_text":"","slides":[{"image":{"ID":100067,"id":100067,"title":"ecom_3017_general.jpeg","filename":"ecom_3017_general.jpeg","filesize":96721,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/11\/ecom_3017_general.jpeg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/ristorante-mex-indo\/ecom_3017_general-jpeg-2\/","alt":"","author":"0","description":"","caption":"","name":"ecom_3017_general-jpeg-2","status":"inherit","uploaded_to":100066,"date":"2024-11-06 07:16:30","modified":"2025-05-12 18:22:00","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":675,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/11\/ecom_3017_general-150x150.jpeg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/11\/ecom_3017_general-300x169.jpeg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/11\/ecom_3017_general-768x432.jpeg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/11\/ecom_3017_general-1024x576.jpeg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/11\/ecom_3017_general.jpeg","1536x1536-width":1200,"1536x1536-height":675,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/11\/ecom_3017_general.jpeg","2048x2048-width":1200,"2048x2048-height":675,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/11\/ecom_3017_general.jpeg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/11\/ecom_3017_general.jpeg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/11\/ecom_3017_general.jpeg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"Ristorante Mex Indo","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"hero_buttons_group":{"buttons":false},"hero_buttons":false,"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":false,"filotto_fill":false,"filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":0,"show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":false,"order_way":false}},"description":"<p>Willkommen! MexIndo ist das typische mexikanische Lokal, das Sie gesucht haben und das in Dalmine gefehlt hat: ein Abend, den Sie mit dem Besten der mexikanischen und spanischen K\u00fcche genie\u00dfen k\u00f6nnen, ohne etwas dem Zufall zu \u00fcberlassen.&#13;<br \/>\nEntdecken Sie die Tandoori- und Currygerichte mit tausend Nuancen und einem raffinierten und harmonischen Geschmack. Das Brot, im Tandoor-Ofen gebacken, verleiht den charakteristischen Geschmack, der Reis ist Basmati. Das angebotene Fleisch ist Huhn und Lamm, der zubereitete Fisch ist Schwertfisch und Garnelen. F\u00fcr diejenigen, die auf Fleisch und Fisch verzichten m\u00f6chten, bietet die Speisekarte auch mehrere vegetarische und vegane Gerichte. Alles wird in speziellen Kupfert\u00f6pfen serviert<\/p>\n","indepth":"","howtogetthere":"","timerange":"","seasonality":"","pairings":"","curiosities":"","awards":"","cancellationpolicy":"","moredetails":"","whatsincluded":"","whatsnotincluded":"","price":"","time":"","service_icons":[],"services":"","parking":"","restaurant":"","breakfast":"","internet":"","children":"","pets":"","latitude":"45.6541672","longitude":"9.6170616","startingprice":"","gpxmap":"","iu_motor_accessibility":"notsure","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_kids":false,"iu_shortprice":"","iu_company_name":"","registered_office":"","iu_addr_streetnumber":"Via Vailetta","iu_addr_postalcode":"24044","iu_addr_city":"Dalmine","iu_addr_province":"Dalmine","iu_phone":"","iu_cell":"","iu_website":"","iu_email":"sarabjit8486@gmail.com","iu_vat":"","iu_document_label":"","iu_document":false,"iu_documents":false,"iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_bookingurl":"","iu_videourl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"","iu_languages":"","iu_minpeople":"","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","iu_reservation":true,"iu_takeaway":true,"iu_delivery":true,"iu_stars":"","iu_rooms":"","iu_beds":"","id_madeep":"","id_visit_manza":"","id_east":"","id_ristora":"233","id_eppen":"","style":"primary","text":"","button_icon":"none","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"validfrom":"","validto":"","hours":"","ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":""},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/100066","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/100066\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media\/100067"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media?parent=100066"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/categories?post=100066"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/tags?post=100066"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/aggr?post=100066"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/area?post=100066"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/kind?post=100066"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/zona?post=100066"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}