{"id":106650,"date":"2025-02-22T10:14:44","date_gmt":"2025-02-22T09:14:44","guid":{"rendered":"https:\/\/visit.valueservice.cloud\/oggetto\/azienda-tallarini-2\/"},"modified":"2025-03-03T17:06:08","modified_gmt":"2025-03-03T16:06:08","slug":"azienda-tallarini","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/azienda-tallarini\/","title":{"rendered":"Unternehmen Tallarini"},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":0,"template":"","categories":[853],"tags":[],"aggr":[],"area":[],"kind":[18730],"zona":[],"class_list":["post-106650","oggetto","type-oggetto","status-publish","hentry","category-was-ist-zu-tun","kind-strutturacommerciale-de"],"acf":{"hero_type":"images","size":"full","slides":[{"image":{"ID":106651,"id":106651,"title":"3052a8ea7e6ac262395144fbe6488cbd_47f1d3cd.jpg","filename":"3052a8ea7e6ac262395144fbe6488cbd_47f1d3cd.jpg","filesize":220657,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/11\/3052a8ea7e6ac262395144fbe6488cbd_47f1d3cd.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/azienda-tallarini\/3052a8ea7e6ac262395144fbe6488cbd_47f1d3cd-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"3052a8ea7e6ac262395144fbe6488cbd_47f1d3cd-jpg-2","status":"inherit","uploaded_to":106650,"date":"2024-11-29 10:30:55","modified":"2024-11-29 10:30:55","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1011,"height":487,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/11\/3052a8ea7e6ac262395144fbe6488cbd_47f1d3cd-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/11\/3052a8ea7e6ac262395144fbe6488cbd_47f1d3cd-300x145.jpg","medium-width":300,"medium-height":145,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/11\/3052a8ea7e6ac262395144fbe6488cbd_47f1d3cd-768x370.jpg","medium_large-width":768,"medium_large-height":370,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/11\/3052a8ea7e6ac262395144fbe6488cbd_47f1d3cd.jpg","large-width":1011,"large-height":487,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/11\/3052a8ea7e6ac262395144fbe6488cbd_47f1d3cd.jpg","1536x1536-width":1011,"1536x1536-height":487,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/11\/3052a8ea7e6ac262395144fbe6488cbd_47f1d3cd.jpg","2048x2048-width":1011,"2048x2048-height":487,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/11\/3052a8ea7e6ac262395144fbe6488cbd_47f1d3cd-300x300.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/11\/3052a8ea7e6ac262395144fbe6488cbd_47f1d3cd-400x400.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/11\/3052a8ea7e6ac262395144fbe6488cbd_47f1d3cd-600x487.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":487}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":106652,"id":106652,"title":"196677a87622456e9eec2da9c61d3a53_6ee76088.jpg","filename":"196677a87622456e9eec2da9c61d3a53_6ee76088.jpg","filesize":128915,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/11\/196677a87622456e9eec2da9c61d3a53_6ee76088.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/azienda-tallarini\/196677a87622456e9eec2da9c61d3a53_6ee76088-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"196677a87622456e9eec2da9c61d3a53_6ee76088-jpg-2","status":"inherit","uploaded_to":106650,"date":"2024-11-29 10:30:56","modified":"2024-11-29 10:30:56","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1013,"height":521,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/11\/196677a87622456e9eec2da9c61d3a53_6ee76088-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/11\/196677a87622456e9eec2da9c61d3a53_6ee76088-300x154.jpg","medium-width":300,"medium-height":154,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/11\/196677a87622456e9eec2da9c61d3a53_6ee76088-768x395.jpg","medium_large-width":768,"medium_large-height":395,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/11\/196677a87622456e9eec2da9c61d3a53_6ee76088.jpg","large-width":1013,"large-height":521,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/11\/196677a87622456e9eec2da9c61d3a53_6ee76088.jpg","1536x1536-width":1013,"1536x1536-height":521,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/11\/196677a87622456e9eec2da9c61d3a53_6ee76088.jpg","2048x2048-width":1013,"2048x2048-height":521,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/11\/196677a87622456e9eec2da9c61d3a53_6ee76088-300x300.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/11\/196677a87622456e9eec2da9c61d3a53_6ee76088-400x400.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/11\/196677a87622456e9eec2da9c61d3a53_6ee76088-600x521.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":521}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":106653,"id":106653,"title":"454cd752a7cc62d1027e8645e9e86421_b995c3ec.jpg","filename":"454cd752a7cc62d1027e8645e9e86421_b995c3ec.jpg","filesize":147119,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/11\/454cd752a7cc62d1027e8645e9e86421_b995c3ec.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/azienda-tallarini\/454cd752a7cc62d1027e8645e9e86421_b995c3ec-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"454cd752a7cc62d1027e8645e9e86421_b995c3ec-jpg-2","status":"inherit","uploaded_to":106650,"date":"2024-11-29 10:30:57","modified":"2024-11-29 10:30:57","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1010,"height":518,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/11\/454cd752a7cc62d1027e8645e9e86421_b995c3ec-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/11\/454cd752a7cc62d1027e8645e9e86421_b995c3ec-300x154.jpg","medium-width":300,"medium-height":154,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/11\/454cd752a7cc62d1027e8645e9e86421_b995c3ec-768x394.jpg","medium_large-width":768,"medium_large-height":394,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/11\/454cd752a7cc62d1027e8645e9e86421_b995c3ec.jpg","large-width":1010,"large-height":518,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/11\/454cd752a7cc62d1027e8645e9e86421_b995c3ec.jpg","1536x1536-width":1010,"1536x1536-height":518,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/11\/454cd752a7cc62d1027e8645e9e86421_b995c3ec.jpg","2048x2048-width":1010,"2048x2048-height":518,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/11\/454cd752a7cc62d1027e8645e9e86421_b995c3ec-300x300.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/11\/454cd752a7cc62d1027e8645e9e86421_b995c3ec-400x400.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/11\/454cd752a7cc62d1027e8645e9e86421_b995c3ec-600x518.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":518}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"filotto_title":"","filotto_sub":"","filotto_layout":"scroll","filotto_fill":"manual","filotto_items":false,"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":"","order_by":"random","order_way":"asc","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":"","order_by":"random","order_way":"asc"},"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"scroll","filotto_fill":"manual","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":"","order_by":"random","order_way":"asc"}},"indepth":"","howtogetthere":"","timerange":"","seasonality":"","pairings":"","curiosities":"","awards":"","cancellationpolicy":"","moredetails":"","whatsincluded":"","whatsnotincluded":"","latitude":"45.666484","longitude":"9.896958","startingprice":"","gpxmap":"","iu_motor_accessibility":"no","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_kids":false,"iu_shortprice":"","iu_addr_postalcode":"24060","iu_addr_city":"Gandosso","iu_addr_province":"Bergamo","iu_phone":"+39 035 834003","iu_cell":"+39 035 834003","iu_email":"reception@tallarini.com","iu_document_label":"","iu_document":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_bookingurl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"","iu_languages":"","iu_minpeople":"","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"id_madeep":"","id_visit_manza":"8490","id_east":"","id_ristora":"","style":"primary","button_icon":"none","icon":{"button_icon":"none"},"function":"link","url":"http:\/\/www.tallarini.com","target":"_blank","url_youtube":"","target_modal":"","cta":{"style":"primary","text":"Kontakt","icon":{"button_icon":"none"},"function":"link","url":"http:\/\/www.tallarini.com","target":"_blank","url_youtube":"","target_modal":""},"validfrom":"","validto":"","iu_timetable":false,"id_eppen":"","description":"<p>Solide, wie alles Bergamaskerische, verbindet das Unternehmen die Produktion und Reifung von Weinen mit dem Empfang von Besuchern.<\/p>\n<p>Der Keller ist in drei R\u00e4ume unterteilt &#8211; Verarbeitung, Lagerung und Verkostung &#8211; und zwar in die gro\u00dfen Stahltanks f\u00fcr Wei\u00dfweine und die Holzf\u00e4sser f\u00fcr Rotweine und Weine zur Reifung. Entlang der W\u00e4nde werden die 240.000 Flaschen, die jedes Jahr produziert werden, gelagert und verfeinert und warten darauf, von Weinliebhabern, Verkostern oder einfach nur Liebhabern guten Weins ge\u00f6ffnet zu werden.   <br \/>Jeder Tallarini Wein bezieht seine gro\u00dfe Qualit\u00e4t aus den Weinbergen: geringe Ertr\u00e4ge, die Suche nach dem perfekten Erntezeitpunkt, die manuelle Auswahl der Trauben.<\/p>\n<p>Technik und Tradition sorgen f\u00fcr das beste Endergebnis: kleine H\u00f6lzer, Barriques und Tonneaux f\u00fcr die gro\u00dfen Weine; Stahl f\u00fcr die j\u00fcngeren Wei\u00dfweine. Sanftes Pressen, Kryomazeration, Verschnitt nach Bordeaux-Art und sorgf\u00e4ltiges Trocknen der Trauben sind die Methoden, die peinlich genau eingehalten werden.   <br \/>Die endg\u00fcltige Reifung findet immer in der Flasche statt: Sie kann bei trinkfertigen Weinen einige Monate, bei Weinen, die lange gelagert werden, bis zu mehreren Jahren betragen.<\/p>\n","text":"Kontakt","buttons":[{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","select_post":null,"target":"_self","url_youtube":"","target_modal":""}],"hero_title":"Unternehmen Tallarini","hero_text":"<p>Die Kunst und die Liebe zum Weinbau werden sorgf\u00e4ltig durch modernste Technologie und \u00f6nologische Forschung erg\u00e4nzt.<\/p>\n","price":"<p>.<\/p>\n","time":"<p>T\u00e4glich<br \/>11.00-12.30<br \/>16.30-18.00<\/p>\n<p>unter Vorbehalt<\/p>\n","iu_addr_streetnumber":"Via Fontanile, 10","iu_website":"http:\/\/www.tallarini.com"},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/106650","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/106650\/revisions"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media?parent=106650"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/categories?post=106650"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/tags?post=106650"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/aggr?post=106650"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/area?post=106650"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/kind?post=106650"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/zona?post=106650"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}