{"id":112814,"date":"2025-06-08T14:59:18","date_gmt":"2025-06-08T12:59:18","guid":{"rendered":"https:\/\/visit.valueservice.cloud\/oggetto\/112814\/"},"modified":"2025-05-12T19:55:00","modified_gmt":"2025-05-12T17:55:00","slug":"hochseilgaerten","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/hochseilgaerten\/","title":{"rendered":"Hochseilg\u00e4rten"},"excerpt":{"rendered":"<p>Erlebe ein Abenteuer hoch in den B\u00e4umen!<\/p>\n","protected":false},"author":0,"featured_media":184556,"template":"","categories":[524,521],"tags":[17244],"aggr":[],"area":[],"kind":[18703],"zona":[],"class_list":["post-112814","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-erlebnisse","category-esperienze","tag-spas-de","kind-esperienza-de"],"acf":{"buttons":[{"style":"primary","text":"Kaufen","icon":{"button_icon":"none"},"function":"content","url":"","select_post":"","target":"_self","url_youtube":"","target_modal":"buyExp"},{"style":"primary","text":"Kontakt","icon":{"button_icon":"none"},"function":"content","url":"","select_post":"","target":"_self","url_youtube":"","target_modal":"modalContact"}],"hero_type":"images","video_youtube_url":"","video_vimeo_url":"","size":"full","hero_title":"Hochseilg\u00e4rten","hero_text":"<p>Erlebe ein Abenteuer hoch in den B\u00e4umen!<\/p>\n","slides":[{"image":{"ID":184556,"id":184556,"title":"ec_service_4401_1","filename":"ec_service_4401_1.jpg","filesize":169108,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4401_1.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/hochseilgaerten\/ec_service_4401_1-2\/","alt":"","author":"0","description":"","caption":"","name":"ec_service_4401_1-2","status":"inherit","uploaded_to":112814,"date":"2025-04-22 17:51:02","modified":"2025-05-12 17:55:02","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":557,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4401_1-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4401_1-300x139.jpg","medium-width":300,"medium-height":139,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4401_1-768x356.jpg","medium_large-width":768,"medium_large-height":356,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4401_1-1024x475.jpg","large-width":1024,"large-height":475,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4401_1.jpg","1536x1536-width":1200,"1536x1536-height":557,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4401_1.jpg","2048x2048-width":1200,"2048x2048-height":557,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4401_1.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":139,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4401_1.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":186,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4401_1.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":279}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":112838,"id":112838,"title":"ec_service_4401_1_2.jpg","filename":"ec_service_4401_1_2.jpg","filesize":133363,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_2.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/hochseilgaerten\/ec_service_4401_1_2-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"ec_service_4401_1_2-jpg-2","status":"inherit","uploaded_to":112814,"date":"2024-12-17 17:01:01","modified":"2025-05-12 17:55:01","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":585,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_2-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_2-300x146.jpg","medium-width":300,"medium-height":146,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_2-768x374.jpg","medium_large-width":768,"medium_large-height":374,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_2-1024x499.jpg","large-width":1024,"large-height":499,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_2.jpg","1536x1536-width":1200,"1536x1536-height":585,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_2.jpg","2048x2048-width":1200,"2048x2048-height":585,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_2-300x300.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_2-400x400.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_2-600x585.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":585}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":112839,"id":112839,"title":"ec_service_4401_1_3.jpg","filename":"ec_service_4401_1_3.jpg","filesize":74142,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_3.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/hochseilgaerten\/ec_service_4401_1_3-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"ec_service_4401_1_3-jpg-2","status":"inherit","uploaded_to":112814,"date":"2024-12-17 17:01:02","modified":"2025-05-12 17:55:01","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":584,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_3-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_3-300x146.jpg","medium-width":300,"medium-height":146,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_3-768x374.jpg","medium_large-width":768,"medium_large-height":374,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_3-1024x498.jpg","large-width":1024,"large-height":498,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_3.jpg","1536x1536-width":1200,"1536x1536-height":584,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_3.jpg","2048x2048-width":1200,"2048x2048-height":584,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_3-300x300.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_3-400x400.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_3-600x584.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":584}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":112840,"id":112840,"title":"ec_service_4401_1_4.jpg","filename":"ec_service_4401_1_4.jpg","filesize":169108,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_4.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/hochseilgaerten\/ec_service_4401_1_4-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"ec_service_4401_1_4-jpg-2","status":"inherit","uploaded_to":112814,"date":"2024-12-17 17:01:03","modified":"2025-05-12 17:55:01","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":557,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_4-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_4-300x139.jpg","medium-width":300,"medium-height":139,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_4-768x356.jpg","medium_large-width":768,"medium_large-height":356,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_4-1024x475.jpg","large-width":1024,"large-height":475,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_4.jpg","1536x1536-width":1200,"1536x1536-height":557,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_4.jpg","2048x2048-width":1200,"2048x2048-height":557,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_4-300x300.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_4-400x400.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_4-600x557.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":557}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":112841,"id":112841,"title":"ec_service_4401_1_5.jpg","filename":"ec_service_4401_1_5.jpg","filesize":192650,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_5.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/hochseilgaerten\/ec_service_4401_1_5-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"ec_service_4401_1_5-jpg-2","status":"inherit","uploaded_to":112814,"date":"2024-12-17 17:01:04","modified":"2025-05-12 17:55:01","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":553,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_5-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_5-300x138.jpg","medium-width":300,"medium-height":138,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_5-768x354.jpg","medium_large-width":768,"medium_large-height":354,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_5-1024x472.jpg","large-width":1024,"large-height":472,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_5.jpg","1536x1536-width":1200,"1536x1536-height":553,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_5.jpg","2048x2048-width":1200,"2048x2048-height":553,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_5-300x300.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_5-400x400.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_5-600x553.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":553}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":112842,"id":112842,"title":"ec_service_4401_1_6.jpg","filename":"ec_service_4401_1_6.jpg","filesize":108708,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_6.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/hochseilgaerten\/ec_service_4401_1_6-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"ec_service_4401_1_6-jpg-2","status":"inherit","uploaded_to":112814,"date":"2024-12-17 17:01:05","modified":"2025-05-12 17:55:01","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":486,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_6-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_6-300x122.jpg","medium-width":300,"medium-height":122,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_6-768x311.jpg","medium_large-width":768,"medium_large-height":311,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_6-1024x415.jpg","large-width":1024,"large-height":415,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_6.jpg","1536x1536-width":1200,"1536x1536-height":486,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_6.jpg","2048x2048-width":1200,"2048x2048-height":486,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_6-300x300.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_6-400x400.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_6-600x486.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":486}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"hero_buttons_group":{"buttons":[{"style":"primary","text":"Kaufen","icon":{"button_icon":"none"},"function":"content","url":"","select_post":"","target":"_self","url_youtube":"","target_modal":"buyExp"},{"style":"primary","text":"Kontakt","icon":{"button_icon":"none"},"function":"content","url":"","select_post":"","target":"_self","url_youtube":"","target_modal":"modalContact"}]},"hero_buttons":false,"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"scroll","filotto_fill":"manual","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"random","order_way":"asc"}},"description":"<p>WAS DU TUN WIRST:<br \/>\n&#8211; Ein Eintauchen in die Natur dank der Hochseilparcours<br \/>\n&#8211; Du wirst einen Wald in gro\u00dfer H\u00f6he erkunden, dank der verschiedenen \u00dcberg\u00e4nge, die einen Baum mit dem anderen verbinden. \u00dcber tibetische Br\u00fccken, Zip-Lines, Lianen, schwebende Baumst\u00e4mme und vieles mehr wirst du deinen Mut auf die Probe stellen.<br \/>\n&#8211; Mit dem gleichen Ticket kannst du w\u00e4hlen, ob du den Park in Torre Boldone, nur wenige Minuten von Bergamo entfernt, oder den in Roncola am Fu\u00dfe des Imagna-Tals besuchen m\u00f6chtest.<br \/>\n&#8211; Je nach gew\u00e4hlter Dauer wirst du aufregende Abenteuer in den Baumwipfeln erleben, dabei in h\u00f6chster Sicherheit und unter der Aufsicht des Teams des Parks.<\/p>\n<p>WAS DICH ERWARTET:<br \/>\nMit Parchi Avventura Bergamo verdoppelt sich der Spa\u00df! Du kannst zwischen dem Park in Roncola, in der malerischen Umgebung des Imagna-Tals, umgeben von jahrhundertealten B\u00e4umen, oder dem Park in Torre Boldone w\u00e4hlen, einem gro\u00dfen gr\u00fcnen Lungengebiet, nur wenige Minuten von der Stadt Bergamo entfernt, das du bequem vom Stadtzentrum mit der elektrischen Stra\u00dfenbahn TEB oder dem st\u00e4dtischen Bus ATB erreichen kannst.<br \/>\nIndem du eine Reihe von Parcours \u00fcberwindest und mitten in der Natur wanderst, wirst du zwischen den B\u00e4umen schwebend, \u00fcber Holzbr\u00fccken gehen und dich von Seilbahnen ins Tal st\u00fcrzen: alles in absoluter Sicherheit und mit Respekt f\u00fcr die Natur.<br \/>\nIm Park von Torre Boldone k\u00f6nnen die Kleinsten auch auf dem Spielplatz spielen und sich im Wasserbrunnen vergn\u00fcgen, sowie die K\u00f6stlichkeiten im Restaurant Into The Woods genie\u00dfen.<\/p>\n<p>Der Eintritt in beide Parks ist KOSTENLOS, es wird nur f\u00fcr den Zugang zu den Hochseilparcours bezahlt.<\/p>\n","indepth":"","howtogetthere":"","timerange":"<p>Von M\u00e4rz bis November 2025<br \/>\n(\u00dcberpr\u00fcfe den Kalender auf parchiavventurabergamo.it)<\/p>\n","seasonality":"","pairings":"","curiosities":"","awards":"","cancellationpolicy":"<p>Das Ticket ist offen und gilt an jedem \u00d6ffnungstag der Hochseilparcours w\u00e4hrend der gesamten Saison 2025.<\/p>\n","moredetails":"<p>Ticketarten und Preise: <\/p>\n<p>ERWACHSENE ab 140 cm K\u00f6rpergr\u00f6\u00dfe<br \/>\n1 Stunde: 17 Euro<br \/>\n2 Stunden: 22 Euro<br \/>\n3 Stunden: 27 Euro<br \/>\nTageskarte: 35 Euro  <\/p>\n<p>KINDER von 110 cm bis 140 cm K\u00f6rpergr\u00f6\u00dfe<br \/>\n1 Stunde: 13 Euro<br \/>\n2 Stunden: 17 Euro<br \/>\n3 Stunden: 21 Euro<br \/>\nTageskarte: 30 Euro  <\/p>\n<p>KINDER unter 110 cm K\u00f6rpergr\u00f6\u00dfe<br \/>\n1 Stunde: 9,50 Euro<br \/>\n2 Stunden: 11,50 Euro<br \/>\nTageskarte: 20 Euro  <\/p>\n<p>ORT UND ZEITRAUM:<br \/>\nMit dem gekauften Ticket kannst du das Datum selbst w\u00e4hlen  von M\u00e4rz bis November, je nach \u00d6ffnung des Abenteuerparks  und du kannst entscheiden, in welchem Abenteuerpark du dein Erlebnis genie\u00dfen m\u00f6chtest.<br \/>\n&#8211; PARCO AVVENTURA DELLA RONCOLA<br \/>\nVia Canale 19<br \/>\n24030 Roncola (BG)<br \/>\n&#8211; PARCO AVVENTURA DI TORRE BOLDONE<br \/>\nVia Ugo Foscolo 10<br \/>\n24020 Torre Boldone (BG)<br \/>\nIm Parco Avventura di Torre Boldone kannst du das Restaurant Into The Woods entdecken.  <\/p>\n<p>PARCOURS<br \/>\n3 einfache Parcours f\u00fcr die Kleinsten<br \/>\n4 Parcours geeignet f\u00fcr Kinder ab 110 cm bis 140 cm: 1 einfach, 2 mittel\/einfach und 1 mittel<br \/>\n3 Parcours nur f\u00fcr Kinder ab 140 cm geeignet, alle 3 mittel\/schwierig  <\/p>\n<p>Der Eintritt in die Parks ist KOSTENLOS, du zahlst nur, wenn du die Hochseilparcours betrittst.<br \/>\nDie Parcours sind f\u00fcr gro\u00dfe und kleine Abenteurer geeignet, ab 3 Jahren bis maximal 100 kg K\u00f6rpergewicht.  <\/p>\n<p>KLEIDUNG<br \/>\nEs wird bequeme, sportliche Kleidung mit Turnschuhen oder Wanderschuhen empfohlen!<br \/>\nAus Sicherheitsgr\u00fcnden sind Flip-Flops oder offene Sandalen VERBOTEN.<\/p>\n","whatsincluded":"<p>&#8211; Zugang zum Park<br \/>\n&#8211; Zugang zu den Hochseilparcours zwischen den B\u00e4umen<br \/>\n&#8211; Ein Team von ausgebildeten und qualifizierten Instruktoren zur Unterst\u00fctzung<br \/>\n&#8211; Klettergurte und die notwendige Ausr\u00fcstung, um die Attraktionen zu nutzen<\/p>\n","whatsnotincluded":"<p>&#8211; Transport von und zu den Erlebnisorten<br \/>\n&#8211; Mahlzeiten<br \/>\n&#8211; Alles, was nicht ausdr\u00fccklich unter &#8220;Was enthalten ist&#8221; aufgef\u00fchrt ist.<\/p>\n","price":"","time":"","service_icons":[],"services":"","parking":"","restaurant":"","breakfast":"","internet":"","children":"","pets":"","latitude":"45.71302760","longitude":"9.70447610","startingprice":"17.00","gpxmap":"","iu_cognitive_accessibility":"notsure","iu_kids":false,"iu_shortprice":"","iu_company_name":"","registered_office":"","iu_addr_streetnumber":"Via Ugo Foscolo","iu_addr_postalcode":"24020","iu_addr_city":"Torre Boldone","iu_addr_province":"Bergamo","iu_phone":"","iu_cell":"","iu_website":"","iu_email":"","iu_vat":"","iu_document_label":"","iu_document":false,"iu_documents":false,"iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"Parco Avventura Bergamo , Via Nelson Mandela, Treviolo","iu_bookingurl":"https:\/\/back-services.com\/newfront\/services.htm?channelid=652&lang=deu&no_qr=si&styleid=3073&ecomid=4401&serviceid=1","iu_videourl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"1h - 2h - 3h - den ganzen Tag","iu_languages":"Englisch - Italienisch","iu_minpeople":"Mindestens 1 Person","iu_maxpeople":"Maximal 50 Personen","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"iu_stars":"","iu_rooms":"","iu_beds":"","id_madeep":"652_4401_1","id_visit_manza":"","id_east":"","id_ristora":"","id_eppen":"","style":"primary","text":"","button_icon":"none","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"validfrom":"01\/03\/2025","validto":"30\/11\/2025","hours":"","ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":"","review":false,"modules":false,"filotto_layout":"scroll","filotto_fill":"manual","filotto_items":false,"iu_motor_accessibility":"no","iu_visual_accessibility":"no","iu_auditory_accessibility":"no","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"random","order_way":"asc"},"or_filter":false,"max_elements":"","show_total":false,"see_all":false,"order_by":"random","order_way":"asc","experience_data":{"description":"<p>WAS DU TUN WIRST:<br \/>\n&#8211; Ein Eintauchen in die Natur dank der Hochseilparcours<br \/>\n&#8211; Du wirst einen Wald in gro\u00dfer H\u00f6he erkunden, dank der verschiedenen \u00dcberg\u00e4nge, die einen Baum mit dem anderen verbinden. \u00dcber tibetische Br\u00fccken, Zip-Lines, Lianen, schwebende Baumst\u00e4mme und vieles mehr wirst du deinen Mut auf die Probe stellen.<br \/>\n&#8211; Mit dem gleichen Ticket kannst du w\u00e4hlen, ob du den Park in Torre Boldone, nur wenige Minuten von Bergamo entfernt, oder den in Roncola am Fu\u00dfe des Imagna-Tals besuchen m\u00f6chtest.<br \/>\n&#8211; Je nach gew\u00e4hlter Dauer wirst du aufregende Abenteuer in den Baumwipfeln erleben, dabei in h\u00f6chster Sicherheit und unter der Aufsicht des Teams des Parks.<\/p>\n<p>WAS DICH ERWARTET:<br \/>\nMit Parchi Avventura Bergamo verdoppelt sich der Spa\u00df! Du kannst zwischen dem Park in Roncola, in der malerischen Umgebung des Imagna-Tals, umgeben von jahrhundertealten B\u00e4umen, oder dem Park in Torre Boldone w\u00e4hlen, einem gro\u00dfen gr\u00fcnen Lungengebiet, nur wenige Minuten von der Stadt Bergamo entfernt, das du bequem vom Stadtzentrum mit der elektrischen Stra\u00dfenbahn TEB oder dem st\u00e4dtischen Bus ATB erreichen kannst.<br \/>\nIndem du eine Reihe von Parcours \u00fcberwindest und mitten in der Natur wanderst, wirst du zwischen den B\u00e4umen schwebend, \u00fcber Holzbr\u00fccken gehen und dich von Seilbahnen ins Tal st\u00fcrzen: alles in absoluter Sicherheit und mit Respekt f\u00fcr die Natur.<br \/>\nIm Park von Torre Boldone k\u00f6nnen die Kleinsten auch auf dem Spielplatz spielen und sich im Wasserbrunnen vergn\u00fcgen, sowie die K\u00f6stlichkeiten im Restaurant Into The Woods genie\u00dfen.<\/p>\n<p>Der Eintritt in beide Parks ist KOSTENLOS, es wird nur f\u00fcr den Zugang zu den Hochseilparcours bezahlt.<\/p>\n","indepth":"","latitude":"45.71302760","longitude":"9.70447610","iu_motor_accessibility":"no","iu_visual_accessibility":"no","iu_auditory_accessibility":"no","iu_cognitive_accessibility":"notsure","iu_addr_streetnumber":"Via Ugo Foscolo","iu_addr_postalcode":"24020","iu_addr_city":"Torre Boldone","iu_addr_province":"Bergamo","timerange":"<p>Von M\u00e4rz bis November 2025<br \/>\n(\u00dcberpr\u00fcfe den Kalender auf parchiavventurabergamo.it)<\/p>\n","cancellationpolicy":"<p>Das Ticket ist offen und gilt an jedem \u00d6ffnungstag der Hochseilparcours w\u00e4hrend der gesamten Saison 2025.<\/p>\n","moredetails":"<p>Ticketarten und Preise: <\/p>\n<p>ERWACHSENE ab 140 cm K\u00f6rpergr\u00f6\u00dfe<br \/>\n1 Stunde: 17 Euro<br \/>\n2 Stunden: 22 Euro<br \/>\n3 Stunden: 27 Euro<br \/>\nTageskarte: 35 Euro  <\/p>\n<p>KINDER von 110 cm bis 140 cm K\u00f6rpergr\u00f6\u00dfe<br \/>\n1 Stunde: 13 Euro<br \/>\n2 Stunden: 17 Euro<br \/>\n3 Stunden: 21 Euro<br \/>\nTageskarte: 30 Euro  <\/p>\n<p>KINDER unter 110 cm K\u00f6rpergr\u00f6\u00dfe<br \/>\n1 Stunde: 9,50 Euro<br \/>\n2 Stunden: 11,50 Euro<br \/>\nTageskarte: 20 Euro  <\/p>\n<p>ORT UND ZEITRAUM:<br \/>\nMit dem gekauften Ticket kannst du das Datum selbst w\u00e4hlen  von M\u00e4rz bis November, je nach \u00d6ffnung des Abenteuerparks  und du kannst entscheiden, in welchem Abenteuerpark du dein Erlebnis genie\u00dfen m\u00f6chtest.<br \/>\n&#8211; PARCO AVVENTURA DELLA RONCOLA<br \/>\nVia Canale 19<br \/>\n24030 Roncola (BG)<br \/>\n&#8211; PARCO AVVENTURA DI TORRE BOLDONE<br \/>\nVia Ugo Foscolo 10<br \/>\n24020 Torre Boldone (BG)<br \/>\nIm Parco Avventura di Torre Boldone kannst du das Restaurant Into The Woods entdecken.  <\/p>\n<p>PARCOURS<br \/>\n3 einfache Parcours f\u00fcr die Kleinsten<br \/>\n4 Parcours geeignet f\u00fcr Kinder ab 110 cm bis 140 cm: 1 einfach, 2 mittel\/einfach und 1 mittel<br \/>\n3 Parcours nur f\u00fcr Kinder ab 140 cm geeignet, alle 3 mittel\/schwierig  <\/p>\n<p>Der Eintritt in die Parks ist KOSTENLOS, du zahlst nur, wenn du die Hochseilparcours betrittst.<br \/>\nDie Parcours sind f\u00fcr gro\u00dfe und kleine Abenteurer geeignet, ab 3 Jahren bis maximal 100 kg K\u00f6rpergewicht.  <\/p>\n<p>KLEIDUNG<br \/>\nEs wird bequeme, sportliche Kleidung mit Turnschuhen oder Wanderschuhen empfohlen!<br \/>\nAus Sicherheitsgr\u00fcnden sind Flip-Flops oder offene Sandalen VERBOTEN.<\/p>\n","whatsincluded":"<p>&#8211; Zugang zum Park<br \/>\n&#8211; Zugang zu den Hochseilparcours zwischen den B\u00e4umen<br \/>\n&#8211; Ein Team von ausgebildeten und qualifizierten Instruktoren zur Unterst\u00fctzung<br \/>\n&#8211; Klettergurte und die notwendige Ausr\u00fcstung, um die Attraktionen zu nutzen<\/p>\n","whatsnotincluded":"<p>&#8211; Transport von und zu den Erlebnisorten<br \/>\n&#8211; Mahlzeiten<br \/>\n&#8211; Alles, was nicht ausdr\u00fccklich unter &#8220;Was enthalten ist&#8221; aufgef\u00fchrt ist.<\/p>\n","startingprice":"17.00","id_madeep":"652_4401_1","iu_minpeople":"Mindestens 1 Person","iu_maxpeople":"Maximal 50 Personen","iu_languages":"Englisch - Italienisch","iu_duration":"1h - 2h - 3h - den ganzen Tag","iu_difficulty":"","iu_bookingurl":"https:\/\/back-services.com\/newfront\/services.htm?channelid=652&lang=deu&no_qr=si&styleid=3073&ecomid=4401&serviceid=1","iu_manager":"Parco Avventura Bergamo , Via Nelson Mandela, Treviolo","review":false,"validfrom":"01\/03\/2025","validto":"30\/11\/2025"},"featured_video":false,"is_an_ambassador":false,"only_ambassadors":false},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/112814","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/112814\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media\/184556"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media?parent=112814"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/categories?post=112814"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/tags?post=112814"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/aggr?post=112814"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/area?post=112814"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/kind?post=112814"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/zona?post=112814"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}