{"id":113793,"date":"2025-06-08T14:56:08","date_gmt":"2025-06-08T12:56:08","guid":{"rendered":"https:\/\/visit.valueservice.cloud\/oggetto\/copia\/"},"modified":"2025-05-12T19:49:57","modified_gmt":"2025-05-12T17:49:57","slug":"fliegenfischen-auf-einheimische-forellen-in-den-baechen-der-bergamasker-taeler","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/fliegenfischen-auf-einheimische-forellen-in-den-baechen-der-bergamasker-taeler\/","title":{"rendered":"Fliegenfischen auf einheimische Forellen in den B\u00e4chen der Bergamasker T\u00e4ler"},"excerpt":{"rendered":"<p>Erlebe ein einzigartiges Abenteuer, begleitet von erfahrenem Personal, in den Voralpen von Bergamo. Probiere die Fliegenfischtechnik auf Fario- und Marmorata-Forellen!<\/p>\n","protected":false},"author":0,"featured_media":184017,"template":"","categories":[524],"tags":[17226],"aggr":[],"area":[],"kind":[18703],"zona":[],"class_list":["post-113793","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-erlebnisse","tag-im-freien-de","kind-esperienza-de"],"acf":{"buttons":[{"style":"primary","text":"Kaufen","icon":{"button_icon":"none"},"function":"content","url":"","select_post":"","target":"_self","url_youtube":"","target_modal":"buyExp"},{"style":"primary","text":"Kontakt","icon":{"button_icon":"none"},"function":"content","url":"","select_post":"","target":"_self","url_youtube":"","target_modal":"modalContact"}],"hero_type":"images","video_youtube_url":"","video_vimeo_url":"","size":"full","hero_title":"Fliegenfischen auf einheimische Forellen in den B\u00e4chen der Bergamasker T\u00e4ler","hero_text":"<p>Erlebe ein einzigartiges Abenteuer, begleitet von erfahrenem Personal, in den Voralpen von Bergamo. Probiere die Fliegenfischtechnik auf Fario- und Marmorata-Forellen!<\/p>\n","slides":[{"image":{"ID":184017,"id":184017,"title":"ec_service_2549_3","filename":"ec_service_2549_3.jpg","filesize":188454,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_2549_3.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/fliegenfischen-auf-einheimische-forellen-in-den-baechen-der-bergamasker-taeler\/ec_service_2549_3-2\/","alt":"","author":"0","description":"","caption":"","name":"ec_service_2549_3-2","status":"inherit","uploaded_to":113793,"date":"2025-04-22 17:48:29","modified":"2025-05-12 17:49:58","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":538,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_2549_3-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_2549_3-300x135.jpg","medium-width":300,"medium-height":135,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_2549_3-768x344.jpg","medium_large-width":768,"medium_large-height":344,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_2549_3-1024x459.jpg","large-width":1024,"large-height":459,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_2549_3.jpg","1536x1536-width":1200,"1536x1536-height":538,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_2549_3.jpg","2048x2048-width":1200,"2048x2048-height":538,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_2549_3.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":135,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_2549_3.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":179,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_2549_3.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":269}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":113795,"id":113795,"title":"ec_service_2549_3_2.jpg","filename":"ec_service_2549_3_2.jpg","filesize":124339,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_2549_3_2.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/fliegenfischen-auf-einheimische-forellen-in-den-baechen-der-bergamasker-taeler\/ec_service_2549_3_2-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"ec_service_2549_3_2-jpg-2","status":"inherit","uploaded_to":113793,"date":"2025-01-15 16:00:20","modified":"2025-05-12 17:49:58","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":647,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_2549_3_2-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_2549_3_2-300x162.jpg","medium-width":300,"medium-height":162,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_2549_3_2-768x414.jpg","medium_large-width":768,"medium_large-height":414,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_2549_3_2-1024x552.jpg","large-width":1024,"large-height":552,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_2549_3_2.jpg","1536x1536-width":1200,"1536x1536-height":647,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_2549_3_2.jpg","2048x2048-width":1200,"2048x2048-height":647,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_2549_3_2-300x300.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_2549_3_2-400x400.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_2549_3_2-600x600.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":113796,"id":113796,"title":"ec_service_2549_3_3.jpg","filename":"ec_service_2549_3_3.jpg","filesize":70500,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_2549_3_3.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/fliegenfischen-auf-einheimische-forellen-in-den-baechen-der-bergamasker-taeler\/ec_service_2549_3_3-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"ec_service_2549_3_3-jpg-2","status":"inherit","uploaded_to":113793,"date":"2025-01-15 16:00:21","modified":"2025-05-12 17:49:58","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":666,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_2549_3_3-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_2549_3_3-300x167.jpg","medium-width":300,"medium-height":167,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_2549_3_3-768x426.jpg","medium_large-width":768,"medium_large-height":426,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_2549_3_3-1024x568.jpg","large-width":1024,"large-height":568,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_2549_3_3.jpg","1536x1536-width":1200,"1536x1536-height":666,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_2549_3_3.jpg","2048x2048-width":1200,"2048x2048-height":666,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_2549_3_3-300x300.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_2549_3_3-400x400.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_2549_3_3-600x600.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":113797,"id":113797,"title":"ec_service_2549_3_4.jpg","filename":"ec_service_2549_3_4.jpg","filesize":145928,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_2549_3_4.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/fliegenfischen-auf-einheimische-forellen-in-den-baechen-der-bergamasker-taeler\/ec_service_2549_3_4-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"ec_service_2549_3_4-jpg-2","status":"inherit","uploaded_to":113793,"date":"2025-01-15 16:00:22","modified":"2025-05-12 17:49:58","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":675,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_2549_3_4-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_2549_3_4-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_2549_3_4-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_2549_3_4-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_2549_3_4.jpg","1536x1536-width":1200,"1536x1536-height":675,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_2549_3_4.jpg","2048x2048-width":1200,"2048x2048-height":675,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_2549_3_4-300x300.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_2549_3_4-400x400.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_2549_3_4-600x600.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":114155,"id":114155,"title":"ec_service_2549_3_5.jpg","filename":"ec_service_2549_3_5.jpg","filesize":137695,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_2549_3_5.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/fliegenfischen-auf-einheimische-forellen-in-den-baechen-der-bergamasker-taeler\/ec_service_2549_3_5-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"ec_service_2549_3_5-jpg-2","status":"inherit","uploaded_to":113793,"date":"2025-01-20 11:00:31","modified":"2025-05-12 17:49:58","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":710,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_2549_3_5-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_2549_3_5-300x178.jpg","medium-width":300,"medium-height":178,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_2549_3_5-768x454.jpg","medium_large-width":768,"medium_large-height":454,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_2549_3_5-1024x606.jpg","large-width":1024,"large-height":606,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_2549_3_5.jpg","1536x1536-width":1200,"1536x1536-height":710,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_2549_3_5.jpg","2048x2048-width":1200,"2048x2048-height":710,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_2549_3_5-300x300.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_2549_3_5-400x400.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_2549_3_5-600x600.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"hero_buttons_group":{"buttons":[{"style":"primary","text":"Kaufen","icon":{"button_icon":"none"},"function":"content","url":"","select_post":"","target":"_self","url_youtube":"","target_modal":"buyExp"},{"style":"primary","text":"Kontakt","icon":{"button_icon":"none"},"function":"content","url":"","select_post":"","target":"_self","url_youtube":"","target_modal":"modalContact"}]},"hero_buttons":false,"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"scroll","filotto_fill":"manual","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"random","order_way":"asc"}},"description":"<p>WAS DU TUN WIRST:<br \/>\n&#8211; Fliegenfischen in den B\u00e4chen der Fl\u00fcsse Brembo, Serio oder Oglio auf Marmorata- und Fario-Forellen.<br \/>\n&#8211; An deiner Seite eine qualifizierte Angelguide, akkreditiert bei der Italienischen Vereinigung der professionellen Angelguides (AIGUPP).<\/p>\n<p>WAS DICH ERWARTET:<br \/>\nDie italienischen Alpen, mit ihren Bergen, B\u00e4chen, Fl\u00fcssen und T\u00e4lern im Norden Italiens, bieten eine einzigartige Gelegenheit f\u00fcr Fliegenfischerei- und Tenkara-Enthusiasten oder f\u00fcr Angler, die eine unvergessliche Reise erleben m\u00f6chten.<\/p>\n<p>Das Fischen in den Nebenfl\u00fcssen des Brembo, Serio und Oglio findet in wundersch\u00f6nen B\u00e4chen der italienischen Alpen statt. Die Fl\u00fcsse Brembo und Serio sind nur 15 Minuten von der Stadt Bergamo entfernt, w\u00e4hrend das Oglio in der N\u00e4he von Brescia liegt (nur 15 Minuten vom Iseosee und 25 Minuten von Brescia entfernt) und nur 45 Minuten von Mailand. Diese Fl\u00fcsse sind bekannt f\u00fcr den reichlichen Bestand an Fario-Forellen und einige seltene und charakteristische Marmorata-Forellen.<\/p>\n<p>Der Tag wird von Fliegenfischerei-Guides gef\u00fchrt, die von AIGUPP (Associazione Italiana Guide Professionali di Pesca) und IGFA (International Game Fishing Association) qualifiziert sind und dich w\u00e4hrend des Tages professionell begleiten werden.<\/p>\n<p>H\u00f6hepunkte des Erlebnisses:<br \/>\n&#8211; Fliegenfischen auf Fario- und Marmorata-Forellen.<br \/>\n&#8211; Die Natur der Valli Bergamasche.<br \/>\n&#8211; Tipps und Ratschl\u00e4ge, wie man den Tag in den T\u00e4lern am besten verbringt, auch f\u00fcr Familien und Begleiter, die nicht angeln.<br \/>\n&#8211; Angelguide-Service f\u00fcr einzelne Angler oder kleine Gruppen (maximal 4 Angler), mit einem Guide f\u00fcr jeweils 2 Angler.<br \/>\n&#8211; Inklusive semi-professionellem Fotoservice.<\/p>\n","indepth":"","howtogetthere":"","timerange":"<p>Angelsaison: M\u00e4rz, April, Mai, Juni, Juli, August, September, Oktober<br \/>\nJeden Tag der Woche, von 8:00 bis 19:00 Uhr: die Angelstunden betragen 7 Stunden.<\/p>\n","seasonality":"","pairings":"","curiosities":"","awards":"","cancellationpolicy":"<p>Im Falle eines &#8220;No Shows&#8221; wird der Betrag zu 100% einbehalten.<\/p>\n<p>Stornierung vor dem geplanten Datum:<br \/>\n&#8211; 10 Tage: 100% R\u00fcckerstattung der Anzahlung<br \/>\n&#8211; 5 Tage: 50% R\u00fcckerstattung der Anzahlung<br \/>\n&#8211; 0\/5 Tage: Keine R\u00fcckerstattung<\/p>\n<p>Der Veranstalter der Erfahrung beh\u00e4lt sich das Recht vor, die Route bei ung\u00fcnstigen Umst\u00e4nden, wie ung\u00fcnstigen Wetterbedingungen oder Bedingungen der Gew\u00e4sser, zu \u00e4ndern.<\/p>\n","moredetails":"<p>Treffpunkt:<br \/>\nJe nachdem, ob der Angeltag im Valle Seriana, im Val di Scalve, im Valle Brembana oder im Valle Camonica stattfindet, wird der Treffpunkt an einem Ort entlang der Stra\u00dfe zum Tal liegen. Der genaue Treffpunkt wird nach der Buchung gemeinsam mit den Veranstaltern der Erfahrung festgelegt.<\/p>\n<p>Geeignete Outdoor-Bekleidung ist erforderlich.<\/p>\n<p>Bedingungen f\u00fcr die Buchung: Buchung bis zu 5 Tage vor dem festgelegten Datum.<\/p>\n","whatsincluded":"<p>&#8211; Angelguide-Service mit Begleitung<br \/>\n(Die Dauer des Angeltages variiert je nach Saison, betr\u00e4gt jedoch mindestens 7\/8 Stunden)<br \/>\n&#8211; Verwaltung der Genehmigungsprozesse (Angellizenz und Erlaubnis zum Zugang zu den Gew\u00e4ssern)<br \/>\n&#8211; Semi-professioneller Fotoservice<\/p>\n","whatsnotincluded":"<p>&#8211; Italienische Angellizenz (Kosten 23,00 Euro pro Angler, g\u00fcltig f\u00fcr ein Jahr)<br \/>\n&#8211; Kosten f\u00fcr die Erlaubnis zum Zugang zu den Gew\u00e4ssern  variabel ab 20,00 Euro pro Angler und Tag.<br \/>\n&#8211; Transfer von und zum Angelpunkt (kann jedoch bei der Buchung angefragt werden)<br \/>\n&#8211; Alle anderen Elemente, die nicht in &#8220;Was ist enthalten&#8221; aufgef\u00fchrt sind.<\/p>\n","price":"","time":"","service_icons":[],"services":"","parking":"","restaurant":"","breakfast":"","internet":"","children":"","pets":"","latitude":"45.86405600","longitude":"9.88331140","startingprice":"190.00","gpxmap":"","iu_kids":false,"iu_shortprice":"","iu_company_name":"","registered_office":"","iu_addr_streetnumber":"Via Europa, 111","iu_addr_postalcode":"24028","iu_addr_city":"Ponte Nossa","iu_addr_province":"Bergamo","iu_phone":"","iu_cell":"","iu_website":"","iu_email":"","iu_vat":"","iu_document_label":"","iu_document":false,"iu_documents":false,"iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"Alps Store & Fishing Service, Via Martin Luther King, 4, Grassobbio","iu_bookingurl":"https:\/\/back-services.com\/newfront\/services.htm?channelid=652&lang=deu&no_qr=si&styleid=3073&ecomid=2549&serviceid=3","iu_videourl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"den ganzen Tag","iu_languages":"Italienisch - Englisch","iu_minpeople":"Mindestens 1 Person","iu_maxpeople":"Maximal 4 Personen","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"iu_stars":"","iu_rooms":"","iu_beds":"","id_madeep":"652_2549_3","id_visit_manza":"","id_east":"","id_ristora":"","id_eppen":"","style":"primary","text":"","button_icon":"none","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"validfrom":"15\/01\/2025","validto":"31\/10\/2025","hours":"","ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":"","review":false,"modules":false,"filotto_layout":"scroll","filotto_fill":"manual","filotto_items":false,"iu_motor_accessibility":"no","iu_visual_accessibility":"no","iu_auditory_accessibility":"yes","iu_cognitive_accessibility":"no","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"random","order_way":"asc"},"or_filter":false,"max_elements":"","show_total":false,"see_all":false,"order_by":"random","order_way":"asc","only_ambassadors":false},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/113793","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/113793\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media\/184017"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media?parent=113793"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/categories?post=113793"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/tags?post=113793"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/aggr?post=113793"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/area?post=113793"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/kind?post=113793"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/zona?post=113793"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}