{"id":116689,"date":"2025-06-08T14:59:24","date_gmt":"2025-06-08T12:59:24","guid":{"rendered":"https:\/\/visit.valueservice.cloud\/oggetto\/copia\/"},"modified":"2025-05-12T19:55:12","modified_gmt":"2025-05-12T17:55:12","slug":"san-pellegrino-terme-und-die-kaesesorten-des-valle-brembana","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/san-pellegrino-terme-und-die-kaesesorten-des-valle-brembana\/","title":{"rendered":"San Pellegrino Terme und die K\u00e4sesorten des Valle Brembana"},"excerpt":{"rendered":"<p>F\u00fchrung durch den Bauernhof Patrick Giupponi, Verkostung typischer Produkte und Outdoor-Spiel durch die Stra\u00dfen von San Pellegrino Terme.<\/p>\n","protected":false},"author":0,"featured_media":184570,"template":"","categories":[524,521],"tags":[17268],"aggr":[],"area":[],"kind":[18703],"zona":[],"class_list":["post-116689","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-erlebnisse","category-esperienze","tag-smart-orobie-de","kind-esperienza-de"],"acf":{"buttons":[{"style":"primary","text":"Kaufen","icon":{"button_icon":"none"},"function":"content","url":"","select_post":"","target":"_self","url_youtube":"","target_modal":"buyExp"},{"style":"primary","text":"Kontakt","icon":{"button_icon":"none"},"function":"content","url":"","select_post":"","target":"_self","url_youtube":"","target_modal":"modalContact"}],"hero_type":"images","video_youtube_url":"","video_vimeo_url":"","size":"full","hero_title":"San Pellegrino Terme und die K\u00e4sesorten des Valle Brembana","hero_text":"<p>F\u00fchrung durch den Bauernhof Patrick Giupponi, Verkostung typischer Produkte und Outdoor-Spiel durch die Stra\u00dfen von San Pellegrino Terme.<\/p>\n","slides":[{"image":{"ID":184570,"id":184570,"title":"ec_service_4413_2","filename":"ec_service_4413_2.jpg","filesize":118569,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4413_2.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/san-pellegrino-terme-und-die-kaesesorten-des-valle-brembana\/ec_service_4413_2-2\/","alt":"","author":"0","description":"","caption":"","name":"ec_service_4413_2-2","status":"inherit","uploaded_to":116689,"date":"2025-04-22 17:51:06","modified":"2025-05-12 17:55:13","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":430,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4413_2-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4413_2-300x108.jpg","medium-width":300,"medium-height":108,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4413_2-768x275.jpg","medium_large-width":768,"medium_large-height":275,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4413_2-1024x367.jpg","large-width":1024,"large-height":367,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4413_2.jpg","1536x1536-width":1200,"1536x1536-height":430,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4413_2.jpg","2048x2048-width":1200,"2048x2048-height":430,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4413_2.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":108,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4413_2.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":143,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4413_2.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":215}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":118932,"id":118932,"title":"ec_service_4413_2_2.jpg","filename":"ec_service_4413_2_2.jpg","filesize":124613,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/02\/ec_service_4413_2_2.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/san-pellegrino-terme-und-die-kaesesorten-des-valle-brembana\/ec_service_4413_2_2-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"ec_service_4413_2_2-jpg-2","status":"inherit","uploaded_to":116689,"date":"2025-02-13 11:01:41","modified":"2025-05-12 17:55:13","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":566,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/02\/ec_service_4413_2_2-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/02\/ec_service_4413_2_2-300x142.jpg","medium-width":300,"medium-height":142,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/02\/ec_service_4413_2_2-768x362.jpg","medium_large-width":768,"medium_large-height":362,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/02\/ec_service_4413_2_2-1024x483.jpg","large-width":1024,"large-height":483,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/02\/ec_service_4413_2_2.jpg","1536x1536-width":1200,"1536x1536-height":566,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/02\/ec_service_4413_2_2.jpg","2048x2048-width":1200,"2048x2048-height":566,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/02\/ec_service_4413_2_2.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":142,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/02\/ec_service_4413_2_2.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":189,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/02\/ec_service_4413_2_2.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":283}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":118933,"id":118933,"title":"ec_service_4413_2_3.jpg","filename":"ec_service_4413_2_3.jpg","filesize":77820,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/02\/ec_service_4413_2_3.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/san-pellegrino-terme-und-die-kaesesorten-des-valle-brembana\/ec_service_4413_2_3-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"ec_service_4413_2_3-jpg-2","status":"inherit","uploaded_to":116689,"date":"2025-02-13 11:01:42","modified":"2025-05-12 17:55:13","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":631,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/02\/ec_service_4413_2_3-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/02\/ec_service_4413_2_3-300x158.jpg","medium-width":300,"medium-height":158,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/02\/ec_service_4413_2_3-768x404.jpg","medium_large-width":768,"medium_large-height":404,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/02\/ec_service_4413_2_3-1024x538.jpg","large-width":1024,"large-height":538,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/02\/ec_service_4413_2_3.jpg","1536x1536-width":1200,"1536x1536-height":631,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/02\/ec_service_4413_2_3.jpg","2048x2048-width":1200,"2048x2048-height":631,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/02\/ec_service_4413_2_3.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":158,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/02\/ec_service_4413_2_3.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":210,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/02\/ec_service_4413_2_3.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":316}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"hero_buttons_group":{"buttons":[{"style":"primary","text":"Kaufen","icon":{"button_icon":"none"},"function":"content","url":"","select_post":"","target":"_self","url_youtube":"","target_modal":"buyExp"},{"style":"primary","text":"Kontakt","icon":{"button_icon":"none"},"function":"content","url":"","select_post":"","target":"_self","url_youtube":"","target_modal":"modalContact"}]},"hero_buttons":false,"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"scroll","filotto_fill":"manual","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"random","order_way":"asc"}},"description":"<p>Eine leichte und unterhaltsame Erfahrung, die Ihnen gleichzeitig San Pellegrino Terme im Detail n\u00e4herbringt: Hier ist f\u00fcr Sie das San Pellegrino Terme Experience. Die Gemeinde bewahrt Zeugnisse der Belle \u00c9poque im perfekten Liberty-Stil, darunter die eindrucksvollsten das Kasino und das Grand Hotel, beliebte Touristenziele des Hochadels der damaligen Zeit.<\/p>\n<p>PROGRAMM<br \/>\nDie Erfahrung beginnt um 10:30 Uhr mit einer F\u00fchrung durch die Caseificio Giupponi, einen jungen und dynamischen Bauernhof, auf dem die Leidenschaft seit Generationen weitergegeben wird. Hier haben die Besucher die M\u00f6glichkeit, die Geheimnisse der Produktion ihrer ausgezeichneten Milchprodukte zu entdecken, von denen einige f\u00fcr ihre Qualit\u00e4t ausgezeichnet wurden.<br \/>\nSie werden zu einer k\u00f6stlichen Verkostung der Produkte des Caseificio gef\u00fchrt.<br \/>\nNach einem Vormittag voller Geschmackserlebnisse entdecken Sie ab 14:30 Uhr die Wunder von San Pellegrino Terme durch verschiedene Spiele und R\u00e4tsel, die Ihnen die Sch\u00f6nheiten des Ortes und deren Geschichte n\u00e4herbringen.<\/p>\n","indepth":"","howtogetthere":"","timerange":"<p>Der erste Samstag der Monate M\u00e4rz, April, Mai und Juni:<\/p>\n<p>M\u00e4rz 2025<br \/>\nApril 2025<br \/>\nMai 2025<br \/>\nJuni 2025<\/p>\n","seasonality":"","pairings":"","curiosities":"","awards":"","cancellationpolicy":"<p>Keine R\u00fcckerstattung bei Nichterscheinen.<br \/>\nKostenlose Stornierung bis 7 Tage vor dem Erlebnisdatum.<br \/>\nWenn die Stornierung nicht innerhalb der 7 Tage vor dem Service erfolgt, wird der gesamte Betrag in Rechnung gestellt.<\/p>\n","moredetails":"<p>PREISE<br \/>\nDie Erfahrung kostet 29 Euro pro Person.<br \/>\nF\u00fcr Kinder von 0 bis 3 Jahren ist sie kostenlos.<\/p>\n","whatsincluded":"<p>&#8211; Gef\u00fchrte Besichtigung des Bauernhofs Patrick Giupponi<br \/>\n&#8211; Verkostung von typischen Produkten, angeboten vom Bauernhof<br \/>\n&#8211; Kit f\u00fcr das SanpeGame, das Spiel zur Entdeckung von San Pellegrino Terme<\/p>\n","whatsnotincluded":"<p>&#8211; Transport von \/ zu den Erlebnisorten<br \/>\n&#8211; Alles, was nicht unter &#8220;Was enthalten ist&#8221; aufgef\u00fchrt ist<\/p>\n","price":"","time":"","service_icons":[],"services":"","parking":"","restaurant":"","breakfast":"","internet":"","children":"","pets":"","latitude":"45.82830820","longitude":"9.66962060","startingprice":"29.00","gpxmap":"","iu_kids":false,"iu_shortprice":"","iu_company_name":"","registered_office":"","iu_addr_streetnumber":"Via Pregalleno, 11","iu_addr_postalcode":"24016","iu_addr_city":"San Pellegrino Terme","iu_addr_province":"Bergamo","iu_phone":"","iu_cell":"","iu_website":"","iu_email":"","iu_vat":"","iu_document_label":"","iu_document":false,"iu_documents":false,"iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"Road 470 srls, Via Busi Cariani, 28, San giovanni bianco","iu_bookingurl":"https:\/\/back-services.com\/newfront\/services.htm?channelid=652&lang=deu&no_qr=si&styleid=3073&ecomid=4413&serviceid=2","iu_videourl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"4h","iu_languages":"Italienisch","iu_minpeople":"Mindestens 1 Person","iu_maxpeople":"Maximal 10 Personen","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"iu_stars":"","iu_rooms":"","iu_beds":"","id_madeep":"652_4413_2","id_visit_manza":"","id_east":"","id_ristora":"","id_eppen":"","style":"primary","text":"","button_icon":"none","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"validfrom":"31\/01\/2025","validto":"31\/01\/2035","hours":"","ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":"","review":false,"modules":false,"filotto_layout":"scroll","filotto_fill":"manual","filotto_items":false,"iu_motor_accessibility":"no","iu_visual_accessibility":"no","iu_auditory_accessibility":"no","iu_cognitive_accessibility":"no","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"random","order_way":"asc"},"or_filter":false,"max_elements":"","show_total":false,"see_all":false,"order_by":"random","order_way":"asc","experience_data":{"description":"<p>Eine leichte und unterhaltsame Erfahrung, die Ihnen gleichzeitig San Pellegrino Terme im Detail n\u00e4herbringt: Hier ist f\u00fcr Sie das San Pellegrino Terme Experience. Die Gemeinde bewahrt Zeugnisse der Belle \u00c9poque im perfekten Liberty-Stil, darunter die eindrucksvollsten das Kasino und das Grand Hotel, beliebte Touristenziele des Hochadels der damaligen Zeit.<\/p>\n<p>PROGRAMM<br \/>\nDie Erfahrung beginnt um 10:30 Uhr mit einer F\u00fchrung durch die Caseificio Giupponi, einen jungen und dynamischen Bauernhof, auf dem die Leidenschaft seit Generationen weitergegeben wird. Hier haben die Besucher die M\u00f6glichkeit, die Geheimnisse der Produktion ihrer ausgezeichneten Milchprodukte zu entdecken, von denen einige f\u00fcr ihre Qualit\u00e4t ausgezeichnet wurden.<br \/>\nSie werden zu einer k\u00f6stlichen Verkostung der Produkte des Caseificio gef\u00fchrt.<br \/>\nNach einem Vormittag voller Geschmackserlebnisse entdecken Sie ab 14:30 Uhr die Wunder von San Pellegrino Terme durch verschiedene Spiele und R\u00e4tsel, die Ihnen die Sch\u00f6nheiten des Ortes und deren Geschichte n\u00e4herbringen.<\/p>\n","indepth":"","latitude":"45.82830820","longitude":"9.66962060","iu_motor_accessibility":"no","iu_visual_accessibility":"no","iu_auditory_accessibility":"no","iu_cognitive_accessibility":"no","iu_addr_streetnumber":"Via Pregalleno, 11","iu_addr_postalcode":"24016","iu_addr_city":"San Pellegrino Terme","iu_addr_province":"Bergamo","timerange":"<p>Der erste Samstag der Monate M\u00e4rz, April, Mai und Juni:<\/p>\n<p>M\u00e4rz 2025<br \/>\nApril 2025<br \/>\nMai 2025<br \/>\nJuni 2025<\/p>\n","cancellationpolicy":"<p>Keine R\u00fcckerstattung bei Nichterscheinen.<br \/>\nKostenlose Stornierung bis 7 Tage vor dem Erlebnisdatum.<br \/>\nWenn die Stornierung nicht innerhalb der 7 Tage vor dem Service erfolgt, wird der gesamte Betrag in Rechnung gestellt.<\/p>\n","moredetails":"<p>PREISE<br \/>\nDie Erfahrung kostet 29 Euro pro Person.<br \/>\nF\u00fcr Kinder von 0 bis 3 Jahren ist sie kostenlos.<\/p>\n","whatsincluded":"<p>&#8211; Gef\u00fchrte Besichtigung des Bauernhofs Patrick Giupponi<br \/>\n&#8211; Verkostung von typischen Produkten, angeboten vom Bauernhof<br \/>\n&#8211; Kit f\u00fcr das SanpeGame, das Spiel zur Entdeckung von San Pellegrino Terme<\/p>\n","whatsnotincluded":"<p>&#8211; Transport von \/ zu den Erlebnisorten<br \/>\n&#8211; Alles, was nicht unter &#8220;Was enthalten ist&#8221; aufgef\u00fchrt ist<\/p>\n","startingprice":"29.00","id_madeep":"652_4413_2","iu_minpeople":"Mindestens 1 Person","iu_maxpeople":"Maximal 10 Personen","iu_languages":"Italienisch","iu_duration":"4h","iu_difficulty":"","iu_bookingurl":"https:\/\/back-services.com\/newfront\/services.htm?channelid=652&lang=deu&no_qr=si&styleid=3073&ecomid=4413&serviceid=2","iu_manager":"Road 470 srls, Via Busi Cariani, 28, San giovanni bianco","review":false,"validfrom":"31\/01\/2025","validto":"31\/01\/2035"},"featured_video":false,"is_an_ambassador":false,"only_ambassadors":false},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/116689","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/116689\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media\/184570"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media?parent=116689"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/categories?post=116689"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/tags?post=116689"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/aggr?post=116689"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/area?post=116689"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/kind?post=116689"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/zona?post=116689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}