{"id":121935,"date":"2025-06-08T14:57:56","date_gmt":"2025-06-08T12:57:56","guid":{"rendered":"https:\/\/visit.valueservice.cloud\/oggetto\/erlebnis-fur-gruppen-entdeckung-des-landwirtschaftlichen-bieres-und-naturlehrpfad-in-rogno-copia\/"},"modified":"2025-05-12T19:52:55","modified_gmt":"2025-05-12T17:52:55","slug":"auf-entdeckung-der-agrar-bier","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/auf-entdeckung-der-agrar-bier\/","title":{"rendered":"Auf Entdeckung der Agrar-Bier"},"excerpt":{"rendered":"<p>Besuche eine handwerkliche Brauerei und koste ihre K\u00f6stlichkeiten.<\/p>\n","protected":false},"author":0,"featured_media":184311,"template":"","categories":[524,521],"tags":[],"aggr":[],"area":[],"kind":[18703],"zona":[],"class_list":["post-121935","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-erlebnisse","category-esperienze","kind-esperienza-de"],"acf":{"buttons":[{"style":"primary","text":"Kaufen","icon":{"button_icon":"none"},"function":"content","url":"","select_post":"","target":"_self","url_youtube":"","target_modal":"buyExp"},{"style":"primary","text":"Kontakt","icon":{"button_icon":"none"},"function":"content","url":"","select_post":"","target":"_self","url_youtube":"","target_modal":"modalContact"}],"hero_type":"images","video_youtube_url":"","video_vimeo_url":"","size":"full","hero_title":"Auf Entdeckung der Agrar-Bier","hero_text":"<p>Besuche eine handwerkliche Brauerei und koste ihre K\u00f6stlichkeiten.<\/p>\n","hero_buttons_group":{"buttons":[{"style":"primary","text":"Kaufen","icon":{"button_icon":"none"},"function":"content","url":"","select_post":"","target":"_self","url_youtube":"","target_modal":"buyExp"},{"style":"primary","text":"Kontakt","icon":{"button_icon":"none"},"function":"content","url":"","select_post":"","target":"_self","url_youtube":"","target_modal":"modalContact"}]},"hero_buttons":false,"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"scroll","filotto_fill":"manual","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"random","order_way":"asc"}},"description":"<p>Jeden Samstag um 17:00 Uhr bietet die landwirtschaftliche Brauerei Pagus in Darfo Boario Terme die M\u00f6glichkeit zu einer Verkostung, bei der Erkl\u00e4rungen und interessante Fakten rund um die Welt des Bieres geliefert werden. Anschlie\u00dfend erwartet dich ein sensorisches Labor, in dem du mehr \u00fcber die Rohstoffe erf\u00e4hrst, die zur Herstellung des Bieres verwendet werden. Die landwirtschaftliche Gesellschaft Pagus besitzt ein Grundst\u00fcck, auf dem Gerste, Weizen, schwarzer Spelzmais und Hopfen angebaut werden: Hier stehen km 0, Produktverfolgbarkeit und Nachhaltigkeit im Vordergrund.<\/p>\n<p>Zum Abschluss der Prozess-Erkl\u00e4rung und des sensorischen Labors wird dir eine Verkostung von 3 Bieren der Brauerei Pagus angeboten, begleitet von typischen Produkten der Region.<\/p>\n<p>Au\u00dferdem hast du die M\u00f6glichkeit, die handwerklich gebrauten Biere im Verkaufsbereich der Area Pagus in Darfo Boario Terme zu kaufen.<\/p>\n","indepth":"","howtogetthere":"","timerange":"<p>Jeden Samstag um 17:00 Uhr<\/p>\n","seasonality":"","pairings":"","curiosities":"","awards":"","cancellationpolicy":"<p>Keine R\u00fcckerstattung bei Nichterscheinen<br \/>\nKostenlose Stornierung innerhalb von 4 Tagen ab dem Datum des gebuchten Erlebnisses.<\/p>\n","moredetails":"<p>PREISE<br \/>\nDie Erfahrung ist nur f\u00fcr Erwachsene und kostet 15 Euro pro Person.<\/p>\n","whatsincluded":"<p>&#8211; Gef\u00fchrte Besichtigung des landwirtschaftlichen Betriebs Pagus<br \/>\n&#8211; Verkostung von Pagus Landwirtschafts-Bier und lokalen Spezialit\u00e4ten<\/p>\n","whatsnotincluded":"<p>&#8211; Transfers zu und von den Orten des Erlebnisses<br \/>\n&#8211; alles, was nicht ausdr\u00fccklich im Abschnitt &#8220;was enthalten ist&#8221; erw\u00e4hnt wird<\/p>\n","price":"","time":"","service_icons":[],"services":"","parking":"","restaurant":"","breakfast":"","internet":"","children":"","pets":"","latitude":"45.86885750","longitude":"10.15218020","startingprice":"15.00","gpxmap":"","iu_visual_accessibility":"notsure","iu_kids":false,"iu_shortprice":"","iu_company_name":"","registered_office":"","iu_addr_streetnumber":"Via Nazionale","iu_addr_postalcode":"25047","iu_addr_city":"Darfo Boario Terme","iu_addr_province":"Brescia","iu_phone":"","iu_cell":"","iu_website":"","iu_email":"","iu_vat":"","iu_document_label":"","iu_document":false,"iu_documents":false,"iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"Societ\u00e0 Agricola Pagus , Via Montegrappa, 43, Rogno","iu_bookingurl":"https:\/\/back-services.com\/newfront\/services.htm?channelid=652&lang=deu&no_qr=si&styleid=3073&ecomid=4135&serviceid=3","iu_videourl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"1h","iu_languages":"Italienisch - Englisch","iu_minpeople":"Mindestens 1 Person","iu_maxpeople":"Maximal 15 Personen","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"iu_stars":"","iu_rooms":"","iu_beds":"","id_madeep":"652_4135_3","id_visit_manza":"","id_east":"","id_ristora":"","id_eppen":"","style":"primary","text":"","button_icon":"none","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"validfrom":"14\/03\/2024","validto":"19\/10\/2025","hours":"","ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":"","review":false,"modules":false,"filotto_layout":"scroll","filotto_fill":"manual","filotto_items":false,"iu_motor_accessibility":"no","iu_auditory_accessibility":"yes","iu_cognitive_accessibility":"no","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"random","order_way":"asc"},"or_filter":false,"max_elements":"","show_total":false,"see_all":false,"order_by":"random","order_way":"asc","experience_data":{"description":"<p>Jeden Samstag um 17:00 Uhr bietet die landwirtschaftliche Brauerei Pagus in Darfo Boario Terme die M\u00f6glichkeit zu einer Verkostung, bei der Erkl\u00e4rungen und interessante Fakten rund um die Welt des Bieres geliefert werden. Anschlie\u00dfend erwartet dich ein sensorisches Labor, in dem du mehr \u00fcber die Rohstoffe erf\u00e4hrst, die zur Herstellung des Bieres verwendet werden. Die landwirtschaftliche Gesellschaft Pagus besitzt ein Grundst\u00fcck, auf dem Gerste, Weizen, schwarzer Spelzmais und Hopfen angebaut werden: Hier stehen km 0, Produktverfolgbarkeit und Nachhaltigkeit im Vordergrund.<\/p>\n<p>Zum Abschluss der Prozess-Erkl\u00e4rung und des sensorischen Labors wird dir eine Verkostung von 3 Bieren der Brauerei Pagus angeboten, begleitet von typischen Produkten der Region.<\/p>\n<p>Au\u00dferdem hast du die M\u00f6glichkeit, die handwerklich gebrauten Biere im Verkaufsbereich der Area Pagus in Darfo Boario Terme zu kaufen.<\/p>\n","indepth":"","latitude":"45.86885750","longitude":"10.15218020","iu_motor_accessibility":"no","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"yes","iu_cognitive_accessibility":"no","iu_addr_streetnumber":"Via Nazionale","iu_addr_postalcode":"25047","iu_addr_city":"Darfo Boario Terme","iu_addr_province":"Brescia","timerange":"<p>Jeden Samstag um 17:00 Uhr<\/p>\n","cancellationpolicy":"<p>Keine R\u00fcckerstattung bei Nichterscheinen<br \/>\nKostenlose Stornierung innerhalb von 4 Tagen ab dem Datum des gebuchten Erlebnisses.<\/p>\n","moredetails":"<p>PREISE<br \/>\nDie Erfahrung ist nur f\u00fcr Erwachsene und kostet 15 Euro pro Person.<\/p>\n","whatsincluded":"<p>&#8211; Gef\u00fchrte Besichtigung des landwirtschaftlichen Betriebs Pagus<br \/>\n&#8211; Verkostung von Pagus Landwirtschafts-Bier und lokalen Spezialit\u00e4ten<\/p>\n","whatsnotincluded":"<p>&#8211; Transfers zu und von den Orten des Erlebnisses<br \/>\n&#8211; alles, was nicht ausdr\u00fccklich im Abschnitt &#8220;was enthalten ist&#8221; erw\u00e4hnt wird<\/p>\n","startingprice":"15.00","id_madeep":"652_4135_3","iu_minpeople":"Mindestens 1 Person","iu_maxpeople":"Maximal 15 Personen","iu_languages":"Italienisch - Englisch","iu_duration":"1h","iu_difficulty":"","iu_bookingurl":"https:\/\/back-services.com\/newfront\/services.htm?channelid=652&lang=deu&no_qr=si&styleid=3073&ecomid=4135&serviceid=3","iu_manager":"Societ\u00e0 Agricola Pagus , Via Montegrappa, 43, Rogno","review":false,"validfrom":"14\/03\/2024","validto":"19\/10\/2025"},"featured_video":false,"is_an_ambassador":false,"only_ambassadors":false,"slides":[{"image":{"ID":184311,"id":184311,"title":"ec_service_4135_3","filename":"ec_service_4135_3.jpg","filesize":120338,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4135_3.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/auf-entdeckung-der-agrar-bier\/ec_service_4135_3-2\/","alt":"","author":"0","description":"","caption":"","name":"ec_service_4135_3-2","status":"inherit","uploaded_to":121935,"date":"2025-04-22 17:49:46","modified":"2025-05-12 17:52:56","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":549,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4135_3-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4135_3-300x137.jpg","medium-width":300,"medium-height":137,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4135_3-768x351.jpg","medium_large-width":768,"medium_large-height":351,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4135_3-1024x468.jpg","large-width":1024,"large-height":468,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4135_3.jpg","1536x1536-width":1200,"1536x1536-height":549,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4135_3.jpg","2048x2048-width":1200,"2048x2048-height":549,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4135_3.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":137,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4135_3.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":183,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4135_3.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":275}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":121950,"id":121950,"title":"ec_service_4135_3_2.jpg","filename":"ec_service_4135_3_2.jpg","filesize":55499,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/02\/ec_service_4135_3_2.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/ec_service_4135_3_2-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"ec_service_4135_3_2-jpg-2","status":"inherit","uploaded_to":0,"date":"2025-02-18 16:13:19","modified":"2025-05-12 09:40:57","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":387,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/02\/ec_service_4135_3_2-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/02\/ec_service_4135_3_2-300x97.jpg","medium-width":300,"medium-height":97,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/02\/ec_service_4135_3_2-768x248.jpg","medium_large-width":768,"medium_large-height":248,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/02\/ec_service_4135_3_2-1024x330.jpg","large-width":1024,"large-height":330,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/02\/ec_service_4135_3_2.jpg","1536x1536-width":1200,"1536x1536-height":387,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/02\/ec_service_4135_3_2.jpg","2048x2048-width":1200,"2048x2048-height":387,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/02\/ec_service_4135_3_2.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":97,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/02\/ec_service_4135_3_2.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":129,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/02\/ec_service_4135_3_2.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":194}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":121951,"id":121951,"title":"ec_service_4135_3_3.jpg","filename":"ec_service_4135_3_3.jpg","filesize":57329,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/02\/ec_service_4135_3_3.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/ec_service_4135_3_3-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"ec_service_4135_3_3-jpg-2","status":"inherit","uploaded_to":0,"date":"2025-02-18 16:13:20","modified":"2025-05-12 09:40:57","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":464,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/02\/ec_service_4135_3_3-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/02\/ec_service_4135_3_3-300x116.jpg","medium-width":300,"medium-height":116,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/02\/ec_service_4135_3_3-768x297.jpg","medium_large-width":768,"medium_large-height":297,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/02\/ec_service_4135_3_3-1024x396.jpg","large-width":1024,"large-height":396,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/02\/ec_service_4135_3_3.jpg","1536x1536-width":1200,"1536x1536-height":464,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/02\/ec_service_4135_3_3.jpg","2048x2048-width":1200,"2048x2048-height":464,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/02\/ec_service_4135_3_3.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":116,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/02\/ec_service_4135_3_3.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":155,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/02\/ec_service_4135_3_3.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":232}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}]},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/121935","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/121935\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media\/184311"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media?parent=121935"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/categories?post=121935"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/tags?post=121935"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/aggr?post=121935"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/area?post=121935"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/kind?post=121935"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/zona?post=121935"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}