{"id":125617,"date":"2025-02-25T13:42:34","date_gmt":"2025-02-25T12:42:34","guid":{"rendered":"https:\/\/visit.valueservice.cloud\/oggetto\/parcours-culturel-bergamo-brescia\/"},"modified":"2025-05-12T13:51:38","modified_gmt":"2025-05-12T11:51:38","slug":"parcours-culturel-bergamo-brescia","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/parcours-culturel-bergamo-brescia\/","title":{"rendered":"Parcours culturel Bergamo Brescia"},"excerpt":{"rendered":"","protected":false},"author":7,"featured_media":41761,"template":"","categories":[],"tags":[],"aggr":[],"area":[],"kind":[349],"zona":[],"class_list":["post-125617","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","kind-itinerario"],"acf":{"slides":[{"image":false,"video":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/02\/POI-Ciclovia-BGBS.mp4","video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"Parcours culturel Bergamo Brescia","text":"<p>Une aventure \u00e0 v\u00e9lo entre culture et nature<\/p>\n","hero_slide_buttons":{"buttons":[{"style":"primary","text":"Guarda il video ","icon":{"button_icon":"none"},"function":"video","url":"","select_post":null,"target":false,"url_youtube":"https:\/\/www.youtube.com\/watch?v=ooATx-rXSp4","target_modal":""}]},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"scroll","filotto_fill":"manual","filotto_items":[{"object":false,"title":"","image":false,"youtubeurl":"","label_cta":"","url":"","target":"_self","preview":""}],"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":0,"show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":false,"order_way":false}},"modules":[{"acf_fc_layout":"two_columns_module","tcm_title":{"title_text":""},"tcm_ui":[{"label":"Longueur totale :","value":"170 km"},{"label":"Route principale :  ","value":"76 km"},{"label":"Anneaux de variante suppl\u00e9mentaires :  ","value":"70 km"},{"label":"Points d'int\u00e9r\u00eat :","value":"plus de 800"},{"label":"Itin\u00e9raires p\u00e9destres :","value":"8 km"}],"tcm_content":[{"acf_fc_layout":"text","text":"<p>L&#8217;itin\u00e9raire cyclable culturel Bergame-Brescia relie les deux villes, <strong>Capitales de la culture 2023<\/strong>, gr\u00e2ce \u00e0 un parcours de <strong>76 km<\/strong> qui traverse des centres historiques, des villages et des sites culturels, offrant une exp\u00e9rience s\u00fbre et agr\u00e9able. Sur certains tron\u00e7ons, l&#8217;itin\u00e9raire se divise, ce qui permet d&#8217;explorer<strong> 13 boucles suppl\u00e9mentaires<\/strong> \u00e0 l&#8217;itin\u00e9raire principal, pour un total de 70 km. Ces boucles sont compl\u00e9t\u00e9es par des itin\u00e9raires de promenade dans des <strong>centres historiques ou des espaces naturels<\/strong>, d&#8217;une longueur totale de <strong>8 km<\/strong>, ainsi que par 19 km de liaisons avec des gares et d&#8217;autres lieux d&#8217;int\u00e9r\u00eat.  <\/p>\n<p>L&#8217;<strong>itin\u00e9raire est accessible \u00e0 tous<\/strong> et combine la passion du <strong>v\u00e9lo<\/strong>, du <strong>sport<\/strong> et du <strong>tourisme lent<\/strong>, offrant au total 170 km de possibilit\u00e9s de d\u00e9couvrir le patrimoine culturel et naturel de la r\u00e9gion.<\/p>\n"}]},{"acf_fc_layout":"two_columns_module","tcm_title":{"title_text":""},"tcm_ui":false,"tcm_content":[{"acf_fc_layout":"googlemap_embed","map":{"locations":false,"file_kml":false}},{"acf_fc_layout":"buttons","buttons":[{"style":"primary","text":"Scarica la traccia gpx partenza da Bergamo","icon":{"button_icon":"none"},"function":"link","url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/02\/percorso-principale-direzione-Brescia.gpx","select_post":null,"target":"_blank","url_youtube":"","target_modal":""},{"style":"primary","text":"Scarica la traccia gpx partenza da Brescia","icon":{"button_icon":"none"},"function":"link","url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/02\/percorso-principale-direzione-Bergamo-2.gpx","select_post":null,"target":"_blank","url_youtube":"","target_modal":""}]}]},{"acf_fc_layout":"two_columns_module","tcm_title":{"title_text":"Plus de 800 points d'int\u00e9r\u00eat"},"tcm_ui":false,"tcm_content":[{"acf_fc_layout":"text","text":"<p>Le long des 76 km de l&#8217;itin\u00e9raire et des 70 km de boucles suppl\u00e9mentaires, vous pouvez explorer<strong> plus de 800 points d&#8217;int\u00e9r\u00eat artistiques et culturels.<\/strong> P\u00e9dalez entre plaines et collines, \u00e0 la d\u00e9couverte de <strong>ch\u00e2teaux<\/strong>, de <strong>demeures historiques<\/strong>, d&#8217;<strong>anciens monast\u00e8res<\/strong> et d&#8217;exemples d&#8217;<strong>arch\u00e9ologie industrielle<\/strong>.<br \/>\nSuivez les itin\u00e9raires des <strong>chemins de fer historiques<\/strong> en p\u00e9dalant entre les fermes. Rejoignez le <strong>lac d&#8217;Iseo<\/strong> et la r\u00e9serve naturelle de <strong>Torbiere del Sebino.<\/strong><br \/>\nEt n&#8217;oubliez pas de prendre le temps de d\u00e9couvrir le patrimoine gastronomique et vinicole local, en passant par les <strong>vignobles de Val Calepio<\/strong> et de <strong>Franciacorta<\/strong>. <\/p>\n"},{"acf_fc_layout":"buttons","buttons":[{"style":"primary","text":"Scopri i punti d'interesse","icon":{"button_icon":"none"},"function":"link","url":"https:\/\/cicloviaculturalebgbs.it\/punti_interesse","select_post":null,"target":"_blank","url_youtube":"","target_modal":""}]}]},{"acf_fc_layout":"two_columns_module","tcm_title":{"title_text":"L'itin\u00e9raire cyclable accessible en 4 \u00e9tapes"},"tcm_ui":false,"tcm_content":[{"acf_fc_layout":"text","text":"<p>La piste cyclable culturelle Bergame-Brescia a \u00e9t\u00e9 con\u00e7ue pour \u00eatre <strong>accessible aux cyclistes \u00e0 mobilit\u00e9 r\u00e9duite<\/strong>, en divisant le parcours en quatre \u00e9tapes d&#8217;environ 20 km chacune. Des travaux ont \u00e9t\u00e9 effectu\u00e9s pour s\u00e9curiser plusieurs intersections et installer une <strong>signalisation d&#8217;information \u00e0 la lisibilit\u00e9 facilit\u00e9e<\/strong>. <strong><br \/>\n L&#8217;itin\u00e9raire a \u00e9t\u00e9 adapt\u00e9 au passage de<\/strong> <strong>v\u00e9los \u00e0 main<\/strong>, de <strong>tandems<\/strong> et de fauteuils roulants <strong>\u00e9lectriques<\/strong>, en accordant une attention particuli\u00e8re \u00e0 la s\u00e9paration du trafic automobile, \u00e0 la gestion des diff\u00e9rences de hauteur, \u00e0 la largeur de l&#8217;itin\u00e9raire, \u00e0 la limitation des pentes et \u00e0 l&#8217;homog\u00e9n\u00e9it\u00e9 des surfaces.<br \/>\nChacune des quatre \u00e9tapes dispose d&#8217;au moins une structure d&#8217;accueil accessible, \u00e9quip\u00e9e de fauteuils roulants pliants pour faciliter les d\u00e9placements \u00e0 l&#8217;int\u00e9rieur de celle-ci. De nombreux restaurants situ\u00e9s le long de l&#8217;itin\u00e9raire proposent des fauteuils roulants pliants pour faciliter l&#8217;entr\u00e9e des cyclistes sur des v\u00e9los \u00e0 main.<br \/>\nDiff\u00e9rents points d&#8217;int\u00e9r\u00eat ont \u00e9t\u00e9 cartographi\u00e9s pour mettre en \u00e9vidence leur degr\u00e9 d&#8217;accessibilit\u00e9, avec une liste disponible de lieux enti\u00e8rement accessibles.<br \/>\nIl est possible de t\u00e9l\u00e9charger des pistes GPX de l&#8217;itin\u00e9raire cycliste dans une version accessible, avec des d\u00e9parts \u00e0 la fois de Bergame et de Brescia.  <\/p>\n"},{"acf_fc_layout":"buttons","buttons":[{"style":"primary","text":"Scopri di pi\u00f9 sulle tappe accessibili","icon":{"button_icon":"vbiplus"},"function":"link","url":"https:\/\/cicloviaculturalebgbs.it\/sezione-stai-la-ciclovia-accessibile-in-4-tappe","select_post":null,"target":"_self","url_youtube":"","target_modal":""}]}]}],"filotto_layout":"scroll","filotto_fill":"manual","filotto_items":[{"object":false,"title":"","image":false,"youtubeurl":"","label_cta":"","url":"","target":"_self","preview":""}],"hero_type":"content","size":"full","featured_video":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/02\/POI-Ciclovia-BGBS_SH.mp4","is_an_ambassador":false},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/125617","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/types\/oggetto"}],"author":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/users\/7"}],"version-history":[{"count":1,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/125617\/revisions"}],"predecessor-version":[{"id":207051,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/125617\/revisions\/207051"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media\/41761"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media?parent=125617"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/categories?post=125617"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/tags?post=125617"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/aggr?post=125617"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/area?post=125617"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/kind?post=125617"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/zona?post=125617"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}