{"id":140229,"date":"2025-06-08T14:59:04","date_gmt":"2025-06-08T12:59:04","guid":{"rendered":"https:\/\/visit.valueservice.cloud\/oggetto\/bootstour-auf-dem-iseosee\/"},"modified":"2025-05-12T19:54:39","modified_gmt":"2025-05-12T17:54:39","slug":"bootstour-auf-dem-iseosee","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/bootstour-auf-dem-iseosee\/","title":{"rendered":"Bootstour auf dem Iseosee"},"excerpt":{"rendered":"<p>Entdecken Sie die malerischsten Orte des Sees bei dieser privaten Bootstour.<\/p>\n","protected":false},"author":0,"featured_media":184507,"template":"","categories":[524,521],"tags":[17226],"aggr":[],"area":[],"kind":[18703],"zona":[],"class_list":["post-140229","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-erlebnisse","category-esperienze","tag-im-freien-de","kind-esperienza-de"],"acf":{"buttons":[{"style":"primary","text":"Kaufen","icon":{"button_icon":"none"},"function":"content","url":"","select_post":"","target":"_self","url_youtube":"","target_modal":"buyExp"},{"style":"primary","text":"Kontakt","icon":{"button_icon":"none"},"function":"content","url":"","select_post":"","target":"_self","url_youtube":"","target_modal":"modalContact"}],"hero_type":"images","video_youtube_url":"","video_vimeo_url":"","size":"full","hero_title":"Bootstour auf dem Iseosee","hero_text":"<p>Entdecken Sie die malerischsten Orte des Sees bei dieser privaten Bootstour.<\/p>\n","hero_buttons_group":{"buttons":[{"style":"primary","text":"Kaufen","icon":{"button_icon":"none"},"function":"content","url":"","select_post":"","target":"_self","url_youtube":"","target_modal":"buyExp"},{"style":"primary","text":"Kontakt","icon":{"button_icon":"none"},"function":"content","url":"","select_post":"","target":"_self","url_youtube":"","target_modal":"modalContact"}]},"hero_buttons":false,"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"","filotto_fill":"","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""}},"description":"<p>&#8211; Eine aufregende private Bootstour entlang der ikonischsten Orte des Iseosees<br \/>\n&#8211; Sie werden an einigen Panoramapunkten anhalten, um die Sch\u00f6nheit des Sees festzuhalten<\/p>\n<p>WAS SIE ERWARTET<\/p>\n<p>Bei dieser Seetour wird der Kapit\u00e4n des Bootes Sie zu geheimen Orten des Iseosees f\u00fchren: Beginnend in Gr\u00e9 di Solto Collina geht es nach Norden, um die charakteristische Schlucht mit kristallklarem Wasser (der Bogn) in Riva di Solto und den Wasserfall in Castro zu bewundern. Sie fahren auch entlang der Uferpromenade von Lovere und folgen den Geschichten vergangener Damen, bevor Sie sich in Richtung Montisola begeben, der gr\u00f6\u00dften Seeinsel Europas, die f\u00fcr ihr typisches Handwerk und das Trocknen von Sardinen bekannt ist.<\/p>\n<p>Das Boot f\u00e4hrt langsam, um jeden Moment an Bord zu genie\u00dfen und die Sicherheit aller zu gew\u00e4hrleisten: Die Tour ist auch f\u00fcr die Kleinen geeignet.<\/p>\n<p>Alle Touren, die f\u00fcr 1, 2, 3 oder 4 Stunden verf\u00fcgbar sind, beinhalten einen oder mehrere Stopps zum Entspannen und Bewundern der malerischsten Orte des Sees.<\/p>\n<p>Lassen Sie Ihren Kapit\u00e4n das Boot und die Navigation \u00fcbernehmen: Genie\u00dfen Sie Ihre private Kreuzfahrt und die Geschichten dieses magischen Ortes in v\u00f6lliger Ruhe!<\/p>\n","indepth":"","howtogetthere":"","timerange":"<p>Das ganze Jahr<\/p>\n","seasonality":"","pairings":"","curiosities":"","awards":"","cancellationpolicy":"<p>Innerhalb von 1 Monat ab dem gebuchten Datum: vollst\u00e4ndige R\u00fcckerstattung der Reservierung<br \/>\nBis zu 15 Tage vor dem gebuchten Datum: 50% R\u00fcckerstattung der Reservierung<br \/>\nAb dem 14. Tag: keine R\u00fcckerstattung<br \/>\n\u00c4nderungen des Datums sind, vorbehaltlich Verf\u00fcgbarkeit, bis zu 15 Tage vorher m\u00f6glich, ohne dass Strafgeb\u00fchren anfallen.<br \/>\nBei widrigen Wetterbedingungen ist es m\u00f6glich, das Datum vorbehaltlich Verf\u00fcgbarkeit zu \u00e4ndern oder mit vollst\u00e4ndiger R\u00fcckerstattung der Reservierung zu stornieren.<br \/>\nKeine R\u00fcckerstattung bei Nichterscheinen<\/p>\n","moredetails":"<p>TREFFPUNKT<br \/>\nBei Sportaction, in Localit\u00e0 Gr\u00e9 in Solto Collina.<\/p>\n<p>ZEITEN<br \/>\nMorgentour: 9:30 Uhr<br \/>\nNachmittagstour: 14:30 Uhr<\/p>\n<p>Treffen 30 Minuten vor der angegebenen Zeit.<\/p>\n<p>PREISE:<br \/>\n1-Stunde-Tour: 180 Euro<br \/>\n2-Stunden-Tour: 360 Euro<br \/>\n3-Stunden-Tour: 540 Euro<br \/>\n4-Stunden-Tour: 720 Euro<\/p>\n<p>Maximal 6 Teilnehmer.<br \/>\nF\u00fcr besseren Komfort an Bord: 5 Teilnehmer<\/p>\n<p>WEITERE INFO<br \/>\nDer Iseosee ist zum Schwimmen geeignet.<br \/>\nEmpfohlen zum Mitnehmen: Hut, Handtuch, Badeanzug, Sonnencreme, ein Sweatshirt oder eine Windjacke, Flip-Flops oder bequeme Schuhe.<\/p>\n<p>DAS BOOT<br \/>\nDie Fahrten finden an Bord der Dulse statt, einem 7,5 Meter langen ligurischen Kabinenboot, dem einzigen seiner Art am Iseosee. Gebaut von den renommierten Cantieri Sciallino in Ceriale (SV).<\/p>\n","whatsincluded":"<p>&#8211; Exklusive Nutzung des Bootes f\u00fcr 1 bis 6 Personen<br \/>\n&#8211; Kapit\u00e4n an Bord<br \/>\n&#8211; Treibstoff<br \/>\n&#8211; Sicherheitsausr\u00fcstung<br \/>\n&#8211; Anlegestellen<\/p>\n","whatsnotincluded":"<p>&#8211; Transfer zum Ausgangsort<br \/>\n&#8211; Trinkgelder und pers\u00f6nliche Extras<br \/>\n&#8211; Alles, was nicht unter &#8220;was ist inbegriffen&#8221; angegeben ist<\/p>\n","price":"","time":"","service_icons":[],"services":"","parking":"","restaurant":"","breakfast":"","internet":"","children":"","pets":"","latitude":"45.78809470","longitude":"10.05386750","startingprice":"180.00","gpxmap":"","iu_kids":false,"iu_shortprice":"","iu_company_name":"","registered_office":"","iu_addr_streetnumber":"SS469","iu_addr_postalcode":"24060","iu_addr_city":"Gr\u00e9","iu_addr_province":"Bergamo","iu_phone":"","iu_cell":"","iu_website":"","iu_email":"","iu_vat":"","iu_document_label":"","iu_document":false,"iu_documents":false,"iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"Iseo Boat Tour , Via Sottoprovinciale, 1\/G, Albino","iu_bookingurl":"https:\/\/back-services.com\/newfront\/services.htm?channelid=652&lang=deu&no_qr=si&styleid=3073&ecomid=4303&serviceid=1","iu_videourl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"2h","iu_languages":"Englisch - Italienisch","iu_minpeople":"Mindestens 1 Person","iu_maxpeople":"Maximal 6 Personen","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"iu_stars":"","iu_rooms":"","iu_beds":"","id_madeep":"652_4303_1","id_visit_manza":"","id_east":"","id_ristora":"","id_eppen":"","style":"primary","text":"","button_icon":"none","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"validfrom":"08\/07\/2024","validto":"08\/07\/2025","hours":"","ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":"","review":false,"filotto_layout":"","filotto_fill":"","iu_motor_accessibility":"no","iu_visual_accessibility":"no","iu_auditory_accessibility":"yes","iu_cognitive_accessibility":"yes","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""},"max_elements":"","show_total":false,"see_all":false,"order_by":"","order_way":"","only_ambassadors":false,"slides":false},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/140229","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/140229\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media\/184507"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media?parent=140229"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/categories?post=140229"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/tags?post=140229"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/aggr?post=140229"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/area?post=140229"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/kind?post=140229"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/zona?post=140229"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}