{"id":178744,"date":"2025-04-18T13:04:38","date_gmt":"2025-04-18T11:04:38","guid":{"rendered":"https:\/\/visit.valueservice.cloud\/oggetto\/serendipity\/"},"modified":"2025-04-18T15:16:57","modified_gmt":"2025-04-18T13:16:57","slug":"serendipity","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/serendipity\/","title":{"rendered":"SERENDIPITY"},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":148564,"template":"","categories":[1002],"tags":[],"aggr":[],"area":[],"kind":[18725],"zona":[],"class_list":["post-178744","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-schlaf","kind-strutturaricettiva-de"],"acf":{"hero_type":"images","video_youtube_url":"","video_vimeo_url":"","size":"full","hero_title":"SERENDIPITY","hero_text":"<p>Sch\u00f6ne Wohnung in der Oberstadt\u00a0<\/p>\n","slides":[{"image":{"ID":148564,"id":148564,"title":"4868c3f2970b91520def7aa86641051b_f5cce99a.jpg","filename":"4868c3f2970b91520def7aa86641051b_f5cce99a-scaled.jpg","filesize":410355,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4868c3f2970b91520def7aa86641051b_f5cce99a-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/serendipity\/4868c3f2970b91520def7aa86641051b_f5cce99a-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"4868c3f2970b91520def7aa86641051b_f5cce99a-jpg-2","status":"inherit","uploaded_to":178744,"date":"2025-04-17 14:39:13","modified":"2025-04-18 13:16:59","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1256,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4868c3f2970b91520def7aa86641051b_f5cce99a-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4868c3f2970b91520def7aa86641051b_f5cce99a-300x147.jpg","medium-width":300,"medium-height":147,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4868c3f2970b91520def7aa86641051b_f5cce99a-768x377.jpg","medium_large-width":768,"medium_large-height":377,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4868c3f2970b91520def7aa86641051b_f5cce99a-1024x503.jpg","large-width":1024,"large-height":503,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4868c3f2970b91520def7aa86641051b_f5cce99a-1536x754.jpg","1536x1536-width":1536,"1536x1536-height":754,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4868c3f2970b91520def7aa86641051b_f5cce99a-2048x1005.jpg","2048x2048-width":2048,"2048x2048-height":1005,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4868c3f2970b91520def7aa86641051b_f5cce99a-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":147,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4868c3f2970b91520def7aa86641051b_f5cce99a-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":196,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4868c3f2970b91520def7aa86641051b_f5cce99a-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":294}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"buttons":false,"hero_buttons_group":{"buttons":false},"hero_buttons":false,"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":false,"filotto_fill":false,"filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":0,"show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":false,"order_way":false}},"description":"<p>Die Wohnung ist eine Zweizimmerwohnung mit einem mit Sorgfalt und Aufmerksamkeit eingerichteten Dachboden. Die Wohnung liegt im vierten und obersten Stockwerk ohne Aufzug an der Hauptverkehrsader des historischen Zentrums, die Via Gombito.\u00a0&#13;<br \/>\nDie Wohnung ist auf 2 Ebenen aufgeteilt: ein Schlafzimmer im Zwischengeschoss, ein Badezimmer mit Dusche und Bidet, ein Kleiderschrank und der Wohnbereich mit einer K\u00fcche mit Geschirrsp\u00fcler und Backofen sowie einem Sofa mit TV-Schrank.&#13;<br \/>\n\u00a0&#13;<br \/>\nEs bietet kostenfreies WLAN und Blick auf die Stadt.<\/p>\n","indepth":"<p>Die Wohnung befindet sich an der Hauptstra\u00dfe der Oberstadt in Bergamo, 200 m von der Piazza Vecchia und 1 km vom Donizetti-Theater entfernt.\u00a0&#13;<br \/>\nIn der N\u00e4he aller kulturellen St\u00e4tten und Stra\u00dfen, die von Bars, Restaurants und Gesch\u00e4ften belebt werden.\u00a0&#13;<br \/>\nKostenpflichtige Parkm\u00f6glichkeiten auf der Piazza Mercato del Fieno, 100 m vom Apartment entfernt.&#13;<br \/>\n\u00a0&#13;<br \/>\nZu den beliebten Sehensw\u00fcrdigkeiten in der N\u00e4he des Hotels z\u00e4hlen die Kirche Santa Maria Maggiore, die Carrara Akademie und das Donizetti Bergamo Theater. Der n\u00e4chstgelegene Flughafen ist der 8 km von der Unterkunft entfernte internationale Flughafen Orio Al Serio.&#13;<br \/>\n\u00a0<\/p>\n","howtogetthere":"","timerange":"","seasonality":"","pairings":"","curiosities":"","awards":"","cancellationpolicy":"","moredetails":"","whatsincluded":"","whatsnotincluded":"","price":"","services":"<p>Die Kurtaxe betr\u00e4gt 6% pro Person und Nacht.&#13;<br \/>\n &#13;<br \/>\nDie Reinigungskosten betragen 25 \u20ac pro Aufenthalt.<\/p>\n","parking":"<p>Kostenpflichtige Parkm\u00f6glichkeiten auf der Piazza Mercato del Fieno, 100 m vom Apartment entfernt.<\/p>\n","restaurant":"","breakfast":"","internet":"<p>Kostenloses WLAN in der gesamten Wohnung<\/p>\n","children":"","pets":"","latitude":"45.703549","longitude":"9.664269","startingprice":"","gpxmap":"","iu_motor_accessibility":"notsure","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_kids":false,"iu_shortprice":"","iu_company_name":"Maria Danesi","registered_office":"","iu_addr_streetnumber":"Via Gombito, 15","iu_addr_postalcode":"24129","iu_addr_city":"Bergamo","iu_addr_province":"BG","iu_phone":"","iu_cell":"3392775884","iu_website":"","iu_email":"amministrazione@bergamelli.it","iu_vat":"dnsmra63a58b157o","iu_document_label":"","iu_document":false,"iu_documents":false,"iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_bookingurl":"","iu_videourl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"","iu_languages":"","iu_minpeople":"","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"iu_stars":"","iu_rooms":"1","iu_beds":"2","id_madeep":"","id_visit_manza":"9225","id_east":"","id_ristora":"","id_eppen":"","style":"primary","text":"","button_icon":"none","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"validfrom":"","validto":"","hours":"","tcm_content":false,"accessibilitycontent":{"tcm_content":false},"accessibilityicons":[],"ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":"","time":"<p>&#13;<br \/>\nCheck-in Arrivo&#13;<br \/>\ndalle 14:00 alle 21:00&#13;<br \/>\nAl check-in gli ospiti devono esibire un documento di riconoscimento con foto e una carta di credito.&#13;<br \/>\nDovrai comunicare in anticipo alla struttura il tuo orario di arrivo.&#13;<br \/>\nCheck-out Partenza&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\nDalle 00:00 alle 11:00&#13;<\/p>\n","service_icons":[{"value":"wifi","label":"Wi-Fi"},{"value":"hairdryer","label":"Asciugacapelli"},{"value":"shower","label":"Bagni con doccia"},{"value":"tv_room","label":"TV in camera"}]},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/178744","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/178744\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media\/148564"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media?parent=178744"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/categories?post=178744"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/tags?post=178744"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/aggr?post=178744"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/area?post=178744"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/kind?post=178744"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/zona?post=178744"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}