{"id":178827,"date":"2025-04-18T13:07:29","date_gmt":"2025-04-18T11:07:29","guid":{"rendered":"https:\/\/visit.valueservice.cloud\/oggetto\/colleonis-lodge-verdellino\/"},"modified":"2025-04-18T15:21:03","modified_gmt":"2025-04-18T13:21:03","slug":"colleonis-lodge-verdellino","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/colleonis-lodge-verdellino\/","title":{"rendered":"Colleoni&#8217;s Lodge Verdellino"},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":150901,"template":"","categories":[1002],"tags":[],"aggr":[],"area":[],"kind":[18725],"zona":[],"class_list":["post-178827","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-schlaf","kind-strutturaricettiva-de"],"acf":{"hero_type":"images","video_youtube_url":"","video_vimeo_url":"","size":"full","hero_title":"Colleoni's Lodge Verdellino","hero_text":"<p>Colleoni&#8217;s Lodge Verdellino &#8211; Zwei Apartments f\u00fcr Familien und Gesch\u00e4ftsreisende, im Herzen der Provinz Bergamo.<\/p>\n<p>&#13;<\/p>\n<p>Dachgeschoss-Apartment (90 qm) f\u00fcr 4 Personen + Standard-Apartment (75 qm) f\u00fcr 5 Personen.<\/p>\n","buttons":false,"hero_buttons_group":{"buttons":false},"hero_buttons":false,"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":false,"filotto_fill":false,"filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":0,"show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":false,"order_way":false}},"description":"<p>Unser Betrieb wird famili\u00e4r gef\u00fchrt, wir k\u00fcmmern uns pers\u00f6nlich um die Pflege und Sauberkeit des Hauses, vor allem aber um das Willkommenhei\u00dfen und Beraten unserer G\u00e4ste. Seit Anfang 2024 haben wir das Geb\u00e4ude energetisch modernisiert, um Ihnen in den kalten Wintertagen eine warme Behaglichkeit und an hei\u00dfen Tagen angenehme Frische zu bieten. Unsere gr\u00f6\u00dfte Freude und Zufriedenheit ist es, von unseren G\u00e4sten zu h\u00f6ren, dass sie sich bei uns wohlgef\u00fchlt haben, als w\u00e4ren sie zu Hause gewesen. Kinder lieben es, in unseren ger\u00e4umigen Wohnbereichen oder auf unseren hellen Terrassen zu spielen. An klaren Tagen k\u00f6nnen Sie vom Nordbalkon aus das Panorama unserer Berge und unseres Bergamo Alta sehen. Es gibt wirklich viel in der Umgebung zu entdecken! Wir haben viele Geschichten zu erz\u00e4hlen.<\/p>\n","indepth":"<p>Wie Sie auf den Fotos in der Galerie sehen k\u00f6nnen, bieten wir zwei ger\u00e4umige, ruhige, helle und gut ausgestattete Apartments, die sich ideal f\u00fcr Familien, Berufst\u00e4tige oder Gesch\u00e4ftsreisende eignen. Ein Dachgeschoss-Apartment von 90 qm auf der zweiten Etage mit 4 Betten und ein Apartment von 75 qm auf der ersten Etage mit 5 Betten. Badezimmer mit Dusche und Badewanne. Gro\u00dfe Terrassen. Die K\u00fcchen sind mit Geschirr und verschiedenen K\u00fcchenutensilien, Geschirrsp\u00fcler, Mikrowelle, K\u00fchlschrank und Kaffeemaschine ausgestattet. Kostenloser Parkplatz auf dem Gel\u00e4nde.&#13;<br \/>\nWir befinden uns nur wenige Schritte vom Bahnhof Verdello\/Dalmine an der Strecke Bergamo-Milano entfernt, die Bergamo in 10 Minuten und Mailand in 40 Minuten verbindet.&#13;<br \/>\n8 km von den Autobahnabfahrten Dalmine oder Capriate San Gervasio entfernt.&#13;<br \/>\nHauptdienstleistungen oder Sehensw\u00fcrdigkeiten in der N\u00e4he:&#13;<br \/>\nFreizeitpark Leolandia &#8211; Capriate San Gervasio&#13;<br \/>\nUNESCO-Weltkulturerbe Villaggio Crespi D&#8217;adda&#13;<br \/>\nRadwege im Park des Flusses Adda mit Wasserkraftwerken und den Schleusen von Leonardo &#8211; Trezzo d&#8217;Adda&#13;<br \/>\nKrankenhaus Clinica S. Marco Zingonia Gruppo San Donato \u2013 Osio Sotto&#13;<br \/>\nHyperbare Oxygenationseinrichtung Neurorehabilitation Institut \u2013 Ciserano&#13;<br \/>\nSportzentrum Bortolotti-Atalanta \u2013 Ciserano&#13;<br \/>\nSchulcampus mit weiterf\u00fchrenden Schulen und Universit\u00e4t Dalmine<\/p>\n","howtogetthere":"<p>\u00a0&#13;<br \/>\nErreichbar von:&#13;<br \/>\nAUSFAHRT DALMINE &#8211; 12 Minuten &#8211; 7,6 km &#8211; Richtung S\u00fcden nach Osio Sotto&#13;<br \/>\nAUSFAHRT CAPRIATE S. GERVASIO &#8211; LEOLANDIA &#8211; 11 Minuten &#8211; 8 km&#13;<br \/>\nBAHNHOF FS VERDELLO &#8211; DALMINE &#8211; 1 Minute &#8211; 150 m&#13;<br \/>\nPOLICLINICO SAN MARCO &#8211; Osio Sotto &#8211; 6 Minuten &#8211; 3,8 km&#13;<br \/>\nSPORTZENTRUM BORTOLOTTI-ATALANTA &#8211; Ciserano &#8211; 6 Minuten &#8211; 2,8 km<\/p>\n","timerange":"","seasonality":"","pairings":"","curiosities":"","awards":"","cancellationpolicy":"","moredetails":"","whatsincluded":"","whatsnotincluded":"","price":"<p>F\u00fcr Kostenvoranschl\u00e4ge kontaktieren Sie bitte die Nummer 3356020014.<\/p>\n","services":"<p>Keine Kurtaxe erforderlich.<\/p>\n","parking":"<p>Kostenloser privater Parkplatz vorhanden. Ein geschlossener Garagenstellplatz steht ebenfalls zur Verf\u00fcgung, auch zur eventuellen Aufbewahrung von Fahrr\u00e4dern.<\/p>\n","restaurant":"<p>Das n\u00e4chstgelegene Restaurant\/Pizzeria ist 300 Meter entfernt.<\/p>\n","breakfast":"<p>Es gibt mehrere Bars in unmittelbarer N\u00e4he zur Unterkunft.<\/p>\n","internet":"<p>WLAN inklusive.<\/p>\n","children":"<p>Babybett-Service verf\u00fcgbar.<\/p>\n","pets":"<p>Keine Haustiere erlaubt.<\/p>\n","latitude":"45.606745","longitude":"9.619434","startingprice":"","gpxmap":"","iu_motor_accessibility":"notsure","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_kids":true,"iu_shortprice":"","iu_company_name":"Colleoni's Lodge - di Rossoni Maria Grazia","registered_office":"Via Quasimodo, 4 24040-VERDELLINO-BG","iu_addr_streetnumber":"Via Quasimodo 4","iu_addr_postalcode":"24040","iu_addr_city":"Bergamo","iu_addr_province":"BG","iu_phone":"","iu_cell":"3356020014","iu_website":"","iu_email":"colleonilodge@gmail.com","iu_vat":"","iu_document_label":"","iu_document":false,"iu_documents":false,"iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_bookingurl":"","iu_videourl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"","iu_languages":"","iu_minpeople":"","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"iu_stars":"","iu_rooms":"4","iu_beds":"9","id_madeep":"","id_visit_manza":"10777","id_east":"","id_ristora":"","id_eppen":"","style":"primary","text":"","button_icon":"none","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"validfrom":"","validto":"","hours":"","tcm_content":false,"accessibilitycontent":{"tcm_content":false},"accessibilityicons":[],"slides":[{"image":{"ID":150901,"id":150901,"title":"ccbc23fb600e2050126de65bde53b4d0_153c5c97.jpg","filename":"ccbc23fb600e2050126de65bde53b4d0_153c5c97.jpg","filesize":560975,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ccbc23fb600e2050126de65bde53b4d0_153c5c97.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/colleonis-lodge-verdellino\/ccbc23fb600e2050126de65bde53b4d0_153c5c97-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"ccbc23fb600e2050126de65bde53b4d0_153c5c97-jpg-2","status":"inherit","uploaded_to":178827,"date":"2025-04-17 14:48:12","modified":"2025-04-18 13:21:04","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2048,"height":1153,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ccbc23fb600e2050126de65bde53b4d0_153c5c97-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ccbc23fb600e2050126de65bde53b4d0_153c5c97-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ccbc23fb600e2050126de65bde53b4d0_153c5c97-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ccbc23fb600e2050126de65bde53b4d0_153c5c97-1024x577.jpg","large-width":1024,"large-height":577,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ccbc23fb600e2050126de65bde53b4d0_153c5c97-1536x865.jpg","1536x1536-width":1536,"1536x1536-height":865,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ccbc23fb600e2050126de65bde53b4d0_153c5c97.jpg","2048x2048-width":2048,"2048x2048-height":1153,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ccbc23fb600e2050126de65bde53b4d0_153c5c97.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ccbc23fb600e2050126de65bde53b4d0_153c5c97.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ccbc23fb600e2050126de65bde53b4d0_153c5c97.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":150908,"id":150908,"title":"0a020efecf1f6247203a3de3fcb80332_b7f80e17.jpg","filename":"0a020efecf1f6247203a3de3fcb80332_b7f80e17-scaled.jpg","filesize":465384,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0a020efecf1f6247203a3de3fcb80332_b7f80e17-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/colleonis-lodge-verdellino\/0a020efecf1f6247203a3de3fcb80332_b7f80e17-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"0a020efecf1f6247203a3de3fcb80332_b7f80e17-jpg-2","status":"inherit","uploaded_to":178827,"date":"2025-04-17 14:48:13","modified":"2025-04-18 13:21:04","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1440,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0a020efecf1f6247203a3de3fcb80332_b7f80e17-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0a020efecf1f6247203a3de3fcb80332_b7f80e17-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0a020efecf1f6247203a3de3fcb80332_b7f80e17-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0a020efecf1f6247203a3de3fcb80332_b7f80e17-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0a020efecf1f6247203a3de3fcb80332_b7f80e17-1536x864.jpg","1536x1536-width":1536,"1536x1536-height":864,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0a020efecf1f6247203a3de3fcb80332_b7f80e17-2048x1152.jpg","2048x2048-width":2048,"2048x2048-height":1152,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0a020efecf1f6247203a3de3fcb80332_b7f80e17-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0a020efecf1f6247203a3de3fcb80332_b7f80e17-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0a020efecf1f6247203a3de3fcb80332_b7f80e17-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":150915,"id":150915,"title":"41f97ae9d8cb6e299b924f2f95a6fbc2_097e3e48.jpg","filename":"41f97ae9d8cb6e299b924f2f95a6fbc2_097e3e48-scaled.jpg","filesize":495032,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/41f97ae9d8cb6e299b924f2f95a6fbc2_097e3e48-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/colleonis-lodge-verdellino\/41f97ae9d8cb6e299b924f2f95a6fbc2_097e3e48-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"41f97ae9d8cb6e299b924f2f95a6fbc2_097e3e48-jpg-2","status":"inherit","uploaded_to":178827,"date":"2025-04-17 14:48:15","modified":"2025-04-18 13:21:04","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1440,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/41f97ae9d8cb6e299b924f2f95a6fbc2_097e3e48-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/41f97ae9d8cb6e299b924f2f95a6fbc2_097e3e48-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/41f97ae9d8cb6e299b924f2f95a6fbc2_097e3e48-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/41f97ae9d8cb6e299b924f2f95a6fbc2_097e3e48-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/41f97ae9d8cb6e299b924f2f95a6fbc2_097e3e48-1536x864.jpg","1536x1536-width":1536,"1536x1536-height":864,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/41f97ae9d8cb6e299b924f2f95a6fbc2_097e3e48-2048x1152.jpg","2048x2048-width":2048,"2048x2048-height":1152,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/41f97ae9d8cb6e299b924f2f95a6fbc2_097e3e48-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/41f97ae9d8cb6e299b924f2f95a6fbc2_097e3e48-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/41f97ae9d8cb6e299b924f2f95a6fbc2_097e3e48-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":150922,"id":150922,"title":"be7a2bb4bffaddd4b04ac583a6d3dd01_e5571351.jpg","filename":"be7a2bb4bffaddd4b04ac583a6d3dd01_e5571351-scaled.jpg","filesize":432949,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/be7a2bb4bffaddd4b04ac583a6d3dd01_e5571351-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/colleonis-lodge-verdellino\/be7a2bb4bffaddd4b04ac583a6d3dd01_e5571351-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"be7a2bb4bffaddd4b04ac583a6d3dd01_e5571351-jpg-2","status":"inherit","uploaded_to":178827,"date":"2025-04-17 14:48:17","modified":"2025-04-18 13:21:04","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1440,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/be7a2bb4bffaddd4b04ac583a6d3dd01_e5571351-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/be7a2bb4bffaddd4b04ac583a6d3dd01_e5571351-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/be7a2bb4bffaddd4b04ac583a6d3dd01_e5571351-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/be7a2bb4bffaddd4b04ac583a6d3dd01_e5571351-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/be7a2bb4bffaddd4b04ac583a6d3dd01_e5571351-1536x864.jpg","1536x1536-width":1536,"1536x1536-height":864,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/be7a2bb4bffaddd4b04ac583a6d3dd01_e5571351-2048x1152.jpg","2048x2048-width":2048,"2048x2048-height":1152,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/be7a2bb4bffaddd4b04ac583a6d3dd01_e5571351-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/be7a2bb4bffaddd4b04ac583a6d3dd01_e5571351-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/be7a2bb4bffaddd4b04ac583a6d3dd01_e5571351-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":150929,"id":150929,"title":"80f812cb9eef70eecb92a548e3fc2116_8b79de81.jpg","filename":"80f812cb9eef70eecb92a548e3fc2116_8b79de81-scaled.jpg","filesize":396275,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/80f812cb9eef70eecb92a548e3fc2116_8b79de81-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/colleonis-lodge-verdellino\/80f812cb9eef70eecb92a548e3fc2116_8b79de81-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"80f812cb9eef70eecb92a548e3fc2116_8b79de81-jpg-2","status":"inherit","uploaded_to":178827,"date":"2025-04-17 14:48:19","modified":"2025-04-18 13:21:04","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1440,"height":2560,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/80f812cb9eef70eecb92a548e3fc2116_8b79de81-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/80f812cb9eef70eecb92a548e3fc2116_8b79de81-169x300.jpg","medium-width":169,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/80f812cb9eef70eecb92a548e3fc2116_8b79de81-768x1365.jpg","medium_large-width":768,"medium_large-height":1365,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/80f812cb9eef70eecb92a548e3fc2116_8b79de81-576x1024.jpg","large-width":576,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/80f812cb9eef70eecb92a548e3fc2116_8b79de81-864x1536.jpg","1536x1536-width":864,"1536x1536-height":1536,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/80f812cb9eef70eecb92a548e3fc2116_8b79de81-1152x2048.jpg","2048x2048-width":1152,"2048x2048-height":2048,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/80f812cb9eef70eecb92a548e3fc2116_8b79de81-scaled.jpg","gform-image-choice-sm-width":169,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/80f812cb9eef70eecb92a548e3fc2116_8b79de81-scaled.jpg","gform-image-choice-md-width":225,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/80f812cb9eef70eecb92a548e3fc2116_8b79de81-scaled.jpg","gform-image-choice-lg-width":338,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":150936,"id":150936,"title":"f949ba045f6c82f7a01a2d9cfb1f3a08_b6e8eeaf.jpg","filename":"f949ba045f6c82f7a01a2d9cfb1f3a08_b6e8eeaf-scaled.jpg","filesize":428336,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f949ba045f6c82f7a01a2d9cfb1f3a08_b6e8eeaf-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/colleonis-lodge-verdellino\/f949ba045f6c82f7a01a2d9cfb1f3a08_b6e8eeaf-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"f949ba045f6c82f7a01a2d9cfb1f3a08_b6e8eeaf-jpg-2","status":"inherit","uploaded_to":178827,"date":"2025-04-17 14:48:21","modified":"2025-04-18 13:21:04","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1440,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f949ba045f6c82f7a01a2d9cfb1f3a08_b6e8eeaf-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f949ba045f6c82f7a01a2d9cfb1f3a08_b6e8eeaf-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f949ba045f6c82f7a01a2d9cfb1f3a08_b6e8eeaf-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f949ba045f6c82f7a01a2d9cfb1f3a08_b6e8eeaf-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f949ba045f6c82f7a01a2d9cfb1f3a08_b6e8eeaf-1536x864.jpg","1536x1536-width":1536,"1536x1536-height":864,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f949ba045f6c82f7a01a2d9cfb1f3a08_b6e8eeaf-2048x1152.jpg","2048x2048-width":2048,"2048x2048-height":1152,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f949ba045f6c82f7a01a2d9cfb1f3a08_b6e8eeaf-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f949ba045f6c82f7a01a2d9cfb1f3a08_b6e8eeaf-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f949ba045f6c82f7a01a2d9cfb1f3a08_b6e8eeaf-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":150943,"id":150943,"title":"8a78b6c577d8f194402730dd4bc11965_dfce357f.jpg","filename":"8a78b6c577d8f194402730dd4bc11965_dfce357f.jpg","filesize":295480,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8a78b6c577d8f194402730dd4bc11965_dfce357f.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/colleonis-lodge-verdellino\/8a78b6c577d8f194402730dd4bc11965_dfce357f-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"8a78b6c577d8f194402730dd4bc11965_dfce357f-jpg-2","status":"inherit","uploaded_to":178827,"date":"2025-04-17 14:48:23","modified":"2025-04-18 13:21:04","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1280,"height":720,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8a78b6c577d8f194402730dd4bc11965_dfce357f-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8a78b6c577d8f194402730dd4bc11965_dfce357f-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8a78b6c577d8f194402730dd4bc11965_dfce357f-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8a78b6c577d8f194402730dd4bc11965_dfce357f-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8a78b6c577d8f194402730dd4bc11965_dfce357f.jpg","1536x1536-width":1280,"1536x1536-height":720,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8a78b6c577d8f194402730dd4bc11965_dfce357f.jpg","2048x2048-width":1280,"2048x2048-height":720,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8a78b6c577d8f194402730dd4bc11965_dfce357f.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8a78b6c577d8f194402730dd4bc11965_dfce357f.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8a78b6c577d8f194402730dd4bc11965_dfce357f.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":150950,"id":150950,"title":"a5c7b2aae47dbab9c0a3830b6f8aea3c_6481a4d2.jpg","filename":"a5c7b2aae47dbab9c0a3830b6f8aea3c_6481a4d2.jpg","filesize":191938,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a5c7b2aae47dbab9c0a3830b6f8aea3c_6481a4d2.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/colleonis-lodge-verdellino\/a5c7b2aae47dbab9c0a3830b6f8aea3c_6481a4d2-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"a5c7b2aae47dbab9c0a3830b6f8aea3c_6481a4d2-jpg-2","status":"inherit","uploaded_to":178827,"date":"2025-04-17 14:48:24","modified":"2025-04-18 13:21:04","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1280,"height":720,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a5c7b2aae47dbab9c0a3830b6f8aea3c_6481a4d2-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a5c7b2aae47dbab9c0a3830b6f8aea3c_6481a4d2-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a5c7b2aae47dbab9c0a3830b6f8aea3c_6481a4d2-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a5c7b2aae47dbab9c0a3830b6f8aea3c_6481a4d2-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a5c7b2aae47dbab9c0a3830b6f8aea3c_6481a4d2.jpg","1536x1536-width":1280,"1536x1536-height":720,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a5c7b2aae47dbab9c0a3830b6f8aea3c_6481a4d2.jpg","2048x2048-width":1280,"2048x2048-height":720,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a5c7b2aae47dbab9c0a3830b6f8aea3c_6481a4d2.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a5c7b2aae47dbab9c0a3830b6f8aea3c_6481a4d2.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a5c7b2aae47dbab9c0a3830b6f8aea3c_6481a4d2.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":150957,"id":150957,"title":"58a7d06548528a0f4fdd3c2b4da1d9ec_db05bb4c.jpg","filename":"58a7d06548528a0f4fdd3c2b4da1d9ec_db05bb4c-scaled.jpg","filesize":416512,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/58a7d06548528a0f4fdd3c2b4da1d9ec_db05bb4c-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/colleonis-lodge-verdellino\/58a7d06548528a0f4fdd3c2b4da1d9ec_db05bb4c-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"58a7d06548528a0f4fdd3c2b4da1d9ec_db05bb4c-jpg-2","status":"inherit","uploaded_to":178827,"date":"2025-04-17 14:48:26","modified":"2025-04-18 13:21:04","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1440,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/58a7d06548528a0f4fdd3c2b4da1d9ec_db05bb4c-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/58a7d06548528a0f4fdd3c2b4da1d9ec_db05bb4c-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/58a7d06548528a0f4fdd3c2b4da1d9ec_db05bb4c-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/58a7d06548528a0f4fdd3c2b4da1d9ec_db05bb4c-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/58a7d06548528a0f4fdd3c2b4da1d9ec_db05bb4c-1536x864.jpg","1536x1536-width":1536,"1536x1536-height":864,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/58a7d06548528a0f4fdd3c2b4da1d9ec_db05bb4c-2048x1152.jpg","2048x2048-width":2048,"2048x2048-height":1152,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/58a7d06548528a0f4fdd3c2b4da1d9ec_db05bb4c-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/58a7d06548528a0f4fdd3c2b4da1d9ec_db05bb4c-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/58a7d06548528a0f4fdd3c2b4da1d9ec_db05bb4c-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":150964,"id":150964,"title":"99ecf8abe3b3c3727fabddfbaf3c9dbc_40f1d7f1.jpg","filename":"99ecf8abe3b3c3727fabddfbaf3c9dbc_40f1d7f1-scaled.jpg","filesize":586563,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/99ecf8abe3b3c3727fabddfbaf3c9dbc_40f1d7f1-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/colleonis-lodge-verdellino\/99ecf8abe3b3c3727fabddfbaf3c9dbc_40f1d7f1-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"99ecf8abe3b3c3727fabddfbaf3c9dbc_40f1d7f1-jpg-2","status":"inherit","uploaded_to":178827,"date":"2025-04-17 14:48:28","modified":"2025-04-18 13:21:04","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1440,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/99ecf8abe3b3c3727fabddfbaf3c9dbc_40f1d7f1-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/99ecf8abe3b3c3727fabddfbaf3c9dbc_40f1d7f1-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/99ecf8abe3b3c3727fabddfbaf3c9dbc_40f1d7f1-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/99ecf8abe3b3c3727fabddfbaf3c9dbc_40f1d7f1-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/99ecf8abe3b3c3727fabddfbaf3c9dbc_40f1d7f1-1536x864.jpg","1536x1536-width":1536,"1536x1536-height":864,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/99ecf8abe3b3c3727fabddfbaf3c9dbc_40f1d7f1-2048x1152.jpg","2048x2048-width":2048,"2048x2048-height":1152,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/99ecf8abe3b3c3727fabddfbaf3c9dbc_40f1d7f1-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/99ecf8abe3b3c3727fabddfbaf3c9dbc_40f1d7f1-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/99ecf8abe3b3c3727fabddfbaf3c9dbc_40f1d7f1-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":150971,"id":150971,"title":"b832397e9c30cc233eededd419090fd5_eedf63fa.jpg","filename":"b832397e9c30cc233eededd419090fd5_eedf63fa-scaled.jpg","filesize":835650,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b832397e9c30cc233eededd419090fd5_eedf63fa-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/colleonis-lodge-verdellino\/b832397e9c30cc233eededd419090fd5_eedf63fa-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"b832397e9c30cc233eededd419090fd5_eedf63fa-jpg-2","status":"inherit","uploaded_to":178827,"date":"2025-04-17 14:48:30","modified":"2025-04-18 13:21:04","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1440,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b832397e9c30cc233eededd419090fd5_eedf63fa-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b832397e9c30cc233eededd419090fd5_eedf63fa-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b832397e9c30cc233eededd419090fd5_eedf63fa-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b832397e9c30cc233eededd419090fd5_eedf63fa-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b832397e9c30cc233eededd419090fd5_eedf63fa-1536x864.jpg","1536x1536-width":1536,"1536x1536-height":864,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b832397e9c30cc233eededd419090fd5_eedf63fa-2048x1152.jpg","2048x2048-width":2048,"2048x2048-height":1152,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b832397e9c30cc233eededd419090fd5_eedf63fa-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b832397e9c30cc233eededd419090fd5_eedf63fa-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b832397e9c30cc233eededd419090fd5_eedf63fa-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":150978,"id":150978,"title":"644bde7c562648ea2c9f0b924e6cd3fa_283255b1.jpg","filename":"644bde7c562648ea2c9f0b924e6cd3fa_283255b1-scaled.jpg","filesize":401044,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/644bde7c562648ea2c9f0b924e6cd3fa_283255b1-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/colleonis-lodge-verdellino\/644bde7c562648ea2c9f0b924e6cd3fa_283255b1-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"644bde7c562648ea2c9f0b924e6cd3fa_283255b1-jpg-2","status":"inherit","uploaded_to":178827,"date":"2025-04-17 14:48:32","modified":"2025-04-18 13:21:05","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1440,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/644bde7c562648ea2c9f0b924e6cd3fa_283255b1-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/644bde7c562648ea2c9f0b924e6cd3fa_283255b1-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/644bde7c562648ea2c9f0b924e6cd3fa_283255b1-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/644bde7c562648ea2c9f0b924e6cd3fa_283255b1-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/644bde7c562648ea2c9f0b924e6cd3fa_283255b1-1536x864.jpg","1536x1536-width":1536,"1536x1536-height":864,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/644bde7c562648ea2c9f0b924e6cd3fa_283255b1-2048x1152.jpg","2048x2048-width":2048,"2048x2048-height":1152,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/644bde7c562648ea2c9f0b924e6cd3fa_283255b1-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/644bde7c562648ea2c9f0b924e6cd3fa_283255b1-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/644bde7c562648ea2c9f0b924e6cd3fa_283255b1-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":150985,"id":150985,"title":"8b2d8717b89141dd147eb64ae26b7134_6a1ba308.jpg","filename":"8b2d8717b89141dd147eb64ae26b7134_6a1ba308-scaled.jpg","filesize":575951,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8b2d8717b89141dd147eb64ae26b7134_6a1ba308-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/colleonis-lodge-verdellino\/8b2d8717b89141dd147eb64ae26b7134_6a1ba308-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"8b2d8717b89141dd147eb64ae26b7134_6a1ba308-jpg-2","status":"inherit","uploaded_to":178827,"date":"2025-04-17 14:48:34","modified":"2025-04-18 13:21:05","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1440,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8b2d8717b89141dd147eb64ae26b7134_6a1ba308-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8b2d8717b89141dd147eb64ae26b7134_6a1ba308-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8b2d8717b89141dd147eb64ae26b7134_6a1ba308-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8b2d8717b89141dd147eb64ae26b7134_6a1ba308-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8b2d8717b89141dd147eb64ae26b7134_6a1ba308-1536x864.jpg","1536x1536-width":1536,"1536x1536-height":864,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8b2d8717b89141dd147eb64ae26b7134_6a1ba308-2048x1152.jpg","2048x2048-width":2048,"2048x2048-height":1152,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8b2d8717b89141dd147eb64ae26b7134_6a1ba308-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8b2d8717b89141dd147eb64ae26b7134_6a1ba308-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8b2d8717b89141dd147eb64ae26b7134_6a1ba308-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":150992,"id":150992,"title":"1337e2335a810c416aa454807ada06b5_7ba0bfbd.jpg","filename":"1337e2335a810c416aa454807ada06b5_7ba0bfbd-scaled.jpg","filesize":467211,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1337e2335a810c416aa454807ada06b5_7ba0bfbd-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/colleonis-lodge-verdellino\/1337e2335a810c416aa454807ada06b5_7ba0bfbd-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"1337e2335a810c416aa454807ada06b5_7ba0bfbd-jpg-2","status":"inherit","uploaded_to":178827,"date":"2025-04-17 14:48:36","modified":"2025-04-18 13:21:05","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1440,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1337e2335a810c416aa454807ada06b5_7ba0bfbd-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1337e2335a810c416aa454807ada06b5_7ba0bfbd-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1337e2335a810c416aa454807ada06b5_7ba0bfbd-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1337e2335a810c416aa454807ada06b5_7ba0bfbd-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1337e2335a810c416aa454807ada06b5_7ba0bfbd-1536x864.jpg","1536x1536-width":1536,"1536x1536-height":864,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1337e2335a810c416aa454807ada06b5_7ba0bfbd-2048x1152.jpg","2048x2048-width":2048,"2048x2048-height":1152,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1337e2335a810c416aa454807ada06b5_7ba0bfbd-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1337e2335a810c416aa454807ada06b5_7ba0bfbd-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1337e2335a810c416aa454807ada06b5_7ba0bfbd-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":150999,"id":150999,"title":"3959a4bcaab09f9f1fb95fcbd57940a3_914e425c.jpg","filename":"3959a4bcaab09f9f1fb95fcbd57940a3_914e425c-scaled.jpg","filesize":548104,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3959a4bcaab09f9f1fb95fcbd57940a3_914e425c-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/colleonis-lodge-verdellino\/3959a4bcaab09f9f1fb95fcbd57940a3_914e425c-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"3959a4bcaab09f9f1fb95fcbd57940a3_914e425c-jpg-2","status":"inherit","uploaded_to":178827,"date":"2025-04-17 14:48:38","modified":"2025-04-18 13:21:05","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1440,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3959a4bcaab09f9f1fb95fcbd57940a3_914e425c-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3959a4bcaab09f9f1fb95fcbd57940a3_914e425c-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3959a4bcaab09f9f1fb95fcbd57940a3_914e425c-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3959a4bcaab09f9f1fb95fcbd57940a3_914e425c-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3959a4bcaab09f9f1fb95fcbd57940a3_914e425c-1536x864.jpg","1536x1536-width":1536,"1536x1536-height":864,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3959a4bcaab09f9f1fb95fcbd57940a3_914e425c-2048x1152.jpg","2048x2048-width":2048,"2048x2048-height":1152,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3959a4bcaab09f9f1fb95fcbd57940a3_914e425c-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3959a4bcaab09f9f1fb95fcbd57940a3_914e425c-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3959a4bcaab09f9f1fb95fcbd57940a3_914e425c-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":151006,"id":151006,"title":"7ba235185404919bafb5345487ed04a6_b6e8eeaf.jpg","filename":"7ba235185404919bafb5345487ed04a6_b6e8eeaf-scaled.jpg","filesize":428336,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7ba235185404919bafb5345487ed04a6_b6e8eeaf-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/colleonis-lodge-verdellino\/7ba235185404919bafb5345487ed04a6_b6e8eeaf-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"7ba235185404919bafb5345487ed04a6_b6e8eeaf-jpg-2","status":"inherit","uploaded_to":178827,"date":"2025-04-17 14:48:41","modified":"2025-04-18 13:21:05","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1440,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7ba235185404919bafb5345487ed04a6_b6e8eeaf-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7ba235185404919bafb5345487ed04a6_b6e8eeaf-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7ba235185404919bafb5345487ed04a6_b6e8eeaf-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7ba235185404919bafb5345487ed04a6_b6e8eeaf-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7ba235185404919bafb5345487ed04a6_b6e8eeaf-1536x864.jpg","1536x1536-width":1536,"1536x1536-height":864,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7ba235185404919bafb5345487ed04a6_b6e8eeaf-2048x1152.jpg","2048x2048-width":2048,"2048x2048-height":1152,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7ba235185404919bafb5345487ed04a6_b6e8eeaf-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7ba235185404919bafb5345487ed04a6_b6e8eeaf-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7ba235185404919bafb5345487ed04a6_b6e8eeaf-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":151013,"id":151013,"title":"f8197dbe5b1951fda0e6ed566b34ffd7_044b471b.jpg","filename":"f8197dbe5b1951fda0e6ed566b34ffd7_044b471b-scaled.jpg","filesize":536516,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f8197dbe5b1951fda0e6ed566b34ffd7_044b471b-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/colleonis-lodge-verdellino\/f8197dbe5b1951fda0e6ed566b34ffd7_044b471b-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"f8197dbe5b1951fda0e6ed566b34ffd7_044b471b-jpg-2","status":"inherit","uploaded_to":178827,"date":"2025-04-17 14:48:43","modified":"2025-04-18 13:21:05","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1440,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f8197dbe5b1951fda0e6ed566b34ffd7_044b471b-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f8197dbe5b1951fda0e6ed566b34ffd7_044b471b-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f8197dbe5b1951fda0e6ed566b34ffd7_044b471b-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f8197dbe5b1951fda0e6ed566b34ffd7_044b471b-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f8197dbe5b1951fda0e6ed566b34ffd7_044b471b-1536x864.jpg","1536x1536-width":1536,"1536x1536-height":864,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f8197dbe5b1951fda0e6ed566b34ffd7_044b471b-2048x1152.jpg","2048x2048-width":2048,"2048x2048-height":1152,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f8197dbe5b1951fda0e6ed566b34ffd7_044b471b-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f8197dbe5b1951fda0e6ed566b34ffd7_044b471b-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f8197dbe5b1951fda0e6ed566b34ffd7_044b471b-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":151020,"id":151020,"title":"c497bcd66cad0a2445a7b5c3eae8845e_8ba72a43.jpg","filename":"c497bcd66cad0a2445a7b5c3eae8845e_8ba72a43-scaled.jpg","filesize":462553,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c497bcd66cad0a2445a7b5c3eae8845e_8ba72a43-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/colleonis-lodge-verdellino\/c497bcd66cad0a2445a7b5c3eae8845e_8ba72a43-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"c497bcd66cad0a2445a7b5c3eae8845e_8ba72a43-jpg-2","status":"inherit","uploaded_to":178827,"date":"2025-04-17 14:48:45","modified":"2025-04-18 13:21:05","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1440,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c497bcd66cad0a2445a7b5c3eae8845e_8ba72a43-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c497bcd66cad0a2445a7b5c3eae8845e_8ba72a43-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c497bcd66cad0a2445a7b5c3eae8845e_8ba72a43-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c497bcd66cad0a2445a7b5c3eae8845e_8ba72a43-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c497bcd66cad0a2445a7b5c3eae8845e_8ba72a43-1536x864.jpg","1536x1536-width":1536,"1536x1536-height":864,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c497bcd66cad0a2445a7b5c3eae8845e_8ba72a43-2048x1152.jpg","2048x2048-width":2048,"2048x2048-height":1152,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c497bcd66cad0a2445a7b5c3eae8845e_8ba72a43-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c497bcd66cad0a2445a7b5c3eae8845e_8ba72a43-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c497bcd66cad0a2445a7b5c3eae8845e_8ba72a43-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":151027,"id":151027,"title":"3950a189716580ffd401d78e207355d2_d8d130ab.jpg","filename":"3950a189716580ffd401d78e207355d2_d8d130ab-scaled.jpg","filesize":1049017,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3950a189716580ffd401d78e207355d2_d8d130ab-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/colleonis-lodge-verdellino\/3950a189716580ffd401d78e207355d2_d8d130ab-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"3950a189716580ffd401d78e207355d2_d8d130ab-jpg-2","status":"inherit","uploaded_to":178827,"date":"2025-04-17 14:48:48","modified":"2025-04-18 13:21:05","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1440,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3950a189716580ffd401d78e207355d2_d8d130ab-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3950a189716580ffd401d78e207355d2_d8d130ab-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3950a189716580ffd401d78e207355d2_d8d130ab-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3950a189716580ffd401d78e207355d2_d8d130ab-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3950a189716580ffd401d78e207355d2_d8d130ab-1536x864.jpg","1536x1536-width":1536,"1536x1536-height":864,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3950a189716580ffd401d78e207355d2_d8d130ab-2048x1152.jpg","2048x2048-width":2048,"2048x2048-height":1152,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3950a189716580ffd401d78e207355d2_d8d130ab-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3950a189716580ffd401d78e207355d2_d8d130ab-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3950a189716580ffd401d78e207355d2_d8d130ab-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"time":"<p>In linea di massima il check-in dopo le ore 15,00 ed il check-out entro le ore 10,00.<\/p>\n","ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":"","service_icons":[{"value":"parking","label":"Parcheggio gratuito"},{"value":"wifi","label":"Wi-Fi"},{"value":"air_conditioner","label":"Aria condizionata"},{"value":"hairdryer","label":"Asciugacapelli"},{"value":"shower","label":"Bagni con doccia"},{"value":"bathrooms","label":"Bagni con vasca"},{"value":"balcony","label":"Balcone"},{"value":"safe_deposit_box","label":"Cassetta di sicurezza"},{"value":"mini_bar","label":"Frigo bar"},{"value":"satellite_tv","label":"TV satellitare"},{"value":"eurocard","label":"Eurocard \/ Mastercard"}]},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/178827","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/178827\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media\/150901"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media?parent=178827"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/categories?post=178827"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/tags?post=178827"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/aggr?post=178827"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/area?post=178827"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/kind?post=178827"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/zona?post=178827"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}