{"id":178939,"date":"2025-04-18T13:11:04","date_gmt":"2025-04-18T11:11:04","guid":{"rendered":"https:\/\/visit.valueservice.cloud\/oggetto\/olimpic-hostel\/"},"modified":"2025-04-18T15:25:17","modified_gmt":"2025-04-18T13:25:17","slug":"olimpic-hostel","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/olimpic-hostel\/","title":{"rendered":"Olimpic Hostel"},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":153652,"template":"","categories":[1002],"tags":[],"aggr":[],"area":[],"kind":[18725],"zona":[],"class_list":["post-178939","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-schlaf","kind-strutturaricettiva-de"],"acf":{"hero_type":"images","video_youtube_url":"","video_vimeo_url":"","size":"full","hero_title":"Olimpic Hostel","hero_text":"<p>Gem\u00fctliche, ger\u00e4umige und saubere Zimmer in einem Kontext von Ruhe und nat\u00fcrlicher Sch\u00f6nheit<\/p>\n","slides":[{"image":{"ID":153652,"id":153652,"title":"a1acf7c8af7ad75dd51164233beed52e_e9904e80.jpg","filename":"a1acf7c8af7ad75dd51164233beed52e_e9904e80.jpg","filesize":242781,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a1acf7c8af7ad75dd51164233beed52e_e9904e80.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/olimpic-hostel\/a1acf7c8af7ad75dd51164233beed52e_e9904e80-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"a1acf7c8af7ad75dd51164233beed52e_e9904e80-jpg-2","status":"inherit","uploaded_to":178939,"date":"2025-04-17 14:59:37","modified":"2025-04-18 13:25:19","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":660,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a1acf7c8af7ad75dd51164233beed52e_e9904e80-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a1acf7c8af7ad75dd51164233beed52e_e9904e80-300x125.jpg","medium-width":300,"medium-height":125,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a1acf7c8af7ad75dd51164233beed52e_e9904e80-768x321.jpg","medium_large-width":768,"medium_large-height":321,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a1acf7c8af7ad75dd51164233beed52e_e9904e80-1024x428.jpg","large-width":1024,"large-height":428,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a1acf7c8af7ad75dd51164233beed52e_e9904e80-1536x642.jpg","1536x1536-width":1536,"1536x1536-height":642,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a1acf7c8af7ad75dd51164233beed52e_e9904e80.jpg","2048x2048-width":1580,"2048x2048-height":660,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a1acf7c8af7ad75dd51164233beed52e_e9904e80.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":125,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a1acf7c8af7ad75dd51164233beed52e_e9904e80.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":167,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a1acf7c8af7ad75dd51164233beed52e_e9904e80.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":251}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":153659,"id":153659,"title":"6dcf09a3fa9a212058f17990e8986da8_5b74364c.jpg","filename":"6dcf09a3fa9a212058f17990e8986da8_5b74364c.jpg","filesize":284325,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6dcf09a3fa9a212058f17990e8986da8_5b74364c.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/olimpic-hostel\/6dcf09a3fa9a212058f17990e8986da8_5b74364c-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"6dcf09a3fa9a212058f17990e8986da8_5b74364c-jpg-2","status":"inherit","uploaded_to":178939,"date":"2025-04-17 14:59:38","modified":"2025-04-18 13:25:19","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":743,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6dcf09a3fa9a212058f17990e8986da8_5b74364c-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6dcf09a3fa9a212058f17990e8986da8_5b74364c-300x141.jpg","medium-width":300,"medium-height":141,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6dcf09a3fa9a212058f17990e8986da8_5b74364c-768x361.jpg","medium_large-width":768,"medium_large-height":361,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6dcf09a3fa9a212058f17990e8986da8_5b74364c-1024x482.jpg","large-width":1024,"large-height":482,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6dcf09a3fa9a212058f17990e8986da8_5b74364c-1536x722.jpg","1536x1536-width":1536,"1536x1536-height":722,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6dcf09a3fa9a212058f17990e8986da8_5b74364c.jpg","2048x2048-width":1580,"2048x2048-height":743,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6dcf09a3fa9a212058f17990e8986da8_5b74364c.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":141,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6dcf09a3fa9a212058f17990e8986da8_5b74364c.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":188,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6dcf09a3fa9a212058f17990e8986da8_5b74364c.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":282}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":153666,"id":153666,"title":"b7002aa64c7feae9a049801f5f3fb65d_7e043e6d.jpg","filename":"b7002aa64c7feae9a049801f5f3fb65d_7e043e6d.jpg","filesize":330181,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b7002aa64c7feae9a049801f5f3fb65d_7e043e6d.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/olimpic-hostel\/b7002aa64c7feae9a049801f5f3fb65d_7e043e6d-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"b7002aa64c7feae9a049801f5f3fb65d_7e043e6d-jpg-2","status":"inherit","uploaded_to":178939,"date":"2025-04-17 14:59:39","modified":"2025-04-18 13:25:19","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":785,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b7002aa64c7feae9a049801f5f3fb65d_7e043e6d-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b7002aa64c7feae9a049801f5f3fb65d_7e043e6d-300x149.jpg","medium-width":300,"medium-height":149,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b7002aa64c7feae9a049801f5f3fb65d_7e043e6d-768x382.jpg","medium_large-width":768,"medium_large-height":382,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b7002aa64c7feae9a049801f5f3fb65d_7e043e6d-1024x509.jpg","large-width":1024,"large-height":509,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b7002aa64c7feae9a049801f5f3fb65d_7e043e6d-1536x763.jpg","1536x1536-width":1536,"1536x1536-height":763,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b7002aa64c7feae9a049801f5f3fb65d_7e043e6d.jpg","2048x2048-width":1580,"2048x2048-height":785,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b7002aa64c7feae9a049801f5f3fb65d_7e043e6d.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":149,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b7002aa64c7feae9a049801f5f3fb65d_7e043e6d.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":199,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b7002aa64c7feae9a049801f5f3fb65d_7e043e6d.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":298}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":153673,"id":153673,"title":"08ec763ae2735ad13eab203f928cabec_36c793f3.jpg","filename":"08ec763ae2735ad13eab203f928cabec_36c793f3.jpg","filesize":304754,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/08ec763ae2735ad13eab203f928cabec_36c793f3.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/olimpic-hostel\/08ec763ae2735ad13eab203f928cabec_36c793f3-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"08ec763ae2735ad13eab203f928cabec_36c793f3-jpg-2","status":"inherit","uploaded_to":178939,"date":"2025-04-17 14:59:40","modified":"2025-04-18 13:25:19","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":750,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/08ec763ae2735ad13eab203f928cabec_36c793f3-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/08ec763ae2735ad13eab203f928cabec_36c793f3-300x142.jpg","medium-width":300,"medium-height":142,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/08ec763ae2735ad13eab203f928cabec_36c793f3-768x365.jpg","medium_large-width":768,"medium_large-height":365,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/08ec763ae2735ad13eab203f928cabec_36c793f3-1024x486.jpg","large-width":1024,"large-height":486,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/08ec763ae2735ad13eab203f928cabec_36c793f3-1536x729.jpg","1536x1536-width":1536,"1536x1536-height":729,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/08ec763ae2735ad13eab203f928cabec_36c793f3.jpg","2048x2048-width":1580,"2048x2048-height":750,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/08ec763ae2735ad13eab203f928cabec_36c793f3.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":142,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/08ec763ae2735ad13eab203f928cabec_36c793f3.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":190,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/08ec763ae2735ad13eab203f928cabec_36c793f3.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":285}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":153680,"id":153680,"title":"eb1ac0c9ae505227a9fdbc408fd8a80c_fd920ab1.jpg","filename":"eb1ac0c9ae505227a9fdbc408fd8a80c_fd920ab1.jpg","filesize":295237,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/eb1ac0c9ae505227a9fdbc408fd8a80c_fd920ab1.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/olimpic-hostel\/eb1ac0c9ae505227a9fdbc408fd8a80c_fd920ab1-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"eb1ac0c9ae505227a9fdbc408fd8a80c_fd920ab1-jpg-2","status":"inherit","uploaded_to":178939,"date":"2025-04-17 14:59:41","modified":"2025-04-18 13:25:19","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":757,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/eb1ac0c9ae505227a9fdbc408fd8a80c_fd920ab1-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/eb1ac0c9ae505227a9fdbc408fd8a80c_fd920ab1-300x144.jpg","medium-width":300,"medium-height":144,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/eb1ac0c9ae505227a9fdbc408fd8a80c_fd920ab1-768x368.jpg","medium_large-width":768,"medium_large-height":368,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/eb1ac0c9ae505227a9fdbc408fd8a80c_fd920ab1-1024x491.jpg","large-width":1024,"large-height":491,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/eb1ac0c9ae505227a9fdbc408fd8a80c_fd920ab1-1536x736.jpg","1536x1536-width":1536,"1536x1536-height":736,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/eb1ac0c9ae505227a9fdbc408fd8a80c_fd920ab1.jpg","2048x2048-width":1580,"2048x2048-height":757,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/eb1ac0c9ae505227a9fdbc408fd8a80c_fd920ab1.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":144,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/eb1ac0c9ae505227a9fdbc408fd8a80c_fd920ab1.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":192,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/eb1ac0c9ae505227a9fdbc408fd8a80c_fd920ab1.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":287}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":153687,"id":153687,"title":"a86eabd5170eeec182f38b24ce169d3c_b732ef97.jpg","filename":"a86eabd5170eeec182f38b24ce169d3c_b732ef97.jpg","filesize":208170,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a86eabd5170eeec182f38b24ce169d3c_b732ef97.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/olimpic-hostel\/a86eabd5170eeec182f38b24ce169d3c_b732ef97-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"a86eabd5170eeec182f38b24ce169d3c_b732ef97-jpg-2","status":"inherit","uploaded_to":178939,"date":"2025-04-17 14:59:42","modified":"2025-04-18 13:25:19","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":732,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a86eabd5170eeec182f38b24ce169d3c_b732ef97-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a86eabd5170eeec182f38b24ce169d3c_b732ef97-300x139.jpg","medium-width":300,"medium-height":139,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a86eabd5170eeec182f38b24ce169d3c_b732ef97-768x356.jpg","medium_large-width":768,"medium_large-height":356,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a86eabd5170eeec182f38b24ce169d3c_b732ef97-1024x474.jpg","large-width":1024,"large-height":474,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a86eabd5170eeec182f38b24ce169d3c_b732ef97-1536x712.jpg","1536x1536-width":1536,"1536x1536-height":712,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a86eabd5170eeec182f38b24ce169d3c_b732ef97.jpg","2048x2048-width":1580,"2048x2048-height":732,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a86eabd5170eeec182f38b24ce169d3c_b732ef97.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":139,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a86eabd5170eeec182f38b24ce169d3c_b732ef97.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":185,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a86eabd5170eeec182f38b24ce169d3c_b732ef97.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":278}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"buttons":false,"hero_buttons_group":{"buttons":false},"hero_buttons":false,"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":false,"filotto_fill":false,"filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":0,"show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":false,"order_way":false}},"description":"<p>Das Olimpic Hostel befindet sich in Schilpario, etwa 70 km vom Stadtzentrum von Bergamo und dem Flughafen von Bergamo, 15,5 km von den Skipisten von Colere und nur 600 m von der Fisi-Langlaufloipe und auch in der N\u00e4he des Passo del Vivione, entfernt.&#13;<br \/>\n\u00a0&#13;<br \/>\nDie Herberge verf\u00fcgt \u00fcber 9 sehr ger\u00e4umige Zimmer mit Panoramablick auf die Orobischen Voralpen, mit 1, 2, 3 oder 4 Betten, Badezimmer mit Handt\u00fcchern f\u00fcr G\u00e4ste.&#13;<br \/>\nDas Olimpic Hostel wird sowohl von Paaren als auch von Familien gew\u00e4hlt und was es auszeichnet, ist die Aufmerksamkeit auf Sauberkeit und Kundenempfang.&#13;<br \/>\nAll dies bietet eine sehr entspannte Atmosph\u00e4re mit Blick in die herrliche Natur.&#13;<br \/>\n\u00a0&#13;<br \/>\nDie Herberge bietet seinen G\u00e4sten einen Gemeinschaftsraum im Erdgeschoss mit Kabel-TV sowie einen Raum, in dem Sie Fahrr\u00e4der und Skiausr\u00fcstung sicher aufbewahren k\u00f6<\/p>\n","indepth":"<p>Der Name der Herberge stammt aus der Anzahl der Familienmitglieder der Besitzer, die an den Olympischen Spielen teilgenommen haben. Nordic Walking-Exkursionen f\u00fcr G\u00e4ste der Herberge werden ebenfalls organisiert, ohne dass eine Mindestteilnehmerzahl erreicht werden muss.<\/p>\n","howtogetthere":"","timerange":"","seasonality":"","pairings":"","curiosities":"","awards":"","cancellationpolicy":"","moredetails":"","whatsincluded":"","whatsnotincluded":"","price":"","services":"<p>Vereinbarung mit dem Skilanglaufverband Schilpario Centrofondo<\/p>\n","parking":"<p>Beide Privatparkpl\u00e4tze stehen zur Verf\u00fcgung und kostenfreie \u00f6ffentliche Parkpl\u00e4tze stehen an der Unterkunft zur Verf\u00fcgung.<\/p>\n","restaurant":"","breakfast":"","internet":"<p>Kostenloser WIFI in der Struktur<\/p>\n","children":"<p>Spielbereich f\u00fcr Kinder.&#13;<br \/>\nBabybetten sind auf Anfrage erh\u00e4ltlich<\/p>\n","pets":"<p>Tiere sind willkommen<\/p>\n","latitude":"46.009719","longitude":"10.155528","startingprice":"","gpxmap":"","iu_motor_accessibility":"yes","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_kids":true,"iu_shortprice":"","iu_company_name":"","registered_office":"","iu_addr_streetnumber":"Via della Costa, 14","iu_addr_postalcode":"24020","iu_addr_city":"Bergamo","iu_addr_province":"BG","iu_phone":"+39034655044","iu_cell":"+393482650651","iu_website":"","iu_email":"","iu_vat":"","iu_document_label":"","iu_document":false,"iu_documents":false,"iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_bookingurl":"","iu_videourl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"","iu_languages":"","iu_minpeople":"","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"iu_stars":"","iu_rooms":"","iu_beds":"","id_madeep":"","id_visit_manza":"6966","id_east":"","id_ristora":"","id_eppen":"","style":"primary","text":"","button_icon":"none","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"validfrom":"","validto":"","hours":"","tcm_content":false,"accessibilitycontent":{"tcm_content":false},"accessibilityicons":[],"time":"<p>Check in:\u00a0 dalle 17.00Check out: entro le 10.00<\/p>\n","ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":"","service_icons":[{"value":"disabled_access","label":"Accessibile disabili"},{"value":"groups_welcome","label":"Accettazione gruppi"},{"value":"elevator","label":"Ascensore"},{"value":"parking","label":"Parcheggio gratuito"},{"value":"wifi","label":"Wi-Fi"},{"value":"park_garden","label":"Parco \/ Giardino"},{"value":"pets_allowed","label":"Ammessi piccoli animali"},{"value":"shower","label":"Bagni con doccia"},{"value":"balcony","label":"Balcone"}]},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/178939","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/178939\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media\/153652"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media?parent=178939"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/categories?post=178939"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/tags?post=178939"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/aggr?post=178939"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/area?post=178939"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/kind?post=178939"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/zona?post=178939"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}