{"id":179026,"date":"2025-04-18T13:14:45","date_gmt":"2025-04-18T11:14:45","guid":{"rendered":"https:\/\/visit.valueservice.cloud\/oggetto\/vulcano-village-albergo-diffuso-ferienhaus-fremdenzimmer-bed-breakfast\/"},"modified":"2025-04-18T15:28:51","modified_gmt":"2025-04-18T13:28:51","slug":"vulcano-village-albergo-diffuso-ferienhaus-fremdenzimmer-bed-breakfast","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/vulcano-village-albergo-diffuso-ferienhaus-fremdenzimmer-bed-breakfast\/","title":{"rendered":"Vulcano Village [Albergo Diffuso &#8211; Ferienhaus &#8211; Fremdenzimmer &#8211; Bed &#038; Breakfast]"},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":155644,"template":"","categories":[1002],"tags":[],"aggr":[],"area":[],"kind":[18725],"zona":[],"class_list":["post-179026","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-schlaf","kind-strutturaricettiva-de"],"acf":{"hero_type":"images","video_youtube_url":"","video_vimeo_url":"","size":"full","hero_title":"Vulcano Village [Albergo Diffuso - Ferienhaus - Fremdenzimmer - Bed & Breakfast]","hero_text":"<p>Das Vulcano Village befindet sich in Castro (BG) und entwickelt sich vom Seeufer, wo sich das <a href='https:\/\/vulcanovillage.com\/restaurant-pizza\/'>Restaurant-Pizzeria<\/a> befindet, in der Altstadt, mit seinen alten renovierten <a href='https:\/\/vulcanovillage.com\/presentazione\/'>H\u00e4usern<\/a>, den geschmackvoll eingerichteten <a href='https:\/\/vulcanovillage.com\/camere\/'>Zimmern<\/a> und dem neuen <a href='https:\/\/vulcanovillage.com\/presentazione\/'>Albergo Diffuso<\/a><\/p>\n<p>&#13;<\/p>\n<p>\u00a0<\/p>\n","buttons":false,"hero_buttons_group":{"buttons":false},"hero_buttons":false,"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":false,"filotto_fill":false,"filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":0,"show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":false,"order_way":false}},"description":"<p>Das Vulcano Village ist:&#13;<br \/>\n\u2192 Restaurant Pizzeria: einladend und mit einem herrlichen Blick auf den See wurde das Vulcano Village Restaurant Pizzeria vor kurzem renoviert und bietet eine renommierte und einfallsreiche, aber traditionelle K\u00fcche;&#13;<br \/>\n\u2192 Albergo Diffuso: eine neue Art von Tourismus, mit alten H\u00e4usern, die k\u00fcrzlich renoviert wurden und dem historischen Zentrum neues Leben einhauchen. Das Albergo Diffuso besteht aus 4 ger\u00e4umigen Apartments, 5 Zimmern in modernem Stil und ab 2017 ein komplettes Haus f\u00fcr unsere G\u00e4ste.&#13;<br \/>\n\u2192 Ferienhaus: ein Residence, bestehend aus einer gro\u00dfen Wohnung, die bis zu 7 Personen beherbergen kann, und 3 Mini-Apartments, die alle komplett m\u00f6bliert und mit einer K\u00fcche ausgestattet sind.&#13;<br \/>\n\u2192 B&#038;B: 5 Zimmer mit allem Komfort, gem\u00fctlich, einschlie\u00dflich unabh\u00e4ngiger Heizung, Balkon. Es hat auch ein Zimmer f\u00fcr behinderte G\u00e4ste. Alle Angebote sind h\u00f6chstens 400m von der Rezeption entfernt, in unserem Ristorante Pizzeria Vulcano&#13;<br \/>\nUnsere G\u00e4ste k\u00f6nnen kostenlos Wi-Fi-Verbindung nutzen.&#13;<br \/>\nFahrr\u00e4der stehen den G\u00e4sten kostenlos zur Verf\u00fcgung, um die eindrucksvollsten Ecken der Gegend zu entdecken. (Die Verantwortung des Fahrzeugs liegt beim Kunden, der es benutzt)&#13;<br \/>\nEs ist m\u00f6glich einen kostenpflichtigen Parkplatz in unserer Garage zu reservieren; es gibt aber auch einen gro\u00dfen \u00f6ffentlichen Parkplatz in der N\u00e4he.<\/p>\n","indepth":"","howtogetthere":"<p>Die Rezeption befindet sich in unserem Ristorante Pizzeria Vulcano, am See, neben der Ampel<\/p>\n","timerange":"","seasonality":"","pairings":"","curiosities":"","awards":"","cancellationpolicy":"","moredetails":"","whatsincluded":"","whatsnotincluded":"","price":"","services":"","parking":"<p>Parkplatz in der Garage: 6,00 \u20ac pro Nacht&#13;<br \/>\nParkplatz auf dem privaten Parkplatz: 4,00 \u20ac pro Nacht&#13;<br \/>\nKostenlose \u00f6ffentliche Parkpl\u00e4tze in der N\u00e4he<\/p>\n","restaurant":"<p>Unser Restaurant Pizzeria bietet lokale und nationale Gerichte mit einer gro\u00dfen Auswahl an Gerichten mit Fleisch und Fisch, Pizzas und fabelhaften hausgemachten Desserts<\/p>\n","breakfast":"<p>Buffet mit frischen hei\u00dfen Getr\u00e4nken, s\u00fc\u00dfen und herzhaften Produkten (Joghurt, Marmeladen, S\u00e4fte, K\u00e4se, Aufschnitt, Geb\u00e4ck Brioches, frisches Brot &#8230;)<\/p>\n","internet":"<p>kostenloses WiFi im gesamten Hotel<\/p>\n","children":"","pets":"<p>Auf Anfrage kostenlos erlaubt<\/p>\n","latitude":"45.802540","longitude":"10.065649","startingprice":"","gpxmap":"","iu_motor_accessibility":"notsure","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_kids":false,"iu_shortprice":"","iu_company_name":"Trattoria Vulcano di Savoldelli P.E. & C. snc","registered_office":"","iu_addr_streetnumber":"Piazza porto n. 18","iu_addr_postalcode":"24063","iu_addr_city":"Bergamo","iu_addr_province":"BG","iu_phone":"+39035983434","iu_cell":"","iu_website":"http:\/\/www.vulcanovillage.com","iu_email":"info@vulcanovillage.it","iu_vat":"","iu_document_label":"","iu_document":false,"iu_documents":false,"iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_bookingurl":"","iu_videourl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"","iu_languages":"","iu_minpeople":"","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"iu_stars":"","iu_rooms":"","iu_beds":"","id_madeep":"","id_visit_manza":"4939","id_east":"","id_ristora":"","id_eppen":"","style":"primary","text":"","button_icon":"none","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"validfrom":"","validto":"","hours":"","tcm_content":false,"accessibilitycontent":{"tcm_content":false},"accessibilityicons":[],"slides":[{"image":{"ID":155644,"id":155644,"title":"06e9505804f1a34261084c96299f3f47_8e9f48a8.jpg","filename":"06e9505804f1a34261084c96299f3f47_8e9f48a8-scaled.jpg","filesize":267071,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/06e9505804f1a34261084c96299f3f47_8e9f48a8-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/vulcano-village-albergo-diffuso-ferienhaus-fremdenzimmer-bed-breakfast\/06e9505804f1a34261084c96299f3f47_8e9f48a8-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"06e9505804f1a34261084c96299f3f47_8e9f48a8-jpg-2","status":"inherit","uploaded_to":179026,"date":"2025-04-17 15:08:51","modified":"2025-04-18 13:28:53","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1714,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/06e9505804f1a34261084c96299f3f47_8e9f48a8-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/06e9505804f1a34261084c96299f3f47_8e9f48a8-300x201.jpg","medium-width":300,"medium-height":201,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/06e9505804f1a34261084c96299f3f47_8e9f48a8-768x514.jpg","medium_large-width":768,"medium_large-height":514,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/06e9505804f1a34261084c96299f3f47_8e9f48a8-1024x685.jpg","large-width":1024,"large-height":685,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/06e9505804f1a34261084c96299f3f47_8e9f48a8-1536x1028.jpg","1536x1536-width":1536,"1536x1536-height":1028,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/06e9505804f1a34261084c96299f3f47_8e9f48a8-2048x1371.jpg","2048x2048-width":2048,"2048x2048-height":1371,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/06e9505804f1a34261084c96299f3f47_8e9f48a8-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":201,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/06e9505804f1a34261084c96299f3f47_8e9f48a8-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":268,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/06e9505804f1a34261084c96299f3f47_8e9f48a8-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":402}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":155651,"id":155651,"title":"fdd8efe76f6170ad73568a0bb7df02cf_335a7dee.jpg","filename":"fdd8efe76f6170ad73568a0bb7df02cf_335a7dee.jpg","filesize":119334,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fdd8efe76f6170ad73568a0bb7df02cf_335a7dee.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/vulcano-village-albergo-diffuso-ferienhaus-fremdenzimmer-bed-breakfast\/fdd8efe76f6170ad73568a0bb7df02cf_335a7dee-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"fdd8efe76f6170ad73568a0bb7df02cf_335a7dee-jpg-2","status":"inherit","uploaded_to":179026,"date":"2025-04-17 15:08:53","modified":"2025-04-18 13:28:53","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1024,"height":686,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fdd8efe76f6170ad73568a0bb7df02cf_335a7dee-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fdd8efe76f6170ad73568a0bb7df02cf_335a7dee-300x201.jpg","medium-width":300,"medium-height":201,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fdd8efe76f6170ad73568a0bb7df02cf_335a7dee-768x515.jpg","medium_large-width":768,"medium_large-height":515,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fdd8efe76f6170ad73568a0bb7df02cf_335a7dee.jpg","large-width":1024,"large-height":686,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fdd8efe76f6170ad73568a0bb7df02cf_335a7dee.jpg","1536x1536-width":1024,"1536x1536-height":686,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fdd8efe76f6170ad73568a0bb7df02cf_335a7dee.jpg","2048x2048-width":1024,"2048x2048-height":686,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fdd8efe76f6170ad73568a0bb7df02cf_335a7dee.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":201,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fdd8efe76f6170ad73568a0bb7df02cf_335a7dee.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":268,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fdd8efe76f6170ad73568a0bb7df02cf_335a7dee.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":402}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":155658,"id":155658,"title":"014c7c4cf8e0359f05c8e6204f5b4b1b_16b5298e.jpg","filename":"014c7c4cf8e0359f05c8e6204f5b4b1b_16b5298e.jpg","filesize":276799,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/014c7c4cf8e0359f05c8e6204f5b4b1b_16b5298e.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/vulcano-village-albergo-diffuso-ferienhaus-fremdenzimmer-bed-breakfast\/014c7c4cf8e0359f05c8e6204f5b4b1b_16b5298e-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"014c7c4cf8e0359f05c8e6204f5b4b1b_16b5298e-jpg-2","status":"inherit","uploaded_to":179026,"date":"2025-04-17 15:08:54","modified":"2025-04-18 13:28:53","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1280,"height":857,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/014c7c4cf8e0359f05c8e6204f5b4b1b_16b5298e-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/014c7c4cf8e0359f05c8e6204f5b4b1b_16b5298e-300x201.jpg","medium-width":300,"medium-height":201,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/014c7c4cf8e0359f05c8e6204f5b4b1b_16b5298e-768x514.jpg","medium_large-width":768,"medium_large-height":514,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/014c7c4cf8e0359f05c8e6204f5b4b1b_16b5298e-1024x686.jpg","large-width":1024,"large-height":686,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/014c7c4cf8e0359f05c8e6204f5b4b1b_16b5298e.jpg","1536x1536-width":1280,"1536x1536-height":857,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/014c7c4cf8e0359f05c8e6204f5b4b1b_16b5298e.jpg","2048x2048-width":1280,"2048x2048-height":857,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/014c7c4cf8e0359f05c8e6204f5b4b1b_16b5298e.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":201,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/014c7c4cf8e0359f05c8e6204f5b4b1b_16b5298e.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":268,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/014c7c4cf8e0359f05c8e6204f5b4b1b_16b5298e.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":402}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":155665,"id":155665,"title":"e2351c31a0aa2ceb7d26bc3a2d95493d_5a8a6018.jpg","filename":"e2351c31a0aa2ceb7d26bc3a2d95493d_5a8a6018.jpg","filesize":204773,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e2351c31a0aa2ceb7d26bc3a2d95493d_5a8a6018.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/vulcano-village-albergo-diffuso-ferienhaus-fremdenzimmer-bed-breakfast\/e2351c31a0aa2ceb7d26bc3a2d95493d_5a8a6018-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"e2351c31a0aa2ceb7d26bc3a2d95493d_5a8a6018-jpg-2","status":"inherit","uploaded_to":179026,"date":"2025-04-17 15:08:55","modified":"2025-04-18 13:28:53","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1024,"height":686,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e2351c31a0aa2ceb7d26bc3a2d95493d_5a8a6018-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e2351c31a0aa2ceb7d26bc3a2d95493d_5a8a6018-300x201.jpg","medium-width":300,"medium-height":201,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e2351c31a0aa2ceb7d26bc3a2d95493d_5a8a6018-768x515.jpg","medium_large-width":768,"medium_large-height":515,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e2351c31a0aa2ceb7d26bc3a2d95493d_5a8a6018.jpg","large-width":1024,"large-height":686,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e2351c31a0aa2ceb7d26bc3a2d95493d_5a8a6018.jpg","1536x1536-width":1024,"1536x1536-height":686,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e2351c31a0aa2ceb7d26bc3a2d95493d_5a8a6018.jpg","2048x2048-width":1024,"2048x2048-height":686,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e2351c31a0aa2ceb7d26bc3a2d95493d_5a8a6018.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":201,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e2351c31a0aa2ceb7d26bc3a2d95493d_5a8a6018.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":268,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e2351c31a0aa2ceb7d26bc3a2d95493d_5a8a6018.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":402}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":155672,"id":155672,"title":"e2c9755d5f180046c83564bf6b5df1a1_25b0b757.jpg","filename":"e2c9755d5f180046c83564bf6b5df1a1_25b0b757.jpg","filesize":141585,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e2c9755d5f180046c83564bf6b5df1a1_25b0b757.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/vulcano-village-albergo-diffuso-ferienhaus-fremdenzimmer-bed-breakfast\/e2c9755d5f180046c83564bf6b5df1a1_25b0b757-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"e2c9755d5f180046c83564bf6b5df1a1_25b0b757-jpg-2","status":"inherit","uploaded_to":179026,"date":"2025-04-17 15:08:56","modified":"2025-04-18 13:28:53","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":800,"height":536,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e2c9755d5f180046c83564bf6b5df1a1_25b0b757-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e2c9755d5f180046c83564bf6b5df1a1_25b0b757-300x201.jpg","medium-width":300,"medium-height":201,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e2c9755d5f180046c83564bf6b5df1a1_25b0b757-768x515.jpg","medium_large-width":768,"medium_large-height":515,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e2c9755d5f180046c83564bf6b5df1a1_25b0b757.jpg","large-width":800,"large-height":536,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e2c9755d5f180046c83564bf6b5df1a1_25b0b757.jpg","1536x1536-width":800,"1536x1536-height":536,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e2c9755d5f180046c83564bf6b5df1a1_25b0b757.jpg","2048x2048-width":800,"2048x2048-height":536,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e2c9755d5f180046c83564bf6b5df1a1_25b0b757.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":201,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e2c9755d5f180046c83564bf6b5df1a1_25b0b757.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":268,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e2c9755d5f180046c83564bf6b5df1a1_25b0b757.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":402}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":155679,"id":155679,"title":"f354ef2ae19777e9702388eb3f444241_0909d19a.jpg","filename":"f354ef2ae19777e9702388eb3f444241_0909d19a.jpg","filesize":208710,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f354ef2ae19777e9702388eb3f444241_0909d19a.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/vulcano-village-albergo-diffuso-ferienhaus-fremdenzimmer-bed-breakfast\/f354ef2ae19777e9702388eb3f444241_0909d19a-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"f354ef2ae19777e9702388eb3f444241_0909d19a-jpg-2","status":"inherit","uploaded_to":179026,"date":"2025-04-17 15:08:57","modified":"2025-04-18 13:28:53","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1024,"height":686,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f354ef2ae19777e9702388eb3f444241_0909d19a-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f354ef2ae19777e9702388eb3f444241_0909d19a-300x201.jpg","medium-width":300,"medium-height":201,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f354ef2ae19777e9702388eb3f444241_0909d19a-768x515.jpg","medium_large-width":768,"medium_large-height":515,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f354ef2ae19777e9702388eb3f444241_0909d19a.jpg","large-width":1024,"large-height":686,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f354ef2ae19777e9702388eb3f444241_0909d19a.jpg","1536x1536-width":1024,"1536x1536-height":686,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f354ef2ae19777e9702388eb3f444241_0909d19a.jpg","2048x2048-width":1024,"2048x2048-height":686,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f354ef2ae19777e9702388eb3f444241_0909d19a.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":201,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f354ef2ae19777e9702388eb3f444241_0909d19a.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":268,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f354ef2ae19777e9702388eb3f444241_0909d19a.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":402}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":155686,"id":155686,"title":"a5463c0ab6fd652ba55311874453ea5f_1ab45923.jpg","filename":"a5463c0ab6fd652ba55311874453ea5f_1ab45923.jpg","filesize":206589,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a5463c0ab6fd652ba55311874453ea5f_1ab45923.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/vulcano-village-albergo-diffuso-ferienhaus-fremdenzimmer-bed-breakfast\/a5463c0ab6fd652ba55311874453ea5f_1ab45923-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"a5463c0ab6fd652ba55311874453ea5f_1ab45923-jpg-2","status":"inherit","uploaded_to":179026,"date":"2025-04-17 15:08:58","modified":"2025-04-18 13:28:53","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1076,"height":720,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a5463c0ab6fd652ba55311874453ea5f_1ab45923-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a5463c0ab6fd652ba55311874453ea5f_1ab45923-300x201.jpg","medium-width":300,"medium-height":201,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a5463c0ab6fd652ba55311874453ea5f_1ab45923-768x514.jpg","medium_large-width":768,"medium_large-height":514,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a5463c0ab6fd652ba55311874453ea5f_1ab45923-1024x685.jpg","large-width":1024,"large-height":685,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a5463c0ab6fd652ba55311874453ea5f_1ab45923.jpg","1536x1536-width":1076,"1536x1536-height":720,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a5463c0ab6fd652ba55311874453ea5f_1ab45923.jpg","2048x2048-width":1076,"2048x2048-height":720,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a5463c0ab6fd652ba55311874453ea5f_1ab45923.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":201,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a5463c0ab6fd652ba55311874453ea5f_1ab45923.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":268,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a5463c0ab6fd652ba55311874453ea5f_1ab45923.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":401}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"time":"<p>sempre Aperto&#13;<br \/>\nCheck-in: dalle 14:30 alle 23.00&#13;<br \/>\ncheck-out: dalle 08:00 alle 10.30<\/p>\n","ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":"","service_icons":[{"value":"groups_welcome","label":"Accettazione gruppi"},{"value":"restaurant","label":"Ristorante"},{"value":"banquet_hall","label":"Sala banchetti"},{"value":"meeting_room","label":"Sala riunioni"},{"value":"wifi","label":"Wi-Fi"},{"value":"pets_allowed","label":"Ammessi piccoli animali"},{"value":"air_conditioner","label":"Aria condizionata"},{"value":"hairdryer","label":"Asciugacapelli"},{"value":"shower","label":"Bagni con doccia"},{"value":"bathrooms_with_tub","label":"Bagni con idromassaggio"},{"value":"bathrooms","label":"Bagni con vasca"},{"value":"balcony","label":"Balcone"},{"value":"tv_room","label":"TV in camera"},{"value":"bancomat","label":"Bancomat"},{"value":"visa","label":"Visa"},{"value":"mastercard","label":"Mastercard"}]},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/179026","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/179026\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media\/155644"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media?parent=179026"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/categories?post=179026"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/tags?post=179026"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/aggr?post=179026"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/area?post=179026"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/kind?post=179026"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/zona?post=179026"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}