{"id":179047,"date":"2025-04-18T13:15:42","date_gmt":"2025-04-18T11:15:42","guid":{"rendered":"https:\/\/visit.valueservice.cloud\/oggetto\/hotel-camoretti\/"},"modified":"2025-04-18T15:29:36","modified_gmt":"2025-04-18T13:29:36","slug":"hotel-camoretti","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/hotel-camoretti\/","title":{"rendered":"Hotel Camoretti"},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":156092,"template":"","categories":[1002],"tags":[],"aggr":[],"area":[],"kind":[18725],"zona":[],"class_list":["post-179047","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-schlaf","kind-strutturaricettiva-de"],"acf":{"hero_type":"images","video_youtube_url":"","video_vimeo_url":"","size":"full","hero_title":"Hotel Camoretti","hero_text":"<p>Auf den H\u00fcgeln von Almenno San Bartolomeo mit herrlichem Blick \u00fcber das Tal von Bergamo, ist das Hotel Restaurant Camoretti Synonym f\u00fcr Gastfreundschaft im Namen der Gastronomie<\/p>\n","slides":[{"image":{"ID":156092,"id":156092,"title":"3f7e437482b34a02ea90851de9963e53_4ebfb379.jpg","filename":"3f7e437482b34a02ea90851de9963e53_4ebfb379.jpg","filesize":367759,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3f7e437482b34a02ea90851de9963e53_4ebfb379.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/hotel-camoretti\/3f7e437482b34a02ea90851de9963e53_4ebfb379-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"3f7e437482b34a02ea90851de9963e53_4ebfb379-jpg-2","status":"inherit","uploaded_to":179047,"date":"2025-04-17 15:10:32","modified":"2025-04-18 13:29:38","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":656,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3f7e437482b34a02ea90851de9963e53_4ebfb379-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3f7e437482b34a02ea90851de9963e53_4ebfb379-300x125.jpg","medium-width":300,"medium-height":125,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3f7e437482b34a02ea90851de9963e53_4ebfb379-768x319.jpg","medium_large-width":768,"medium_large-height":319,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3f7e437482b34a02ea90851de9963e53_4ebfb379-1024x425.jpg","large-width":1024,"large-height":425,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3f7e437482b34a02ea90851de9963e53_4ebfb379-1536x638.jpg","1536x1536-width":1536,"1536x1536-height":638,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3f7e437482b34a02ea90851de9963e53_4ebfb379.jpg","2048x2048-width":1580,"2048x2048-height":656,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3f7e437482b34a02ea90851de9963e53_4ebfb379.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":125,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3f7e437482b34a02ea90851de9963e53_4ebfb379.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":166,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3f7e437482b34a02ea90851de9963e53_4ebfb379.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":249}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":156099,"id":156099,"title":"63ff2f6dc229382542657723f507254a_c04296a2.jpg","filename":"63ff2f6dc229382542657723f507254a_c04296a2.jpg","filesize":251860,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/63ff2f6dc229382542657723f507254a_c04296a2.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/hotel-camoretti\/63ff2f6dc229382542657723f507254a_c04296a2-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"63ff2f6dc229382542657723f507254a_c04296a2-jpg-2","status":"inherit","uploaded_to":179047,"date":"2025-04-17 15:10:33","modified":"2025-04-18 13:29:38","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/63ff2f6dc229382542657723f507254a_c04296a2-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/63ff2f6dc229382542657723f507254a_c04296a2-300x107.jpg","medium-width":300,"medium-height":107,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/63ff2f6dc229382542657723f507254a_c04296a2-768x275.jpg","medium_large-width":768,"medium_large-height":275,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/63ff2f6dc229382542657723f507254a_c04296a2-1024x366.jpg","large-width":1024,"large-height":366,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/63ff2f6dc229382542657723f507254a_c04296a2-1536x549.jpg","1536x1536-width":1536,"1536x1536-height":549,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/63ff2f6dc229382542657723f507254a_c04296a2.jpg","2048x2048-width":1580,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/63ff2f6dc229382542657723f507254a_c04296a2.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":107,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/63ff2f6dc229382542657723f507254a_c04296a2.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":143,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/63ff2f6dc229382542657723f507254a_c04296a2.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":215}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":156106,"id":156106,"title":"88a918004e2f1bfbd4a9a9bea1afec35_94f74958.jpg","filename":"88a918004e2f1bfbd4a9a9bea1afec35_94f74958.jpg","filesize":183388,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/88a918004e2f1bfbd4a9a9bea1afec35_94f74958.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/hotel-camoretti\/88a918004e2f1bfbd4a9a9bea1afec35_94f74958-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"88a918004e2f1bfbd4a9a9bea1afec35_94f74958-jpg-2","status":"inherit","uploaded_to":179047,"date":"2025-04-17 15:10:34","modified":"2025-04-18 13:29:38","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/88a918004e2f1bfbd4a9a9bea1afec35_94f74958-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/88a918004e2f1bfbd4a9a9bea1afec35_94f74958-300x107.jpg","medium-width":300,"medium-height":107,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/88a918004e2f1bfbd4a9a9bea1afec35_94f74958-768x275.jpg","medium_large-width":768,"medium_large-height":275,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/88a918004e2f1bfbd4a9a9bea1afec35_94f74958-1024x366.jpg","large-width":1024,"large-height":366,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/88a918004e2f1bfbd4a9a9bea1afec35_94f74958-1536x549.jpg","1536x1536-width":1536,"1536x1536-height":549,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/88a918004e2f1bfbd4a9a9bea1afec35_94f74958.jpg","2048x2048-width":1580,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/88a918004e2f1bfbd4a9a9bea1afec35_94f74958.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":107,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/88a918004e2f1bfbd4a9a9bea1afec35_94f74958.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":143,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/88a918004e2f1bfbd4a9a9bea1afec35_94f74958.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":215}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":156113,"id":156113,"title":"1485dd29ee0c0df35e43d5de54004ad9_9b68d6cf.jpg","filename":"1485dd29ee0c0df35e43d5de54004ad9_9b68d6cf.jpg","filesize":178381,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1485dd29ee0c0df35e43d5de54004ad9_9b68d6cf.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/hotel-camoretti\/1485dd29ee0c0df35e43d5de54004ad9_9b68d6cf-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"1485dd29ee0c0df35e43d5de54004ad9_9b68d6cf-jpg-2","status":"inherit","uploaded_to":179047,"date":"2025-04-17 15:10:35","modified":"2025-04-18 13:29:38","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1485dd29ee0c0df35e43d5de54004ad9_9b68d6cf-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1485dd29ee0c0df35e43d5de54004ad9_9b68d6cf-300x107.jpg","medium-width":300,"medium-height":107,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1485dd29ee0c0df35e43d5de54004ad9_9b68d6cf-768x275.jpg","medium_large-width":768,"medium_large-height":275,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1485dd29ee0c0df35e43d5de54004ad9_9b68d6cf-1024x366.jpg","large-width":1024,"large-height":366,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1485dd29ee0c0df35e43d5de54004ad9_9b68d6cf-1536x549.jpg","1536x1536-width":1536,"1536x1536-height":549,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1485dd29ee0c0df35e43d5de54004ad9_9b68d6cf.jpg","2048x2048-width":1580,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1485dd29ee0c0df35e43d5de54004ad9_9b68d6cf.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":107,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1485dd29ee0c0df35e43d5de54004ad9_9b68d6cf.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":143,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1485dd29ee0c0df35e43d5de54004ad9_9b68d6cf.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":215}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":156120,"id":156120,"title":"ddd35395b3349febd4344a469ef0c0fd_6e928f9a.jpg","filename":"ddd35395b3349febd4344a469ef0c0fd_6e928f9a.jpg","filesize":185944,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ddd35395b3349febd4344a469ef0c0fd_6e928f9a.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/hotel-camoretti\/ddd35395b3349febd4344a469ef0c0fd_6e928f9a-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"ddd35395b3349febd4344a469ef0c0fd_6e928f9a-jpg-2","status":"inherit","uploaded_to":179047,"date":"2025-04-17 15:10:36","modified":"2025-04-18 13:29:38","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ddd35395b3349febd4344a469ef0c0fd_6e928f9a-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ddd35395b3349febd4344a469ef0c0fd_6e928f9a-300x107.jpg","medium-width":300,"medium-height":107,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ddd35395b3349febd4344a469ef0c0fd_6e928f9a-768x275.jpg","medium_large-width":768,"medium_large-height":275,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ddd35395b3349febd4344a469ef0c0fd_6e928f9a-1024x366.jpg","large-width":1024,"large-height":366,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ddd35395b3349febd4344a469ef0c0fd_6e928f9a-1536x549.jpg","1536x1536-width":1536,"1536x1536-height":549,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ddd35395b3349febd4344a469ef0c0fd_6e928f9a.jpg","2048x2048-width":1580,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ddd35395b3349febd4344a469ef0c0fd_6e928f9a.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":107,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ddd35395b3349febd4344a469ef0c0fd_6e928f9a.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":143,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ddd35395b3349febd4344a469ef0c0fd_6e928f9a.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":215}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":156127,"id":156127,"title":"231ac2e79548922231fe43e477c1c7e3_c88beb24.jpg","filename":"231ac2e79548922231fe43e477c1c7e3_c88beb24.jpg","filesize":225444,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/231ac2e79548922231fe43e477c1c7e3_c88beb24.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/hotel-camoretti\/231ac2e79548922231fe43e477c1c7e3_c88beb24-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"231ac2e79548922231fe43e477c1c7e3_c88beb24-jpg-2","status":"inherit","uploaded_to":179047,"date":"2025-04-17 15:10:37","modified":"2025-04-18 13:29:38","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/231ac2e79548922231fe43e477c1c7e3_c88beb24-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/231ac2e79548922231fe43e477c1c7e3_c88beb24-300x107.jpg","medium-width":300,"medium-height":107,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/231ac2e79548922231fe43e477c1c7e3_c88beb24-768x275.jpg","medium_large-width":768,"medium_large-height":275,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/231ac2e79548922231fe43e477c1c7e3_c88beb24-1024x366.jpg","large-width":1024,"large-height":366,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/231ac2e79548922231fe43e477c1c7e3_c88beb24-1536x549.jpg","1536x1536-width":1536,"1536x1536-height":549,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/231ac2e79548922231fe43e477c1c7e3_c88beb24.jpg","2048x2048-width":1580,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/231ac2e79548922231fe43e477c1c7e3_c88beb24.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":107,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/231ac2e79548922231fe43e477c1c7e3_c88beb24.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":143,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/231ac2e79548922231fe43e477c1c7e3_c88beb24.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":215}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":156134,"id":156134,"title":"eca752d51addb8735fd692517417ffb4_b89c86db.jpg","filename":"eca752d51addb8735fd692517417ffb4_b89c86db.jpg","filesize":246464,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/eca752d51addb8735fd692517417ffb4_b89c86db.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/hotel-camoretti\/eca752d51addb8735fd692517417ffb4_b89c86db-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"eca752d51addb8735fd692517417ffb4_b89c86db-jpg-2","status":"inherit","uploaded_to":179047,"date":"2025-04-17 15:10:38","modified":"2025-04-18 13:29:38","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/eca752d51addb8735fd692517417ffb4_b89c86db-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/eca752d51addb8735fd692517417ffb4_b89c86db-300x107.jpg","medium-width":300,"medium-height":107,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/eca752d51addb8735fd692517417ffb4_b89c86db-768x275.jpg","medium_large-width":768,"medium_large-height":275,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/eca752d51addb8735fd692517417ffb4_b89c86db-1024x366.jpg","large-width":1024,"large-height":366,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/eca752d51addb8735fd692517417ffb4_b89c86db-1536x549.jpg","1536x1536-width":1536,"1536x1536-height":549,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/eca752d51addb8735fd692517417ffb4_b89c86db.jpg","2048x2048-width":1580,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/eca752d51addb8735fd692517417ffb4_b89c86db.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":107,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/eca752d51addb8735fd692517417ffb4_b89c86db.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":143,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/eca752d51addb8735fd692517417ffb4_b89c86db.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":215}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"buttons":false,"hero_buttons_group":{"buttons":false},"hero_buttons":false,"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":false,"filotto_fill":false,"filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":0,"show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":false,"order_way":false}},"description":"<p>Umgeben Imagna Tal, ist das Hotel Restaurant Camoretti der ideale Ort f\u00fcr diejenigen, die ruhigen Momente in der Natur genie\u00dfen wollen, ohne auf Komfort zu verzichten.&#13;<br \/>\nCamoretti ist ein Synonym f\u00fcr Eleganz, H\u00f6flichkeit und Qualit\u00e4t, in der Lage, alle Arten von Veranstaltungen in gro\u00dfen R\u00e4umen oder in der Sommer Veranda, im elegante Speisesaal mit den sch\u00f6nen Buntglasfenstern oder im Garten, ideal f\u00fcr Cocktails und Buffet, gerecht zu werden, die Ihnen erlauben werden sich wohl f\u00fchlen.<\/p>\n","indepth":"","howtogetthere":"","timerange":"","seasonality":"","pairings":"","curiosities":"","awards":"","cancellationpolicy":"","moredetails":"","whatsincluded":"","whatsnotincluded":"","price":"","time":"","services":"<p>Auf Anfrage:&#13;<br \/>\n&#8211; Eintritt Golf Club Bergamo L&#8217;Albenza&#13;<br \/>\n&#8211; Veranstaltungstickets &#13;<br \/>\n&#8211; Taxi&#13;<br \/>\n&#8211; Auto mit Fahrer<\/p>\n","parking":"<p>Das Hotel verf\u00fcgt \u00fcber einen gro\u00dfen Parkplatz im Freien und einen privaten \u00fcberdachten Parkplatz zur kostenlosen Benutzung.<\/p>\n","restaurant":"<p>Das Restaurant im Hotel wird von der Rota Familie verwaltet, die in der Gastronomie seit \u00fcber 50 Jahren t\u00e4tig ist. Die K\u00fcche bietet traditionelle Gerichte und Spezialit\u00e4ten aus Bergamo  in einer modernen Art und Weise mit neuen Aromen wiederentdeckt.<\/p>\n","breakfast":"<p>Jeden Morgen bieten wir unseren G\u00e4sten ein reichhaltiges amerikanisches Fr\u00fchst\u00fcck oder ein kontinentales Buffet im Fr\u00fchst\u00fccksraum  im Erdgeschoss. Zum Fr\u00fchst\u00fcck bieten wir  Brot, Backwaren , Butter, K\u00e4se, Aufschnitt, Eiern, Joghurt, Obst, Kaffee, Tee, hei\u00dfer Schokolade, Fruchtsaft, Marmelade, M\u00fcsli.<\/p>\n","internet":"<p>WiFi kostenlos im gesamten Hotel verf\u00fcgbar<\/p>\n","children":"","pets":"<p>Nur auf Anfrage.<\/p>\n","latitude":"45.752265","longitude":"9.555117","startingprice":"","gpxmap":"","iu_motor_accessibility":"yes","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_kids":false,"iu_shortprice":"","iu_company_name":"RO.GI. S.r.l.","registered_office":"","iu_addr_streetnumber":"via Camoretti 2\/a","iu_addr_postalcode":"24030","iu_addr_city":"Bergamo","iu_addr_province":"BG","iu_phone":"+39 035550468","iu_cell":"","iu_website":"http:\/\/www.camoretti.it","iu_email":"info@camoretti.it","iu_vat":"","iu_document_label":"","iu_document":false,"iu_documents":false,"iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_bookingurl":"","iu_videourl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"","iu_languages":"","iu_minpeople":"","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"iu_stars":"3","iu_rooms":"","iu_beds":"","id_madeep":"","id_visit_manza":"4433","id_east":"","id_ristora":"","id_eppen":"","style":"primary","text":"","button_icon":"none","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"validfrom":"","validto":"","hours":"","tcm_content":false,"accessibilitycontent":{"tcm_content":false},"accessibilityicons":[],"ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":"","service_icons":[{"value":"disabled_access","label":"Accessibile disabili"},{"value":"groups_welcome","label":"Accettazione gruppi"},{"value":"elevator","label":"Ascensore"},{"value":"bar","label":"Bar"},{"value":"audiovisual_equipment","label":"Impianti audiovisivi"},{"value":"parking","label":"Parcheggio gratuito"},{"value":"park_garden","label":"Parco \/ Giardino"},{"value":"pool","label":"Piscina"},{"value":"restaurant","label":"Ristorante"},{"value":"banquet_hall","label":"Sala banchetti"},{"value":"conference_hall","label":"Sala congressi"},{"value":"meeting_room","label":"Sala riunioni"},{"value":"tv_lounge","label":"Sala TV"},{"value":"wifi","label":"Wi-Fi"},{"value":"pets_allowed","label":"Ammessi piccoli animali"},{"value":"air_conditioner","label":"Aria condizionata"},{"value":"hairdryer","label":"Asciugacapelli"},{"value":"shower","label":"Bagni con doccia"},{"value":"safe_deposit_box","label":"Cassetta di sicurezza"},{"value":"mini_bar","label":"Frigo bar"},{"value":"room_service","label":"Servizio in camera"},{"value":"tv_room","label":"TV in camera"},{"value":"satellite_tv","label":"TV satellitare"},{"value":"bancomat","label":"Bancomat"},{"value":"visa","label":"Visa"},{"value":"mastercard","label":"Mastercard"},{"value":"eurocard","label":"Eurocard \/ Mastercard"},{"value":"amex","label":"American Express"},{"value":"diners","label":"Diners Club"}]},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/179047","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/179047\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media\/156092"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media?parent=179047"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/categories?post=179047"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/tags?post=179047"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/aggr?post=179047"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/area?post=179047"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/kind?post=179047"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/zona?post=179047"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}