{"id":179076,"date":"2025-04-18T13:16:42","date_gmt":"2025-04-18T11:16:42","guid":{"rendered":"https:\/\/visit.valueservice.cloud\/oggetto\/casa-mario-lupo\/"},"modified":"2025-04-18T15:31:05","modified_gmt":"2025-04-18T13:31:05","slug":"casa-mario-lupo","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/casa-mario-lupo\/","title":{"rendered":"Casa Mario Lupo"},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":157045,"template":"","categories":[1002],"tags":[],"aggr":[],"area":[],"kind":[18725],"zona":[],"class_list":["post-179076","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-schlaf","kind-strutturaricettiva-de"],"acf":{"hero_type":"images","video_youtube_url":"","video_vimeo_url":"","size":"full","hero_title":"Casa Mario Lupo","hero_text":"<p>Casa Mario Lupo seit \u00fcber 8 Jahren in der Oberstadt von Bergamo ist einer der authentischsten und attraktivsten Herbergen.<\/p>\n","slides":[{"image":{"ID":157045,"id":157045,"title":"7df6f26811e73424c2ce615e51e45c31_e8340551.jpg","filename":"7df6f26811e73424c2ce615e51e45c31_e8340551-scaled.jpg","filesize":990865,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7df6f26811e73424c2ce615e51e45c31_e8340551-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/casa-mario-lupo\/7df6f26811e73424c2ce615e51e45c31_e8340551-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"7df6f26811e73424c2ce615e51e45c31_e8340551-jpg-2","status":"inherit","uploaded_to":179076,"date":"2025-04-17 15:14:15","modified":"2025-04-18 13:31:07","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1920,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7df6f26811e73424c2ce615e51e45c31_e8340551-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7df6f26811e73424c2ce615e51e45c31_e8340551-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7df6f26811e73424c2ce615e51e45c31_e8340551-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7df6f26811e73424c2ce615e51e45c31_e8340551-1024x768.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7df6f26811e73424c2ce615e51e45c31_e8340551-1536x1152.jpg","1536x1536-width":1536,"1536x1536-height":1152,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7df6f26811e73424c2ce615e51e45c31_e8340551-2048x1536.jpg","2048x2048-width":2048,"2048x2048-height":1536,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7df6f26811e73424c2ce615e51e45c31_e8340551-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7df6f26811e73424c2ce615e51e45c31_e8340551-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7df6f26811e73424c2ce615e51e45c31_e8340551-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":157052,"id":157052,"title":"59bd932f610f999476ac84750843e0c7_0e262d14.jpg","filename":"59bd932f610f999476ac84750843e0c7_0e262d14.jpg","filesize":515107,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/59bd932f610f999476ac84750843e0c7_0e262d14.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/casa-mario-lupo\/59bd932f610f999476ac84750843e0c7_0e262d14-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"59bd932f610f999476ac84750843e0c7_0e262d14-jpg-2","status":"inherit","uploaded_to":179076,"date":"2025-04-17 15:14:17","modified":"2025-04-18 13:31:07","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2048,"height":1536,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/59bd932f610f999476ac84750843e0c7_0e262d14-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/59bd932f610f999476ac84750843e0c7_0e262d14-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/59bd932f610f999476ac84750843e0c7_0e262d14-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/59bd932f610f999476ac84750843e0c7_0e262d14-1024x768.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/59bd932f610f999476ac84750843e0c7_0e262d14-1536x1152.jpg","1536x1536-width":1536,"1536x1536-height":1152,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/59bd932f610f999476ac84750843e0c7_0e262d14.jpg","2048x2048-width":2048,"2048x2048-height":1536,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/59bd932f610f999476ac84750843e0c7_0e262d14.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/59bd932f610f999476ac84750843e0c7_0e262d14.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/59bd932f610f999476ac84750843e0c7_0e262d14.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":157059,"id":157059,"title":"8480231fbe02d3d51e1ca3bfe47acd45_eb8aea5f.jpg","filename":"8480231fbe02d3d51e1ca3bfe47acd45_eb8aea5f-scaled.jpg","filesize":475493,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8480231fbe02d3d51e1ca3bfe47acd45_eb8aea5f-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/casa-mario-lupo\/8480231fbe02d3d51e1ca3bfe47acd45_eb8aea5f-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"8480231fbe02d3d51e1ca3bfe47acd45_eb8aea5f-jpg-2","status":"inherit","uploaded_to":179076,"date":"2025-04-17 15:14:19","modified":"2025-04-18 13:31:07","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1920,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8480231fbe02d3d51e1ca3bfe47acd45_eb8aea5f-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8480231fbe02d3d51e1ca3bfe47acd45_eb8aea5f-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8480231fbe02d3d51e1ca3bfe47acd45_eb8aea5f-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8480231fbe02d3d51e1ca3bfe47acd45_eb8aea5f-1024x768.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8480231fbe02d3d51e1ca3bfe47acd45_eb8aea5f-1536x1152.jpg","1536x1536-width":1536,"1536x1536-height":1152,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8480231fbe02d3d51e1ca3bfe47acd45_eb8aea5f-2048x1536.jpg","2048x2048-width":2048,"2048x2048-height":1536,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8480231fbe02d3d51e1ca3bfe47acd45_eb8aea5f-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8480231fbe02d3d51e1ca3bfe47acd45_eb8aea5f-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8480231fbe02d3d51e1ca3bfe47acd45_eb8aea5f-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":157066,"id":157066,"title":"4bf932c231ce15c25dba2476bf35dc4c_344ad118.jpg","filename":"4bf932c231ce15c25dba2476bf35dc4c_344ad118-scaled.jpg","filesize":456764,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4bf932c231ce15c25dba2476bf35dc4c_344ad118-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/casa-mario-lupo\/4bf932c231ce15c25dba2476bf35dc4c_344ad118-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"4bf932c231ce15c25dba2476bf35dc4c_344ad118-jpg-2","status":"inherit","uploaded_to":179076,"date":"2025-04-17 15:14:21","modified":"2025-04-18 13:31:07","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1920,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4bf932c231ce15c25dba2476bf35dc4c_344ad118-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4bf932c231ce15c25dba2476bf35dc4c_344ad118-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4bf932c231ce15c25dba2476bf35dc4c_344ad118-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4bf932c231ce15c25dba2476bf35dc4c_344ad118-1024x768.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4bf932c231ce15c25dba2476bf35dc4c_344ad118-1536x1152.jpg","1536x1536-width":1536,"1536x1536-height":1152,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4bf932c231ce15c25dba2476bf35dc4c_344ad118-2048x1536.jpg","2048x2048-width":2048,"2048x2048-height":1536,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4bf932c231ce15c25dba2476bf35dc4c_344ad118-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4bf932c231ce15c25dba2476bf35dc4c_344ad118-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4bf932c231ce15c25dba2476bf35dc4c_344ad118-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":157073,"id":157073,"title":"9e7bdaeaeab849f924da613e535fe9b5_3aef2a19.jpg","filename":"9e7bdaeaeab849f924da613e535fe9b5_3aef2a19-scaled.jpg","filesize":792642,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9e7bdaeaeab849f924da613e535fe9b5_3aef2a19-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/casa-mario-lupo\/9e7bdaeaeab849f924da613e535fe9b5_3aef2a19-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"9e7bdaeaeab849f924da613e535fe9b5_3aef2a19-jpg-2","status":"inherit","uploaded_to":179076,"date":"2025-04-17 15:14:23","modified":"2025-04-18 13:31:07","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1706,"height":2560,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9e7bdaeaeab849f924da613e535fe9b5_3aef2a19-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9e7bdaeaeab849f924da613e535fe9b5_3aef2a19-200x300.jpg","medium-width":200,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9e7bdaeaeab849f924da613e535fe9b5_3aef2a19-768x1152.jpg","medium_large-width":768,"medium_large-height":1152,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9e7bdaeaeab849f924da613e535fe9b5_3aef2a19-682x1024.jpg","large-width":682,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9e7bdaeaeab849f924da613e535fe9b5_3aef2a19-1024x1536.jpg","1536x1536-width":1024,"1536x1536-height":1536,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9e7bdaeaeab849f924da613e535fe9b5_3aef2a19-1365x2048.jpg","2048x2048-width":1365,"2048x2048-height":2048,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9e7bdaeaeab849f924da613e535fe9b5_3aef2a19-scaled.jpg","gform-image-choice-sm-width":200,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9e7bdaeaeab849f924da613e535fe9b5_3aef2a19-scaled.jpg","gform-image-choice-md-width":267,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9e7bdaeaeab849f924da613e535fe9b5_3aef2a19-scaled.jpg","gform-image-choice-lg-width":400,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":157080,"id":157080,"title":"35fca0637976647ba5f2af33ddf0640e_6593875b.jpg","filename":"35fca0637976647ba5f2af33ddf0640e_6593875b-scaled.jpg","filesize":898170,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/35fca0637976647ba5f2af33ddf0640e_6593875b-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/casa-mario-lupo\/35fca0637976647ba5f2af33ddf0640e_6593875b-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"35fca0637976647ba5f2af33ddf0640e_6593875b-jpg-2","status":"inherit","uploaded_to":179076,"date":"2025-04-17 15:14:26","modified":"2025-04-18 13:31:07","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1920,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/35fca0637976647ba5f2af33ddf0640e_6593875b-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/35fca0637976647ba5f2af33ddf0640e_6593875b-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/35fca0637976647ba5f2af33ddf0640e_6593875b-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/35fca0637976647ba5f2af33ddf0640e_6593875b-1024x768.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/35fca0637976647ba5f2af33ddf0640e_6593875b-1536x1152.jpg","1536x1536-width":1536,"1536x1536-height":1152,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/35fca0637976647ba5f2af33ddf0640e_6593875b-2048x1536.jpg","2048x2048-width":2048,"2048x2048-height":1536,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/35fca0637976647ba5f2af33ddf0640e_6593875b-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/35fca0637976647ba5f2af33ddf0640e_6593875b-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/35fca0637976647ba5f2af33ddf0640e_6593875b-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":157087,"id":157087,"title":"a09895a4b9fa0229c6552f76bc847b74_cba8f803.jpg","filename":"a09895a4b9fa0229c6552f76bc847b74_cba8f803-scaled.jpg","filesize":768540,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a09895a4b9fa0229c6552f76bc847b74_cba8f803-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/casa-mario-lupo\/a09895a4b9fa0229c6552f76bc847b74_cba8f803-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"a09895a4b9fa0229c6552f76bc847b74_cba8f803-jpg-2","status":"inherit","uploaded_to":179076,"date":"2025-04-17 15:14:28","modified":"2025-04-18 13:31:07","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1920,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a09895a4b9fa0229c6552f76bc847b74_cba8f803-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a09895a4b9fa0229c6552f76bc847b74_cba8f803-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a09895a4b9fa0229c6552f76bc847b74_cba8f803-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a09895a4b9fa0229c6552f76bc847b74_cba8f803-1024x768.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a09895a4b9fa0229c6552f76bc847b74_cba8f803-1536x1152.jpg","1536x1536-width":1536,"1536x1536-height":1152,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a09895a4b9fa0229c6552f76bc847b74_cba8f803-2048x1536.jpg","2048x2048-width":2048,"2048x2048-height":1536,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a09895a4b9fa0229c6552f76bc847b74_cba8f803-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a09895a4b9fa0229c6552f76bc847b74_cba8f803-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a09895a4b9fa0229c6552f76bc847b74_cba8f803-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":157094,"id":157094,"title":"a3cf6cadb993d1254f6e0bb20c4b5210_44b87d56.jpg","filename":"a3cf6cadb993d1254f6e0bb20c4b5210_44b87d56.jpg","filesize":106596,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a3cf6cadb993d1254f6e0bb20c4b5210_44b87d56.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/casa-mario-lupo\/a3cf6cadb993d1254f6e0bb20c4b5210_44b87d56-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"a3cf6cadb993d1254f6e0bb20c4b5210_44b87d56-jpg-2","status":"inherit","uploaded_to":179076,"date":"2025-04-17 15:14:30","modified":"2025-04-18 13:31:07","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":480,"height":640,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a3cf6cadb993d1254f6e0bb20c4b5210_44b87d56-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a3cf6cadb993d1254f6e0bb20c4b5210_44b87d56-225x300.jpg","medium-width":225,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a3cf6cadb993d1254f6e0bb20c4b5210_44b87d56.jpg","medium_large-width":480,"medium_large-height":640,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a3cf6cadb993d1254f6e0bb20c4b5210_44b87d56.jpg","large-width":480,"large-height":640,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a3cf6cadb993d1254f6e0bb20c4b5210_44b87d56.jpg","1536x1536-width":480,"1536x1536-height":640,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a3cf6cadb993d1254f6e0bb20c4b5210_44b87d56.jpg","2048x2048-width":480,"2048x2048-height":640,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a3cf6cadb993d1254f6e0bb20c4b5210_44b87d56.jpg","gform-image-choice-sm-width":225,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a3cf6cadb993d1254f6e0bb20c4b5210_44b87d56.jpg","gform-image-choice-md-width":300,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a3cf6cadb993d1254f6e0bb20c4b5210_44b87d56.jpg","gform-image-choice-lg-width":450,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":157101,"id":157101,"title":"4459b25e104cc2e3873c6e9f738f0791_590fe314.jpg","filename":"4459b25e104cc2e3873c6e9f738f0791_590fe314.jpg","filesize":99034,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4459b25e104cc2e3873c6e9f738f0791_590fe314.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/casa-mario-lupo\/4459b25e104cc2e3873c6e9f738f0791_590fe314-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"4459b25e104cc2e3873c6e9f738f0791_590fe314-jpg-2","status":"inherit","uploaded_to":179076,"date":"2025-04-17 15:14:31","modified":"2025-04-18 13:31:07","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":480,"height":640,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4459b25e104cc2e3873c6e9f738f0791_590fe314-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4459b25e104cc2e3873c6e9f738f0791_590fe314-225x300.jpg","medium-width":225,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4459b25e104cc2e3873c6e9f738f0791_590fe314.jpg","medium_large-width":480,"medium_large-height":640,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4459b25e104cc2e3873c6e9f738f0791_590fe314.jpg","large-width":480,"large-height":640,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4459b25e104cc2e3873c6e9f738f0791_590fe314.jpg","1536x1536-width":480,"1536x1536-height":640,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4459b25e104cc2e3873c6e9f738f0791_590fe314.jpg","2048x2048-width":480,"2048x2048-height":640,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4459b25e104cc2e3873c6e9f738f0791_590fe314.jpg","gform-image-choice-sm-width":225,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4459b25e104cc2e3873c6e9f738f0791_590fe314.jpg","gform-image-choice-md-width":300,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4459b25e104cc2e3873c6e9f738f0791_590fe314.jpg","gform-image-choice-lg-width":450,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":157108,"id":157108,"title":"59c9845e14e7e37fce34c62207aab56f_8f9923ba.jpg","filename":"59c9845e14e7e37fce34c62207aab56f_8f9923ba.jpg","filesize":131708,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/59c9845e14e7e37fce34c62207aab56f_8f9923ba.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/casa-mario-lupo\/59c9845e14e7e37fce34c62207aab56f_8f9923ba-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"59c9845e14e7e37fce34c62207aab56f_8f9923ba-jpg-2","status":"inherit","uploaded_to":179076,"date":"2025-04-17 15:14:32","modified":"2025-04-18 13:31:07","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":640,"height":480,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/59c9845e14e7e37fce34c62207aab56f_8f9923ba-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/59c9845e14e7e37fce34c62207aab56f_8f9923ba-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/59c9845e14e7e37fce34c62207aab56f_8f9923ba.jpg","medium_large-width":640,"medium_large-height":480,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/59c9845e14e7e37fce34c62207aab56f_8f9923ba.jpg","large-width":640,"large-height":480,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/59c9845e14e7e37fce34c62207aab56f_8f9923ba.jpg","1536x1536-width":640,"1536x1536-height":480,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/59c9845e14e7e37fce34c62207aab56f_8f9923ba.jpg","2048x2048-width":640,"2048x2048-height":480,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/59c9845e14e7e37fce34c62207aab56f_8f9923ba.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/59c9845e14e7e37fce34c62207aab56f_8f9923ba.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/59c9845e14e7e37fce34c62207aab56f_8f9923ba.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":157115,"id":157115,"title":"6df73184cc599c07f259ee0c347a8cdd_c06f55f9.jpg","filename":"6df73184cc599c07f259ee0c347a8cdd_c06f55f9-scaled.jpg","filesize":433856,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6df73184cc599c07f259ee0c347a8cdd_c06f55f9-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/casa-mario-lupo\/6df73184cc599c07f259ee0c347a8cdd_c06f55f9-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"6df73184cc599c07f259ee0c347a8cdd_c06f55f9-jpg-2","status":"inherit","uploaded_to":179076,"date":"2025-04-17 15:14:32","modified":"2025-04-18 13:31:07","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1920,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6df73184cc599c07f259ee0c347a8cdd_c06f55f9-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6df73184cc599c07f259ee0c347a8cdd_c06f55f9-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6df73184cc599c07f259ee0c347a8cdd_c06f55f9-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6df73184cc599c07f259ee0c347a8cdd_c06f55f9-1024x768.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6df73184cc599c07f259ee0c347a8cdd_c06f55f9-1536x1152.jpg","1536x1536-width":1536,"1536x1536-height":1152,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6df73184cc599c07f259ee0c347a8cdd_c06f55f9-2048x1536.jpg","2048x2048-width":2048,"2048x2048-height":1536,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6df73184cc599c07f259ee0c347a8cdd_c06f55f9-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6df73184cc599c07f259ee0c347a8cdd_c06f55f9-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6df73184cc599c07f259ee0c347a8cdd_c06f55f9-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":157122,"id":157122,"title":"c636bc8f0a8071344fd9a382db93f427_c5cf3761.jpg","filename":"c636bc8f0a8071344fd9a382db93f427_c5cf3761-scaled.jpg","filesize":444740,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c636bc8f0a8071344fd9a382db93f427_c5cf3761-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/casa-mario-lupo\/c636bc8f0a8071344fd9a382db93f427_c5cf3761-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"c636bc8f0a8071344fd9a382db93f427_c5cf3761-jpg-2","status":"inherit","uploaded_to":179076,"date":"2025-04-17 15:14:35","modified":"2025-04-18 13:31:07","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1920,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c636bc8f0a8071344fd9a382db93f427_c5cf3761-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c636bc8f0a8071344fd9a382db93f427_c5cf3761-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c636bc8f0a8071344fd9a382db93f427_c5cf3761-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c636bc8f0a8071344fd9a382db93f427_c5cf3761-1024x768.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c636bc8f0a8071344fd9a382db93f427_c5cf3761-1536x1152.jpg","1536x1536-width":1536,"1536x1536-height":1152,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c636bc8f0a8071344fd9a382db93f427_c5cf3761-2048x1536.jpg","2048x2048-width":2048,"2048x2048-height":1536,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c636bc8f0a8071344fd9a382db93f427_c5cf3761-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c636bc8f0a8071344fd9a382db93f427_c5cf3761-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c636bc8f0a8071344fd9a382db93f427_c5cf3761-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":157129,"id":157129,"title":"500cfe92b46b7eeb9c961f3d4d29d868_a77c3377.jpg","filename":"500cfe92b46b7eeb9c961f3d4d29d868_a77c3377-scaled.jpg","filesize":383775,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/500cfe92b46b7eeb9c961f3d4d29d868_a77c3377-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/casa-mario-lupo\/500cfe92b46b7eeb9c961f3d4d29d868_a77c3377-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"500cfe92b46b7eeb9c961f3d4d29d868_a77c3377-jpg-2","status":"inherit","uploaded_to":179076,"date":"2025-04-17 15:14:37","modified":"2025-04-18 13:31:07","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1920,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/500cfe92b46b7eeb9c961f3d4d29d868_a77c3377-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/500cfe92b46b7eeb9c961f3d4d29d868_a77c3377-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/500cfe92b46b7eeb9c961f3d4d29d868_a77c3377-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/500cfe92b46b7eeb9c961f3d4d29d868_a77c3377-1024x768.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/500cfe92b46b7eeb9c961f3d4d29d868_a77c3377-1536x1152.jpg","1536x1536-width":1536,"1536x1536-height":1152,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/500cfe92b46b7eeb9c961f3d4d29d868_a77c3377-2048x1536.jpg","2048x2048-width":2048,"2048x2048-height":1536,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/500cfe92b46b7eeb9c961f3d4d29d868_a77c3377-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/500cfe92b46b7eeb9c961f3d4d29d868_a77c3377-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/500cfe92b46b7eeb9c961f3d4d29d868_a77c3377-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":157136,"id":157136,"title":"ab27ed7099548b50c3d12001eb059503_38bb62d8.jpg","filename":"ab27ed7099548b50c3d12001eb059503_38bb62d8.jpg","filesize":703647,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ab27ed7099548b50c3d12001eb059503_38bb62d8.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/casa-mario-lupo\/ab27ed7099548b50c3d12001eb059503_38bb62d8-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"ab27ed7099548b50c3d12001eb059503_38bb62d8-jpg-2","status":"inherit","uploaded_to":179076,"date":"2025-04-17 15:14:40","modified":"2025-04-18 13:31:07","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1536,"height":2048,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ab27ed7099548b50c3d12001eb059503_38bb62d8-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ab27ed7099548b50c3d12001eb059503_38bb62d8-225x300.jpg","medium-width":225,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ab27ed7099548b50c3d12001eb059503_38bb62d8-768x1024.jpg","medium_large-width":768,"medium_large-height":1024,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ab27ed7099548b50c3d12001eb059503_38bb62d8-768x1024.jpg","large-width":768,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ab27ed7099548b50c3d12001eb059503_38bb62d8-1152x1536.jpg","1536x1536-width":1152,"1536x1536-height":1536,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ab27ed7099548b50c3d12001eb059503_38bb62d8.jpg","2048x2048-width":1536,"2048x2048-height":2048,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ab27ed7099548b50c3d12001eb059503_38bb62d8.jpg","gform-image-choice-sm-width":225,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ab27ed7099548b50c3d12001eb059503_38bb62d8.jpg","gform-image-choice-md-width":300,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ab27ed7099548b50c3d12001eb059503_38bb62d8.jpg","gform-image-choice-lg-width":450,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"buttons":false,"hero_buttons_group":{"buttons":false},"hero_buttons":false,"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":false,"filotto_fill":false,"filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":0,"show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":false,"order_way":false}},"description":"<p>Das Haus befindet sich im historischen Zentrum der Oberstadt, genau in der Via Mario Lupo 12, hinter der Kathedrale von Sant&#8217;Alessandro, nur 100 Meter von der Piazza Vecchia, 50 Meter vom Tourismusamt und der oberen Seilbahn, in Piazza Mercato delle Scarpe.&#13;<br \/>\nEs ist ein Geb\u00e4ude, das in den fr\u00fchen Jahren des sechszehnten Jahrhundert gebaut wurde und besteht aus mehreren Wohnungen, alle mit eigenem Eingang und WC. Von gro\u00dfen historischem Interesse sind die Spalten des Eingangs des Hauses aus dem Jahr 1515\u00a0 und die barocke Fresken, die zu den oberen Etagen f\u00fchren.&#13;<br \/>\nDer Service beim Fr\u00fchst\u00fcck ist auf der zweiten Etage serviert, im Garten mit Pflanzen und Blumen, von dem Sie den Dom von Bergamo bewundern<\/p>\n","indepth":"<p>Das Haus ist schon seit vielen Jahren ein Meilenstein f\u00fcr G\u00e4ste, die kommen, um unsere Familie , die hier seit \u00fcber 25 Jahren lebt, zu besuchen, und findet deswegen zahlreiche Informationen, Tipps und Nachrichten \u00fcber die Stadt und die Provinz von Bergamo<\/p>\n","howtogetthere":"<p>Via Mario Lupo befindet sich direkt hinter dem Dom von Bergamo, vom Turm von Gombito hinauf (Via Gombito), 50 Meter links<\/p>\n","timerange":"","seasonality":"","pairings":"","curiosities":"","awards":"","cancellationpolicy":"","moredetails":"","whatsincluded":"","whatsnotincluded":"","price":"","services":"<p>In Bergamo betr\u00e4gt die Kurtaxe 2 Euro pro Person pro Nacht  (f\u00fcr Aufenthalte von mehr als 10 Tage zahlen Sie nur 20 Euro)<\/p>\n","parking":"<p>Kostenloses Parken (nicht reservierbar ) in der verkehrsberuhigte Zone&#13;<br \/>\nPrivate Parkpl\u00e4tze  gegen eine Geb\u00fchr am in der Piazza Mercato del Fieno<\/p>\n","restaurant":"","breakfast":"<p>Es wird ein klassisches kontinentales Fr\u00fchst\u00fcck mit einer Auswahl an s\u00fc\u00dfen und salzigen Speisen angeboten<\/p>\n","internet":"<p>Kostenloser Wi-Fi in der ganzen Struktur<\/p>\n","children":"","pets":"<p>Nicht erlaubt<\/p>\n","latitude":"45.703394","longitude":"9.663501","startingprice":"","gpxmap":"","iu_motor_accessibility":"notsure","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_kids":true,"iu_shortprice":"","iu_company_name":"Casa Mario lupo di Gianmauro Bonfanti","registered_office":"","iu_addr_streetnumber":"Via mario lupo 12","iu_addr_postalcode":"24129","iu_addr_city":"Bergamo","iu_addr_province":"BG","iu_phone":"+39035247046","iu_cell":"+393289235505","iu_website":"http:\/\/www.casamariolupo.it","iu_email":"info@casamariolupo.it","iu_vat":"","iu_document_label":"","iu_document":false,"iu_documents":false,"iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_bookingurl":"","iu_videourl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"","iu_languages":"","iu_minpeople":"","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"iu_stars":"","iu_rooms":"2","iu_beds":"8","id_madeep":"","id_visit_manza":"5718","id_east":"","id_ristora":"","id_eppen":"","style":"primary","text":"","button_icon":"none","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"validfrom":"","validto":"","hours":"","tcm_content":false,"accessibilitycontent":{"tcm_content":false},"accessibilityicons":[],"time":"<p>check in dalle 14.00- 22.30&#13;<br \/>\ncheck out dalle 5.00 alle 11.00&#13;<br \/>\n\u00a0<\/p>\n","ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":"","service_icons":[{"value":"park_garden","label":"Parco \/ Giardino"},{"value":"wifi","label":"Wi-Fi"},{"value":"hairdryer","label":"Asciugacapelli"},{"value":"shower","label":"Bagni con doccia"},{"value":"bathrooms","label":"Bagni con vasca"},{"value":"balcony","label":"Balcone"},{"value":"satellite_tv","label":"TV satellitare"},{"value":"bancomat","label":"Bancomat"},{"value":"visa","label":"Visa"},{"value":"mastercard","label":"Mastercard"},{"value":"eurocard","label":"Eurocard \/ Mastercard"}]},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/179076","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/179076\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media\/157045"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media?parent=179076"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/categories?post=179076"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/tags?post=179076"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/aggr?post=179076"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/area?post=179076"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/kind?post=179076"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/zona?post=179076"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}