{"id":179133,"date":"2025-04-18T13:19:11","date_gmt":"2025-04-18T11:19:11","guid":{"rendered":"https:\/\/visit.valueservice.cloud\/oggetto\/apartments-alpi-orobie\/"},"modified":"2025-04-18T15:33:18","modified_gmt":"2025-04-18T13:33:18","slug":"apartments-alpi-orobie","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/apartments-alpi-orobie\/","title":{"rendered":"Apartments Alpi Orobie"},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":158271,"template":"","categories":[1002],"tags":[],"aggr":[],"area":[],"kind":[18725],"zona":[],"class_list":["post-179133","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-schlaf","kind-strutturaricettiva-de"],"acf":{"hero_type":"images","video_youtube_url":"","video_vimeo_url":"","size":"full","hero_title":"Apartments Alpi Orobie","hero_text":"<p>Die Apartments Alpi Orobie befinden sich in Serina, eine 20-min\u00fctige Fahrt von San Pellegrino Terme, 25 Autominuten von Selvino und 35 km von Bergamo entfernt<\/p>\n","slides":[{"image":{"ID":158271,"id":158271,"title":"c43cd58235d2d2fb09d4ccbce6f81e09_66a9d3d0.jpg","filename":"c43cd58235d2d2fb09d4ccbce6f81e09_66a9d3d0-scaled.jpg","filesize":336306,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c43cd58235d2d2fb09d4ccbce6f81e09_66a9d3d0-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/apartments-alpi-orobie\/c43cd58235d2d2fb09d4ccbce6f81e09_66a9d3d0-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"c43cd58235d2d2fb09d4ccbce6f81e09_66a9d3d0-jpg-2","status":"inherit","uploaded_to":179133,"date":"2025-04-17 15:19:32","modified":"2025-04-18 13:33:20","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1702,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c43cd58235d2d2fb09d4ccbce6f81e09_66a9d3d0-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c43cd58235d2d2fb09d4ccbce6f81e09_66a9d3d0-300x199.jpg","medium-width":300,"medium-height":199,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c43cd58235d2d2fb09d4ccbce6f81e09_66a9d3d0-768x511.jpg","medium_large-width":768,"medium_large-height":511,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c43cd58235d2d2fb09d4ccbce6f81e09_66a9d3d0-1024x681.jpg","large-width":1024,"large-height":681,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c43cd58235d2d2fb09d4ccbce6f81e09_66a9d3d0-1536x1021.jpg","1536x1536-width":1536,"1536x1536-height":1021,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c43cd58235d2d2fb09d4ccbce6f81e09_66a9d3d0-2048x1362.jpg","2048x2048-width":2048,"2048x2048-height":1362,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c43cd58235d2d2fb09d4ccbce6f81e09_66a9d3d0-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":199,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c43cd58235d2d2fb09d4ccbce6f81e09_66a9d3d0-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":266,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c43cd58235d2d2fb09d4ccbce6f81e09_66a9d3d0-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":399}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":158278,"id":158278,"title":"0f27dedcf79ae4933fa89adf810c5e63_82f80cbf.jpg","filename":"0f27dedcf79ae4933fa89adf810c5e63_82f80cbf-scaled.jpg","filesize":907316,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0f27dedcf79ae4933fa89adf810c5e63_82f80cbf-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/apartments-alpi-orobie\/0f27dedcf79ae4933fa89adf810c5e63_82f80cbf-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"0f27dedcf79ae4933fa89adf810c5e63_82f80cbf-jpg-2","status":"inherit","uploaded_to":179133,"date":"2025-04-17 15:19:34","modified":"2025-04-18 13:33:20","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1702,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0f27dedcf79ae4933fa89adf810c5e63_82f80cbf-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0f27dedcf79ae4933fa89adf810c5e63_82f80cbf-300x199.jpg","medium-width":300,"medium-height":199,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0f27dedcf79ae4933fa89adf810c5e63_82f80cbf-768x511.jpg","medium_large-width":768,"medium_large-height":511,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0f27dedcf79ae4933fa89adf810c5e63_82f80cbf-1024x681.jpg","large-width":1024,"large-height":681,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0f27dedcf79ae4933fa89adf810c5e63_82f80cbf-1536x1021.jpg","1536x1536-width":1536,"1536x1536-height":1021,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0f27dedcf79ae4933fa89adf810c5e63_82f80cbf-2048x1362.jpg","2048x2048-width":2048,"2048x2048-height":1362,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0f27dedcf79ae4933fa89adf810c5e63_82f80cbf-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":199,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0f27dedcf79ae4933fa89adf810c5e63_82f80cbf-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":266,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0f27dedcf79ae4933fa89adf810c5e63_82f80cbf-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":399}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":158285,"id":158285,"title":"870a2e80587263d86c07d81ac439b503_a8881e7f.jpg","filename":"870a2e80587263d86c07d81ac439b503_a8881e7f-scaled.jpg","filesize":581311,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/870a2e80587263d86c07d81ac439b503_a8881e7f-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/apartments-alpi-orobie\/870a2e80587263d86c07d81ac439b503_a8881e7f-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"870a2e80587263d86c07d81ac439b503_a8881e7f-jpg-2","status":"inherit","uploaded_to":179133,"date":"2025-04-17 15:19:36","modified":"2025-04-18 13:33:20","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1702,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/870a2e80587263d86c07d81ac439b503_a8881e7f-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/870a2e80587263d86c07d81ac439b503_a8881e7f-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/870a2e80587263d86c07d81ac439b503_a8881e7f-768x511.jpg","medium_large-width":768,"medium_large-height":511,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/870a2e80587263d86c07d81ac439b503_a8881e7f-1024x681.jpg","large-width":1024,"large-height":681,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/870a2e80587263d86c07d81ac439b503_a8881e7f-1536x1021.jpg","1536x1536-width":1536,"1536x1536-height":1021,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/870a2e80587263d86c07d81ac439b503_a8881e7f-2048x1362.jpg","2048x2048-width":2048,"2048x2048-height":1362,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/870a2e80587263d86c07d81ac439b503_a8881e7f-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":199,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/870a2e80587263d86c07d81ac439b503_a8881e7f-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":266,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/870a2e80587263d86c07d81ac439b503_a8881e7f-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":399}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":158292,"id":158292,"title":"87d4d9a6fe7962357114c9e603973635_5a1188f8.jpg","filename":"87d4d9a6fe7962357114c9e603973635_5a1188f8-scaled.jpg","filesize":454438,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/87d4d9a6fe7962357114c9e603973635_5a1188f8-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/apartments-alpi-orobie\/87d4d9a6fe7962357114c9e603973635_5a1188f8-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"87d4d9a6fe7962357114c9e603973635_5a1188f8-jpg-2","status":"inherit","uploaded_to":179133,"date":"2025-04-17 15:19:38","modified":"2025-04-18 13:33:20","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1702,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/87d4d9a6fe7962357114c9e603973635_5a1188f8-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/87d4d9a6fe7962357114c9e603973635_5a1188f8-300x199.jpg","medium-width":300,"medium-height":199,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/87d4d9a6fe7962357114c9e603973635_5a1188f8-768x511.jpg","medium_large-width":768,"medium_large-height":511,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/87d4d9a6fe7962357114c9e603973635_5a1188f8-1024x681.jpg","large-width":1024,"large-height":681,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/87d4d9a6fe7962357114c9e603973635_5a1188f8-1536x1021.jpg","1536x1536-width":1536,"1536x1536-height":1021,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/87d4d9a6fe7962357114c9e603973635_5a1188f8-2048x1362.jpg","2048x2048-width":2048,"2048x2048-height":1362,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/87d4d9a6fe7962357114c9e603973635_5a1188f8-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":199,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/87d4d9a6fe7962357114c9e603973635_5a1188f8-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":266,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/87d4d9a6fe7962357114c9e603973635_5a1188f8-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":399}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"buttons":false,"hero_buttons_group":{"buttons":false},"hero_buttons":false,"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":false,"filotto_fill":false,"filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":0,"show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":false,"order_way":false}},"description":"<p>Wir sind umgeben von dem Gr\u00fcn der Orobischen Voralpen, wir k\u00f6nnen unser Brombeeren anbieten, wir werden eine Omelette mit Minze aus unserem Garten machen, die Erdbeeren aus unserem Gem\u00fcsegarten essen, unseren kostbaren Safran probieren,\u00a0 unsere Chow Chow Laika und Liuk, Macchia unser K\u00e4tzchen, Trilly unser britisches Shorthair K\u00e4tzchen vorstellen.&#13;<br \/>\nWir f\u00fchren Sie zu einem Spaziergang im Wald, bis zu einem Bach, viele Tiere, die den Wald bev\u00f6lkern, treffen und wir werden von dem Gesang der V\u00f6gel begleitet sein<\/p>\n","indepth":"","howtogetthere":"","timerange":"","seasonality":"","pairings":"","curiosities":"","awards":"","cancellationpolicy":"","moredetails":"","whatsincluded":"","whatsnotincluded":"","price":"","services":"","parking":"<p>Privatparkplatz in der Anlage, wenn nicht vorhanden, In der Umgebung gibt es kostenlose Parkpl\u00e4tze<\/p>\n","restaurant":"<p>Es gibt viele Restaurants in der Gegend, wo Sie die typische italienische und bergamaskische K\u00fcche genie\u00dfen k\u00f6nnen<\/p>\n","breakfast":"<p>In der Gegend gibt es Konditoreien mit leckerem Fr\u00fchst\u00fcck<\/p>\n","internet":"","children":"<p>Kinder sind willkommen, bis das Alter von 3 Jahren ist der Aufenthalt kostenlos<\/p>\n","pets":"<p>Haustiere willkommen<\/p>\n","latitude":"45.874072","longitude":"9.730537","startingprice":"","gpxmap":"","iu_motor_accessibility":"yes","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_kids":true,"iu_shortprice":"","iu_company_name":"azienda induviduale","registered_office":"","iu_addr_streetnumber":"Via Dante 1","iu_addr_postalcode":"24017","iu_addr_city":"Bergamo","iu_addr_province":"BG","iu_phone":"+39 3397289494","iu_cell":"+39 3397289494","iu_website":"","iu_email":"carraragen@alice.it","iu_vat":"","iu_document_label":"","iu_document":false,"iu_documents":false,"iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_bookingurl":"","iu_videourl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"","iu_languages":"","iu_minpeople":"","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"iu_stars":"","iu_rooms":"","iu_beds":"","id_madeep":"","id_visit_manza":"7519","id_east":"","id_ristora":"","id_eppen":"","style":"primary","text":"","button_icon":"none","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"validfrom":"","validto":"","hours":"","tcm_content":false,"accessibilitycontent":{"tcm_content":false},"accessibilityicons":[],"time":"<p>Arrivo&#13;<br \/>\nDalle 13:00 alle 15:00&#13;<br \/>\n\u00a0&#13;<br \/>\n&#13;<br \/>\n Partenza &#13;<br \/>\nDalle 08:00 alle 10:00&#13;<\/p>\n","ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":"","service_icons":[{"value":"disabled_access","label":"Accessibile disabili"},{"value":"groups_welcome","label":"Accettazione gruppi"},{"value":"audiovisual_equipment","label":"Impianti audiovisivi"},{"value":"parking","label":"Parcheggio gratuito"},{"value":"park_garden","label":"Parco \/ Giardino"},{"value":"pets_allowed","label":"Ammessi piccoli animali"},{"value":"hairdryer","label":"Asciugacapelli"},{"value":"shower","label":"Bagni con doccia"},{"value":"bathrooms","label":"Bagni con vasca"},{"value":"balcony","label":"Balcone"},{"value":"tv_room","label":"TV in camera"}]},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/179133","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/179133\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media\/158271"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media?parent=179133"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/categories?post=179133"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/tags?post=179133"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/aggr?post=179133"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/area?post=179133"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/kind?post=179133"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/zona?post=179133"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}