{"id":179158,"date":"2025-04-18T13:19:55","date_gmt":"2025-04-18T11:19:55","guid":{"rendered":"https:\/\/visit.valueservice.cloud\/oggetto\/design-hotel-gombithotel\/"},"modified":"2025-04-28T22:59:27","modified_gmt":"2025-04-28T20:59:27","slug":"design-hotel-gombithotel","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/design-hotel-gombithotel\/","title":{"rendered":"Design Hotel Gombithotel"},"excerpt":{"rendered":"","protected":false},"author":49,"featured_media":159502,"template":"","categories":[1002],"tags":[],"aggr":[17681],"area":[],"kind":[18725],"zona":[],"class_list":["post-179158","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-schlaf","aggr-accessibilita-on-de","kind-strutturaricettiva-de"],"acf":{"hero_type":"images","video_youtube_url":"","video_vimeo_url":"","size":"full","hero_title":"Design Hotel Gombithotel","hero_text":"<p>Ein Ort f\u00fcr Tr\u00e4umer, von Tr\u00e4umer geschaffen<\/p>\n","slides":[{"image":{"ID":159502,"id":159502,"title":"e0736d92b272341231cd367e552c582c_a0fd4458.jpg","filename":"e0736d92b272341231cd367e552c582c_a0fd4458.jpg","filesize":1163700,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e0736d92b272341231cd367e552c582c_a0fd4458.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/design-hotel-gombithotel\/e0736d92b272341231cd367e552c582c_a0fd4458-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"e0736d92b272341231cd367e552c582c_a0fd4458-jpg-2","status":"inherit","uploaded_to":179158,"date":"2025-04-18 08:24:14","modified":"2025-04-18 13:34:19","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1902,"height":1920,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e0736d92b272341231cd367e552c582c_a0fd4458-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e0736d92b272341231cd367e552c582c_a0fd4458-297x300.jpg","medium-width":297,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e0736d92b272341231cd367e552c582c_a0fd4458-768x775.jpg","medium_large-width":768,"medium_large-height":775,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e0736d92b272341231cd367e552c582c_a0fd4458-1014x1024.jpg","large-width":1014,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e0736d92b272341231cd367e552c582c_a0fd4458-1522x1536.jpg","1536x1536-width":1522,"1536x1536-height":1536,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e0736d92b272341231cd367e552c582c_a0fd4458.jpg","2048x2048-width":1902,"2048x2048-height":1920,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e0736d92b272341231cd367e552c582c_a0fd4458.jpg","gform-image-choice-sm-width":297,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e0736d92b272341231cd367e552c582c_a0fd4458.jpg","gform-image-choice-md-width":396,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e0736d92b272341231cd367e552c582c_a0fd4458.jpg","gform-image-choice-lg-width":594,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":159509,"id":159509,"title":"fa25487b394855a792f1bdaebf199752_0eb6ae1d.png","filename":"fa25487b394855a792f1bdaebf199752_0eb6ae1d.png","filesize":1705694,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fa25487b394855a792f1bdaebf199752_0eb6ae1d.png","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/design-hotel-gombithotel\/fa25487b394855a792f1bdaebf199752_0eb6ae1d-png-2\/","alt":"","author":"0","description":"","caption":"","name":"fa25487b394855a792f1bdaebf199752_0eb6ae1d-png-2","status":"inherit","uploaded_to":179158,"date":"2025-04-18 08:24:15","modified":"2025-04-18 13:34:19","menu_order":0,"mime_type":"image\/png","type":"image","subtype":"png","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1500,"height":818,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fa25487b394855a792f1bdaebf199752_0eb6ae1d-150x150.png","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fa25487b394855a792f1bdaebf199752_0eb6ae1d-300x164.png","medium-width":300,"medium-height":164,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fa25487b394855a792f1bdaebf199752_0eb6ae1d-768x419.png","medium_large-width":768,"medium_large-height":419,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fa25487b394855a792f1bdaebf199752_0eb6ae1d-1024x558.png","large-width":1024,"large-height":558,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fa25487b394855a792f1bdaebf199752_0eb6ae1d.png","1536x1536-width":1500,"1536x1536-height":818,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fa25487b394855a792f1bdaebf199752_0eb6ae1d.png","2048x2048-width":1500,"2048x2048-height":818,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fa25487b394855a792f1bdaebf199752_0eb6ae1d.png","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":164,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fa25487b394855a792f1bdaebf199752_0eb6ae1d.png","gform-image-choice-md-width":400,"gform-image-choice-md-height":218,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fa25487b394855a792f1bdaebf199752_0eb6ae1d.png","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":327}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":159516,"id":159516,"title":"4f1aa83eb96b622933aacc0fc343772a_90fb2ed5.png","filename":"4f1aa83eb96b622933aacc0fc343772a_90fb2ed5.png","filesize":2169779,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4f1aa83eb96b622933aacc0fc343772a_90fb2ed5.png","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/design-hotel-gombithotel\/4f1aa83eb96b622933aacc0fc343772a_90fb2ed5-png-2\/","alt":"","author":"0","description":"","caption":"","name":"4f1aa83eb96b622933aacc0fc343772a_90fb2ed5-png-2","status":"inherit","uploaded_to":179158,"date":"2025-04-18 08:24:18","modified":"2025-04-18 13:34:19","menu_order":0,"mime_type":"image\/png","type":"image","subtype":"png","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1600,"height":1068,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4f1aa83eb96b622933aacc0fc343772a_90fb2ed5-150x150.png","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4f1aa83eb96b622933aacc0fc343772a_90fb2ed5-300x200.png","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4f1aa83eb96b622933aacc0fc343772a_90fb2ed5-768x513.png","medium_large-width":768,"medium_large-height":513,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4f1aa83eb96b622933aacc0fc343772a_90fb2ed5-1024x684.png","large-width":1024,"large-height":684,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4f1aa83eb96b622933aacc0fc343772a_90fb2ed5-1536x1025.png","1536x1536-width":1536,"1536x1536-height":1025,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4f1aa83eb96b622933aacc0fc343772a_90fb2ed5.png","2048x2048-width":1600,"2048x2048-height":1068,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4f1aa83eb96b622933aacc0fc343772a_90fb2ed5.png","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4f1aa83eb96b622933aacc0fc343772a_90fb2ed5.png","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4f1aa83eb96b622933aacc0fc343772a_90fb2ed5.png","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":401}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":159523,"id":159523,"title":"ddf042dfd19208073fcc3178ad4d3e25_16b88320.png","filename":"ddf042dfd19208073fcc3178ad4d3e25_16b88320.png","filesize":1445469,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ddf042dfd19208073fcc3178ad4d3e25_16b88320.png","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/design-hotel-gombithotel\/ddf042dfd19208073fcc3178ad4d3e25_16b88320-png-2\/","alt":"","author":"0","description":"","caption":"","name":"ddf042dfd19208073fcc3178ad4d3e25_16b88320-png-2","status":"inherit","uploaded_to":179158,"date":"2025-04-18 08:24:31","modified":"2025-04-18 13:34:19","menu_order":0,"mime_type":"image\/png","type":"image","subtype":"png","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1560,"height":632,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ddf042dfd19208073fcc3178ad4d3e25_16b88320-150x150.png","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ddf042dfd19208073fcc3178ad4d3e25_16b88320-300x122.png","medium-width":300,"medium-height":122,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ddf042dfd19208073fcc3178ad4d3e25_16b88320-768x311.png","medium_large-width":768,"medium_large-height":311,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ddf042dfd19208073fcc3178ad4d3e25_16b88320-1024x415.png","large-width":1024,"large-height":415,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ddf042dfd19208073fcc3178ad4d3e25_16b88320-1536x622.png","1536x1536-width":1536,"1536x1536-height":622,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ddf042dfd19208073fcc3178ad4d3e25_16b88320.png","2048x2048-width":1560,"2048x2048-height":632,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ddf042dfd19208073fcc3178ad4d3e25_16b88320.png","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":122,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ddf042dfd19208073fcc3178ad4d3e25_16b88320.png","gform-image-choice-md-width":400,"gform-image-choice-md-height":162,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ddf042dfd19208073fcc3178ad4d3e25_16b88320.png","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":243}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":159530,"id":159530,"title":"05ebd1b13aa2c9087cb6b4dcce942f28_5e076bb5.png","filename":"05ebd1b13aa2c9087cb6b4dcce942f28_5e076bb5.png","filesize":2079964,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/05ebd1b13aa2c9087cb6b4dcce942f28_5e076bb5.png","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/design-hotel-gombithotel\/05ebd1b13aa2c9087cb6b4dcce942f28_5e076bb5-png-2\/","alt":"","author":"0","description":"","caption":"","name":"05ebd1b13aa2c9087cb6b4dcce942f28_5e076bb5-png-2","status":"inherit","uploaded_to":179158,"date":"2025-04-18 08:24:36","modified":"2025-04-18 13:34:19","menu_order":0,"mime_type":"image\/png","type":"image","subtype":"png","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1292,"height":862,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/05ebd1b13aa2c9087cb6b4dcce942f28_5e076bb5-150x150.png","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/05ebd1b13aa2c9087cb6b4dcce942f28_5e076bb5-300x200.png","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/05ebd1b13aa2c9087cb6b4dcce942f28_5e076bb5-768x512.png","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/05ebd1b13aa2c9087cb6b4dcce942f28_5e076bb5-1024x683.png","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/05ebd1b13aa2c9087cb6b4dcce942f28_5e076bb5.png","1536x1536-width":1292,"1536x1536-height":862,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/05ebd1b13aa2c9087cb6b4dcce942f28_5e076bb5.png","2048x2048-width":1292,"2048x2048-height":862,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/05ebd1b13aa2c9087cb6b4dcce942f28_5e076bb5.png","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/05ebd1b13aa2c9087cb6b4dcce942f28_5e076bb5.png","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/05ebd1b13aa2c9087cb6b4dcce942f28_5e076bb5.png","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":159537,"id":159537,"title":"4fcb3afcf106b24958059b29dbaf7a56_1e2fb163.png","filename":"4fcb3afcf106b24958059b29dbaf7a56_1e2fb163.png","filesize":2146187,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4fcb3afcf106b24958059b29dbaf7a56_1e2fb163.png","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/design-hotel-gombithotel\/4fcb3afcf106b24958059b29dbaf7a56_1e2fb163-png-2\/","alt":"","author":"0","description":"","caption":"","name":"4fcb3afcf106b24958059b29dbaf7a56_1e2fb163-png-2","status":"inherit","uploaded_to":179158,"date":"2025-04-18 08:24:40","modified":"2025-04-18 13:34:19","menu_order":0,"mime_type":"image\/png","type":"image","subtype":"png","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1480,"height":1116,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4fcb3afcf106b24958059b29dbaf7a56_1e2fb163-150x150.png","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4fcb3afcf106b24958059b29dbaf7a56_1e2fb163-300x226.png","medium-width":300,"medium-height":226,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4fcb3afcf106b24958059b29dbaf7a56_1e2fb163-768x579.png","medium_large-width":768,"medium_large-height":579,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4fcb3afcf106b24958059b29dbaf7a56_1e2fb163-1024x772.png","large-width":1024,"large-height":772,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4fcb3afcf106b24958059b29dbaf7a56_1e2fb163.png","1536x1536-width":1480,"1536x1536-height":1116,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4fcb3afcf106b24958059b29dbaf7a56_1e2fb163.png","2048x2048-width":1480,"2048x2048-height":1116,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4fcb3afcf106b24958059b29dbaf7a56_1e2fb163.png","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":226,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4fcb3afcf106b24958059b29dbaf7a56_1e2fb163.png","gform-image-choice-md-width":400,"gform-image-choice-md-height":302,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4fcb3afcf106b24958059b29dbaf7a56_1e2fb163.png","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":452}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"buttons":false,"hero_buttons_group":{"buttons":false},"hero_buttons":false,"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"","filotto_fill":"","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""}},"description":"<p>Gedacht f\u00fcr all die, die einen Platz als k\u00fcnstlerische Faszination suchen, ist das GombitHotel das erste Design-Hotel innerhalb der alten Mauern, in der Oberstadt von Bergamo, das \u00e4ltere Teil von Bergamo. Angrenzend an den Gombito Turm, einem Geb\u00e4ude aus dem dreizehnten Jahrhundert aus Stein, sowohl Sammelort als auch Werkstattraum, ist das Hotel ein Versuchslabor\u00a0 und Galerie, wo junge K\u00fcnstler zusammen arbeiten, um die Innenr\u00e4ume\u00a0 am Leben zu halten.Ein Ort f\u00fcr Tr\u00e4umer, von Tr\u00e4umern geschaffen<\/p>\n","indepth":"<p>Da sich die Struktur\u00a0 in einem Gebiet Verkehrsbeschr\u00e4nkungen befindet, falls Sie mit dem Auto anreisen m\u00f6chten, bitten wir Sie uns ihren Kfz-Kennzeichen-Nummer mitzuteilen, so dass Sie eine Sondergenehmigung\u00a0 f\u00fcr das Fahren und kostenlose Parkpl\u00e4tze\u00a0 erhalten k\u00f6nnen.&#13;<br \/>\nWenn Sie m\u00f6chten, verf\u00fcgen wir \u00fcber einen Parkplatz\u00a0 in einer Garage nicht weit von unserem Hotel, und wir w\u00fcrden uns freuen, ihn f\u00fcr Sie gegen einen Tagespreis\u00a0 von 25,00 \u20ac zu reservieren.<\/p>\n","howtogetthere":"","timerange":"","seasonality":"","pairings":"","curiosities":"","awards":"","cancellationpolicy":"","moredetails":"","whatsincluded":"","whatsnotincluded":"","price":"","time":"","services":"","parking":"","restaurant":"","breakfast":"","internet":"","children":"","pets":"","latitude":"45.703606","longitude":"9.663710","startingprice":"","gpxmap":"","iu_motor_accessibility":"yes","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_kids":true,"iu_shortprice":"","iu_company_name":"GombitHotel srl","registered_office":"","iu_addr_streetnumber":"Via Mario Lupo 6","iu_addr_postalcode":"24129","iu_addr_city":"Bergamo","iu_addr_province":"BG","iu_phone":"+39 035 247009","iu_cell":"","iu_website":"http:\/\/www.gombithotel.it","iu_email":"info@gombithotel.it","iu_vat":"","iu_document_label":"","iu_document":false,"iu_documents":false,"iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_bookingurl":"","iu_videourl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"","iu_languages":"","iu_minpeople":"","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"iu_stars":"4","iu_rooms":"","iu_beds":"","id_madeep":"","id_visit_manza":"4452","id_east":"","id_ristora":"","id_eppen":"","style":"primary","text":"","button_icon":"none","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"validfrom":"","validto":"","hours":"","tcm_content":[{"acf_fc_layout":"text","text":"<p>DIENSTLEISTUNGEN F\u00dcR BEHINDERTE&#13;<br \/>\nZug\u00e4ngliche Zimmer:\u00a0zwei Vierfachzimmer&#13;<br \/>\nBarrierefreie Zimmerkategorie:\u00a0Deluxe&#13;<br \/>\nParkplatz:\u00a0Vertrag mit der Struktur f\u00fcr \u00fcberdachter Parkplatz&#13;<br \/>\n\u00a0&#13;<br \/>\nDas Gombithotel ist ein Hotel mit modernen und gestalterischen M\u00f6beln. Das Hotel liegt an einer leicht bergauf f\u00fchrenden Stra\u00dfe.&#13;<br \/>\n\u00a0&#13;<br \/>\nDer Zugang zur Struktur hat eine 2,5 cm lange Stufe und die Eingangst\u00fcr ist breit und aufschiebbar. Die T\u00fcr ist etwas schwer und es kann schwierig sein, sie zu \u00f6ffnen. Das Personal an der Rezeption steht dem Kunden zur Verf\u00fcgung.&#13;<br \/>\n\u00a0&#13;<br \/>\nNach der Hoteleingangst\u00fcr gibt es einen Plattformmechanismus, um einige Schritte zu \u00fcberwinden: maximale Kapazit\u00e4t 300 kg.&#13;<br \/>\nDas Hotel bietet Bed &#038; Breakfast-Dienstleistungen.&#13;<br \/>\n\u00a0&#13;<br \/>\nEs gibt 2 Deluxe-Zimmer, die f\u00fcr G\u00e4ste mit eingeschr\u00e4nkter Mobilit\u00e4t zug\u00e4nglich sind. Die Zimmer sind Doppelzimmer und ein Doppelschlafsofa f\u00fcr bis zu 4 Personen. Sie verf\u00fcgen \u00fcber ein barrierefreies Badezimmer mit Haltegriffen und einer ebenerdigen Dusche. Es gibt keinen speziellen Sitz in der Dusche, ein Plastikstuhl wird auf Anfrage zur Verf\u00fcgung gestellt.&#13;<br \/>\n\u00a0&#13;<br \/>\nDie Schlafzimmer und der Fr\u00fchst\u00fccksraum sind mit dem Aufzug mit 81 cm \u00f6ffnenden T\u00fcren und 130 cm Tiefe erreichbar. Im Fr\u00fchst\u00fccksraum befindet sich ein barrierefreies Badezimmer. Die Tische sind 71 cm hoch.&#13;<br \/>\n\u00a0&#13;<br \/>\nDas Gombithotel bietet die M\u00f6glichkeit, Ihr Auto auf einem Partnerparkplatz 3 Minuten vom Hotel entfernt zu parken: Garage San Pancrazio&#13;<br \/>\n\u00a0&#13;<br \/>\nAlternativ gibt es auf der Piazza Mercato del Fieno spezielle Parkpl\u00e4tze: In diesem Fall kann die Person im Rollstuhl, wenn sie alleine unterwegs ist, ihr Gep\u00e4ck eindeutig zuerst im Hotel lassen und gegebenenfalls um Hilfe bitten.&#13;<br \/>\n\u00a0<\/p>\n"},{"acf_fc_layout":"text","text":"<p>Zimmer:&#13;<br \/>\nBreite der Zimmereingangst\u00fcr: 75cm&#13;<br \/>\nBetth\u00f6he: 75cm&#13;<br \/>\nLeerer Raum unter dem Bett: NEIN&#13;<br \/>\nBadezimmer:&#13;<br \/>\nBreite der Eingangst\u00fcr des Badezimmers: 87 cm&#13;<br \/>\nToilettenh\u00f6he: 54cm&#13;<br \/>\nToilettengriffh\u00f6he: 80 cm&#13;<br \/>\nWaschbeckenh\u00f6he: 76cm&#13;<br \/>\nDusch\u00f6ffnung auf Bodenh\u00f6he: 90 cm\u00a0&#13;<br \/>\n\u00a0&#13;<br \/>\n\u00a0<\/p>\n"}],"accessibilitycontent":{"tcm_content":[{"acf_fc_layout":"text","text":"<p>DIENSTLEISTUNGEN F\u00dcR BEHINDERTE&#13;<br \/>\nZug\u00e4ngliche Zimmer:\u00a0zwei Vierfachzimmer&#13;<br \/>\nBarrierefreie Zimmerkategorie:\u00a0Deluxe&#13;<br \/>\nParkplatz:\u00a0Vertrag mit der Struktur f\u00fcr \u00fcberdachter Parkplatz&#13;<br \/>\n\u00a0&#13;<br \/>\nDas Gombithotel ist ein Hotel mit modernen und gestalterischen M\u00f6beln. Das Hotel liegt an einer leicht bergauf f\u00fchrenden Stra\u00dfe.&#13;<br \/>\n\u00a0&#13;<br \/>\nDer Zugang zur Struktur hat eine 2,5 cm lange Stufe und die Eingangst\u00fcr ist breit und aufschiebbar. Die T\u00fcr ist etwas schwer und es kann schwierig sein, sie zu \u00f6ffnen. Das Personal an der Rezeption steht dem Kunden zur Verf\u00fcgung.&#13;<br \/>\n\u00a0&#13;<br \/>\nNach der Hoteleingangst\u00fcr gibt es einen Plattformmechanismus, um einige Schritte zu \u00fcberwinden: maximale Kapazit\u00e4t 300 kg.&#13;<br \/>\nDas Hotel bietet Bed &#038; Breakfast-Dienstleistungen.&#13;<br \/>\n\u00a0&#13;<br \/>\nEs gibt 2 Deluxe-Zimmer, die f\u00fcr G\u00e4ste mit eingeschr\u00e4nkter Mobilit\u00e4t zug\u00e4nglich sind. Die Zimmer sind Doppelzimmer und ein Doppelschlafsofa f\u00fcr bis zu 4 Personen. Sie verf\u00fcgen \u00fcber ein barrierefreies Badezimmer mit Haltegriffen und einer ebenerdigen Dusche. Es gibt keinen speziellen Sitz in der Dusche, ein Plastikstuhl wird auf Anfrage zur Verf\u00fcgung gestellt.&#13;<br \/>\n\u00a0&#13;<br \/>\nDie Schlafzimmer und der Fr\u00fchst\u00fccksraum sind mit dem Aufzug mit 81 cm \u00f6ffnenden T\u00fcren und 130 cm Tiefe erreichbar. Im Fr\u00fchst\u00fccksraum befindet sich ein barrierefreies Badezimmer. Die Tische sind 71 cm hoch.&#13;<br \/>\n\u00a0&#13;<br \/>\nDas Gombithotel bietet die M\u00f6glichkeit, Ihr Auto auf einem Partnerparkplatz 3 Minuten vom Hotel entfernt zu parken: Garage San Pancrazio&#13;<br \/>\n\u00a0&#13;<br \/>\nAlternativ gibt es auf der Piazza Mercato del Fieno spezielle Parkpl\u00e4tze: In diesem Fall kann die Person im Rollstuhl, wenn sie alleine unterwegs ist, ihr Gep\u00e4ck eindeutig zuerst im Hotel lassen und gegebenenfalls um Hilfe bitten.&#13;<br \/>\n\u00a0<\/p>\n"},{"acf_fc_layout":"text","text":"<p>Zimmer:&#13;<br \/>\nBreite der Zimmereingangst\u00fcr: 75cm&#13;<br \/>\nBetth\u00f6he: 75cm&#13;<br \/>\nLeerer Raum unter dem Bett: NEIN&#13;<br \/>\nBadezimmer:&#13;<br \/>\nBreite der Eingangst\u00fcr des Badezimmers: 87 cm&#13;<br \/>\nToilettenh\u00f6he: 54cm&#13;<br \/>\nToilettengriffh\u00f6he: 80 cm&#13;<br \/>\nWaschbeckenh\u00f6he: 76cm&#13;<br \/>\nDusch\u00f6ffnung auf Bodenh\u00f6he: 90 cm\u00a0&#13;<br \/>\n\u00a0&#13;<br \/>\n\u00a0<\/p>\n"}]},"accessibilityicons":["Doccia filo pavimento","Bagno con maniglioni"],"filotto_layout":"","filotto_fill":"","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""},"max_elements":"","show_total":false,"see_all":false,"order_by":"","order_way":"","only_ambassadors":false,"ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":"","stars":"4*","service_icons":[{"value":"disabled_access","label":"Accessibile disabili"},{"value":"groups_welcome","label":"Accettazione gruppi"},{"value":"elevator","label":"Ascensore"},{"value":"bar","label":"Bar"},{"value":"safe","label":"safe"},{"value":"laundry","label":"Lavanderia"},{"value":"parking","label":"Parcheggio gratuito"},{"value":"night_porter","label":"Portiere notturno"},{"value":"meeting_room","label":"Sala riunioni"},{"value":"tv_lounge","label":"Sala TV"},{"value":"wifi","label":"Wi-Fi"},{"value":"pets_allowed","label":"Ammessi piccoli animali"},{"value":"air_conditioner","label":"Aria condizionata"},{"value":"hairdryer","label":"Asciugacapelli"},{"value":"shower","label":"Bagni con doccia"},{"value":"bathrooms","label":"Bagni con vasca"},{"value":"safe_deposit_box","label":"Cassetta di sicurezza"},{"value":"electronic_key","label":"Chiave elettronica"},{"value":"mini_bar","label":"Frigo bar"},{"value":"room_service","label":"Servizio in camera"},{"value":"tv_room","label":"TV in camera"},{"value":"satellite_tv","label":"TV satellitare"},{"value":"bancomat","label":"Bancomat"},{"value":"visa","label":"Visa"},{"value":"mastercard","label":"Mastercard"},{"value":"eurocard","label":"Eurocard \/ Mastercard"},{"value":"amex","label":"American Express"}]},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/179158","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/types\/oggetto"}],"author":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/users\/49"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/179158\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media\/159502"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media?parent=179158"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/categories?post=179158"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/tags?post=179158"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/aggr?post=179158"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/area?post=179158"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/kind?post=179158"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/zona?post=179158"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}