{"id":179213,"date":"2025-04-18T13:22:07","date_gmt":"2025-04-18T11:22:07","guid":{"rendered":"https:\/\/visit.valueservice.cloud\/oggetto\/colletto-agribiorelais\/"},"modified":"2025-04-18T15:36:58","modified_gmt":"2025-04-18T13:36:58","slug":"colletto-agribiorelais","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/colletto-agribiorelais\/","title":{"rendered":"COLLETTO AGRIBIORELAIS"},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":161230,"template":"","categories":[1002],"tags":[],"aggr":[],"area":[],"kind":[18725],"zona":[],"class_list":["post-179213","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-schlaf","kind-strutturaricettiva-de"],"acf":{"hero_type":"images","video_youtube_url":"","video_vimeo_url":"","size":"full","hero_title":"COLLETTO AGRIBIORELAIS","hero_text":"<p>Elegantes Landbiorelais, wo Entspannung und Authentizit\u00e4t sich miteinander verschmelzen<\/p>\n","slides":[{"image":{"ID":161230,"id":161230,"title":"b9a6db87d109e5e2212977eabd6685e3_ce66e496.jpg","filename":"b9a6db87d109e5e2212977eabd6685e3_ce66e496.jpg","filesize":443898,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b9a6db87d109e5e2212977eabd6685e3_ce66e496.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/colletto-agribiorelais\/b9a6db87d109e5e2212977eabd6685e3_ce66e496-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"b9a6db87d109e5e2212977eabd6685e3_ce66e496-jpg-2","status":"inherit","uploaded_to":179213,"date":"2025-04-18 08:32:10","modified":"2025-04-18 13:37:00","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":741,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b9a6db87d109e5e2212977eabd6685e3_ce66e496-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b9a6db87d109e5e2212977eabd6685e3_ce66e496-300x141.jpg","medium-width":300,"medium-height":141,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b9a6db87d109e5e2212977eabd6685e3_ce66e496-768x360.jpg","medium_large-width":768,"medium_large-height":360,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b9a6db87d109e5e2212977eabd6685e3_ce66e496-1024x480.jpg","large-width":1024,"large-height":480,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b9a6db87d109e5e2212977eabd6685e3_ce66e496-1536x720.jpg","1536x1536-width":1536,"1536x1536-height":720,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b9a6db87d109e5e2212977eabd6685e3_ce66e496.jpg","2048x2048-width":1580,"2048x2048-height":741,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b9a6db87d109e5e2212977eabd6685e3_ce66e496.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":141,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b9a6db87d109e5e2212977eabd6685e3_ce66e496.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":188,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b9a6db87d109e5e2212977eabd6685e3_ce66e496.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":281}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":161237,"id":161237,"title":"2f7e5f68ab3c7db3b7ad1a7fec0905e0_6872ebb1.jpg","filename":"2f7e5f68ab3c7db3b7ad1a7fec0905e0_6872ebb1.jpg","filesize":235623,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2f7e5f68ab3c7db3b7ad1a7fec0905e0_6872ebb1.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/colletto-agribiorelais\/2f7e5f68ab3c7db3b7ad1a7fec0905e0_6872ebb1-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"2f7e5f68ab3c7db3b7ad1a7fec0905e0_6872ebb1-jpg-2","status":"inherit","uploaded_to":179213,"date":"2025-04-18 08:32:11","modified":"2025-04-18 13:37:00","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1577,"height":657,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2f7e5f68ab3c7db3b7ad1a7fec0905e0_6872ebb1-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2f7e5f68ab3c7db3b7ad1a7fec0905e0_6872ebb1-300x125.jpg","medium-width":300,"medium-height":125,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2f7e5f68ab3c7db3b7ad1a7fec0905e0_6872ebb1-768x320.jpg","medium_large-width":768,"medium_large-height":320,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2f7e5f68ab3c7db3b7ad1a7fec0905e0_6872ebb1-1024x427.jpg","large-width":1024,"large-height":427,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2f7e5f68ab3c7db3b7ad1a7fec0905e0_6872ebb1-1536x640.jpg","1536x1536-width":1536,"1536x1536-height":640,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2f7e5f68ab3c7db3b7ad1a7fec0905e0_6872ebb1.jpg","2048x2048-width":1577,"2048x2048-height":657,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2f7e5f68ab3c7db3b7ad1a7fec0905e0_6872ebb1.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":125,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2f7e5f68ab3c7db3b7ad1a7fec0905e0_6872ebb1.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":167,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2f7e5f68ab3c7db3b7ad1a7fec0905e0_6872ebb1.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":250}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"buttons":false,"hero_buttons_group":{"buttons":false},"hero_buttons":false,"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"","filotto_fill":"","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""}},"description":"<p>Das Colletto LandBioRelais befindet sich in Adrara San Martino in den H\u00fcgeln des Iseo-Sees und ist eine Oase der Ruhe auf 10 Hektar Wald, Weinbergen und Olivenhainen.&#13;<br \/>\nEin ehemaliges Herrenhaus, das heute in ein modernes Design-Bauernhaus umgewandelt wurde, das perfekt mit den Elementen der Natur harmoniert. Das Holz, der freiliegende Stein, der abgeh\u00e4ngte Kamin und die sechs komfortablen Zimmer schaffen eine einzigartige Atmosph\u00e4re. Ideal, um die Ruhe der Landschaft zu genie\u00dfen, um die K\u00f6stlichkeiten der Gastgeber zu probieren oder um eine romantische Auszeit zu verbringen.&#13;<br \/>\nDie Panoramaterrassen bieten einen atemberaubenden Blick, einen 360 \u00b0 Blick auf die T\u00e4ler an der Grenze zwischen Bergamo und Brescia. Ein Au\u00dfenpool im Garten, auf dem H\u00fcgel, f\u00fcr ein Bad mit Aussicht, Die Eigent\u00fcmer, die sehr auf die Werte von Umweltbilanz und Nachhaltigkeit achten, verwenden nur umweltvertr\u00e4gliche Materialien. Sie k\u00f6nnen Bio- und Null-Kilometer-Produkte probieren: Obst, Marmeladen, Honig, \u00d6l und Made-In-Colletto Weine. In der K\u00fcche vereinen sich Einfachheit und Kreativit\u00e4t zu raffinierten und eleganten Gerichten, die den typischen Geschmack der Region unterstreichen.<\/p>\n","indepth":"","howtogetthere":"","timerange":"","seasonality":"","pairings":"","curiosities":"","awards":"","cancellationpolicy":"","moredetails":"","whatsincluded":"","whatsnotincluded":"","price":"","time":"","services":"","parking":"","restaurant":"","breakfast":"","internet":"","children":"","pets":"","latitude":"45.689834","longitude":"9.947611","startingprice":"","gpxmap":"","iu_motor_accessibility":"notsure","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_kids":false,"iu_shortprice":"","iu_company_name":"","registered_office":"","iu_addr_streetnumber":"Via Colletto, 6","iu_addr_postalcode":"24060","iu_addr_city":"Bergamo","iu_addr_province":"BG","iu_phone":"","iu_cell":"","iu_website":"https:\/\/www.collettoagribiorelais.it\/","iu_email":"","iu_vat":"","iu_document_label":"","iu_document":false,"iu_documents":false,"iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_bookingurl":"","iu_videourl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"","iu_languages":"","iu_minpeople":"","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"iu_stars":"","iu_rooms":"","iu_beds":"","id_madeep":"","id_visit_manza":"8307","id_east":"","id_ristora":"","id_eppen":"","style":"primary","text":"","button_icon":"none","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"validfrom":"","validto":"","hours":"","tcm_content":false,"accessibilitycontent":{"tcm_content":false},"accessibilityicons":[],"filotto_layout":"","filotto_fill":"","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""},"max_elements":"","show_total":false,"see_all":false,"order_by":"","order_way":"","only_ambassadors":false,"service_icons":[],"ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":""},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/179213","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/179213\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media\/161230"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media?parent=179213"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/categories?post=179213"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/tags?post=179213"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/aggr?post=179213"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/area?post=179213"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/kind?post=179213"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/zona?post=179213"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}