{"id":179327,"date":"2025-04-18T13:25:25","date_gmt":"2025-04-18T11:25:25","guid":{"rendered":"https:\/\/visit.valueservice.cloud\/oggetto\/la-terrazza-del-centro\/"},"modified":"2025-04-18T15:41:01","modified_gmt":"2025-04-18T13:41:01","slug":"la-terrazza-del-centro","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/la-terrazza-del-centro\/","title":{"rendered":"LA TERRAZZA DEL CENTRO"},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":163668,"template":"","categories":[1002],"tags":[],"aggr":[],"area":[],"kind":[18725],"zona":[],"class_list":["post-179327","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-schlaf","kind-strutturaricettiva-de"],"acf":{"hero_type":"images","video_youtube_url":"","video_vimeo_url":"","size":"full","hero_title":"LA TERRAZZA DEL CENTRO","hero_text":"<p>Im Zentrum von Bergamo, Studio-Apartment mit einer gro\u00dfen ruhigen Terrasse.<\/p>\n","slides":[{"image":{"ID":163668,"id":163668,"title":"694de2ea151befaa05a185860ce6d482_a644855d.jpg","filename":"694de2ea151befaa05a185860ce6d482_a644855d.jpg","filesize":139173,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/694de2ea151befaa05a185860ce6d482_a644855d.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/la-terrazza-del-centro\/694de2ea151befaa05a185860ce6d482_a644855d-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"694de2ea151befaa05a185860ce6d482_a644855d-jpg-2","status":"inherit","uploaded_to":179327,"date":"2025-04-18 08:43:50","modified":"2025-04-18 13:41:03","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1280,"height":960,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/694de2ea151befaa05a185860ce6d482_a644855d-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/694de2ea151befaa05a185860ce6d482_a644855d-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/694de2ea151befaa05a185860ce6d482_a644855d-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/694de2ea151befaa05a185860ce6d482_a644855d-1024x768.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/694de2ea151befaa05a185860ce6d482_a644855d.jpg","1536x1536-width":1280,"1536x1536-height":960,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/694de2ea151befaa05a185860ce6d482_a644855d.jpg","2048x2048-width":1280,"2048x2048-height":960,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/694de2ea151befaa05a185860ce6d482_a644855d.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/694de2ea151befaa05a185860ce6d482_a644855d.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/694de2ea151befaa05a185860ce6d482_a644855d.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":163675,"id":163675,"title":"d1eaba0e78eb831e693c4e6778f53286_0d7738d0.jpg","filename":"d1eaba0e78eb831e693c4e6778f53286_0d7738d0-scaled.jpg","filesize":882154,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d1eaba0e78eb831e693c4e6778f53286_0d7738d0-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/la-terrazza-del-centro\/d1eaba0e78eb831e693c4e6778f53286_0d7738d0-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"d1eaba0e78eb831e693c4e6778f53286_0d7738d0-jpg-2","status":"inherit","uploaded_to":179327,"date":"2025-04-18 08:43:51","modified":"2025-04-18 13:41:03","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2419,"height":2560,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d1eaba0e78eb831e693c4e6778f53286_0d7738d0-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d1eaba0e78eb831e693c4e6778f53286_0d7738d0-283x300.jpg","medium-width":283,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d1eaba0e78eb831e693c4e6778f53286_0d7738d0-768x813.jpg","medium_large-width":768,"medium_large-height":813,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d1eaba0e78eb831e693c4e6778f53286_0d7738d0-967x1024.jpg","large-width":967,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d1eaba0e78eb831e693c4e6778f53286_0d7738d0-1451x1536.jpg","1536x1536-width":1451,"1536x1536-height":1536,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d1eaba0e78eb831e693c4e6778f53286_0d7738d0-1935x2048.jpg","2048x2048-width":1935,"2048x2048-height":2048,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d1eaba0e78eb831e693c4e6778f53286_0d7738d0-scaled.jpg","gform-image-choice-sm-width":283,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d1eaba0e78eb831e693c4e6778f53286_0d7738d0-scaled.jpg","gform-image-choice-md-width":378,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d1eaba0e78eb831e693c4e6778f53286_0d7738d0-scaled.jpg","gform-image-choice-lg-width":567,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":163682,"id":163682,"title":"04edd459d85386244714f62eab9ef4dd_4f12d953.jpg","filename":"04edd459d85386244714f62eab9ef4dd_4f12d953-scaled.jpg","filesize":567666,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/04edd459d85386244714f62eab9ef4dd_4f12d953-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/la-terrazza-del-centro\/04edd459d85386244714f62eab9ef4dd_4f12d953-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"04edd459d85386244714f62eab9ef4dd_4f12d953-jpg-2","status":"inherit","uploaded_to":179327,"date":"2025-04-18 08:43:54","modified":"2025-04-18 13:41:03","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":2006,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/04edd459d85386244714f62eab9ef4dd_4f12d953-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/04edd459d85386244714f62eab9ef4dd_4f12d953-300x235.jpg","medium-width":300,"medium-height":235,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/04edd459d85386244714f62eab9ef4dd_4f12d953-768x602.jpg","medium_large-width":768,"medium_large-height":602,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/04edd459d85386244714f62eab9ef4dd_4f12d953-1024x803.jpg","large-width":1024,"large-height":803,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/04edd459d85386244714f62eab9ef4dd_4f12d953-1536x1204.jpg","1536x1536-width":1536,"1536x1536-height":1204,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/04edd459d85386244714f62eab9ef4dd_4f12d953-2048x1605.jpg","2048x2048-width":2048,"2048x2048-height":1605,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/04edd459d85386244714f62eab9ef4dd_4f12d953-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":235,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/04edd459d85386244714f62eab9ef4dd_4f12d953-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":313,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/04edd459d85386244714f62eab9ef4dd_4f12d953-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":470}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":163689,"id":163689,"title":"9f3dc290541f3245d7fb27d215a0d685_d75619ef.jpg","filename":"9f3dc290541f3245d7fb27d215a0d685_d75619ef.jpg","filesize":70222,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9f3dc290541f3245d7fb27d215a0d685_d75619ef.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/la-terrazza-del-centro\/9f3dc290541f3245d7fb27d215a0d685_d75619ef-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"9f3dc290541f3245d7fb27d215a0d685_d75619ef-jpg-2","status":"inherit","uploaded_to":179327,"date":"2025-04-18 08:43:57","modified":"2025-04-18 13:41:03","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":600,"height":450,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9f3dc290541f3245d7fb27d215a0d685_d75619ef-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9f3dc290541f3245d7fb27d215a0d685_d75619ef-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9f3dc290541f3245d7fb27d215a0d685_d75619ef.jpg","medium_large-width":600,"medium_large-height":450,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9f3dc290541f3245d7fb27d215a0d685_d75619ef.jpg","large-width":600,"large-height":450,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9f3dc290541f3245d7fb27d215a0d685_d75619ef.jpg","1536x1536-width":600,"1536x1536-height":450,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9f3dc290541f3245d7fb27d215a0d685_d75619ef.jpg","2048x2048-width":600,"2048x2048-height":450,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9f3dc290541f3245d7fb27d215a0d685_d75619ef.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9f3dc290541f3245d7fb27d215a0d685_d75619ef.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9f3dc290541f3245d7fb27d215a0d685_d75619ef.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":163696,"id":163696,"title":"a9234dd3283b5b55e891cb954899e5db_e2ea9f0b.jpg","filename":"a9234dd3283b5b55e891cb954899e5db_e2ea9f0b-scaled.jpg","filesize":442783,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a9234dd3283b5b55e891cb954899e5db_e2ea9f0b-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/la-terrazza-del-centro\/a9234dd3283b5b55e891cb954899e5db_e2ea9f0b-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"a9234dd3283b5b55e891cb954899e5db_e2ea9f0b-jpg-2","status":"inherit","uploaded_to":179327,"date":"2025-04-18 08:43:58","modified":"2025-04-18 13:41:03","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1861,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a9234dd3283b5b55e891cb954899e5db_e2ea9f0b-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a9234dd3283b5b55e891cb954899e5db_e2ea9f0b-300x218.jpg","medium-width":300,"medium-height":218,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a9234dd3283b5b55e891cb954899e5db_e2ea9f0b-768x558.jpg","medium_large-width":768,"medium_large-height":558,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a9234dd3283b5b55e891cb954899e5db_e2ea9f0b-1024x744.jpg","large-width":1024,"large-height":744,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a9234dd3283b5b55e891cb954899e5db_e2ea9f0b-1536x1117.jpg","1536x1536-width":1536,"1536x1536-height":1117,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a9234dd3283b5b55e891cb954899e5db_e2ea9f0b-2048x1489.jpg","2048x2048-width":2048,"2048x2048-height":1489,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a9234dd3283b5b55e891cb954899e5db_e2ea9f0b-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":218,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a9234dd3283b5b55e891cb954899e5db_e2ea9f0b-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":291,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a9234dd3283b5b55e891cb954899e5db_e2ea9f0b-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":436}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"buttons":false,"hero_buttons_group":{"buttons":false},"hero_buttons":false,"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"","filotto_fill":"","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""}},"description":"<p>Das La Terrazza del Centro bietet Unterk\u00fcnfte mit kostenfreiem WLAN im Zentrum von Bergamo. Die Unterkunft verf\u00fcgt \u00fcber eine moderne Einrichtung und einer gro\u00dfe Terrasse. Das Apartment verf\u00fcgt \u00fcber eine voll ausgestattete K\u00fcchenzeile mit einem Esstisch und ein Doppelbett mit einem Flachbild-TV. Das private Badezimmer ist mit einer Dusche, kostenlosen Pflegeprodukten und einem Haartrockner ausgestattet. Das La Terrazza del Centro liegt 1 km vom Bahnhof von Bergamo entfernt. Der Flughafen Bergamo Orio al Serio ist eine 10-min\u00fctige Autofahrt entfernt.<\/p>\n","indepth":"","howtogetthere":"","timerange":"","seasonality":"","pairings":"","curiosities":"","awards":"","cancellationpolicy":"","moredetails":"","whatsincluded":"","whatsnotincluded":"","price":"<p>\u20ac 66,00<\/p>\n","services":"","parking":"","restaurant":"","breakfast":"","internet":"","children":"","pets":"","latitude":"45.692707","longitude":"9.662271","startingprice":"","gpxmap":"","iu_motor_accessibility":"notsure","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_kids":false,"iu_shortprice":"","iu_company_name":"BIZIOLI LEGNO SRL","registered_office":"Bizioli Legno srl&#13;\nVia Roma 27&#13;\n24020 Gorle (BG)","iu_addr_streetnumber":"via Broseta, 8","iu_addr_postalcode":"24125","iu_addr_city":"Bergamo","iu_addr_province":"BG","iu_phone":"+393331319041","iu_cell":"+393331319041","iu_website":"","iu_email":"dmrcase@gmail.com","iu_vat":"","iu_document_label":"","iu_document":false,"iu_documents":false,"iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_bookingurl":"","iu_videourl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"","iu_languages":"","iu_minpeople":"","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"iu_stars":"","iu_rooms":"1","iu_beds":"2","id_madeep":"","id_visit_manza":"5774","id_east":"","id_ristora":"","id_eppen":"","style":"primary","text":"","button_icon":"none","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"validfrom":"","validto":"","hours":"","tcm_content":false,"accessibilitycontent":{"tcm_content":false},"accessibilityicons":[],"filotto_layout":"","filotto_fill":"","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""},"max_elements":"","show_total":false,"see_all":false,"order_by":"","order_way":"","only_ambassadors":false,"time":"<p>Check-in 14:00 \/ 19:00<\/p>\n","ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":"","service_icons":[{"value":"elevator","label":"Ascensore"},{"value":"wifi","label":"Wi-Fi"},{"value":"pets_allowed","label":"Ammessi piccoli animali"},{"value":"air_conditioner","label":"Aria condizionata"},{"value":"hairdryer","label":"Asciugacapelli"},{"value":"shower","label":"Bagni con doccia"},{"value":"balcony","label":"Balcone"},{"value":"tv_room","label":"TV in camera"},{"value":"bancomat","label":"Bancomat"},{"value":"visa","label":"Visa"},{"value":"mastercard","label":"Mastercard"},{"value":"eurocard","label":"Eurocard \/ Mastercard"}]},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/179327","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/179327\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media\/163668"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media?parent=179327"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/categories?post=179327"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/tags?post=179327"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/aggr?post=179327"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/area?post=179327"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/kind?post=179327"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/zona?post=179327"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}