{"id":179460,"date":"2025-04-18T13:28:30","date_gmt":"2025-04-18T11:28:30","guid":{"rendered":"https:\/\/visit.valueservice.cloud\/oggetto\/home-sweet-home-independent-apartments\/"},"modified":"2025-04-18T15:45:44","modified_gmt":"2025-04-18T13:45:44","slug":"home-sweet-home-independent-apartments","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/home-sweet-home-independent-apartments\/","title":{"rendered":"Home Sweet Home Independent Apartments"},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":166042,"template":"","categories":[1002],"tags":[],"aggr":[],"area":[],"kind":[18725],"zona":[],"class_list":["post-179460","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-schlaf","kind-strutturaricettiva-de"],"acf":{"hero_type":"images","video_youtube_url":"","video_vimeo_url":"","size":"full","hero_title":"Home Sweet Home Independent Apartments","hero_text":"<p>Gem\u00fctlich, hell, komfortabel, so entworfen und gemacht, damit Ihre Unterkunft nicht die typische Hotel- oder B &#038; B-Formel darstellt.<\/p>\n","slides":[{"image":{"ID":166042,"id":166042,"title":"d1601a600edad153745046f2a625e3f2_28a8bfb1.jpg","filename":"d1601a600edad153745046f2a625e3f2_28a8bfb1-scaled.jpg","filesize":994066,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d1601a600edad153745046f2a625e3f2_28a8bfb1-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/home-sweet-home-independent-apartments\/d1601a600edad153745046f2a625e3f2_28a8bfb1-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"d1601a600edad153745046f2a625e3f2_28a8bfb1-jpg-2","status":"inherit","uploaded_to":179460,"date":"2025-04-18 08:53:56","modified":"2025-04-18 13:45:47","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1617,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d1601a600edad153745046f2a625e3f2_28a8bfb1-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d1601a600edad153745046f2a625e3f2_28a8bfb1-300x189.jpg","medium-width":300,"medium-height":189,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d1601a600edad153745046f2a625e3f2_28a8bfb1-768x485.jpg","medium_large-width":768,"medium_large-height":485,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d1601a600edad153745046f2a625e3f2_28a8bfb1-1024x647.jpg","large-width":1024,"large-height":647,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d1601a600edad153745046f2a625e3f2_28a8bfb1-1536x970.jpg","1536x1536-width":1536,"1536x1536-height":970,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d1601a600edad153745046f2a625e3f2_28a8bfb1-2048x1294.jpg","2048x2048-width":2048,"2048x2048-height":1294,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d1601a600edad153745046f2a625e3f2_28a8bfb1-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":189,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d1601a600edad153745046f2a625e3f2_28a8bfb1-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":253,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d1601a600edad153745046f2a625e3f2_28a8bfb1-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":379}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":166049,"id":166049,"title":"db2c1f623f358c2c2e7d77e322001ca3_3276b5ac.jpg","filename":"db2c1f623f358c2c2e7d77e322001ca3_3276b5ac-scaled.jpg","filesize":492650,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/db2c1f623f358c2c2e7d77e322001ca3_3276b5ac-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/home-sweet-home-independent-apartments\/db2c1f623f358c2c2e7d77e322001ca3_3276b5ac-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"db2c1f623f358c2c2e7d77e322001ca3_3276b5ac-jpg-2","status":"inherit","uploaded_to":179460,"date":"2025-04-18 08:53:58","modified":"2025-04-18 13:45:47","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1707,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/db2c1f623f358c2c2e7d77e322001ca3_3276b5ac-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/db2c1f623f358c2c2e7d77e322001ca3_3276b5ac-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/db2c1f623f358c2c2e7d77e322001ca3_3276b5ac-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/db2c1f623f358c2c2e7d77e322001ca3_3276b5ac-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/db2c1f623f358c2c2e7d77e322001ca3_3276b5ac-1536x1024.jpg","1536x1536-width":1536,"1536x1536-height":1024,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/db2c1f623f358c2c2e7d77e322001ca3_3276b5ac-2048x1366.jpg","2048x2048-width":2048,"2048x2048-height":1366,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/db2c1f623f358c2c2e7d77e322001ca3_3276b5ac-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/db2c1f623f358c2c2e7d77e322001ca3_3276b5ac-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/db2c1f623f358c2c2e7d77e322001ca3_3276b5ac-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":166056,"id":166056,"title":"57f8b3a0e70b2113750060b0987d5b79_439d37ea.jpg","filename":"57f8b3a0e70b2113750060b0987d5b79_439d37ea-scaled.jpg","filesize":409873,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/57f8b3a0e70b2113750060b0987d5b79_439d37ea-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/home-sweet-home-independent-apartments\/57f8b3a0e70b2113750060b0987d5b79_439d37ea-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"57f8b3a0e70b2113750060b0987d5b79_439d37ea-jpg-2","status":"inherit","uploaded_to":179460,"date":"2025-04-18 08:54:02","modified":"2025-04-18 13:45:47","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1707,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/57f8b3a0e70b2113750060b0987d5b79_439d37ea-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/57f8b3a0e70b2113750060b0987d5b79_439d37ea-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/57f8b3a0e70b2113750060b0987d5b79_439d37ea-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/57f8b3a0e70b2113750060b0987d5b79_439d37ea-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/57f8b3a0e70b2113750060b0987d5b79_439d37ea-1536x1024.jpg","1536x1536-width":1536,"1536x1536-height":1024,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/57f8b3a0e70b2113750060b0987d5b79_439d37ea-2048x1365.jpg","2048x2048-width":2048,"2048x2048-height":1365,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/57f8b3a0e70b2113750060b0987d5b79_439d37ea-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/57f8b3a0e70b2113750060b0987d5b79_439d37ea-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/57f8b3a0e70b2113750060b0987d5b79_439d37ea-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":166063,"id":166063,"title":"a0d80534c1f41d317d744579168d41fd_59dbd1f4.jpg","filename":"a0d80534c1f41d317d744579168d41fd_59dbd1f4.jpg","filesize":582214,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a0d80534c1f41d317d744579168d41fd_59dbd1f4.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/home-sweet-home-independent-apartments\/a0d80534c1f41d317d744579168d41fd_59dbd1f4-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"a0d80534c1f41d317d744579168d41fd_59dbd1f4-jpg-2","status":"inherit","uploaded_to":179460,"date":"2025-04-18 08:54:05","modified":"2025-04-18 13:45:47","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2048,"height":1365,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a0d80534c1f41d317d744579168d41fd_59dbd1f4-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a0d80534c1f41d317d744579168d41fd_59dbd1f4-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a0d80534c1f41d317d744579168d41fd_59dbd1f4-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a0d80534c1f41d317d744579168d41fd_59dbd1f4-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a0d80534c1f41d317d744579168d41fd_59dbd1f4-1536x1024.jpg","1536x1536-width":1536,"1536x1536-height":1024,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a0d80534c1f41d317d744579168d41fd_59dbd1f4.jpg","2048x2048-width":2048,"2048x2048-height":1365,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a0d80534c1f41d317d744579168d41fd_59dbd1f4.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a0d80534c1f41d317d744579168d41fd_59dbd1f4.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a0d80534c1f41d317d744579168d41fd_59dbd1f4.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":166070,"id":166070,"title":"1b5c116e9b951d76567a2735755de7b6_3276b5ac.jpg","filename":"1b5c116e9b951d76567a2735755de7b6_3276b5ac-scaled.jpg","filesize":492650,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1b5c116e9b951d76567a2735755de7b6_3276b5ac-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/home-sweet-home-independent-apartments\/1b5c116e9b951d76567a2735755de7b6_3276b5ac-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"1b5c116e9b951d76567a2735755de7b6_3276b5ac-jpg-2","status":"inherit","uploaded_to":179460,"date":"2025-04-18 08:54:06","modified":"2025-04-18 13:45:47","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1707,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1b5c116e9b951d76567a2735755de7b6_3276b5ac-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1b5c116e9b951d76567a2735755de7b6_3276b5ac-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1b5c116e9b951d76567a2735755de7b6_3276b5ac-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1b5c116e9b951d76567a2735755de7b6_3276b5ac-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1b5c116e9b951d76567a2735755de7b6_3276b5ac-1536x1024.jpg","1536x1536-width":1536,"1536x1536-height":1024,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1b5c116e9b951d76567a2735755de7b6_3276b5ac-2048x1366.jpg","2048x2048-width":2048,"2048x2048-height":1366,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1b5c116e9b951d76567a2735755de7b6_3276b5ac-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1b5c116e9b951d76567a2735755de7b6_3276b5ac-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1b5c116e9b951d76567a2735755de7b6_3276b5ac-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":166077,"id":166077,"title":"eb365801d9c2d3772434e37ca2bf67aa_bfce953c.jpg","filename":"eb365801d9c2d3772434e37ca2bf67aa_bfce953c.jpg","filesize":151568,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/eb365801d9c2d3772434e37ca2bf67aa_bfce953c.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/home-sweet-home-independent-apartments\/eb365801d9c2d3772434e37ca2bf67aa_bfce953c-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"eb365801d9c2d3772434e37ca2bf67aa_bfce953c-jpg-2","status":"inherit","uploaded_to":179460,"date":"2025-04-18 08:54:09","modified":"2025-04-18 13:45:47","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1080,"height":1350,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/eb365801d9c2d3772434e37ca2bf67aa_bfce953c-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/eb365801d9c2d3772434e37ca2bf67aa_bfce953c-240x300.jpg","medium-width":240,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/eb365801d9c2d3772434e37ca2bf67aa_bfce953c-768x960.jpg","medium_large-width":768,"medium_large-height":960,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/eb365801d9c2d3772434e37ca2bf67aa_bfce953c-819x1024.jpg","large-width":819,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/eb365801d9c2d3772434e37ca2bf67aa_bfce953c.jpg","1536x1536-width":1080,"1536x1536-height":1350,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/eb365801d9c2d3772434e37ca2bf67aa_bfce953c.jpg","2048x2048-width":1080,"2048x2048-height":1350,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/eb365801d9c2d3772434e37ca2bf67aa_bfce953c.jpg","gform-image-choice-sm-width":240,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/eb365801d9c2d3772434e37ca2bf67aa_bfce953c.jpg","gform-image-choice-md-width":320,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/eb365801d9c2d3772434e37ca2bf67aa_bfce953c.jpg","gform-image-choice-lg-width":480,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":166084,"id":166084,"title":"41ff60fbd7111230a86e3625bd510d94_9c918274.jpg","filename":"41ff60fbd7111230a86e3625bd510d94_9c918274.jpg","filesize":327287,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/41ff60fbd7111230a86e3625bd510d94_9c918274.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/home-sweet-home-independent-apartments\/41ff60fbd7111230a86e3625bd510d94_9c918274-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"41ff60fbd7111230a86e3625bd510d94_9c918274-jpg-2","status":"inherit","uploaded_to":179460,"date":"2025-04-18 08:54:10","modified":"2025-04-18 13:45:47","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":926,"height":1024,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/41ff60fbd7111230a86e3625bd510d94_9c918274-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/41ff60fbd7111230a86e3625bd510d94_9c918274-271x300.jpg","medium-width":271,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/41ff60fbd7111230a86e3625bd510d94_9c918274-768x849.jpg","medium_large-width":768,"medium_large-height":849,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/41ff60fbd7111230a86e3625bd510d94_9c918274.jpg","large-width":926,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/41ff60fbd7111230a86e3625bd510d94_9c918274.jpg","1536x1536-width":926,"1536x1536-height":1024,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/41ff60fbd7111230a86e3625bd510d94_9c918274.jpg","2048x2048-width":926,"2048x2048-height":1024,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/41ff60fbd7111230a86e3625bd510d94_9c918274.jpg","gform-image-choice-sm-width":271,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/41ff60fbd7111230a86e3625bd510d94_9c918274.jpg","gform-image-choice-md-width":362,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/41ff60fbd7111230a86e3625bd510d94_9c918274.jpg","gform-image-choice-lg-width":543,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":166091,"id":166091,"title":"d654e698e69978165281f0607b9f4f4c_1995c214.jpg","filename":"d654e698e69978165281f0607b9f4f4c_1995c214-scaled.jpg","filesize":442038,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d654e698e69978165281f0607b9f4f4c_1995c214-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/home-sweet-home-independent-apartments\/d654e698e69978165281f0607b9f4f4c_1995c214-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"d654e698e69978165281f0607b9f4f4c_1995c214-jpg-2","status":"inherit","uploaded_to":179460,"date":"2025-04-18 08:54:11","modified":"2025-04-18 13:45:47","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1244,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d654e698e69978165281f0607b9f4f4c_1995c214-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d654e698e69978165281f0607b9f4f4c_1995c214-300x146.jpg","medium-width":300,"medium-height":146,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d654e698e69978165281f0607b9f4f4c_1995c214-768x373.jpg","medium_large-width":768,"medium_large-height":373,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d654e698e69978165281f0607b9f4f4c_1995c214-1024x498.jpg","large-width":1024,"large-height":498,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d654e698e69978165281f0607b9f4f4c_1995c214-1536x746.jpg","1536x1536-width":1536,"1536x1536-height":746,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d654e698e69978165281f0607b9f4f4c_1995c214-2048x995.jpg","2048x2048-width":2048,"2048x2048-height":995,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d654e698e69978165281f0607b9f4f4c_1995c214-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":146,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d654e698e69978165281f0607b9f4f4c_1995c214-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":194,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d654e698e69978165281f0607b9f4f4c_1995c214-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":292}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":166098,"id":166098,"title":"c084ea46620bcaf3e5bd30ba5d9aa8ca_150514d6.jpg","filename":"c084ea46620bcaf3e5bd30ba5d9aa8ca_150514d6.jpg","filesize":302503,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c084ea46620bcaf3e5bd30ba5d9aa8ca_150514d6.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/home-sweet-home-independent-apartments\/c084ea46620bcaf3e5bd30ba5d9aa8ca_150514d6-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"c084ea46620bcaf3e5bd30ba5d9aa8ca_150514d6-jpg-2","status":"inherit","uploaded_to":179460,"date":"2025-04-18 08:54:14","modified":"2025-04-18 13:45:48","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2048,"height":1371,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c084ea46620bcaf3e5bd30ba5d9aa8ca_150514d6-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c084ea46620bcaf3e5bd30ba5d9aa8ca_150514d6-300x201.jpg","medium-width":300,"medium-height":201,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c084ea46620bcaf3e5bd30ba5d9aa8ca_150514d6-768x514.jpg","medium_large-width":768,"medium_large-height":514,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c084ea46620bcaf3e5bd30ba5d9aa8ca_150514d6-1024x686.jpg","large-width":1024,"large-height":686,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c084ea46620bcaf3e5bd30ba5d9aa8ca_150514d6-1536x1028.jpg","1536x1536-width":1536,"1536x1536-height":1028,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c084ea46620bcaf3e5bd30ba5d9aa8ca_150514d6.jpg","2048x2048-width":2048,"2048x2048-height":1371,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c084ea46620bcaf3e5bd30ba5d9aa8ca_150514d6.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":201,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c084ea46620bcaf3e5bd30ba5d9aa8ca_150514d6.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":268,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c084ea46620bcaf3e5bd30ba5d9aa8ca_150514d6.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":402}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"buttons":false,"hero_buttons_group":{"buttons":false},"hero_buttons":false,"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"","filotto_fill":"","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""}},"description":"<p>Die moderne Einrichtung im Gegensatz zu den Steinw\u00e4nden und Decken mit sichtbaren Holzbalken machen diese Wohnung einzigartig in ihrer Art. Die Unterkunft Home Sweet Home ist strategisch g\u00fcnstig gelegen, um das sch\u00f6ne Bergamo zu erkunden. Alle Zimmer wurden so gestaltet und gebaut, dass Sie sich wie zu Hause f\u00fchlen, einen hohen Qualit\u00e4tsstandard beibehalten und eine hohe Privatsph\u00e4re gew\u00e4hrleisten<\/p>\n","indepth":"","howtogetthere":"<p>Vom Flughafen k\u00f6nnen Sie ein Taxi oder den Shuttlebus nehmen.&#13;<br \/>\nDer Shuttlebus f\u00e4hrt alle 20 Minuten und die n\u00e4chste Haltestelle ist &#8216;Porta Nuova&#8217; im Zentrum von Bergamo. Von dort ist es dann notwendig, zu Fu\u00df bis zur Struktur zu gehen.&#13;<br \/>\nAuto: Autobahn A \/ 4 Mailand &#8211; Venedig Ausfahrt Bergamo, folgen Sie den Schildern zum Zentrum<\/p>\n","timerange":"","seasonality":"","pairings":"","curiosities":"","awards":"","cancellationpolicy":"","moredetails":"","whatsincluded":"","whatsnotincluded":"","price":"<p>Je nach Jahreszeit kann es leichte Abweichungen geben.&#13;<br \/>\n\u00a0&#13;<br \/>\n1 Person: 55 \u20ac&#13;<br \/>\n2 Personen: 75 \u20ac&#13;<br \/>\n3 Personen: 90 \u20ac<\/p>\n","services":"<p>Die Kurtaxe ist bei der Ankunft zu entrichten und entspricht 5% der Kosten f\u00fcr die Unterkunft<\/p>\n","parking":"<p>Parkplatz nicht verf\u00fcgbar. Geb\u00fchrenpflichtige Parkpl\u00e4tze sind in unmittelbarer N\u00e4he zu empfehlen.<\/p>\n","restaurant":"","breakfast":"","internet":"<p>Kostenlose Wi-Fi Verbindung. Gutes Signal<\/p>\n","children":"<p>Kinder sind willkommen.&#13;<br \/>\nBis zu 6 Jahre frei (wenn sie mit den Eltern im Bett schlafen).<\/p>\n","pets":"<p>Keine Haustiere erlaubt.<\/p>\n","latitude":"45.699818","longitude":"9.674870","startingprice":"","gpxmap":"","iu_motor_accessibility":"yes","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_kids":true,"iu_shortprice":"","iu_company_name":"Federica Rigoli","registered_office":"Via Pignolo, 53 Bergamo","iu_addr_streetnumber":"Via Pignolo, 53","iu_addr_postalcode":"24121","iu_addr_city":"Bergamo","iu_addr_province":"BG","iu_phone":"","iu_cell":"+393401853475","iu_website":"https:\/\/www.homesweethomebg.com\/","iu_email":"homesweethomebg@me.com","iu_vat":"RGLFRC88T52A794P","iu_document_label":"","iu_document":false,"iu_documents":false,"iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_bookingurl":"","iu_videourl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"","iu_languages":"","iu_minpeople":"","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"iu_stars":"","iu_rooms":"2","iu_beds":"6","id_madeep":"","id_visit_manza":"5798","id_east":"","id_ristora":"","id_eppen":"","style":"primary","text":"","button_icon":"none","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"validfrom":"","validto":"","hours":"","tcm_content":false,"accessibilitycontent":{"tcm_content":false},"accessibilityicons":[],"filotto_layout":"","filotto_fill":"","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""},"max_elements":"","show_total":false,"see_all":false,"order_by":"","order_way":"","only_ambassadors":false,"time":"<p>check-in dalle ore 13:00 alle ore 24:00&#13;<br \/>\ncheck-out entro le ore 10:00<\/p>\n","ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":"","service_icons":[{"value":"elevator","label":"Ascensore"},{"value":"wifi","label":"Wi-Fi"},{"value":"hairdryer","label":"Asciugacapelli"},{"value":"shower","label":"Bagni con doccia"},{"value":"electronic_key","label":"Chiave elettronica"},{"value":"tv_room","label":"TV in camera"},{"value":"satellite_tv","label":"TV satellitare"},{"value":"bancomat","label":"Bancomat"},{"value":"visa","label":"Visa"},{"value":"mastercard","label":"Mastercard"},{"value":"eurocard","label":"Eurocard \/ Mastercard"}]},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/179460","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/179460\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media\/166042"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media?parent=179460"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/categories?post=179460"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/tags?post=179460"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/aggr?post=179460"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/area?post=179460"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/kind?post=179460"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/zona?post=179460"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}