{"id":179501,"date":"2025-04-18T13:29:43","date_gmt":"2025-04-18T11:29:43","guid":{"rendered":"https:\/\/visit.valueservice.cloud\/oggetto\/hotel-costa\/"},"modified":"2025-04-18T15:47:59","modified_gmt":"2025-04-18T13:47:59","slug":"hotel-costa","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/hotel-costa\/","title":{"rendered":"Hotel Costa"},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":167686,"template":"","categories":[1002],"tags":[],"aggr":[],"area":[],"kind":[18725],"zona":[],"class_list":["post-179501","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-schlaf","kind-strutturaricettiva-de"],"acf":{"hero_type":"images","video_youtube_url":"","video_vimeo_url":"","size":"full","hero_title":"Hotel Costa","hero_text":"<p>Im Herzen der bergamaskischen Voralpen, ist der Hotel Costa der ideale Ort f\u00fcr einen erholsamen Aufenthalt und gutes Essen. Idealer Ausgangspunkt f\u00fcr Wanderungen und Spazierg\u00e4nge in der Natur<\/p>\n","slides":[{"image":{"ID":167686,"id":167686,"title":"c6b53dbf7fc78424276a10daa7fa10f3_c8725268.jpg","filename":"c6b53dbf7fc78424276a10daa7fa10f3_c8725268.jpg","filesize":417752,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c6b53dbf7fc78424276a10daa7fa10f3_c8725268.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/hotel-costa\/c6b53dbf7fc78424276a10daa7fa10f3_c8725268-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"c6b53dbf7fc78424276a10daa7fa10f3_c8725268-jpg-2","status":"inherit","uploaded_to":179501,"date":"2025-04-18 09:00:59","modified":"2025-04-18 13:48:02","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c6b53dbf7fc78424276a10daa7fa10f3_c8725268-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c6b53dbf7fc78424276a10daa7fa10f3_c8725268-300x107.jpg","medium-width":300,"medium-height":107,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c6b53dbf7fc78424276a10daa7fa10f3_c8725268-768x275.jpg","medium_large-width":768,"medium_large-height":275,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c6b53dbf7fc78424276a10daa7fa10f3_c8725268-1024x366.jpg","large-width":1024,"large-height":366,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c6b53dbf7fc78424276a10daa7fa10f3_c8725268-1536x549.jpg","1536x1536-width":1536,"1536x1536-height":549,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c6b53dbf7fc78424276a10daa7fa10f3_c8725268.jpg","2048x2048-width":1580,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c6b53dbf7fc78424276a10daa7fa10f3_c8725268.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":107,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c6b53dbf7fc78424276a10daa7fa10f3_c8725268.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":143,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c6b53dbf7fc78424276a10daa7fa10f3_c8725268.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":215}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":167693,"id":167693,"title":"660f59105a766e7f386ef053c06aaa17_093f1374.jpg","filename":"660f59105a766e7f386ef053c06aaa17_093f1374.jpg","filesize":386124,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/660f59105a766e7f386ef053c06aaa17_093f1374.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/hotel-costa\/660f59105a766e7f386ef053c06aaa17_093f1374-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"660f59105a766e7f386ef053c06aaa17_093f1374-jpg-2","status":"inherit","uploaded_to":179501,"date":"2025-04-18 09:01:00","modified":"2025-04-18 13:48:02","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/660f59105a766e7f386ef053c06aaa17_093f1374-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/660f59105a766e7f386ef053c06aaa17_093f1374-300x107.jpg","medium-width":300,"medium-height":107,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/660f59105a766e7f386ef053c06aaa17_093f1374-768x275.jpg","medium_large-width":768,"medium_large-height":275,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/660f59105a766e7f386ef053c06aaa17_093f1374-1024x366.jpg","large-width":1024,"large-height":366,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/660f59105a766e7f386ef053c06aaa17_093f1374-1536x549.jpg","1536x1536-width":1536,"1536x1536-height":549,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/660f59105a766e7f386ef053c06aaa17_093f1374.jpg","2048x2048-width":1580,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/660f59105a766e7f386ef053c06aaa17_093f1374.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":107,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/660f59105a766e7f386ef053c06aaa17_093f1374.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":143,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/660f59105a766e7f386ef053c06aaa17_093f1374.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":215}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":167700,"id":167700,"title":"52cd09d183c4772fe55d732db6635316_a2f62c01.jpg","filename":"52cd09d183c4772fe55d732db6635316_a2f62c01.jpg","filesize":391723,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/52cd09d183c4772fe55d732db6635316_a2f62c01.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/hotel-costa\/52cd09d183c4772fe55d732db6635316_a2f62c01-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"52cd09d183c4772fe55d732db6635316_a2f62c01-jpg-2","status":"inherit","uploaded_to":179501,"date":"2025-04-18 09:01:01","modified":"2025-04-18 13:48:02","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/52cd09d183c4772fe55d732db6635316_a2f62c01-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/52cd09d183c4772fe55d732db6635316_a2f62c01-300x107.jpg","medium-width":300,"medium-height":107,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/52cd09d183c4772fe55d732db6635316_a2f62c01-768x275.jpg","medium_large-width":768,"medium_large-height":275,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/52cd09d183c4772fe55d732db6635316_a2f62c01-1024x366.jpg","large-width":1024,"large-height":366,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/52cd09d183c4772fe55d732db6635316_a2f62c01-1536x549.jpg","1536x1536-width":1536,"1536x1536-height":549,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/52cd09d183c4772fe55d732db6635316_a2f62c01.jpg","2048x2048-width":1580,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/52cd09d183c4772fe55d732db6635316_a2f62c01.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":107,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/52cd09d183c4772fe55d732db6635316_a2f62c01.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":143,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/52cd09d183c4772fe55d732db6635316_a2f62c01.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":215}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":167707,"id":167707,"title":"ac3d296beedd36cbe20a03b17e64d595_e4adee35.jpg","filename":"ac3d296beedd36cbe20a03b17e64d595_e4adee35.jpg","filesize":377235,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ac3d296beedd36cbe20a03b17e64d595_e4adee35.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/hotel-costa\/ac3d296beedd36cbe20a03b17e64d595_e4adee35-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"ac3d296beedd36cbe20a03b17e64d595_e4adee35-jpg-2","status":"inherit","uploaded_to":179501,"date":"2025-04-18 09:01:02","modified":"2025-04-18 13:48:02","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ac3d296beedd36cbe20a03b17e64d595_e4adee35-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ac3d296beedd36cbe20a03b17e64d595_e4adee35-300x107.jpg","medium-width":300,"medium-height":107,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ac3d296beedd36cbe20a03b17e64d595_e4adee35-768x275.jpg","medium_large-width":768,"medium_large-height":275,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ac3d296beedd36cbe20a03b17e64d595_e4adee35-1024x366.jpg","large-width":1024,"large-height":366,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ac3d296beedd36cbe20a03b17e64d595_e4adee35-1536x549.jpg","1536x1536-width":1536,"1536x1536-height":549,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ac3d296beedd36cbe20a03b17e64d595_e4adee35.jpg","2048x2048-width":1580,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ac3d296beedd36cbe20a03b17e64d595_e4adee35.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":107,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ac3d296beedd36cbe20a03b17e64d595_e4adee35.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":143,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ac3d296beedd36cbe20a03b17e64d595_e4adee35.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":215}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":167714,"id":167714,"title":"d2ad1f7aec8bfea5025e3a78ebcc428f_928d4ee9.jpg","filename":"d2ad1f7aec8bfea5025e3a78ebcc428f_928d4ee9.jpg","filesize":525778,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d2ad1f7aec8bfea5025e3a78ebcc428f_928d4ee9.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/hotel-costa\/d2ad1f7aec8bfea5025e3a78ebcc428f_928d4ee9-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"d2ad1f7aec8bfea5025e3a78ebcc428f_928d4ee9-jpg-2","status":"inherit","uploaded_to":179501,"date":"2025-04-18 09:01:03","modified":"2025-04-18 13:48:02","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d2ad1f7aec8bfea5025e3a78ebcc428f_928d4ee9-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d2ad1f7aec8bfea5025e3a78ebcc428f_928d4ee9-300x107.jpg","medium-width":300,"medium-height":107,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d2ad1f7aec8bfea5025e3a78ebcc428f_928d4ee9-768x275.jpg","medium_large-width":768,"medium_large-height":275,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d2ad1f7aec8bfea5025e3a78ebcc428f_928d4ee9-1024x366.jpg","large-width":1024,"large-height":366,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d2ad1f7aec8bfea5025e3a78ebcc428f_928d4ee9-1536x549.jpg","1536x1536-width":1536,"1536x1536-height":549,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d2ad1f7aec8bfea5025e3a78ebcc428f_928d4ee9.jpg","2048x2048-width":1580,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d2ad1f7aec8bfea5025e3a78ebcc428f_928d4ee9.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":107,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d2ad1f7aec8bfea5025e3a78ebcc428f_928d4ee9.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":143,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d2ad1f7aec8bfea5025e3a78ebcc428f_928d4ee9.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":215}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":167721,"id":167721,"title":"f31254eaf010615d3c6f9dddf9e02fa5_107e2635.jpg","filename":"f31254eaf010615d3c6f9dddf9e02fa5_107e2635.jpg","filesize":529006,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f31254eaf010615d3c6f9dddf9e02fa5_107e2635.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/hotel-costa\/f31254eaf010615d3c6f9dddf9e02fa5_107e2635-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"f31254eaf010615d3c6f9dddf9e02fa5_107e2635-jpg-2","status":"inherit","uploaded_to":179501,"date":"2025-04-18 09:01:04","modified":"2025-04-18 13:48:02","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f31254eaf010615d3c6f9dddf9e02fa5_107e2635-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f31254eaf010615d3c6f9dddf9e02fa5_107e2635-300x107.jpg","medium-width":300,"medium-height":107,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f31254eaf010615d3c6f9dddf9e02fa5_107e2635-768x275.jpg","medium_large-width":768,"medium_large-height":275,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f31254eaf010615d3c6f9dddf9e02fa5_107e2635-1024x366.jpg","large-width":1024,"large-height":366,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f31254eaf010615d3c6f9dddf9e02fa5_107e2635-1536x549.jpg","1536x1536-width":1536,"1536x1536-height":549,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f31254eaf010615d3c6f9dddf9e02fa5_107e2635.jpg","2048x2048-width":1580,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f31254eaf010615d3c6f9dddf9e02fa5_107e2635.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":107,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f31254eaf010615d3c6f9dddf9e02fa5_107e2635.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":143,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f31254eaf010615d3c6f9dddf9e02fa5_107e2635.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":215}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":167728,"id":167728,"title":"1a3986cccb052825fec0fab11ad2accc_bfc70055.jpg","filename":"1a3986cccb052825fec0fab11ad2accc_bfc70055.jpg","filesize":449376,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1a3986cccb052825fec0fab11ad2accc_bfc70055.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/hotel-costa\/1a3986cccb052825fec0fab11ad2accc_bfc70055-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"1a3986cccb052825fec0fab11ad2accc_bfc70055-jpg-2","status":"inherit","uploaded_to":179501,"date":"2025-04-18 09:01:05","modified":"2025-04-18 13:48:02","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1a3986cccb052825fec0fab11ad2accc_bfc70055-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1a3986cccb052825fec0fab11ad2accc_bfc70055-300x107.jpg","medium-width":300,"medium-height":107,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1a3986cccb052825fec0fab11ad2accc_bfc70055-768x275.jpg","medium_large-width":768,"medium_large-height":275,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1a3986cccb052825fec0fab11ad2accc_bfc70055-1024x366.jpg","large-width":1024,"large-height":366,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1a3986cccb052825fec0fab11ad2accc_bfc70055-1536x549.jpg","1536x1536-width":1536,"1536x1536-height":549,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1a3986cccb052825fec0fab11ad2accc_bfc70055.jpg","2048x2048-width":1580,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1a3986cccb052825fec0fab11ad2accc_bfc70055.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":107,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1a3986cccb052825fec0fab11ad2accc_bfc70055.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":143,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1a3986cccb052825fec0fab11ad2accc_bfc70055.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":215}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":167735,"id":167735,"title":"d2054accf263d3be23b74806b59cc5df_f67b5e4a.jpg","filename":"d2054accf263d3be23b74806b59cc5df_f67b5e4a.jpg","filesize":434432,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d2054accf263d3be23b74806b59cc5df_f67b5e4a.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/hotel-costa\/d2054accf263d3be23b74806b59cc5df_f67b5e4a-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"d2054accf263d3be23b74806b59cc5df_f67b5e4a-jpg-2","status":"inherit","uploaded_to":179501,"date":"2025-04-18 09:01:06","modified":"2025-04-18 13:48:02","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d2054accf263d3be23b74806b59cc5df_f67b5e4a-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d2054accf263d3be23b74806b59cc5df_f67b5e4a-300x107.jpg","medium-width":300,"medium-height":107,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d2054accf263d3be23b74806b59cc5df_f67b5e4a-768x275.jpg","medium_large-width":768,"medium_large-height":275,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d2054accf263d3be23b74806b59cc5df_f67b5e4a-1024x366.jpg","large-width":1024,"large-height":366,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d2054accf263d3be23b74806b59cc5df_f67b5e4a-1536x549.jpg","1536x1536-width":1536,"1536x1536-height":549,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d2054accf263d3be23b74806b59cc5df_f67b5e4a.jpg","2048x2048-width":1580,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d2054accf263d3be23b74806b59cc5df_f67b5e4a.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":107,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d2054accf263d3be23b74806b59cc5df_f67b5e4a.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":143,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d2054accf263d3be23b74806b59cc5df_f67b5e4a.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":215}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":167742,"id":167742,"title":"3145edad8bbb15e0a81f8e7bdbfd089e_ae61d000.jpg","filename":"3145edad8bbb15e0a81f8e7bdbfd089e_ae61d000.jpg","filesize":359286,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3145edad8bbb15e0a81f8e7bdbfd089e_ae61d000.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/hotel-costa\/3145edad8bbb15e0a81f8e7bdbfd089e_ae61d000-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"3145edad8bbb15e0a81f8e7bdbfd089e_ae61d000-jpg-2","status":"inherit","uploaded_to":179501,"date":"2025-04-18 09:01:07","modified":"2025-04-18 13:48:02","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3145edad8bbb15e0a81f8e7bdbfd089e_ae61d000-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3145edad8bbb15e0a81f8e7bdbfd089e_ae61d000-300x107.jpg","medium-width":300,"medium-height":107,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3145edad8bbb15e0a81f8e7bdbfd089e_ae61d000-768x275.jpg","medium_large-width":768,"medium_large-height":275,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3145edad8bbb15e0a81f8e7bdbfd089e_ae61d000-1024x366.jpg","large-width":1024,"large-height":366,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3145edad8bbb15e0a81f8e7bdbfd089e_ae61d000-1536x549.jpg","1536x1536-width":1536,"1536x1536-height":549,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3145edad8bbb15e0a81f8e7bdbfd089e_ae61d000.jpg","2048x2048-width":1580,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3145edad8bbb15e0a81f8e7bdbfd089e_ae61d000.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":107,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3145edad8bbb15e0a81f8e7bdbfd089e_ae61d000.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":143,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3145edad8bbb15e0a81f8e7bdbfd089e_ae61d000.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":215}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":167749,"id":167749,"title":"7f5116de905bf69396dd2654e7235198_c263d405.jpg","filename":"7f5116de905bf69396dd2654e7235198_c263d405.jpg","filesize":211281,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7f5116de905bf69396dd2654e7235198_c263d405.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/hotel-costa\/7f5116de905bf69396dd2654e7235198_c263d405-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"7f5116de905bf69396dd2654e7235198_c263d405-jpg-2","status":"inherit","uploaded_to":179501,"date":"2025-04-18 09:01:09","modified":"2025-04-18 13:48:02","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7f5116de905bf69396dd2654e7235198_c263d405-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7f5116de905bf69396dd2654e7235198_c263d405-300x107.jpg","medium-width":300,"medium-height":107,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7f5116de905bf69396dd2654e7235198_c263d405-768x275.jpg","medium_large-width":768,"medium_large-height":275,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7f5116de905bf69396dd2654e7235198_c263d405-1024x366.jpg","large-width":1024,"large-height":366,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7f5116de905bf69396dd2654e7235198_c263d405-1536x549.jpg","1536x1536-width":1536,"1536x1536-height":549,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7f5116de905bf69396dd2654e7235198_c263d405.jpg","2048x2048-width":1580,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7f5116de905bf69396dd2654e7235198_c263d405.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":107,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7f5116de905bf69396dd2654e7235198_c263d405.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":143,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7f5116de905bf69396dd2654e7235198_c263d405.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":215}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":167756,"id":167756,"title":"6858730a5bbec116e8cdb9729554dadf_27f8409f.jpg","filename":"6858730a5bbec116e8cdb9729554dadf_27f8409f.jpg","filesize":287917,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6858730a5bbec116e8cdb9729554dadf_27f8409f.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/hotel-costa\/6858730a5bbec116e8cdb9729554dadf_27f8409f-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"6858730a5bbec116e8cdb9729554dadf_27f8409f-jpg-2","status":"inherit","uploaded_to":179501,"date":"2025-04-18 09:01:10","modified":"2025-04-18 13:48:02","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6858730a5bbec116e8cdb9729554dadf_27f8409f-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6858730a5bbec116e8cdb9729554dadf_27f8409f-300x107.jpg","medium-width":300,"medium-height":107,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6858730a5bbec116e8cdb9729554dadf_27f8409f-768x275.jpg","medium_large-width":768,"medium_large-height":275,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6858730a5bbec116e8cdb9729554dadf_27f8409f-1024x366.jpg","large-width":1024,"large-height":366,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6858730a5bbec116e8cdb9729554dadf_27f8409f-1536x549.jpg","1536x1536-width":1536,"1536x1536-height":549,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6858730a5bbec116e8cdb9729554dadf_27f8409f.jpg","2048x2048-width":1580,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6858730a5bbec116e8cdb9729554dadf_27f8409f.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":107,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6858730a5bbec116e8cdb9729554dadf_27f8409f.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":143,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6858730a5bbec116e8cdb9729554dadf_27f8409f.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":215}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":167763,"id":167763,"title":"fef903d118da20c342d9188232063b13_8db053e9.jpg","filename":"fef903d118da20c342d9188232063b13_8db053e9.jpg","filesize":629714,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fef903d118da20c342d9188232063b13_8db053e9.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/hotel-costa\/fef903d118da20c342d9188232063b13_8db053e9-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"fef903d118da20c342d9188232063b13_8db053e9-jpg-2","status":"inherit","uploaded_to":179501,"date":"2025-04-18 09:01:11","modified":"2025-04-18 13:48:02","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fef903d118da20c342d9188232063b13_8db053e9-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fef903d118da20c342d9188232063b13_8db053e9-300x107.jpg","medium-width":300,"medium-height":107,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fef903d118da20c342d9188232063b13_8db053e9-768x275.jpg","medium_large-width":768,"medium_large-height":275,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fef903d118da20c342d9188232063b13_8db053e9-1024x366.jpg","large-width":1024,"large-height":366,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fef903d118da20c342d9188232063b13_8db053e9-1536x549.jpg","1536x1536-width":1536,"1536x1536-height":549,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fef903d118da20c342d9188232063b13_8db053e9.jpg","2048x2048-width":1580,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fef903d118da20c342d9188232063b13_8db053e9.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":107,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fef903d118da20c342d9188232063b13_8db053e9.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":143,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fef903d118da20c342d9188232063b13_8db053e9.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":215}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":167770,"id":167770,"title":"203bfe30941d3d01b807f4903ff6fff2_8db053e9.jpg","filename":"203bfe30941d3d01b807f4903ff6fff2_8db053e9.jpg","filesize":629714,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/203bfe30941d3d01b807f4903ff6fff2_8db053e9.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/hotel-costa\/203bfe30941d3d01b807f4903ff6fff2_8db053e9-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"203bfe30941d3d01b807f4903ff6fff2_8db053e9-jpg-2","status":"inherit","uploaded_to":179501,"date":"2025-04-18 09:01:12","modified":"2025-04-18 13:48:03","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/203bfe30941d3d01b807f4903ff6fff2_8db053e9-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/203bfe30941d3d01b807f4903ff6fff2_8db053e9-300x107.jpg","medium-width":300,"medium-height":107,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/203bfe30941d3d01b807f4903ff6fff2_8db053e9-768x275.jpg","medium_large-width":768,"medium_large-height":275,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/203bfe30941d3d01b807f4903ff6fff2_8db053e9-1024x366.jpg","large-width":1024,"large-height":366,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/203bfe30941d3d01b807f4903ff6fff2_8db053e9-1536x549.jpg","1536x1536-width":1536,"1536x1536-height":549,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/203bfe30941d3d01b807f4903ff6fff2_8db053e9.jpg","2048x2048-width":1580,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/203bfe30941d3d01b807f4903ff6fff2_8db053e9.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":107,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/203bfe30941d3d01b807f4903ff6fff2_8db053e9.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":143,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/203bfe30941d3d01b807f4903ff6fff2_8db053e9.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":215}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"buttons":false,"hero_buttons_group":{"buttons":false},"hero_buttons":false,"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"","filotto_fill":"","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""}},"description":"<p>Das Hotel liegt in Costa Valle Imagna, ein h\u00fcbsches Dorf im Imagna Tal, und erfreut sich einer ausgezeichneten Panoramalage , zentral, aber ruhig. Auf einem Plateau,\u00a0 verf\u00fcgt es \u00fcber eine Bar, ein Solarium, ein Garten mit Bar, eine Gr\u00fcnanlage\u00a0 mit Kinderspielen\u00a0 und ein Tagungsraum\u00a0 f\u00fcr Seminare und Gesch\u00e4ftstreffen<\/p>\n","indepth":"<p>Das Hotel Ristorante Costa kennzeichnet sich durch eine einladende Familie und seine K\u00fcche aus, mit allem Komfort, renoviert und ganzj\u00e4hrig ge\u00f6ffnet.&#13;<br \/>\nDie Struktur verf\u00fcgt \u00fcber 24 Zimmer f\u00fcr insgesamt f\u00fcnfzig Betten, geschmackvoll eingerichtet und ausgestattet mit eigenem Bad, Farb-TV mit Satellitenempfang , Direktwahltelefon, Heizung und durch die Kunden kontrollierbar, WI-FI-Service und Aufzug.&#13;<br \/>\nZur Verf\u00fcgung der G\u00e4ste stehen auch Zimmer f\u00fcr Behinderte.&#13;<br \/>\nEs ist in der N\u00e4he des Pertus Passes, nur wenige Kilometer vom Roncola Adventure Park und den Sant&#8217;Omobono Thermalb\u00e4der.<\/p>\n","howtogetthere":"<p>MIT DEM AUTO: Von Mailand Autobahn A4 Ausfahrt Capriate oder Dalmine. Von Venedig Autobahn A4 Ausfahrt Bergamo oder Dalmine. An den Autobahnausfahrten\u00a0 folgen Sie den braunen Pfeilen in Richtung Valle Imagna zuerst nach Roncola San Bernardo und dann Costa Valle Imagna.&#13;<br \/>\nMIT DEM FLUGZEUG: Die n\u00e4chsten Flugh\u00e4fen sind Bergamo (25 km), Mailand Linate (55 km) und Mailand Malpensa (120 km).&#13;<br \/>\nMIT DEM ZUG: Die Z\u00fcge IC und EC halten in Bergamo und Ponte San Pietro\u2026<\/p>\n","timerange":"","seasonality":"","pairings":"","curiosities":"","awards":"","cancellationpolicy":"","moredetails":"","whatsincluded":"","whatsnotincluded":"","price":"","services":"<p>H\u00f6flichkeit, Sauberkeit, moderne und effiziente Ausstattung: Das Hotel wurde in der Handelskammer  von Bergamo dank seinen Dienstleistungen \u201eQuality Hotel 2001\u201c ausgezeichnet. Das Hotel bietet einen Shuttle-Service zu den Sant&#8217;Omobono Thermalb\u00e4der und ein Fahrradverleih<\/p>\n","parking":"<p>Privatparkpl\u00e4tze  vor Ort<\/p>\n","restaurant":"<p>Das Restaurant ist im Detail von den Besitzern verwaltet und gepflegt, und durch die Authentizit\u00e4t der Speisen und die Freundlichkeit des Personals gepr\u00e4gt. Die K\u00fcche bevorzugt insbesondere die kulinarische Tradition von Bergamo, mit Wildgerichten , Casoncelli, Pilzen und frisches Geb\u00e4ck. Lokale Produkte wie Pilze, Kr\u00e4uter und Beeren verbessern die Gerichte.&#13;<br \/>\n&#13;<br \/>\nEine sorgf\u00e4ltige Auswahl an Weinen ist auch f\u00fcr die anspruchsvollsten  Kenner<\/p>\n","breakfast":"<p>Fr\u00fchst\u00fcck mit wahrhaften Produkten<\/p>\n","internet":"<p>Kostenfreier Internetzugang  WLAN im gesamten Hotel.<\/p>\n","children":"<p>Alle Kinder unter 4 Jahren \u00fcbernachten kostenlos ( in der vorhandenen Betten).&#13;<br \/>\nAlle Kinder unter 2 Jahren \u00fcbernachten kostenlos (in der vorhandenen Krippen).<\/p>\n","pets":"<p>Tiere nicht erlaubt.<\/p>\n","latitude":"45.802391","longitude":"9.504082","startingprice":"","gpxmap":"","iu_motor_accessibility":"yes","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_kids":false,"iu_shortprice":"","iu_company_name":"Albergo Costa di Brumana Clara & C. Snc","registered_office":"","iu_addr_streetnumber":"via Roma 3\/5","iu_addr_postalcode":"24030","iu_addr_city":"Bergamo","iu_addr_province":"BG","iu_phone":"+39 035865026","iu_cell":"","iu_website":"http:\/\/www.hotelcosta.com","iu_email":"info@hotelcosta.com","iu_vat":"","iu_document_label":"","iu_document":false,"iu_documents":false,"iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_bookingurl":"","iu_videourl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"","iu_languages":"","iu_minpeople":"","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"iu_stars":"3","iu_rooms":"","iu_beds":"","id_madeep":"","id_visit_manza":"4527","id_east":"","id_ristora":"","id_eppen":"","style":"primary","text":"","button_icon":"none","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"validfrom":"","validto":"","hours":"","tcm_content":false,"accessibilitycontent":{"tcm_content":false},"accessibilityicons":[],"filotto_layout":"","filotto_fill":"","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""},"max_elements":"","show_total":false,"see_all":false,"order_by":"","order_way":"","only_ambassadors":false,"time":"<p>Aperto tutto l\u2019anno<\/p>\n","ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":"","service_icons":[{"value":"disabled_access","label":"Accessibile disabili"},{"value":"groups_welcome","label":"Accettazione gruppi"},{"value":"elevator","label":"Ascensore"},{"value":"bar","label":"Bar"},{"value":"safe","label":"safe"},{"value":"audiovisual_equipment","label":"Impianti audiovisivi"},{"value":"parking","label":"Parcheggio gratuito"},{"value":"park_garden","label":"Parco \/ Giardino"},{"value":"restaurant","label":"Ristorante"},{"value":"banquet_hall","label":"Sala banchetti"},{"value":"conference_hall","label":"Sala congressi"},{"value":"meeting_room","label":"Sala riunioni"},{"value":"tv_lounge","label":"Sala TV"},{"value":"solarium","label":"Solarium"},{"value":"wifi","label":"Wi-Fi"},{"value":"air_conditioner","label":"Aria condizionata"},{"value":"hairdryer","label":"Asciugacapelli"},{"value":"shower","label":"Bagni con doccia"},{"value":"bathrooms","label":"Bagni con vasca"},{"value":"safe_deposit_box","label":"Cassetta di sicurezza"},{"value":"mini_bar","label":"Frigo bar"},{"value":"room_service","label":"Servizio in camera"},{"value":"tv_room","label":"TV in camera"},{"value":"satellite_tv","label":"TV satellitare"},{"value":"bancomat","label":"Bancomat"},{"value":"visa","label":"Visa"},{"value":"mastercard","label":"Mastercard"},{"value":"eurocard","label":"Eurocard \/ Mastercard"},{"value":"amex","label":"American Express"}]},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/179501","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/179501\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media\/167686"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media?parent=179501"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/categories?post=179501"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/tags?post=179501"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/aggr?post=179501"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/area?post=179501"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/kind?post=179501"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/zona?post=179501"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}