{"id":179701,"date":"2025-04-18T13:36:19","date_gmt":"2025-04-18T11:36:19","guid":{"rendered":"https:\/\/visit.valueservice.cloud\/oggetto\/stop-e-sleep-bergamo\/"},"modified":"2025-04-18T15:56:11","modified_gmt":"2025-04-18T13:56:11","slug":"stop-e-sleep-bergamo","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/stop-e-sleep-bergamo\/","title":{"rendered":"STOP e SLEEP BERGAMO"},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":173150,"template":"","categories":[1002],"tags":[],"aggr":[],"area":[],"kind":[18725],"zona":[],"class_list":["post-179701","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-schlaf","kind-strutturaricettiva-de"],"acf":{"hero_type":"images","video_youtube_url":"","video_vimeo_url":"","size":"full","hero_title":"STOP e SLEEP BERGAMO","hero_text":"<p>Wohnung im Zentrum von Bergamo, bestehend aus 4 Schlafzimmern und 2 B\u00e4dern, zus\u00e4tzlich zum Fr\u00fchst\u00fccksservice zur Selbstbedienung.<\/p>\n","slides":[{"image":{"ID":173150,"id":173150,"title":"78bf63235e9059ea0977f2a19e187068_ddeec580.jpg","filename":"78bf63235e9059ea0977f2a19e187068_ddeec580.jpg","filesize":269629,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/78bf63235e9059ea0977f2a19e187068_ddeec580.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/stop-e-sleep-bergamo\/78bf63235e9059ea0977f2a19e187068_ddeec580-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"78bf63235e9059ea0977f2a19e187068_ddeec580-jpg-2","status":"inherit","uploaded_to":179701,"date":"2025-04-18 09:23:49","modified":"2025-04-18 13:56:14","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1024,"height":683,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/78bf63235e9059ea0977f2a19e187068_ddeec580-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/78bf63235e9059ea0977f2a19e187068_ddeec580-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/78bf63235e9059ea0977f2a19e187068_ddeec580-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/78bf63235e9059ea0977f2a19e187068_ddeec580.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/78bf63235e9059ea0977f2a19e187068_ddeec580.jpg","1536x1536-width":1024,"1536x1536-height":683,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/78bf63235e9059ea0977f2a19e187068_ddeec580.jpg","2048x2048-width":1024,"2048x2048-height":683,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/78bf63235e9059ea0977f2a19e187068_ddeec580.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/78bf63235e9059ea0977f2a19e187068_ddeec580.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/78bf63235e9059ea0977f2a19e187068_ddeec580.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":173157,"id":173157,"title":"a6b4351645aa17829030c9b8323518bf_66b47566.jpg","filename":"a6b4351645aa17829030c9b8323518bf_66b47566.jpg","filesize":138220,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a6b4351645aa17829030c9b8323518bf_66b47566.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/stop-e-sleep-bergamo\/a6b4351645aa17829030c9b8323518bf_66b47566-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"a6b4351645aa17829030c9b8323518bf_66b47566-jpg-2","status":"inherit","uploaded_to":179701,"date":"2025-04-18 09:23:50","modified":"2025-04-18 13:56:14","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":512,"height":768,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a6b4351645aa17829030c9b8323518bf_66b47566-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a6b4351645aa17829030c9b8323518bf_66b47566-200x300.jpg","medium-width":200,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a6b4351645aa17829030c9b8323518bf_66b47566.jpg","medium_large-width":512,"medium_large-height":768,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a6b4351645aa17829030c9b8323518bf_66b47566.jpg","large-width":512,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a6b4351645aa17829030c9b8323518bf_66b47566.jpg","1536x1536-width":512,"1536x1536-height":768,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a6b4351645aa17829030c9b8323518bf_66b47566.jpg","2048x2048-width":512,"2048x2048-height":768,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a6b4351645aa17829030c9b8323518bf_66b47566.jpg","gform-image-choice-sm-width":200,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a6b4351645aa17829030c9b8323518bf_66b47566.jpg","gform-image-choice-md-width":267,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a6b4351645aa17829030c9b8323518bf_66b47566.jpg","gform-image-choice-lg-width":400,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":173164,"id":173164,"title":"80916d8f0c899433d9597d940b81953c_c44c97fb.jpg","filename":"80916d8f0c899433d9597d940b81953c_c44c97fb.jpg","filesize":97516,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/80916d8f0c899433d9597d940b81953c_c44c97fb.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/stop-e-sleep-bergamo\/80916d8f0c899433d9597d940b81953c_c44c97fb-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"80916d8f0c899433d9597d940b81953c_c44c97fb-jpg-2","status":"inherit","uploaded_to":179701,"date":"2025-04-18 09:23:52","modified":"2025-04-18 13:56:15","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1024,"height":768,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/80916d8f0c899433d9597d940b81953c_c44c97fb-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/80916d8f0c899433d9597d940b81953c_c44c97fb-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/80916d8f0c899433d9597d940b81953c_c44c97fb-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/80916d8f0c899433d9597d940b81953c_c44c97fb.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/80916d8f0c899433d9597d940b81953c_c44c97fb.jpg","1536x1536-width":1024,"1536x1536-height":768,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/80916d8f0c899433d9597d940b81953c_c44c97fb.jpg","2048x2048-width":1024,"2048x2048-height":768,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/80916d8f0c899433d9597d940b81953c_c44c97fb.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/80916d8f0c899433d9597d940b81953c_c44c97fb.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/80916d8f0c899433d9597d940b81953c_c44c97fb.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":173171,"id":173171,"title":"abc41bb8e5ebd9e72bddcf5ebb7a9c69_f9fe71cf.jpg","filename":"abc41bb8e5ebd9e72bddcf5ebb7a9c69_f9fe71cf.jpg","filesize":72752,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/abc41bb8e5ebd9e72bddcf5ebb7a9c69_f9fe71cf.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/stop-e-sleep-bergamo\/abc41bb8e5ebd9e72bddcf5ebb7a9c69_f9fe71cf-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"abc41bb8e5ebd9e72bddcf5ebb7a9c69_f9fe71cf-jpg-2","status":"inherit","uploaded_to":179701,"date":"2025-04-18 09:23:53","modified":"2025-04-18 13:56:15","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":576,"height":768,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/abc41bb8e5ebd9e72bddcf5ebb7a9c69_f9fe71cf-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/abc41bb8e5ebd9e72bddcf5ebb7a9c69_f9fe71cf-225x300.jpg","medium-width":225,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/abc41bb8e5ebd9e72bddcf5ebb7a9c69_f9fe71cf.jpg","medium_large-width":576,"medium_large-height":768,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/abc41bb8e5ebd9e72bddcf5ebb7a9c69_f9fe71cf.jpg","large-width":576,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/abc41bb8e5ebd9e72bddcf5ebb7a9c69_f9fe71cf.jpg","1536x1536-width":576,"1536x1536-height":768,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/abc41bb8e5ebd9e72bddcf5ebb7a9c69_f9fe71cf.jpg","2048x2048-width":576,"2048x2048-height":768,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/abc41bb8e5ebd9e72bddcf5ebb7a9c69_f9fe71cf.jpg","gform-image-choice-sm-width":225,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/abc41bb8e5ebd9e72bddcf5ebb7a9c69_f9fe71cf.jpg","gform-image-choice-md-width":300,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/abc41bb8e5ebd9e72bddcf5ebb7a9c69_f9fe71cf.jpg","gform-image-choice-lg-width":450,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":173178,"id":173178,"title":"35f99b114173e8b0d732ff674cf83618_aaa46b7b.jpg","filename":"35f99b114173e8b0d732ff674cf83618_aaa46b7b.jpg","filesize":135218,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/35f99b114173e8b0d732ff674cf83618_aaa46b7b.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/stop-e-sleep-bergamo\/35f99b114173e8b0d732ff674cf83618_aaa46b7b-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"35f99b114173e8b0d732ff674cf83618_aaa46b7b-jpg-2","status":"inherit","uploaded_to":179701,"date":"2025-04-18 09:23:54","modified":"2025-04-18 13:56:15","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1024,"height":683,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/35f99b114173e8b0d732ff674cf83618_aaa46b7b-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/35f99b114173e8b0d732ff674cf83618_aaa46b7b-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/35f99b114173e8b0d732ff674cf83618_aaa46b7b-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/35f99b114173e8b0d732ff674cf83618_aaa46b7b.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/35f99b114173e8b0d732ff674cf83618_aaa46b7b.jpg","1536x1536-width":1024,"1536x1536-height":683,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/35f99b114173e8b0d732ff674cf83618_aaa46b7b.jpg","2048x2048-width":1024,"2048x2048-height":683,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/35f99b114173e8b0d732ff674cf83618_aaa46b7b.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/35f99b114173e8b0d732ff674cf83618_aaa46b7b.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/35f99b114173e8b0d732ff674cf83618_aaa46b7b.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":173185,"id":173185,"title":"1119c1db832392431fb94febbb3aff78_000711c2.jpg","filename":"1119c1db832392431fb94febbb3aff78_000711c2.jpg","filesize":153032,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1119c1db832392431fb94febbb3aff78_000711c2.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/stop-e-sleep-bergamo\/1119c1db832392431fb94febbb3aff78_000711c2-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"1119c1db832392431fb94febbb3aff78_000711c2-jpg-2","status":"inherit","uploaded_to":179701,"date":"2025-04-18 09:23:55","modified":"2025-04-18 13:56:15","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1024,"height":683,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1119c1db832392431fb94febbb3aff78_000711c2-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1119c1db832392431fb94febbb3aff78_000711c2-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1119c1db832392431fb94febbb3aff78_000711c2-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1119c1db832392431fb94febbb3aff78_000711c2.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1119c1db832392431fb94febbb3aff78_000711c2.jpg","1536x1536-width":1024,"1536x1536-height":683,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1119c1db832392431fb94febbb3aff78_000711c2.jpg","2048x2048-width":1024,"2048x2048-height":683,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1119c1db832392431fb94febbb3aff78_000711c2.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1119c1db832392431fb94febbb3aff78_000711c2.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1119c1db832392431fb94febbb3aff78_000711c2.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":173192,"id":173192,"title":"4668069fffd5abc7db9a105c73d7c2d5_6818278e.jpg","filename":"4668069fffd5abc7db9a105c73d7c2d5_6818278e.jpg","filesize":131131,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4668069fffd5abc7db9a105c73d7c2d5_6818278e.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/stop-e-sleep-bergamo\/4668069fffd5abc7db9a105c73d7c2d5_6818278e-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"4668069fffd5abc7db9a105c73d7c2d5_6818278e-jpg-2","status":"inherit","uploaded_to":179701,"date":"2025-04-18 09:23:56","modified":"2025-04-18 13:56:15","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1024,"height":683,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4668069fffd5abc7db9a105c73d7c2d5_6818278e-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4668069fffd5abc7db9a105c73d7c2d5_6818278e-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4668069fffd5abc7db9a105c73d7c2d5_6818278e-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4668069fffd5abc7db9a105c73d7c2d5_6818278e.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4668069fffd5abc7db9a105c73d7c2d5_6818278e.jpg","1536x1536-width":1024,"1536x1536-height":683,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4668069fffd5abc7db9a105c73d7c2d5_6818278e.jpg","2048x2048-width":1024,"2048x2048-height":683,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4668069fffd5abc7db9a105c73d7c2d5_6818278e.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4668069fffd5abc7db9a105c73d7c2d5_6818278e.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4668069fffd5abc7db9a105c73d7c2d5_6818278e.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":173199,"id":173199,"title":"41fed93cdfeef782763494a211fb26b3_89174b63.jpg","filename":"41fed93cdfeef782763494a211fb26b3_89174b63.jpg","filesize":173017,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/41fed93cdfeef782763494a211fb26b3_89174b63.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/stop-e-sleep-bergamo\/41fed93cdfeef782763494a211fb26b3_89174b63-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"41fed93cdfeef782763494a211fb26b3_89174b63-jpg-2","status":"inherit","uploaded_to":179701,"date":"2025-04-18 09:23:57","modified":"2025-04-18 13:56:15","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1024,"height":683,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/41fed93cdfeef782763494a211fb26b3_89174b63-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/41fed93cdfeef782763494a211fb26b3_89174b63-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/41fed93cdfeef782763494a211fb26b3_89174b63-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/41fed93cdfeef782763494a211fb26b3_89174b63.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/41fed93cdfeef782763494a211fb26b3_89174b63.jpg","1536x1536-width":1024,"1536x1536-height":683,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/41fed93cdfeef782763494a211fb26b3_89174b63.jpg","2048x2048-width":1024,"2048x2048-height":683,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/41fed93cdfeef782763494a211fb26b3_89174b63.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/41fed93cdfeef782763494a211fb26b3_89174b63.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/41fed93cdfeef782763494a211fb26b3_89174b63.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":173206,"id":173206,"title":"e4afc347c56f50c1ae6ac24603586cf1_b28443f6.jpg","filename":"e4afc347c56f50c1ae6ac24603586cf1_b28443f6.jpg","filesize":165462,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e4afc347c56f50c1ae6ac24603586cf1_b28443f6.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/stop-e-sleep-bergamo\/e4afc347c56f50c1ae6ac24603586cf1_b28443f6-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"e4afc347c56f50c1ae6ac24603586cf1_b28443f6-jpg-2","status":"inherit","uploaded_to":179701,"date":"2025-04-18 09:23:58","modified":"2025-04-18 13:56:15","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1024,"height":683,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e4afc347c56f50c1ae6ac24603586cf1_b28443f6-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e4afc347c56f50c1ae6ac24603586cf1_b28443f6-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e4afc347c56f50c1ae6ac24603586cf1_b28443f6-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e4afc347c56f50c1ae6ac24603586cf1_b28443f6.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e4afc347c56f50c1ae6ac24603586cf1_b28443f6.jpg","1536x1536-width":1024,"1536x1536-height":683,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e4afc347c56f50c1ae6ac24603586cf1_b28443f6.jpg","2048x2048-width":1024,"2048x2048-height":683,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e4afc347c56f50c1ae6ac24603586cf1_b28443f6.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e4afc347c56f50c1ae6ac24603586cf1_b28443f6.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e4afc347c56f50c1ae6ac24603586cf1_b28443f6.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":173213,"id":173213,"title":"2f1fe327d36c52448782e73c985799b3_39d72688.jpg","filename":"2f1fe327d36c52448782e73c985799b3_39d72688.jpg","filesize":188045,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2f1fe327d36c52448782e73c985799b3_39d72688.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/stop-e-sleep-bergamo\/2f1fe327d36c52448782e73c985799b3_39d72688-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"2f1fe327d36c52448782e73c985799b3_39d72688-jpg-2","status":"inherit","uploaded_to":179701,"date":"2025-04-18 09:23:59","modified":"2025-04-18 13:56:15","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1024,"height":683,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2f1fe327d36c52448782e73c985799b3_39d72688-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2f1fe327d36c52448782e73c985799b3_39d72688-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2f1fe327d36c52448782e73c985799b3_39d72688-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2f1fe327d36c52448782e73c985799b3_39d72688.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2f1fe327d36c52448782e73c985799b3_39d72688.jpg","1536x1536-width":1024,"1536x1536-height":683,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2f1fe327d36c52448782e73c985799b3_39d72688.jpg","2048x2048-width":1024,"2048x2048-height":683,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2f1fe327d36c52448782e73c985799b3_39d72688.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2f1fe327d36c52448782e73c985799b3_39d72688.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2f1fe327d36c52448782e73c985799b3_39d72688.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":173220,"id":173220,"title":"6754ffc78b790e5595b3cde34c2ad026_c7ecc9ef.jpg","filename":"6754ffc78b790e5595b3cde34c2ad026_c7ecc9ef.jpg","filesize":135078,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6754ffc78b790e5595b3cde34c2ad026_c7ecc9ef.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/stop-e-sleep-bergamo\/6754ffc78b790e5595b3cde34c2ad026_c7ecc9ef-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"6754ffc78b790e5595b3cde34c2ad026_c7ecc9ef-jpg-2","status":"inherit","uploaded_to":179701,"date":"2025-04-18 09:24:00","modified":"2025-04-18 13:56:15","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1024,"height":683,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6754ffc78b790e5595b3cde34c2ad026_c7ecc9ef-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6754ffc78b790e5595b3cde34c2ad026_c7ecc9ef-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6754ffc78b790e5595b3cde34c2ad026_c7ecc9ef-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6754ffc78b790e5595b3cde34c2ad026_c7ecc9ef.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6754ffc78b790e5595b3cde34c2ad026_c7ecc9ef.jpg","1536x1536-width":1024,"1536x1536-height":683,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6754ffc78b790e5595b3cde34c2ad026_c7ecc9ef.jpg","2048x2048-width":1024,"2048x2048-height":683,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6754ffc78b790e5595b3cde34c2ad026_c7ecc9ef.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6754ffc78b790e5595b3cde34c2ad026_c7ecc9ef.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6754ffc78b790e5595b3cde34c2ad026_c7ecc9ef.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":173227,"id":173227,"title":"d3ffc61e4d1b5eb8bdea44400dade004_6ac8ed5d.jpg","filename":"d3ffc61e4d1b5eb8bdea44400dade004_6ac8ed5d.jpg","filesize":135524,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d3ffc61e4d1b5eb8bdea44400dade004_6ac8ed5d.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/stop-e-sleep-bergamo\/d3ffc61e4d1b5eb8bdea44400dade004_6ac8ed5d-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"d3ffc61e4d1b5eb8bdea44400dade004_6ac8ed5d-jpg-2","status":"inherit","uploaded_to":179701,"date":"2025-04-18 09:24:01","modified":"2025-04-18 13:56:15","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1024,"height":683,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d3ffc61e4d1b5eb8bdea44400dade004_6ac8ed5d-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d3ffc61e4d1b5eb8bdea44400dade004_6ac8ed5d-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d3ffc61e4d1b5eb8bdea44400dade004_6ac8ed5d-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d3ffc61e4d1b5eb8bdea44400dade004_6ac8ed5d.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d3ffc61e4d1b5eb8bdea44400dade004_6ac8ed5d.jpg","1536x1536-width":1024,"1536x1536-height":683,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d3ffc61e4d1b5eb8bdea44400dade004_6ac8ed5d.jpg","2048x2048-width":1024,"2048x2048-height":683,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d3ffc61e4d1b5eb8bdea44400dade004_6ac8ed5d.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d3ffc61e4d1b5eb8bdea44400dade004_6ac8ed5d.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d3ffc61e4d1b5eb8bdea44400dade004_6ac8ed5d.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":173234,"id":173234,"title":"bc2988bb381d92510e8f4dbaceffa51f_62afa13f.jpg","filename":"bc2988bb381d92510e8f4dbaceffa51f_62afa13f.jpg","filesize":139901,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bc2988bb381d92510e8f4dbaceffa51f_62afa13f.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/stop-e-sleep-bergamo\/bc2988bb381d92510e8f4dbaceffa51f_62afa13f-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"bc2988bb381d92510e8f4dbaceffa51f_62afa13f-jpg-2","status":"inherit","uploaded_to":179701,"date":"2025-04-18 09:24:02","modified":"2025-04-18 13:56:15","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1024,"height":683,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bc2988bb381d92510e8f4dbaceffa51f_62afa13f-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bc2988bb381d92510e8f4dbaceffa51f_62afa13f-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bc2988bb381d92510e8f4dbaceffa51f_62afa13f-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bc2988bb381d92510e8f4dbaceffa51f_62afa13f.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bc2988bb381d92510e8f4dbaceffa51f_62afa13f.jpg","1536x1536-width":1024,"1536x1536-height":683,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bc2988bb381d92510e8f4dbaceffa51f_62afa13f.jpg","2048x2048-width":1024,"2048x2048-height":683,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bc2988bb381d92510e8f4dbaceffa51f_62afa13f.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bc2988bb381d92510e8f4dbaceffa51f_62afa13f.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bc2988bb381d92510e8f4dbaceffa51f_62afa13f.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":173241,"id":173241,"title":"4ee1b8a31aa3bee8eb8c5d558133f887_250d5ba0.jpg","filename":"4ee1b8a31aa3bee8eb8c5d558133f887_250d5ba0.jpg","filesize":160573,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4ee1b8a31aa3bee8eb8c5d558133f887_250d5ba0.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/stop-e-sleep-bergamo\/4ee1b8a31aa3bee8eb8c5d558133f887_250d5ba0-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"4ee1b8a31aa3bee8eb8c5d558133f887_250d5ba0-jpg-2","status":"inherit","uploaded_to":179701,"date":"2025-04-18 09:24:03","modified":"2025-04-18 13:56:15","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1024,"height":683,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4ee1b8a31aa3bee8eb8c5d558133f887_250d5ba0-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4ee1b8a31aa3bee8eb8c5d558133f887_250d5ba0-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4ee1b8a31aa3bee8eb8c5d558133f887_250d5ba0-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4ee1b8a31aa3bee8eb8c5d558133f887_250d5ba0.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4ee1b8a31aa3bee8eb8c5d558133f887_250d5ba0.jpg","1536x1536-width":1024,"1536x1536-height":683,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4ee1b8a31aa3bee8eb8c5d558133f887_250d5ba0.jpg","2048x2048-width":1024,"2048x2048-height":683,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4ee1b8a31aa3bee8eb8c5d558133f887_250d5ba0.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4ee1b8a31aa3bee8eb8c5d558133f887_250d5ba0.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4ee1b8a31aa3bee8eb8c5d558133f887_250d5ba0.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":173248,"id":173248,"title":"3128b92a7ac803b0e1b49c70b9d22646_81913d5e.jpg","filename":"3128b92a7ac803b0e1b49c70b9d22646_81913d5e.jpg","filesize":144364,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3128b92a7ac803b0e1b49c70b9d22646_81913d5e.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/stop-e-sleep-bergamo\/3128b92a7ac803b0e1b49c70b9d22646_81913d5e-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"3128b92a7ac803b0e1b49c70b9d22646_81913d5e-jpg-2","status":"inherit","uploaded_to":179701,"date":"2025-04-18 09:24:04","modified":"2025-04-18 13:56:16","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1024,"height":683,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3128b92a7ac803b0e1b49c70b9d22646_81913d5e-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3128b92a7ac803b0e1b49c70b9d22646_81913d5e-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3128b92a7ac803b0e1b49c70b9d22646_81913d5e-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3128b92a7ac803b0e1b49c70b9d22646_81913d5e.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3128b92a7ac803b0e1b49c70b9d22646_81913d5e.jpg","1536x1536-width":1024,"1536x1536-height":683,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3128b92a7ac803b0e1b49c70b9d22646_81913d5e.jpg","2048x2048-width":1024,"2048x2048-height":683,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3128b92a7ac803b0e1b49c70b9d22646_81913d5e.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3128b92a7ac803b0e1b49c70b9d22646_81913d5e.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3128b92a7ac803b0e1b49c70b9d22646_81913d5e.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":173255,"id":173255,"title":"29775383920556e8a5c4afafe74064d1_5eb18985.jpg","filename":"29775383920556e8a5c4afafe74064d1_5eb18985.jpg","filesize":160601,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/29775383920556e8a5c4afafe74064d1_5eb18985.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/stop-e-sleep-bergamo\/29775383920556e8a5c4afafe74064d1_5eb18985-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"29775383920556e8a5c4afafe74064d1_5eb18985-jpg-2","status":"inherit","uploaded_to":179701,"date":"2025-04-18 09:24:06","modified":"2025-04-18 13:56:16","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1024,"height":683,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/29775383920556e8a5c4afafe74064d1_5eb18985-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/29775383920556e8a5c4afafe74064d1_5eb18985-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/29775383920556e8a5c4afafe74064d1_5eb18985-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/29775383920556e8a5c4afafe74064d1_5eb18985.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/29775383920556e8a5c4afafe74064d1_5eb18985.jpg","1536x1536-width":1024,"1536x1536-height":683,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/29775383920556e8a5c4afafe74064d1_5eb18985.jpg","2048x2048-width":1024,"2048x2048-height":683,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/29775383920556e8a5c4afafe74064d1_5eb18985.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/29775383920556e8a5c4afafe74064d1_5eb18985.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/29775383920556e8a5c4afafe74064d1_5eb18985.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":173262,"id":173262,"title":"40adf693cf24919e91a1d0151f8296cf_52fe0239.jpg","filename":"40adf693cf24919e91a1d0151f8296cf_52fe0239.jpg","filesize":168196,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/40adf693cf24919e91a1d0151f8296cf_52fe0239.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/stop-e-sleep-bergamo\/40adf693cf24919e91a1d0151f8296cf_52fe0239-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"40adf693cf24919e91a1d0151f8296cf_52fe0239-jpg-2","status":"inherit","uploaded_to":179701,"date":"2025-04-18 09:24:07","modified":"2025-04-18 13:56:16","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1024,"height":683,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/40adf693cf24919e91a1d0151f8296cf_52fe0239-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/40adf693cf24919e91a1d0151f8296cf_52fe0239-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/40adf693cf24919e91a1d0151f8296cf_52fe0239-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/40adf693cf24919e91a1d0151f8296cf_52fe0239.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/40adf693cf24919e91a1d0151f8296cf_52fe0239.jpg","1536x1536-width":1024,"1536x1536-height":683,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/40adf693cf24919e91a1d0151f8296cf_52fe0239.jpg","2048x2048-width":1024,"2048x2048-height":683,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/40adf693cf24919e91a1d0151f8296cf_52fe0239.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/40adf693cf24919e91a1d0151f8296cf_52fe0239.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/40adf693cf24919e91a1d0151f8296cf_52fe0239.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":173269,"id":173269,"title":"1a6a2bc6f9487a0aa64dde357ea44ca6_734abc6d.jpg","filename":"1a6a2bc6f9487a0aa64dde357ea44ca6_734abc6d.jpg","filesize":210588,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1a6a2bc6f9487a0aa64dde357ea44ca6_734abc6d.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/stop-e-sleep-bergamo\/1a6a2bc6f9487a0aa64dde357ea44ca6_734abc6d-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"1a6a2bc6f9487a0aa64dde357ea44ca6_734abc6d-jpg-2","status":"inherit","uploaded_to":179701,"date":"2025-04-18 09:24:08","modified":"2025-04-18 13:56:16","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1024,"height":683,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1a6a2bc6f9487a0aa64dde357ea44ca6_734abc6d-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1a6a2bc6f9487a0aa64dde357ea44ca6_734abc6d-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1a6a2bc6f9487a0aa64dde357ea44ca6_734abc6d-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1a6a2bc6f9487a0aa64dde357ea44ca6_734abc6d.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1a6a2bc6f9487a0aa64dde357ea44ca6_734abc6d.jpg","1536x1536-width":1024,"1536x1536-height":683,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1a6a2bc6f9487a0aa64dde357ea44ca6_734abc6d.jpg","2048x2048-width":1024,"2048x2048-height":683,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1a6a2bc6f9487a0aa64dde357ea44ca6_734abc6d.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1a6a2bc6f9487a0aa64dde357ea44ca6_734abc6d.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1a6a2bc6f9487a0aa64dde357ea44ca6_734abc6d.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":173276,"id":173276,"title":"5aaebb0122b0f95221239438a51a7180_0651c203.jpg","filename":"5aaebb0122b0f95221239438a51a7180_0651c203.jpg","filesize":200488,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5aaebb0122b0f95221239438a51a7180_0651c203.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/stop-e-sleep-bergamo\/5aaebb0122b0f95221239438a51a7180_0651c203-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"5aaebb0122b0f95221239438a51a7180_0651c203-jpg-2","status":"inherit","uploaded_to":179701,"date":"2025-04-18 09:24:09","modified":"2025-04-18 13:56:16","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1024,"height":683,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5aaebb0122b0f95221239438a51a7180_0651c203-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5aaebb0122b0f95221239438a51a7180_0651c203-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5aaebb0122b0f95221239438a51a7180_0651c203-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5aaebb0122b0f95221239438a51a7180_0651c203.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5aaebb0122b0f95221239438a51a7180_0651c203.jpg","1536x1536-width":1024,"1536x1536-height":683,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5aaebb0122b0f95221239438a51a7180_0651c203.jpg","2048x2048-width":1024,"2048x2048-height":683,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5aaebb0122b0f95221239438a51a7180_0651c203.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5aaebb0122b0f95221239438a51a7180_0651c203.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5aaebb0122b0f95221239438a51a7180_0651c203.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":173283,"id":173283,"title":"33e2efa6b0da57f132a74c3814c17e95_734abc6d.jpg","filename":"33e2efa6b0da57f132a74c3814c17e95_734abc6d.jpg","filesize":210588,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/33e2efa6b0da57f132a74c3814c17e95_734abc6d.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/stop-e-sleep-bergamo\/33e2efa6b0da57f132a74c3814c17e95_734abc6d-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"33e2efa6b0da57f132a74c3814c17e95_734abc6d-jpg-2","status":"inherit","uploaded_to":179701,"date":"2025-04-18 09:24:10","modified":"2025-04-18 13:56:16","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1024,"height":683,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/33e2efa6b0da57f132a74c3814c17e95_734abc6d-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/33e2efa6b0da57f132a74c3814c17e95_734abc6d-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/33e2efa6b0da57f132a74c3814c17e95_734abc6d-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/33e2efa6b0da57f132a74c3814c17e95_734abc6d.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/33e2efa6b0da57f132a74c3814c17e95_734abc6d.jpg","1536x1536-width":1024,"1536x1536-height":683,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/33e2efa6b0da57f132a74c3814c17e95_734abc6d.jpg","2048x2048-width":1024,"2048x2048-height":683,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/33e2efa6b0da57f132a74c3814c17e95_734abc6d.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/33e2efa6b0da57f132a74c3814c17e95_734abc6d.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/33e2efa6b0da57f132a74c3814c17e95_734abc6d.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":173290,"id":173290,"title":"47d2736ca653bff19b9516f991d68f21_0651c203.jpg","filename":"47d2736ca653bff19b9516f991d68f21_0651c203.jpg","filesize":200488,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/47d2736ca653bff19b9516f991d68f21_0651c203.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/stop-e-sleep-bergamo\/47d2736ca653bff19b9516f991d68f21_0651c203-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"47d2736ca653bff19b9516f991d68f21_0651c203-jpg-2","status":"inherit","uploaded_to":179701,"date":"2025-04-18 09:24:11","modified":"2025-04-18 13:56:16","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1024,"height":683,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/47d2736ca653bff19b9516f991d68f21_0651c203-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/47d2736ca653bff19b9516f991d68f21_0651c203-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/47d2736ca653bff19b9516f991d68f21_0651c203-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/47d2736ca653bff19b9516f991d68f21_0651c203.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/47d2736ca653bff19b9516f991d68f21_0651c203.jpg","1536x1536-width":1024,"1536x1536-height":683,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/47d2736ca653bff19b9516f991d68f21_0651c203.jpg","2048x2048-width":1024,"2048x2048-height":683,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/47d2736ca653bff19b9516f991d68f21_0651c203.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/47d2736ca653bff19b9516f991d68f21_0651c203.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/47d2736ca653bff19b9516f991d68f21_0651c203.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"buttons":false,"hero_buttons_group":{"buttons":false},"hero_buttons":false,"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"","filotto_fill":"","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""}},"description":"<p>Die Wohnung besteht aus 4 Schlafzimmern und 2 Badezimmern, die mit anderen G\u00e4sten geteilt werden. Wir haben ein Doppel-, ein Dreibett-, ein Vierbett- und ein Familienzimmer f\u00fcr bis zu 6 Personen.&#13;<br \/>\nDas Fr\u00fchst\u00fcck ist immer im Preis inbegriffen; Es handelt sich um ein Selbstbedienungsfr\u00fchst\u00fcck im mediterranen Stil, das daher Kaffee, Milch, Tee, Zwieback, Brot, Marmelade, M\u00fcsli, Saft, Joghurt und Butter umfasst.<\/p>\n","indepth":"<p>Die Check-in-Zeit muss mit dem Gast vereinbart werden, damit wir alle Formalit\u00e4ten von Angesicht zu Angesicht treffen und erledigen k\u00f6nnen, sowie um dem Gast einen besseren Service in Bezug auf alle Informationen zu bieten, die unsere G\u00e4ste anfordern k\u00f6nnen ; Normalerweise wird der Check-in von 14 bis 21 Uhr akzeptiert, kann aber nach Vereinbarung auch zu anderen Zeiten erfolgen.&#13;<br \/>\nDer Check-out erfolgt sp\u00e4testens um 10:30 Uhr, da die Zimmer dann gereinigt und f\u00fcr die n\u00e4chsten G\u00e4ste hergerichtet werden m\u00fcssen.<\/p>\n","howtogetthere":"<p>Die Wohnung befindet sich etwa 400 Meter vom Bus- und Bahnhof entfernt, im Stadtzentrum, nicht weit vom pulsierenden Herzen der Unterstadt entfernt, wo es zahlreiche Gesch\u00e4fte, Bars, Restaurants und Superm\u00e4rkte gibt.&#13;<br \/>\nDer Flughafen Orio al Serio ist nur wenige Minuten mit Bus und Taxi entfernt; Bus n. 1 verbindet Citt\u00e0 Alta \u00fcber den Zug- und Busbahnhof mit dem Flughafen und f\u00e4hrt sehr h\u00e4ufig. Wenn G\u00e4ste einen privaten Transfer w\u00fcnschen, k\u00f6nnen sie uns f\u00fcr Informationen zu Fahrpl\u00e4nen und Preisen kontaktieren.&#13;<br \/>\nWas das Parken betrifft, so gibt es in der Umgebung geb\u00fchrenpflichtige Parkpl\u00e4tze entlang der Stra\u00dfe von 9 bis 19 Uhr und kostenlos von 19 bis 9 Uhr, oder nur 100 Meter entfernt gibt es einen kostenpflichtigen \u00fcberdachten Parkplatz (max. 15 \u20ac pro Tag).<\/p>\n","timerange":"","seasonality":"","pairings":"","curiosities":"","awards":"","cancellationpolicy":"","moredetails":"","whatsincluded":"","whatsnotincluded":"","price":"","services":"<p>Die Kurtaxe ist im Preis nicht enthalten.<\/p>\n","parking":"<p>Was das Parken betrifft, gibt es in der Umgebung geb\u00fchrenpflichtige Parkpl\u00e4tze entlang der Stra\u00dfe von 9 bis 19 Uhr und kostenlos von 19 bis 9 Uhr, oder nur 100 Meter entfernt gibt es einen kostenpflichtigen \u00fcberdachten Parkplatz (max. 15 \u20ac pro Tag).<\/p>\n","restaurant":"","breakfast":"<p>Das Fr\u00fchst\u00fcck ist immer im Preis inbegriffen; Es handelt sich um ein Selbstbedienungsfr\u00fchst\u00fcck im mediterranen Stil, das daher Kaffee, Milch, Tee, Zwieback, Brot, Marmelade, M\u00fcsli, Saft, Joghurt und Butter umfasst.<\/p>\n","internet":"<p>Wi-Fi in der ganzen Wohnung vorhanden<\/p>\n","children":"<p>Kinder werden akzeptiert: kostenlos von 0 bis 3 Jahren, gegen Geb\u00fchr von 3 bis 18 Jahren.<\/p>\n","pets":"","latitude":"45.690712","longitude":"9.671133","startingprice":"","gpxmap":"","iu_motor_accessibility":"notsure","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_kids":true,"iu_shortprice":"","iu_company_name":"Marco Belotti","registered_office":"","iu_addr_streetnumber":"Via Paglia 19","iu_addr_postalcode":"24122","iu_addr_city":"Bergamo","iu_addr_province":"BG","iu_phone":"","iu_cell":"+393518155595","iu_website":"","iu_email":"stopsleepbergamo@gmail.com","iu_vat":"","iu_document_label":"","iu_document":false,"iu_documents":false,"iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_bookingurl":"","iu_videourl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"","iu_languages":"","iu_minpeople":"","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"iu_stars":"","iu_rooms":"4","iu_beds":"","id_madeep":"","id_visit_manza":"4830","id_east":"","id_ristora":"","id_eppen":"","style":"primary","text":"","button_icon":"none","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"validfrom":"","validto":"","hours":"","tcm_content":false,"accessibilitycontent":{"tcm_content":false},"accessibilityicons":[],"filotto_layout":"","filotto_fill":"","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""},"max_elements":"","show_total":false,"see_all":false,"order_by":"","order_way":"","only_ambassadors":false,"time":"<p>Solitamente il check-in \u00e8 accettato dalle 14 alle 21, ma concordandolo si pu\u00f2 fare anche in altri orari.&#13;<br \/>\nIl check-.out si effettua al massimo alle 10:30.<\/p>\n","ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":"","service_icons":[{"value":"groups_welcome","label":"Accettazione gruppi"},{"value":"elevator","label":"Ascensore"},{"value":"audiovisual_equipment","label":"Impianti audiovisivi"},{"value":"wifi","label":"Wi-Fi"},{"value":"hairdryer","label":"Asciugacapelli"},{"value":"shower","label":"Bagni con doccia"},{"value":"tv_room","label":"TV in camera"},{"value":"bancomat","label":"Bancomat"},{"value":"visa","label":"Visa"},{"value":"mastercard","label":"Mastercard"}]},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/179701","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/179701\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media\/173150"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media?parent=179701"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/categories?post=179701"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/tags?post=179701"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/aggr?post=179701"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/area?post=179701"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/kind?post=179701"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/zona?post=179701"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}