{"id":180476,"date":"2025-04-18T13:38:22","date_gmt":"2025-04-18T11:38:22","guid":{"rendered":"https:\/\/visit.valueservice.cloud\/oggetto\/melly-house-in-centro-citta\/"},"modified":"2025-04-18T15:58:14","modified_gmt":"2025-04-18T13:58:14","slug":"melly-house-in-centro-citta","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/melly-house-in-centro-citta\/","title":{"rendered":"Melly House In Centro Citt\u00e0"},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":175317,"template":"","categories":[1002],"tags":[],"aggr":[],"area":[],"kind":[18725],"zona":[],"class_list":["post-180476","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-schlaf","kind-strutturaricettiva-de"],"acf":{"hero_type":"images","video_youtube_url":"","video_vimeo_url":"","size":"full","hero_title":"Melly House In Centro Citt\u00e0","hero_text":"<p>Willkommen im Melly House, einem gem\u00fctlichen Apartment im Herzen von Bergamo. Ideal f\u00fcr Reisende, Paare oder Familien und f\u00fcr beruflich Reisende. Dieser Raum vereint Komfort und Zweckm\u00e4\u00dfigkeit an einem strategischen Standort, der perfekt ist, um die Sch\u00f6nheit der Stadt zu erkunden.<\/p>\n","slides":[{"image":{"ID":175317,"id":175317,"title":"c55b22d26721372a8eb5015790795a77_9c54b82b.jpg","filename":"c55b22d26721372a8eb5015790795a77_9c54b82b.jpg","filesize":433815,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c55b22d26721372a8eb5015790795a77_9c54b82b.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/melly-house-in-centro-citta\/c55b22d26721372a8eb5015790795a77_9c54b82b-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"c55b22d26721372a8eb5015790795a77_9c54b82b-jpg-2","status":"inherit","uploaded_to":180476,"date":"2025-04-18 09:34:34","modified":"2025-04-18 13:58:40","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1170,"height":827,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c55b22d26721372a8eb5015790795a77_9c54b82b-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c55b22d26721372a8eb5015790795a77_9c54b82b-300x212.jpg","medium-width":300,"medium-height":212,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c55b22d26721372a8eb5015790795a77_9c54b82b-768x543.jpg","medium_large-width":768,"medium_large-height":543,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c55b22d26721372a8eb5015790795a77_9c54b82b-1024x724.jpg","large-width":1024,"large-height":724,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c55b22d26721372a8eb5015790795a77_9c54b82b.jpg","1536x1536-width":1170,"1536x1536-height":827,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c55b22d26721372a8eb5015790795a77_9c54b82b.jpg","2048x2048-width":1170,"2048x2048-height":827,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c55b22d26721372a8eb5015790795a77_9c54b82b.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":212,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c55b22d26721372a8eb5015790795a77_9c54b82b.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":283,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c55b22d26721372a8eb5015790795a77_9c54b82b.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":424}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":175324,"id":175324,"title":"2eb9cac4613c07d9aceca5e13a316f74_fc04cabc.jpg","filename":"2eb9cac4613c07d9aceca5e13a316f74_fc04cabc.jpg","filesize":575900,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2eb9cac4613c07d9aceca5e13a316f74_fc04cabc.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/melly-house-in-centro-citta\/2eb9cac4613c07d9aceca5e13a316f74_fc04cabc-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"2eb9cac4613c07d9aceca5e13a316f74_fc04cabc-jpg-2","status":"inherit","uploaded_to":180476,"date":"2025-04-18 09:34:35","modified":"2025-04-18 13:58:40","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1170,"height":1468,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2eb9cac4613c07d9aceca5e13a316f74_fc04cabc-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2eb9cac4613c07d9aceca5e13a316f74_fc04cabc-239x300.jpg","medium-width":239,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2eb9cac4613c07d9aceca5e13a316f74_fc04cabc-768x964.jpg","medium_large-width":768,"medium_large-height":964,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2eb9cac4613c07d9aceca5e13a316f74_fc04cabc-816x1024.jpg","large-width":816,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2eb9cac4613c07d9aceca5e13a316f74_fc04cabc.jpg","1536x1536-width":1170,"1536x1536-height":1468,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2eb9cac4613c07d9aceca5e13a316f74_fc04cabc.jpg","2048x2048-width":1170,"2048x2048-height":1468,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2eb9cac4613c07d9aceca5e13a316f74_fc04cabc.jpg","gform-image-choice-sm-width":239,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2eb9cac4613c07d9aceca5e13a316f74_fc04cabc.jpg","gform-image-choice-md-width":319,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2eb9cac4613c07d9aceca5e13a316f74_fc04cabc.jpg","gform-image-choice-lg-width":478,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":175331,"id":175331,"title":"1789f0510918a59825c3d0bc91f039b9_4d9e7d73.jpg","filename":"1789f0510918a59825c3d0bc91f039b9_4d9e7d73.jpg","filesize":457022,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1789f0510918a59825c3d0bc91f039b9_4d9e7d73.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/melly-house-in-centro-citta\/1789f0510918a59825c3d0bc91f039b9_4d9e7d73-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"1789f0510918a59825c3d0bc91f039b9_4d9e7d73-jpg-2","status":"inherit","uploaded_to":180476,"date":"2025-04-18 09:34:37","modified":"2025-04-18 13:58:40","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1170,"height":1475,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1789f0510918a59825c3d0bc91f039b9_4d9e7d73-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1789f0510918a59825c3d0bc91f039b9_4d9e7d73-238x300.jpg","medium-width":238,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1789f0510918a59825c3d0bc91f039b9_4d9e7d73-768x968.jpg","medium_large-width":768,"medium_large-height":968,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1789f0510918a59825c3d0bc91f039b9_4d9e7d73-812x1024.jpg","large-width":812,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1789f0510918a59825c3d0bc91f039b9_4d9e7d73.jpg","1536x1536-width":1170,"1536x1536-height":1475,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1789f0510918a59825c3d0bc91f039b9_4d9e7d73.jpg","2048x2048-width":1170,"2048x2048-height":1475,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1789f0510918a59825c3d0bc91f039b9_4d9e7d73.jpg","gform-image-choice-sm-width":238,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1789f0510918a59825c3d0bc91f039b9_4d9e7d73.jpg","gform-image-choice-md-width":317,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1789f0510918a59825c3d0bc91f039b9_4d9e7d73.jpg","gform-image-choice-lg-width":476,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":175338,"id":175338,"title":"97c7bd3496bcb9c30e54a4841a065dc3_0d1bae8f.jpg","filename":"97c7bd3496bcb9c30e54a4841a065dc3_0d1bae8f.jpg","filesize":650534,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/97c7bd3496bcb9c30e54a4841a065dc3_0d1bae8f.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/melly-house-in-centro-citta\/97c7bd3496bcb9c30e54a4841a065dc3_0d1bae8f-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"97c7bd3496bcb9c30e54a4841a065dc3_0d1bae8f-jpg-2","status":"inherit","uploaded_to":180476,"date":"2025-04-18 09:34:38","modified":"2025-04-18 13:58:40","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1170,"height":1487,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/97c7bd3496bcb9c30e54a4841a065dc3_0d1bae8f-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/97c7bd3496bcb9c30e54a4841a065dc3_0d1bae8f-236x300.jpg","medium-width":236,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/97c7bd3496bcb9c30e54a4841a065dc3_0d1bae8f-768x976.jpg","medium_large-width":768,"medium_large-height":976,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/97c7bd3496bcb9c30e54a4841a065dc3_0d1bae8f-806x1024.jpg","large-width":806,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/97c7bd3496bcb9c30e54a4841a065dc3_0d1bae8f.jpg","1536x1536-width":1170,"1536x1536-height":1487,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/97c7bd3496bcb9c30e54a4841a065dc3_0d1bae8f.jpg","2048x2048-width":1170,"2048x2048-height":1487,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/97c7bd3496bcb9c30e54a4841a065dc3_0d1bae8f.jpg","gform-image-choice-sm-width":236,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/97c7bd3496bcb9c30e54a4841a065dc3_0d1bae8f.jpg","gform-image-choice-md-width":315,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/97c7bd3496bcb9c30e54a4841a065dc3_0d1bae8f.jpg","gform-image-choice-lg-width":472,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":175345,"id":175345,"title":"c4bafd3fbfc2772f182e9fbbf4df4f09_fd53121e.jpg","filename":"c4bafd3fbfc2772f182e9fbbf4df4f09_fd53121e.jpg","filesize":688511,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c4bafd3fbfc2772f182e9fbbf4df4f09_fd53121e.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/melly-house-in-centro-citta\/c4bafd3fbfc2772f182e9fbbf4df4f09_fd53121e-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"c4bafd3fbfc2772f182e9fbbf4df4f09_fd53121e-jpg-2","status":"inherit","uploaded_to":180476,"date":"2025-04-18 09:34:39","modified":"2025-04-18 13:58:40","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1170,"height":1439,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c4bafd3fbfc2772f182e9fbbf4df4f09_fd53121e-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c4bafd3fbfc2772f182e9fbbf4df4f09_fd53121e-244x300.jpg","medium-width":244,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c4bafd3fbfc2772f182e9fbbf4df4f09_fd53121e-768x945.jpg","medium_large-width":768,"medium_large-height":945,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c4bafd3fbfc2772f182e9fbbf4df4f09_fd53121e-833x1024.jpg","large-width":833,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c4bafd3fbfc2772f182e9fbbf4df4f09_fd53121e.jpg","1536x1536-width":1170,"1536x1536-height":1439,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c4bafd3fbfc2772f182e9fbbf4df4f09_fd53121e.jpg","2048x2048-width":1170,"2048x2048-height":1439,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c4bafd3fbfc2772f182e9fbbf4df4f09_fd53121e.jpg","gform-image-choice-sm-width":244,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c4bafd3fbfc2772f182e9fbbf4df4f09_fd53121e.jpg","gform-image-choice-md-width":325,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c4bafd3fbfc2772f182e9fbbf4df4f09_fd53121e.jpg","gform-image-choice-lg-width":488,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":175352,"id":175352,"title":"0e6db0e758e00950c583c2328a200899_b5cffcf9.jpg","filename":"0e6db0e758e00950c583c2328a200899_b5cffcf9.jpg","filesize":598766,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0e6db0e758e00950c583c2328a200899_b5cffcf9.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/melly-house-in-centro-citta\/0e6db0e758e00950c583c2328a200899_b5cffcf9-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"0e6db0e758e00950c583c2328a200899_b5cffcf9-jpg-2","status":"inherit","uploaded_to":180476,"date":"2025-04-18 09:34:41","modified":"2025-04-18 13:58:41","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1170,"height":1452,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0e6db0e758e00950c583c2328a200899_b5cffcf9-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0e6db0e758e00950c583c2328a200899_b5cffcf9-242x300.jpg","medium-width":242,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0e6db0e758e00950c583c2328a200899_b5cffcf9-768x953.jpg","medium_large-width":768,"medium_large-height":953,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0e6db0e758e00950c583c2328a200899_b5cffcf9-825x1024.jpg","large-width":825,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0e6db0e758e00950c583c2328a200899_b5cffcf9.jpg","1536x1536-width":1170,"1536x1536-height":1452,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0e6db0e758e00950c583c2328a200899_b5cffcf9.jpg","2048x2048-width":1170,"2048x2048-height":1452,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0e6db0e758e00950c583c2328a200899_b5cffcf9.jpg","gform-image-choice-sm-width":242,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0e6db0e758e00950c583c2328a200899_b5cffcf9.jpg","gform-image-choice-md-width":322,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0e6db0e758e00950c583c2328a200899_b5cffcf9.jpg","gform-image-choice-lg-width":483,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":175359,"id":175359,"title":"34f3634a68e54652333e756877cc0c02_23b1efb7.jpg","filename":"34f3634a68e54652333e756877cc0c02_23b1efb7.jpg","filesize":518703,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/34f3634a68e54652333e756877cc0c02_23b1efb7.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/melly-house-in-centro-citta\/34f3634a68e54652333e756877cc0c02_23b1efb7-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"34f3634a68e54652333e756877cc0c02_23b1efb7-jpg-2","status":"inherit","uploaded_to":180476,"date":"2025-04-18 09:34:42","modified":"2025-04-18 13:58:41","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":959,"height":1493,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/34f3634a68e54652333e756877cc0c02_23b1efb7-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/34f3634a68e54652333e756877cc0c02_23b1efb7-193x300.jpg","medium-width":193,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/34f3634a68e54652333e756877cc0c02_23b1efb7-768x1196.jpg","medium_large-width":768,"medium_large-height":1196,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/34f3634a68e54652333e756877cc0c02_23b1efb7-658x1024.jpg","large-width":658,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/34f3634a68e54652333e756877cc0c02_23b1efb7.jpg","1536x1536-width":959,"1536x1536-height":1493,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/34f3634a68e54652333e756877cc0c02_23b1efb7.jpg","2048x2048-width":959,"2048x2048-height":1493,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/34f3634a68e54652333e756877cc0c02_23b1efb7.jpg","gform-image-choice-sm-width":193,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/34f3634a68e54652333e756877cc0c02_23b1efb7.jpg","gform-image-choice-md-width":257,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/34f3634a68e54652333e756877cc0c02_23b1efb7.jpg","gform-image-choice-lg-width":385,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":175366,"id":175366,"title":"56317ca6c813655a59a53049cc55dce1_d6f23e97.jpg","filename":"56317ca6c813655a59a53049cc55dce1_d6f23e97.jpg","filesize":462869,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/56317ca6c813655a59a53049cc55dce1_d6f23e97.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/melly-house-in-centro-citta\/56317ca6c813655a59a53049cc55dce1_d6f23e97-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"56317ca6c813655a59a53049cc55dce1_d6f23e97-jpg-2","status":"inherit","uploaded_to":180476,"date":"2025-04-18 09:34:44","modified":"2025-04-18 13:58:41","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1170,"height":1495,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/56317ca6c813655a59a53049cc55dce1_d6f23e97-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/56317ca6c813655a59a53049cc55dce1_d6f23e97-235x300.jpg","medium-width":235,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/56317ca6c813655a59a53049cc55dce1_d6f23e97-768x981.jpg","medium_large-width":768,"medium_large-height":981,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/56317ca6c813655a59a53049cc55dce1_d6f23e97-801x1024.jpg","large-width":801,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/56317ca6c813655a59a53049cc55dce1_d6f23e97.jpg","1536x1536-width":1170,"1536x1536-height":1495,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/56317ca6c813655a59a53049cc55dce1_d6f23e97.jpg","2048x2048-width":1170,"2048x2048-height":1495,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/56317ca6c813655a59a53049cc55dce1_d6f23e97.jpg","gform-image-choice-sm-width":235,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/56317ca6c813655a59a53049cc55dce1_d6f23e97.jpg","gform-image-choice-md-width":313,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/56317ca6c813655a59a53049cc55dce1_d6f23e97.jpg","gform-image-choice-lg-width":470,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"buttons":false,"hero_buttons_group":{"buttons":false},"hero_buttons":false,"filotto_title":"","filotto_sub":"","filotto_layout":"","filotto_fill":"","only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":"","order_by":"","order_way":"","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":"","order_by":"","order_way":""},"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"","filotto_fill":"","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":"","order_by":"","order_way":""}},"description":"<p>Nur wenige Schritte von den wichtigsten Sehensw\u00fcrdigkeiten entfernt (wie der Altstadt, Gesch\u00e4ften, Restaurants, Museen, Stadion, den Mauern von Bergamo und der Oberstadt) garantiert Melly House einen unvergesslichen Aufenthalt.&#13;<br \/>\nDie Innenr\u00e4ume mit ihrem klassischen und traditionellen Charme sind darauf ausgelegt, eine warme und entspannende Atmosph\u00e4re zu schaffen, mit einfachen und funktionalen M\u00f6beln. Alle G\u00e4ste k\u00f6nnen sich \u00fcber ein Willkommenspaket, schnelles WLAN, Bettw\u00e4sche und Handt\u00fccher freuen, die f\u00fcr einen komfortablen Aufenthalt erforderlich sind.Die Wohnung, etwa 60 m\u00b2 gro\u00df, bietet Platz f\u00fcr bis zu vier Personen, befindet sich im zweiten Stock des Geb\u00e4udes und besteht aus einem gro\u00dfen Eingangsbereich, der mit dem Wohnzimmer verbunden ist, mit einer voll ausgestatteten K\u00fcche und einem ausziehbaren Tisch mit St\u00fchlen. Das Wohnzimmer mit Schlafsofa, 32&#8242; HD-TV und Sony-Soundbar bietet das perfekte Ambiente, um sich nach einem Tag in der Stadt zu entspannen. Das ger\u00e4umige Schlafzimmer mit Doppelbett, Kleiderschrank, Kommode und Nachttischen verf\u00fcgt \u00fcber eine Arbeitsecke mit Schreibtisch und Stuhl. Das Badezimmer mit Fenster besteht aus einer Dusche, Toilette, Bidet, Waschtisch und einem Handtuchw\u00e4rmer.<\/p>\n","indepth":"","howtogetthere":"<p>Die Wohnung befindet sich in der Fu\u00dfg\u00e4ngerzone im Stadtzentrum.&#13;<br \/>\nSie ist leicht vom Flughafen (Entfernung 5,8 km) zu erreichen:&#13;<br \/>\n&#13;<br \/>\nmit dem Bus (ca. 20 Minuten ohne Verkehr): die Haltestelle befindet sich direkt vor dem Ausgang der Ankunftshalle, Linie 1 in Richtung Bergamo, steigen Sie an der Haltestelle Porta Nuova aus und gehen Sie weitere 5 Minuten zu Fu\u00df. Tickets k\u00f6nnen direkt im Bus gekauft werden, auch mit Kreditkarte.&#13;<br \/>\nmit dem Taxi (ca. 13 Minuten ohne Verkehr)&#13;<br \/>\n&#13;<br \/>\nVom Bahnhof Bergamo ist die Wohnung in etwa 10 Minuten zu Fu\u00df erreichbar.<\/p>\n","timerange":"","seasonality":"","pairings":"","curiosities":"","awards":"","cancellationpolicy":"","moredetails":"","whatsincluded":"","whatsnotincluded":"","price":"","services":"","parking":"","restaurant":"","breakfast":"","internet":"<p>Schnelles Wi fi<\/p>\n","children":"","pets":"","latitude":"45.693597","longitude":"9.667039","startingprice":"","gpxmap":"","iu_motor_accessibility":"notsure","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_kids":false,"iu_shortprice":"","iu_company_name":"Vismara Emiliano","registered_office":"","iu_addr_streetnumber":"Via Sant'Orsola, 4","iu_addr_postalcode":"24122","iu_addr_city":"Bergamo","iu_addr_province":"BG","iu_phone":"","iu_cell":"+393492843578","iu_website":"https:\/\/www.airbnb.it\/rooms\/1239043390815457668","iu_email":"emi.vismi@gmail.com","iu_vat":"vsmmln83e03b393h","iu_document_label":"","iu_document":false,"iu_documents":false,"iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_bookingurl":"","iu_videourl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"","iu_languages":"","iu_minpeople":"","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"iu_stars":"","iu_rooms":"1","iu_beds":"4","id_madeep":"","id_visit_manza":"10985","id_east":"","id_ristora":"","id_eppen":"","style":"primary","text":"","button_icon":"none","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"validfrom":"","validto":"","hours":"","tcm_content":false,"accessibilitycontent":{"tcm_content":false},"accessibilityicons":[],"time":"<p>Self check-in dalle 14:00.&#13;<br \/>\nCheck-out fino alle 10:00.<\/p>\n","ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":"","service_icons":[{"value":"laundry","label":"Lavanderia"},{"value":"wifi","label":"Wi-Fi"},{"value":"hairdryer","label":"Asciugacapelli"},{"value":"shower","label":"Bagni con doccia"}]},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/180476","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/180476\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media\/175317"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media?parent=180476"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/categories?post=180476"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/tags?post=180476"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/aggr?post=180476"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/area?post=180476"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/kind?post=180476"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/zona?post=180476"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}