{"id":180508,"date":"2025-04-18T13:39:41","date_gmt":"2025-04-18T11:39:41","guid":{"rendered":"https:\/\/visit.valueservice.cloud\/oggetto\/il-pozzo\/"},"modified":"2025-04-18T15:59:37","modified_gmt":"2025-04-18T13:59:37","slug":"il-pozzo","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/il-pozzo\/","title":{"rendered":"IL POZZO"},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":176092,"template":"","categories":[1002],"tags":[],"aggr":[],"area":[],"kind":[18725],"zona":[],"class_list":["post-180508","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-schlaf","kind-strutturaricettiva-de"],"acf":{"hero_type":"images","video_youtube_url":"","video_vimeo_url":"","size":"full","hero_title":"IL POZZO","hero_text":"","slides":[{"image":{"ID":176092,"id":176092,"title":"12587111453d2798123363b395984f8b_2e984574.jpg","filename":"12587111453d2798123363b395984f8b_2e984574-scaled.jpg","filesize":635207,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/12587111453d2798123363b395984f8b_2e984574-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/il-pozzo\/12587111453d2798123363b395984f8b_2e984574-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"12587111453d2798123363b395984f8b_2e984574-jpg-2","status":"inherit","uploaded_to":180508,"date":"2025-04-18 09:38:33","modified":"2025-04-18 13:59:42","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1920,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/12587111453d2798123363b395984f8b_2e984574-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/12587111453d2798123363b395984f8b_2e984574-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/12587111453d2798123363b395984f8b_2e984574-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/12587111453d2798123363b395984f8b_2e984574-1024x768.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/12587111453d2798123363b395984f8b_2e984574-1536x1152.jpg","1536x1536-width":1536,"1536x1536-height":1152,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/12587111453d2798123363b395984f8b_2e984574-2048x1536.jpg","2048x2048-width":2048,"2048x2048-height":1536,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/12587111453d2798123363b395984f8b_2e984574-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/12587111453d2798123363b395984f8b_2e984574-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/12587111453d2798123363b395984f8b_2e984574-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":176099,"id":176099,"title":"a752881dd9aebd5f8be67c8152c26553_06e3bcd1.jpg","filename":"a752881dd9aebd5f8be67c8152c26553_06e3bcd1-scaled.jpg","filesize":628462,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a752881dd9aebd5f8be67c8152c26553_06e3bcd1-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/il-pozzo\/a752881dd9aebd5f8be67c8152c26553_06e3bcd1-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"a752881dd9aebd5f8be67c8152c26553_06e3bcd1-jpg-2","status":"inherit","uploaded_to":180508,"date":"2025-04-18 09:38:35","modified":"2025-04-18 13:59:42","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":2560,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a752881dd9aebd5f8be67c8152c26553_06e3bcd1-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a752881dd9aebd5f8be67c8152c26553_06e3bcd1-300x300.jpg","medium-width":300,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a752881dd9aebd5f8be67c8152c26553_06e3bcd1-768x768.jpg","medium_large-width":768,"medium_large-height":768,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a752881dd9aebd5f8be67c8152c26553_06e3bcd1-1024x1024.jpg","large-width":1024,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a752881dd9aebd5f8be67c8152c26553_06e3bcd1-1536x1536.jpg","1536x1536-width":1536,"1536x1536-height":1536,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a752881dd9aebd5f8be67c8152c26553_06e3bcd1-2048x2048.jpg","2048x2048-width":2048,"2048x2048-height":2048,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a752881dd9aebd5f8be67c8152c26553_06e3bcd1-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a752881dd9aebd5f8be67c8152c26553_06e3bcd1-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a752881dd9aebd5f8be67c8152c26553_06e3bcd1-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":176106,"id":176106,"title":"65c11c5f417d72da1c992c3943c543b1_f0a0fc57.jpg","filename":"65c11c5f417d72da1c992c3943c543b1_f0a0fc57-scaled.jpg","filesize":444816,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/65c11c5f417d72da1c992c3943c543b1_f0a0fc57-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/il-pozzo\/65c11c5f417d72da1c992c3943c543b1_f0a0fc57-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"65c11c5f417d72da1c992c3943c543b1_f0a0fc57-jpg-2","status":"inherit","uploaded_to":180508,"date":"2025-04-18 09:38:38","modified":"2025-04-18 13:59:42","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1707,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/65c11c5f417d72da1c992c3943c543b1_f0a0fc57-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/65c11c5f417d72da1c992c3943c543b1_f0a0fc57-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/65c11c5f417d72da1c992c3943c543b1_f0a0fc57-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/65c11c5f417d72da1c992c3943c543b1_f0a0fc57-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/65c11c5f417d72da1c992c3943c543b1_f0a0fc57-1536x1024.jpg","1536x1536-width":1536,"1536x1536-height":1024,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/65c11c5f417d72da1c992c3943c543b1_f0a0fc57-2048x1365.jpg","2048x2048-width":2048,"2048x2048-height":1365,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/65c11c5f417d72da1c992c3943c543b1_f0a0fc57-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/65c11c5f417d72da1c992c3943c543b1_f0a0fc57-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/65c11c5f417d72da1c992c3943c543b1_f0a0fc57-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":176113,"id":176113,"title":"70d1c7282065146c0445de4a04347519_5d92f4f1.jpg","filename":"70d1c7282065146c0445de4a04347519_5d92f4f1.jpg","filesize":75643,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/70d1c7282065146c0445de4a04347519_5d92f4f1.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/il-pozzo\/70d1c7282065146c0445de4a04347519_5d92f4f1-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"70d1c7282065146c0445de4a04347519_5d92f4f1-jpg-2","status":"inherit","uploaded_to":180508,"date":"2025-04-18 09:38:41","modified":"2025-04-18 13:59:42","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":640,"height":480,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/70d1c7282065146c0445de4a04347519_5d92f4f1-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/70d1c7282065146c0445de4a04347519_5d92f4f1-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/70d1c7282065146c0445de4a04347519_5d92f4f1.jpg","medium_large-width":640,"medium_large-height":480,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/70d1c7282065146c0445de4a04347519_5d92f4f1.jpg","large-width":640,"large-height":480,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/70d1c7282065146c0445de4a04347519_5d92f4f1.jpg","1536x1536-width":640,"1536x1536-height":480,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/70d1c7282065146c0445de4a04347519_5d92f4f1.jpg","2048x2048-width":640,"2048x2048-height":480,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/70d1c7282065146c0445de4a04347519_5d92f4f1.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/70d1c7282065146c0445de4a04347519_5d92f4f1.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/70d1c7282065146c0445de4a04347519_5d92f4f1.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":176120,"id":176120,"title":"29cd4d12f3869a92df99067a287fb03d_f0a60c4b.jpg","filename":"29cd4d12f3869a92df99067a287fb03d_f0a60c4b.jpg","filesize":149259,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/29cd4d12f3869a92df99067a287fb03d_f0a60c4b.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/il-pozzo\/29cd4d12f3869a92df99067a287fb03d_f0a60c4b-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"29cd4d12f3869a92df99067a287fb03d_f0a60c4b-jpg-2","status":"inherit","uploaded_to":180508,"date":"2025-04-18 09:38:42","modified":"2025-04-18 13:59:42","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":640,"height":480,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/29cd4d12f3869a92df99067a287fb03d_f0a60c4b-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/29cd4d12f3869a92df99067a287fb03d_f0a60c4b-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/29cd4d12f3869a92df99067a287fb03d_f0a60c4b.jpg","medium_large-width":640,"medium_large-height":480,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/29cd4d12f3869a92df99067a287fb03d_f0a60c4b.jpg","large-width":640,"large-height":480,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/29cd4d12f3869a92df99067a287fb03d_f0a60c4b.jpg","1536x1536-width":640,"1536x1536-height":480,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/29cd4d12f3869a92df99067a287fb03d_f0a60c4b.jpg","2048x2048-width":640,"2048x2048-height":480,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/29cd4d12f3869a92df99067a287fb03d_f0a60c4b.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/29cd4d12f3869a92df99067a287fb03d_f0a60c4b.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/29cd4d12f3869a92df99067a287fb03d_f0a60c4b.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":176127,"id":176127,"title":"c137a940257c7a86d67e8924182ccce8_44166749.jpg","filename":"c137a940257c7a86d67e8924182ccce8_44166749.jpg","filesize":108774,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c137a940257c7a86d67e8924182ccce8_44166749.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/il-pozzo\/c137a940257c7a86d67e8924182ccce8_44166749-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"c137a940257c7a86d67e8924182ccce8_44166749-jpg-2","status":"inherit","uploaded_to":180508,"date":"2025-04-18 09:38:43","modified":"2025-04-18 13:59:42","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":720,"height":480,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c137a940257c7a86d67e8924182ccce8_44166749-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c137a940257c7a86d67e8924182ccce8_44166749-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c137a940257c7a86d67e8924182ccce8_44166749.jpg","medium_large-width":720,"medium_large-height":480,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c137a940257c7a86d67e8924182ccce8_44166749.jpg","large-width":720,"large-height":480,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c137a940257c7a86d67e8924182ccce8_44166749.jpg","1536x1536-width":720,"1536x1536-height":480,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c137a940257c7a86d67e8924182ccce8_44166749.jpg","2048x2048-width":720,"2048x2048-height":480,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c137a940257c7a86d67e8924182ccce8_44166749.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c137a940257c7a86d67e8924182ccce8_44166749.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c137a940257c7a86d67e8924182ccce8_44166749.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":176134,"id":176134,"title":"d0678b27c23a56ac4982c62f6ea68763_ab7c50e0.jpg","filename":"d0678b27c23a56ac4982c62f6ea68763_ab7c50e0.jpg","filesize":57735,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d0678b27c23a56ac4982c62f6ea68763_ab7c50e0.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/il-pozzo\/d0678b27c23a56ac4982c62f6ea68763_ab7c50e0-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"d0678b27c23a56ac4982c62f6ea68763_ab7c50e0-jpg-2","status":"inherit","uploaded_to":180508,"date":"2025-04-18 09:38:44","modified":"2025-04-18 13:59:42","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":720,"height":480,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d0678b27c23a56ac4982c62f6ea68763_ab7c50e0-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d0678b27c23a56ac4982c62f6ea68763_ab7c50e0-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d0678b27c23a56ac4982c62f6ea68763_ab7c50e0.jpg","medium_large-width":720,"medium_large-height":480,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d0678b27c23a56ac4982c62f6ea68763_ab7c50e0.jpg","large-width":720,"large-height":480,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d0678b27c23a56ac4982c62f6ea68763_ab7c50e0.jpg","1536x1536-width":720,"1536x1536-height":480,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d0678b27c23a56ac4982c62f6ea68763_ab7c50e0.jpg","2048x2048-width":720,"2048x2048-height":480,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d0678b27c23a56ac4982c62f6ea68763_ab7c50e0.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d0678b27c23a56ac4982c62f6ea68763_ab7c50e0.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d0678b27c23a56ac4982c62f6ea68763_ab7c50e0.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":176141,"id":176141,"title":"0aa1a264da4deb2a26fc57b097ff1018_24397f60.jpg","filename":"0aa1a264da4deb2a26fc57b097ff1018_24397f60.jpg","filesize":77443,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0aa1a264da4deb2a26fc57b097ff1018_24397f60.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/il-pozzo\/0aa1a264da4deb2a26fc57b097ff1018_24397f60-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"0aa1a264da4deb2a26fc57b097ff1018_24397f60-jpg-2","status":"inherit","uploaded_to":180508,"date":"2025-04-18 09:38:45","modified":"2025-04-18 13:59:42","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":720,"height":480,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0aa1a264da4deb2a26fc57b097ff1018_24397f60-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0aa1a264da4deb2a26fc57b097ff1018_24397f60-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0aa1a264da4deb2a26fc57b097ff1018_24397f60.jpg","medium_large-width":720,"medium_large-height":480,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0aa1a264da4deb2a26fc57b097ff1018_24397f60.jpg","large-width":720,"large-height":480,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0aa1a264da4deb2a26fc57b097ff1018_24397f60.jpg","1536x1536-width":720,"1536x1536-height":480,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0aa1a264da4deb2a26fc57b097ff1018_24397f60.jpg","2048x2048-width":720,"2048x2048-height":480,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0aa1a264da4deb2a26fc57b097ff1018_24397f60.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0aa1a264da4deb2a26fc57b097ff1018_24397f60.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0aa1a264da4deb2a26fc57b097ff1018_24397f60.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":176148,"id":176148,"title":"4b9362793ad1199ba7fb9590898a595d_71861c98.jpg","filename":"4b9362793ad1199ba7fb9590898a595d_71861c98.jpg","filesize":80904,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4b9362793ad1199ba7fb9590898a595d_71861c98.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/il-pozzo\/4b9362793ad1199ba7fb9590898a595d_71861c98-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"4b9362793ad1199ba7fb9590898a595d_71861c98-jpg-2","status":"inherit","uploaded_to":180508,"date":"2025-04-18 09:38:46","modified":"2025-04-18 13:59:42","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":720,"height":480,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4b9362793ad1199ba7fb9590898a595d_71861c98-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4b9362793ad1199ba7fb9590898a595d_71861c98-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4b9362793ad1199ba7fb9590898a595d_71861c98.jpg","medium_large-width":720,"medium_large-height":480,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4b9362793ad1199ba7fb9590898a595d_71861c98.jpg","large-width":720,"large-height":480,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4b9362793ad1199ba7fb9590898a595d_71861c98.jpg","1536x1536-width":720,"1536x1536-height":480,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4b9362793ad1199ba7fb9590898a595d_71861c98.jpg","2048x2048-width":720,"2048x2048-height":480,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4b9362793ad1199ba7fb9590898a595d_71861c98.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4b9362793ad1199ba7fb9590898a595d_71861c98.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4b9362793ad1199ba7fb9590898a595d_71861c98.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":176155,"id":176155,"title":"6e713bfe55105c234219fa6d720d5ec5_5be038b2.jpg","filename":"6e713bfe55105c234219fa6d720d5ec5_5be038b2.jpg","filesize":63599,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6e713bfe55105c234219fa6d720d5ec5_5be038b2.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/il-pozzo\/6e713bfe55105c234219fa6d720d5ec5_5be038b2-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"6e713bfe55105c234219fa6d720d5ec5_5be038b2-jpg-2","status":"inherit","uploaded_to":180508,"date":"2025-04-18 09:38:47","modified":"2025-04-18 13:59:42","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":720,"height":480,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6e713bfe55105c234219fa6d720d5ec5_5be038b2-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6e713bfe55105c234219fa6d720d5ec5_5be038b2-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6e713bfe55105c234219fa6d720d5ec5_5be038b2.jpg","medium_large-width":720,"medium_large-height":480,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6e713bfe55105c234219fa6d720d5ec5_5be038b2.jpg","large-width":720,"large-height":480,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6e713bfe55105c234219fa6d720d5ec5_5be038b2.jpg","1536x1536-width":720,"1536x1536-height":480,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6e713bfe55105c234219fa6d720d5ec5_5be038b2.jpg","2048x2048-width":720,"2048x2048-height":480,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6e713bfe55105c234219fa6d720d5ec5_5be038b2.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6e713bfe55105c234219fa6d720d5ec5_5be038b2.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6e713bfe55105c234219fa6d720d5ec5_5be038b2.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":176162,"id":176162,"title":"3a2ab796c5bb323553d81dbdf6a6946a_f9707e40.jpg","filename":"3a2ab796c5bb323553d81dbdf6a6946a_f9707e40.jpg","filesize":73941,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3a2ab796c5bb323553d81dbdf6a6946a_f9707e40.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/il-pozzo\/3a2ab796c5bb323553d81dbdf6a6946a_f9707e40-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"3a2ab796c5bb323553d81dbdf6a6946a_f9707e40-jpg-2","status":"inherit","uploaded_to":180508,"date":"2025-04-18 09:38:48","modified":"2025-04-18 13:59:42","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":720,"height":480,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3a2ab796c5bb323553d81dbdf6a6946a_f9707e40-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3a2ab796c5bb323553d81dbdf6a6946a_f9707e40-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3a2ab796c5bb323553d81dbdf6a6946a_f9707e40.jpg","medium_large-width":720,"medium_large-height":480,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3a2ab796c5bb323553d81dbdf6a6946a_f9707e40.jpg","large-width":720,"large-height":480,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3a2ab796c5bb323553d81dbdf6a6946a_f9707e40.jpg","1536x1536-width":720,"1536x1536-height":480,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3a2ab796c5bb323553d81dbdf6a6946a_f9707e40.jpg","2048x2048-width":720,"2048x2048-height":480,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3a2ab796c5bb323553d81dbdf6a6946a_f9707e40.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3a2ab796c5bb323553d81dbdf6a6946a_f9707e40.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3a2ab796c5bb323553d81dbdf6a6946a_f9707e40.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":176169,"id":176169,"title":"32c3417ed2e68e81bee2fa0eba5a38f4_ed96a657.jpg","filename":"32c3417ed2e68e81bee2fa0eba5a38f4_ed96a657.jpg","filesize":42872,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/32c3417ed2e68e81bee2fa0eba5a38f4_ed96a657.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/il-pozzo\/32c3417ed2e68e81bee2fa0eba5a38f4_ed96a657-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"32c3417ed2e68e81bee2fa0eba5a38f4_ed96a657-jpg-2","status":"inherit","uploaded_to":180508,"date":"2025-04-18 09:38:49","modified":"2025-04-18 13:59:42","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":720,"height":480,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/32c3417ed2e68e81bee2fa0eba5a38f4_ed96a657-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/32c3417ed2e68e81bee2fa0eba5a38f4_ed96a657-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/32c3417ed2e68e81bee2fa0eba5a38f4_ed96a657.jpg","medium_large-width":720,"medium_large-height":480,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/32c3417ed2e68e81bee2fa0eba5a38f4_ed96a657.jpg","large-width":720,"large-height":480,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/32c3417ed2e68e81bee2fa0eba5a38f4_ed96a657.jpg","1536x1536-width":720,"1536x1536-height":480,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/32c3417ed2e68e81bee2fa0eba5a38f4_ed96a657.jpg","2048x2048-width":720,"2048x2048-height":480,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/32c3417ed2e68e81bee2fa0eba5a38f4_ed96a657.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/32c3417ed2e68e81bee2fa0eba5a38f4_ed96a657.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/32c3417ed2e68e81bee2fa0eba5a38f4_ed96a657.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":176176,"id":176176,"title":"e55ec313d2c9c4d3a75febd149d2e655_c49640f1.jpg","filename":"e55ec313d2c9c4d3a75febd149d2e655_c49640f1.jpg","filesize":67771,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e55ec313d2c9c4d3a75febd149d2e655_c49640f1.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/il-pozzo\/e55ec313d2c9c4d3a75febd149d2e655_c49640f1-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"e55ec313d2c9c4d3a75febd149d2e655_c49640f1-jpg-2","status":"inherit","uploaded_to":180508,"date":"2025-04-18 09:38:50","modified":"2025-04-18 13:59:42","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":720,"height":480,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e55ec313d2c9c4d3a75febd149d2e655_c49640f1-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e55ec313d2c9c4d3a75febd149d2e655_c49640f1-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e55ec313d2c9c4d3a75febd149d2e655_c49640f1.jpg","medium_large-width":720,"medium_large-height":480,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e55ec313d2c9c4d3a75febd149d2e655_c49640f1.jpg","large-width":720,"large-height":480,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e55ec313d2c9c4d3a75febd149d2e655_c49640f1.jpg","1536x1536-width":720,"1536x1536-height":480,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e55ec313d2c9c4d3a75febd149d2e655_c49640f1.jpg","2048x2048-width":720,"2048x2048-height":480,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e55ec313d2c9c4d3a75febd149d2e655_c49640f1.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e55ec313d2c9c4d3a75febd149d2e655_c49640f1.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e55ec313d2c9c4d3a75febd149d2e655_c49640f1.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":176183,"id":176183,"title":"a0e7d19aa8a08c573217dfcb4e14fa7a_4a971ee5.jpg","filename":"a0e7d19aa8a08c573217dfcb4e14fa7a_4a971ee5.jpg","filesize":47044,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a0e7d19aa8a08c573217dfcb4e14fa7a_4a971ee5.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/il-pozzo\/a0e7d19aa8a08c573217dfcb4e14fa7a_4a971ee5-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"a0e7d19aa8a08c573217dfcb4e14fa7a_4a971ee5-jpg-2","status":"inherit","uploaded_to":180508,"date":"2025-04-18 09:38:51","modified":"2025-04-18 13:59:43","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":720,"height":480,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a0e7d19aa8a08c573217dfcb4e14fa7a_4a971ee5-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a0e7d19aa8a08c573217dfcb4e14fa7a_4a971ee5-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a0e7d19aa8a08c573217dfcb4e14fa7a_4a971ee5.jpg","medium_large-width":720,"medium_large-height":480,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a0e7d19aa8a08c573217dfcb4e14fa7a_4a971ee5.jpg","large-width":720,"large-height":480,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a0e7d19aa8a08c573217dfcb4e14fa7a_4a971ee5.jpg","1536x1536-width":720,"1536x1536-height":480,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a0e7d19aa8a08c573217dfcb4e14fa7a_4a971ee5.jpg","2048x2048-width":720,"2048x2048-height":480,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a0e7d19aa8a08c573217dfcb4e14fa7a_4a971ee5.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a0e7d19aa8a08c573217dfcb4e14fa7a_4a971ee5.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a0e7d19aa8a08c573217dfcb4e14fa7a_4a971ee5.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"buttons":false,"hero_buttons_group":{"buttons":false},"hero_buttons":false,"filotto_title":"","filotto_sub":"","filotto_layout":"","filotto_fill":"","only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":"","order_by":"","order_way":"","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":"","order_by":"","order_way":""},"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"","filotto_fill":"","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":"","order_by":"","order_way":""}},"description":"","indepth":"","howtogetthere":"","timerange":"","seasonality":"","pairings":"","curiosities":"","awards":"","cancellationpolicy":"","moredetails":"","whatsincluded":"","whatsnotincluded":"","price":"","time":"","services":"","parking":"","restaurant":"","breakfast":"","internet":"","children":"","pets":"","latitude":"45.705595","longitude":"9.664637","startingprice":"","gpxmap":"","iu_motor_accessibility":"notsure","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_kids":true,"iu_shortprice":"","iu_company_name":"MARIA ENRICA ZANETTI","registered_office":"VIA MARIO LUPO 1D","iu_addr_streetnumber":"Via S. Lorenzo, 36","iu_addr_postalcode":"24129","iu_addr_city":"Bergamo","iu_addr_province":"BG","iu_phone":"+39035226205","iu_cell":"+393356346313","iu_website":"http:\/\/www.casavacanzailpozzo.it","iu_email":"mariellazanetti27@gmail.com","iu_vat":"ZNTMNR57E67A794E","iu_document_label":"","iu_document":false,"iu_documents":false,"iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_bookingurl":"","iu_videourl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"","iu_languages":"","iu_minpeople":"","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"iu_stars":"","iu_rooms":"2","iu_beds":"7","id_madeep":"","id_visit_manza":"5361","id_east":"","id_ristora":"","id_eppen":"","style":"primary","text":"","button_icon":"none","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"validfrom":"","validto":"","hours":"","tcm_content":false,"accessibilitycontent":{"tcm_content":false},"accessibilityicons":[],"ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":"","service_icons":[{"value":"laundry","label":"Lavanderia"},{"value":"wifi","label":"Wi-Fi"},{"value":"hairdryer","label":"Asciugacapelli"},{"value":"shower","label":"Bagni con doccia"},{"value":"bathrooms","label":"Bagni con vasca"}]},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/180508","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/180508\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media\/176092"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media?parent=180508"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/categories?post=180508"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/tags?post=180508"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/aggr?post=180508"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/area?post=180508"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/kind?post=180508"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/zona?post=180508"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}