{"id":180555,"date":"2025-04-18T13:40:49","date_gmt":"2025-04-18T11:40:49","guid":{"rendered":"https:\/\/visit.valueservice.cloud\/oggetto\/balcone-al-sole\/"},"modified":"2025-04-18T16:00:58","modified_gmt":"2025-04-18T14:00:58","slug":"balcone-al-sole","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/balcone-al-sole\/","title":{"rendered":"Balcone al sole"},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":177028,"template":"","categories":[1002],"tags":[],"aggr":[],"area":[],"kind":[18725],"zona":[],"class_list":["post-180555","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-schlaf","kind-strutturaricettiva-de"],"acf":{"hero_type":"images","video_youtube_url":"","video_vimeo_url":"","size":"full","hero_title":"Balcone al sole","hero_text":"","slides":[{"image":{"ID":177028,"id":177028,"title":"54ca9dfb9490391b417bda331071ceb8_9c385940.jpg","filename":"54ca9dfb9490391b417bda331071ceb8_9c385940.jpg","filesize":110054,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/54ca9dfb9490391b417bda331071ceb8_9c385940.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/balcone-al-sole\/54ca9dfb9490391b417bda331071ceb8_9c385940-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"54ca9dfb9490391b417bda331071ceb8_9c385940-jpg-2","status":"inherit","uploaded_to":180555,"date":"2025-04-18 09:42:26","modified":"2025-04-18 14:01:20","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":753,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/54ca9dfb9490391b417bda331071ceb8_9c385940-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/54ca9dfb9490391b417bda331071ceb8_9c385940-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/54ca9dfb9490391b417bda331071ceb8_9c385940.jpg","medium_large-width":753,"medium_large-height":565,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/54ca9dfb9490391b417bda331071ceb8_9c385940.jpg","large-width":753,"large-height":565,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/54ca9dfb9490391b417bda331071ceb8_9c385940.jpg","1536x1536-width":753,"1536x1536-height":565,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/54ca9dfb9490391b417bda331071ceb8_9c385940.jpg","2048x2048-width":753,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/54ca9dfb9490391b417bda331071ceb8_9c385940.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/54ca9dfb9490391b417bda331071ceb8_9c385940.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/54ca9dfb9490391b417bda331071ceb8_9c385940.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":177035,"id":177035,"title":"87c42b475af8dd115690e6bd1b2a3dd4_d3096958.jpg","filename":"87c42b475af8dd115690e6bd1b2a3dd4_d3096958.jpg","filesize":133024,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/87c42b475af8dd115690e6bd1b2a3dd4_d3096958.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/balcone-al-sole\/87c42b475af8dd115690e6bd1b2a3dd4_d3096958-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"87c42b475af8dd115690e6bd1b2a3dd4_d3096958-jpg-2","status":"inherit","uploaded_to":180555,"date":"2025-04-18 09:42:27","modified":"2025-04-18 14:01:20","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":753,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/87c42b475af8dd115690e6bd1b2a3dd4_d3096958-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/87c42b475af8dd115690e6bd1b2a3dd4_d3096958-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/87c42b475af8dd115690e6bd1b2a3dd4_d3096958.jpg","medium_large-width":753,"medium_large-height":565,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/87c42b475af8dd115690e6bd1b2a3dd4_d3096958.jpg","large-width":753,"large-height":565,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/87c42b475af8dd115690e6bd1b2a3dd4_d3096958.jpg","1536x1536-width":753,"1536x1536-height":565,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/87c42b475af8dd115690e6bd1b2a3dd4_d3096958.jpg","2048x2048-width":753,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/87c42b475af8dd115690e6bd1b2a3dd4_d3096958.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/87c42b475af8dd115690e6bd1b2a3dd4_d3096958.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/87c42b475af8dd115690e6bd1b2a3dd4_d3096958.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":177042,"id":177042,"title":"e620eae1833f609d99a33832e086b516_131c58d8.jpg","filename":"e620eae1833f609d99a33832e086b516_131c58d8.jpg","filesize":105313,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e620eae1833f609d99a33832e086b516_131c58d8.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/balcone-al-sole\/e620eae1833f609d99a33832e086b516_131c58d8-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"e620eae1833f609d99a33832e086b516_131c58d8-jpg-2","status":"inherit","uploaded_to":180555,"date":"2025-04-18 09:42:28","modified":"2025-04-18 14:01:20","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":848,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e620eae1833f609d99a33832e086b516_131c58d8-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e620eae1833f609d99a33832e086b516_131c58d8-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e620eae1833f609d99a33832e086b516_131c58d8-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e620eae1833f609d99a33832e086b516_131c58d8.jpg","large-width":848,"large-height":565,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e620eae1833f609d99a33832e086b516_131c58d8.jpg","1536x1536-width":848,"1536x1536-height":565,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e620eae1833f609d99a33832e086b516_131c58d8.jpg","2048x2048-width":848,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e620eae1833f609d99a33832e086b516_131c58d8.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e620eae1833f609d99a33832e086b516_131c58d8.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e620eae1833f609d99a33832e086b516_131c58d8.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":177049,"id":177049,"title":"40da852ed5f12d526e422c2249b63a4a_d8bacb62.jpg","filename":"40da852ed5f12d526e422c2249b63a4a_d8bacb62.jpg","filesize":78242,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/40da852ed5f12d526e422c2249b63a4a_d8bacb62.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/balcone-al-sole\/40da852ed5f12d526e422c2249b63a4a_d8bacb62-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"40da852ed5f12d526e422c2249b63a4a_d8bacb62-jpg-2","status":"inherit","uploaded_to":180555,"date":"2025-04-18 09:42:29","modified":"2025-04-18 14:01:20","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":424,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/40da852ed5f12d526e422c2249b63a4a_d8bacb62-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/40da852ed5f12d526e422c2249b63a4a_d8bacb62-225x300.jpg","medium-width":225,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/40da852ed5f12d526e422c2249b63a4a_d8bacb62.jpg","medium_large-width":424,"medium_large-height":565,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/40da852ed5f12d526e422c2249b63a4a_d8bacb62.jpg","large-width":424,"large-height":565,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/40da852ed5f12d526e422c2249b63a4a_d8bacb62.jpg","1536x1536-width":424,"1536x1536-height":565,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/40da852ed5f12d526e422c2249b63a4a_d8bacb62.jpg","2048x2048-width":424,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/40da852ed5f12d526e422c2249b63a4a_d8bacb62.jpg","gform-image-choice-sm-width":225,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/40da852ed5f12d526e422c2249b63a4a_d8bacb62.jpg","gform-image-choice-md-width":300,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/40da852ed5f12d526e422c2249b63a4a_d8bacb62.jpg","gform-image-choice-lg-width":424,"gform-image-choice-lg-height":565}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":177056,"id":177056,"title":"ae2ed2543beda7e5e500e0a6a41f7bae_b3bebf33.jpg","filename":"ae2ed2543beda7e5e500e0a6a41f7bae_b3bebf33.jpg","filesize":119000,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ae2ed2543beda7e5e500e0a6a41f7bae_b3bebf33.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/balcone-al-sole\/ae2ed2543beda7e5e500e0a6a41f7bae_b3bebf33-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"ae2ed2543beda7e5e500e0a6a41f7bae_b3bebf33-jpg-2","status":"inherit","uploaded_to":180555,"date":"2025-04-18 09:42:30","modified":"2025-04-18 14:01:20","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":831,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ae2ed2543beda7e5e500e0a6a41f7bae_b3bebf33-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ae2ed2543beda7e5e500e0a6a41f7bae_b3bebf33-300x204.jpg","medium-width":300,"medium-height":204,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ae2ed2543beda7e5e500e0a6a41f7bae_b3bebf33-768x522.jpg","medium_large-width":768,"medium_large-height":522,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ae2ed2543beda7e5e500e0a6a41f7bae_b3bebf33.jpg","large-width":831,"large-height":565,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ae2ed2543beda7e5e500e0a6a41f7bae_b3bebf33.jpg","1536x1536-width":831,"1536x1536-height":565,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ae2ed2543beda7e5e500e0a6a41f7bae_b3bebf33.jpg","2048x2048-width":831,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ae2ed2543beda7e5e500e0a6a41f7bae_b3bebf33.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":204,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ae2ed2543beda7e5e500e0a6a41f7bae_b3bebf33.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":272,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ae2ed2543beda7e5e500e0a6a41f7bae_b3bebf33.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":408}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":177063,"id":177063,"title":"00fbfc9772322117aa028ba485d129d5_55749218.jpg","filename":"00fbfc9772322117aa028ba485d129d5_55749218.jpg","filesize":99628,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/00fbfc9772322117aa028ba485d129d5_55749218.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/balcone-al-sole\/00fbfc9772322117aa028ba485d129d5_55749218-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"00fbfc9772322117aa028ba485d129d5_55749218-jpg-2","status":"inherit","uploaded_to":180555,"date":"2025-04-18 09:42:31","modified":"2025-04-18 14:01:21","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":847,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/00fbfc9772322117aa028ba485d129d5_55749218-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/00fbfc9772322117aa028ba485d129d5_55749218-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/00fbfc9772322117aa028ba485d129d5_55749218-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/00fbfc9772322117aa028ba485d129d5_55749218.jpg","large-width":847,"large-height":565,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/00fbfc9772322117aa028ba485d129d5_55749218.jpg","1536x1536-width":847,"1536x1536-height":565,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/00fbfc9772322117aa028ba485d129d5_55749218.jpg","2048x2048-width":847,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/00fbfc9772322117aa028ba485d129d5_55749218.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/00fbfc9772322117aa028ba485d129d5_55749218.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/00fbfc9772322117aa028ba485d129d5_55749218.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":177070,"id":177070,"title":"a2734b32390a07101a4eeb6277974897_fd0641d6.jpg","filename":"a2734b32390a07101a4eeb6277974897_fd0641d6.jpg","filesize":121314,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a2734b32390a07101a4eeb6277974897_fd0641d6.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/balcone-al-sole\/a2734b32390a07101a4eeb6277974897_fd0641d6-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"a2734b32390a07101a4eeb6277974897_fd0641d6-jpg-2","status":"inherit","uploaded_to":180555,"date":"2025-04-18 09:42:32","modified":"2025-04-18 14:01:21","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":847,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a2734b32390a07101a4eeb6277974897_fd0641d6-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a2734b32390a07101a4eeb6277974897_fd0641d6-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a2734b32390a07101a4eeb6277974897_fd0641d6-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a2734b32390a07101a4eeb6277974897_fd0641d6.jpg","large-width":847,"large-height":565,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a2734b32390a07101a4eeb6277974897_fd0641d6.jpg","1536x1536-width":847,"1536x1536-height":565,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a2734b32390a07101a4eeb6277974897_fd0641d6.jpg","2048x2048-width":847,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a2734b32390a07101a4eeb6277974897_fd0641d6.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a2734b32390a07101a4eeb6277974897_fd0641d6.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a2734b32390a07101a4eeb6277974897_fd0641d6.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":177077,"id":177077,"title":"a6576e292d5cc6905b2de59dcd2e1d60_e88a1c10.jpg","filename":"a6576e292d5cc6905b2de59dcd2e1d60_e88a1c10.jpg","filesize":103600,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a6576e292d5cc6905b2de59dcd2e1d60_e88a1c10.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/balcone-al-sole\/a6576e292d5cc6905b2de59dcd2e1d60_e88a1c10-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"a6576e292d5cc6905b2de59dcd2e1d60_e88a1c10-jpg-2","status":"inherit","uploaded_to":180555,"date":"2025-04-18 09:42:33","modified":"2025-04-18 14:01:21","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":565,"height":848,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a6576e292d5cc6905b2de59dcd2e1d60_e88a1c10-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a6576e292d5cc6905b2de59dcd2e1d60_e88a1c10-200x300.jpg","medium-width":200,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a6576e292d5cc6905b2de59dcd2e1d60_e88a1c10.jpg","medium_large-width":565,"medium_large-height":848,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a6576e292d5cc6905b2de59dcd2e1d60_e88a1c10.jpg","large-width":565,"large-height":848,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a6576e292d5cc6905b2de59dcd2e1d60_e88a1c10.jpg","1536x1536-width":565,"1536x1536-height":848,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a6576e292d5cc6905b2de59dcd2e1d60_e88a1c10.jpg","2048x2048-width":565,"2048x2048-height":848,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a6576e292d5cc6905b2de59dcd2e1d60_e88a1c10.jpg","gform-image-choice-sm-width":200,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a6576e292d5cc6905b2de59dcd2e1d60_e88a1c10.jpg","gform-image-choice-md-width":267,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a6576e292d5cc6905b2de59dcd2e1d60_e88a1c10.jpg","gform-image-choice-lg-width":400,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":177084,"id":177084,"title":"d3f4c28a4a2a30867cf309a0c058330b_5a59457b.jpg","filename":"d3f4c28a4a2a30867cf309a0c058330b_5a59457b.jpg","filesize":189543,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d3f4c28a4a2a30867cf309a0c058330b_5a59457b.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/balcone-al-sole\/d3f4c28a4a2a30867cf309a0c058330b_5a59457b-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"d3f4c28a4a2a30867cf309a0c058330b_5a59457b-jpg-2","status":"inherit","uploaded_to":180555,"date":"2025-04-18 09:42:34","modified":"2025-04-18 14:01:21","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":565,"height":753,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d3f4c28a4a2a30867cf309a0c058330b_5a59457b-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d3f4c28a4a2a30867cf309a0c058330b_5a59457b-225x300.jpg","medium-width":225,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d3f4c28a4a2a30867cf309a0c058330b_5a59457b.jpg","medium_large-width":565,"medium_large-height":753,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d3f4c28a4a2a30867cf309a0c058330b_5a59457b.jpg","large-width":565,"large-height":753,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d3f4c28a4a2a30867cf309a0c058330b_5a59457b.jpg","1536x1536-width":565,"1536x1536-height":753,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d3f4c28a4a2a30867cf309a0c058330b_5a59457b.jpg","2048x2048-width":565,"2048x2048-height":753,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d3f4c28a4a2a30867cf309a0c058330b_5a59457b.jpg","gform-image-choice-sm-width":225,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d3f4c28a4a2a30867cf309a0c058330b_5a59457b.jpg","gform-image-choice-md-width":300,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d3f4c28a4a2a30867cf309a0c058330b_5a59457b.jpg","gform-image-choice-lg-width":450,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"buttons":false,"hero_buttons_group":{"buttons":false},"hero_buttons":false,"filotto_title":"","filotto_sub":"","filotto_layout":"","filotto_fill":"","only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":"","order_by":"","order_way":"","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":"","order_by":"","order_way":""},"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"","filotto_fill":"","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":"","order_by":"","order_way":""}},"description":"","indepth":"","howtogetthere":"","timerange":"","seasonality":"","pairings":"","curiosities":"","awards":"","cancellationpolicy":"","moredetails":"","whatsincluded":"","whatsnotincluded":"","price":"","services":"","parking":"","restaurant":"","breakfast":"","internet":"","children":"","pets":"","latitude":"45.711456","longitude":"9.697275","startingprice":"","gpxmap":"","iu_motor_accessibility":"notsure","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_kids":false,"iu_shortprice":"","iu_company_name":"Barbara Cremaschi","registered_office":"via Giacomo Radini Tedeschi 8 &#13;\n24124 Bergamo","iu_addr_streetnumber":"Via Giacomo Radini Tedeschi, 8","iu_addr_postalcode":"24124","iu_addr_city":"Bergamo","iu_addr_province":"BG","iu_phone":"","iu_cell":"3356787102","iu_website":"","iu_email":"barcre149@gmail.com","iu_vat":"","iu_document_label":"","iu_document":false,"iu_documents":false,"iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_bookingurl":"","iu_videourl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"","iu_languages":"","iu_minpeople":"","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"iu_stars":"","iu_rooms":"1","iu_beds":"3","id_madeep":"","id_visit_manza":"10748","id_east":"","id_ristora":"","id_eppen":"","style":"primary","text":"","button_icon":"none","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"validfrom":"","validto":"","hours":"","tcm_content":false,"accessibilitycontent":{"tcm_content":false},"accessibilityicons":[],"time":"<p>check in 15.00-21.00&#13;<br \/>\ncheck out 10.00<\/p>\n","ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":"","service_icons":[{"value":"elevator","label":"Ascensore"},{"value":"parking","label":"Parcheggio gratuito"},{"value":"wifi","label":"Wi-Fi"},{"value":"air_conditioner","label":"Aria condizionata"},{"value":"hairdryer","label":"Asciugacapelli"},{"value":"shower","label":"Bagni con doccia"},{"value":"balcony","label":"Balcone"},{"value":"tv_room","label":"TV in camera"}]},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/180555","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/180555\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media\/177028"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media?parent=180555"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/categories?post=180555"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/tags?post=180555"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/aggr?post=180555"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/area?post=180555"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/kind?post=180555"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/zona?post=180555"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}