{"id":182180,"date":"2025-04-18T13:24:07","date_gmt":"2025-04-18T11:24:07","guid":{"rendered":"https:\/\/visit.valueservice.cloud\/oggetto\/uptown-bnb-2-pietro\/"},"modified":"2025-04-18T13:24:07","modified_gmt":"2025-04-18T11:24:07","slug":"uptown-bnb-2-pietro","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/uptown-bnb-2-pietro\/","title":{"rendered":"UpTown B&#8217;n&#8217;B &#8211; 2 pi\u0119tro"},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":162665,"template":"","categories":[991],"tags":[],"aggr":[],"area":[],"kind":[987],"zona":[],"class_list":["post-182180","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-dormire","kind-strutturaricettiva"],"acf":{"slides":[{"image":{"ID":162663,"id":162663,"title":"cd382bb335d068abee032d5ac45c97c3_8a0df1cf.jpg","filename":"cd382bb335d068abee032d5ac45c97c3_8a0df1cf.jpg","filesize":45315,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/cd382bb335d068abee032d5ac45c97c3_8a0df1cf.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/uptown-bnb-2nd-floor\/cd382bb335d068abee032d5ac45c97c3_8a0df1cf-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"cd382bb335d068abee032d5ac45c97c3_8a0df1cf-jpg-2","status":"inherit","uploaded_to":179302,"date":"2025-04-18 08:38:50","modified":"2025-04-18 13:39:51","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":480,"height":360,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/cd382bb335d068abee032d5ac45c97c3_8a0df1cf-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/cd382bb335d068abee032d5ac45c97c3_8a0df1cf-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/cd382bb335d068abee032d5ac45c97c3_8a0df1cf.jpg","medium_large-width":480,"medium_large-height":360,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/cd382bb335d068abee032d5ac45c97c3_8a0df1cf.jpg","large-width":480,"large-height":360,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/cd382bb335d068abee032d5ac45c97c3_8a0df1cf.jpg","1536x1536-width":480,"1536x1536-height":360,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/cd382bb335d068abee032d5ac45c97c3_8a0df1cf.jpg","2048x2048-width":480,"2048x2048-height":360,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/cd382bb335d068abee032d5ac45c97c3_8a0df1cf.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/cd382bb335d068abee032d5ac45c97c3_8a0df1cf.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/cd382bb335d068abee032d5ac45c97c3_8a0df1cf.jpg","gform-image-choice-lg-width":480,"gform-image-choice-lg-height":360}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":162670,"id":162670,"title":"effb22b1a0216491b0a58df106ad6ded_2d73c864.png","filename":"effb22b1a0216491b0a58df106ad6ded_2d73c864-scaled.png","filesize":3656930,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/effb22b1a0216491b0a58df106ad6ded_2d73c864-scaled.png","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/uptown-bnb-2nd-floor\/effb22b1a0216491b0a58df106ad6ded_2d73c864-png-2\/","alt":"","author":"0","description":"","caption":"","name":"effb22b1a0216491b0a58df106ad6ded_2d73c864-png-2","status":"inherit","uploaded_to":179302,"date":"2025-04-18 08:38:51","modified":"2025-04-18 13:39:52","menu_order":0,"mime_type":"image\/png","type":"image","subtype":"png","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1920,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/effb22b1a0216491b0a58df106ad6ded_2d73c864-150x150.png","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/effb22b1a0216491b0a58df106ad6ded_2d73c864-300x225.png","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/effb22b1a0216491b0a58df106ad6ded_2d73c864-768x576.png","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/effb22b1a0216491b0a58df106ad6ded_2d73c864-1024x768.png","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/effb22b1a0216491b0a58df106ad6ded_2d73c864-1536x1152.png","1536x1536-width":1536,"1536x1536-height":1152,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/effb22b1a0216491b0a58df106ad6ded_2d73c864-2048x1536.png","2048x2048-width":2048,"2048x2048-height":1536,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/effb22b1a0216491b0a58df106ad6ded_2d73c864-scaled.png","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/effb22b1a0216491b0a58df106ad6ded_2d73c864-scaled.png","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/effb22b1a0216491b0a58df106ad6ded_2d73c864-scaled.png","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":162677,"id":162677,"title":"0e8abdebfc5a5895945850d1102bd6f7_0d2477a6.png","filename":"0e8abdebfc5a5895945850d1102bd6f7_0d2477a6-scaled.png","filesize":3221630,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0e8abdebfc5a5895945850d1102bd6f7_0d2477a6-scaled.png","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/uptown-bnb-2nd-floor\/0e8abdebfc5a5895945850d1102bd6f7_0d2477a6-png-2\/","alt":"","author":"0","description":"","caption":"","name":"0e8abdebfc5a5895945850d1102bd6f7_0d2477a6-png-2","status":"inherit","uploaded_to":179302,"date":"2025-04-18 08:39:32","modified":"2025-04-18 13:39:52","menu_order":0,"mime_type":"image\/png","type":"image","subtype":"png","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1921,"height":2560,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0e8abdebfc5a5895945850d1102bd6f7_0d2477a6-150x150.png","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0e8abdebfc5a5895945850d1102bd6f7_0d2477a6-225x300.png","medium-width":225,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0e8abdebfc5a5895945850d1102bd6f7_0d2477a6-768x1023.png","medium_large-width":768,"medium_large-height":1023,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0e8abdebfc5a5895945850d1102bd6f7_0d2477a6-768x1024.png","large-width":768,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0e8abdebfc5a5895945850d1102bd6f7_0d2477a6-1153x1536.png","1536x1536-width":1153,"1536x1536-height":1536,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0e8abdebfc5a5895945850d1102bd6f7_0d2477a6-1537x2048.png","2048x2048-width":1537,"2048x2048-height":2048,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0e8abdebfc5a5895945850d1102bd6f7_0d2477a6-scaled.png","gform-image-choice-sm-width":225,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0e8abdebfc5a5895945850d1102bd6f7_0d2477a6-scaled.png","gform-image-choice-md-width":300,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0e8abdebfc5a5895945850d1102bd6f7_0d2477a6-scaled.png","gform-image-choice-lg-width":450,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":162684,"id":162684,"title":"1d26fbd76037ba1a4433491d155edab2_68b488ba.png","filename":"1d26fbd76037ba1a4433491d155edab2_68b488ba.png","filesize":653305,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1d26fbd76037ba1a4433491d155edab2_68b488ba.png","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/uptown-bnb-2nd-floor\/1d26fbd76037ba1a4433491d155edab2_68b488ba-png-2\/","alt":"","author":"0","description":"","caption":"","name":"1d26fbd76037ba1a4433491d155edab2_68b488ba-png-2","status":"inherit","uploaded_to":179302,"date":"2025-04-18 08:40:10","modified":"2025-04-18 13:39:52","menu_order":0,"mime_type":"image\/png","type":"image","subtype":"png","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":975,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1d26fbd76037ba1a4433491d155edab2_68b488ba-150x150.png","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1d26fbd76037ba1a4433491d155edab2_68b488ba-300x174.png","medium-width":300,"medium-height":174,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1d26fbd76037ba1a4433491d155edab2_68b488ba-768x445.png","medium_large-width":768,"medium_large-height":445,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1d26fbd76037ba1a4433491d155edab2_68b488ba.png","large-width":975,"large-height":565,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1d26fbd76037ba1a4433491d155edab2_68b488ba.png","1536x1536-width":975,"1536x1536-height":565,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1d26fbd76037ba1a4433491d155edab2_68b488ba.png","2048x2048-width":975,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1d26fbd76037ba1a4433491d155edab2_68b488ba.png","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":174,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1d26fbd76037ba1a4433491d155edab2_68b488ba.png","gform-image-choice-md-width":400,"gform-image-choice-md-height":232,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1d26fbd76037ba1a4433491d155edab2_68b488ba.png","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":348}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":162691,"id":162691,"title":"f6d9f402612e790d4c37d03450aeb51e_4b5ae05b.png","filename":"f6d9f402612e790d4c37d03450aeb51e_4b5ae05b.png","filesize":575825,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f6d9f402612e790d4c37d03450aeb51e_4b5ae05b.png","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/uptown-bnb-2nd-floor\/f6d9f402612e790d4c37d03450aeb51e_4b5ae05b-png-2\/","alt":"","author":"0","description":"","caption":"","name":"f6d9f402612e790d4c37d03450aeb51e_4b5ae05b-png-2","status":"inherit","uploaded_to":179302,"date":"2025-04-18 08:40:12","modified":"2025-04-18 13:39:52","menu_order":0,"mime_type":"image\/png","type":"image","subtype":"png","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":909,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f6d9f402612e790d4c37d03450aeb51e_4b5ae05b-150x150.png","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f6d9f402612e790d4c37d03450aeb51e_4b5ae05b-300x186.png","medium-width":300,"medium-height":186,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f6d9f402612e790d4c37d03450aeb51e_4b5ae05b-768x477.png","medium_large-width":768,"medium_large-height":477,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f6d9f402612e790d4c37d03450aeb51e_4b5ae05b.png","large-width":909,"large-height":565,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f6d9f402612e790d4c37d03450aeb51e_4b5ae05b.png","1536x1536-width":909,"1536x1536-height":565,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f6d9f402612e790d4c37d03450aeb51e_4b5ae05b.png","2048x2048-width":909,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f6d9f402612e790d4c37d03450aeb51e_4b5ae05b.png","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":186,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f6d9f402612e790d4c37d03450aeb51e_4b5ae05b.png","gform-image-choice-md-width":400,"gform-image-choice-md-height":249,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f6d9f402612e790d4c37d03450aeb51e_4b5ae05b.png","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":373}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":162698,"id":162698,"title":"660b64f1248c81c0f6dcf9191b847e02_308f0ef6.png","filename":"660b64f1248c81c0f6dcf9191b847e02_308f0ef6.png","filesize":375256,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/660b64f1248c81c0f6dcf9191b847e02_308f0ef6.png","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/uptown-bnb-2nd-floor\/660b64f1248c81c0f6dcf9191b847e02_308f0ef6-png-2\/","alt":"","author":"0","description":"","caption":"","name":"660b64f1248c81c0f6dcf9191b847e02_308f0ef6-png-2","status":"inherit","uploaded_to":179302,"date":"2025-04-18 08:40:14","modified":"2025-04-18 13:39:52","menu_order":0,"mime_type":"image\/png","type":"image","subtype":"png","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":863,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/660b64f1248c81c0f6dcf9191b847e02_308f0ef6-150x150.png","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/660b64f1248c81c0f6dcf9191b847e02_308f0ef6-300x196.png","medium-width":300,"medium-height":196,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/660b64f1248c81c0f6dcf9191b847e02_308f0ef6-768x503.png","medium_large-width":768,"medium_large-height":503,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/660b64f1248c81c0f6dcf9191b847e02_308f0ef6.png","large-width":863,"large-height":565,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/660b64f1248c81c0f6dcf9191b847e02_308f0ef6.png","1536x1536-width":863,"1536x1536-height":565,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/660b64f1248c81c0f6dcf9191b847e02_308f0ef6.png","2048x2048-width":863,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/660b64f1248c81c0f6dcf9191b847e02_308f0ef6.png","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":196,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/660b64f1248c81c0f6dcf9191b847e02_308f0ef6.png","gform-image-choice-md-width":400,"gform-image-choice-md-height":262,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/660b64f1248c81c0f6dcf9191b847e02_308f0ef6.png","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":393}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":162705,"id":162705,"title":"0eb6e5f5727e2344c4e9a0204588d6ea_f84a3035.png","filename":"0eb6e5f5727e2344c4e9a0204588d6ea_f84a3035.png","filesize":551432,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0eb6e5f5727e2344c4e9a0204588d6ea_f84a3035.png","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/uptown-bnb-2nd-floor\/0eb6e5f5727e2344c4e9a0204588d6ea_f84a3035-png-2\/","alt":"","author":"0","description":"","caption":"","name":"0eb6e5f5727e2344c4e9a0204588d6ea_f84a3035-png-2","status":"inherit","uploaded_to":179302,"date":"2025-04-18 08:40:16","modified":"2025-04-18 13:39:52","menu_order":0,"mime_type":"image\/png","type":"image","subtype":"png","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":911,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0eb6e5f5727e2344c4e9a0204588d6ea_f84a3035-150x150.png","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0eb6e5f5727e2344c4e9a0204588d6ea_f84a3035-300x186.png","medium-width":300,"medium-height":186,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0eb6e5f5727e2344c4e9a0204588d6ea_f84a3035-768x476.png","medium_large-width":768,"medium_large-height":476,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0eb6e5f5727e2344c4e9a0204588d6ea_f84a3035.png","large-width":911,"large-height":565,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0eb6e5f5727e2344c4e9a0204588d6ea_f84a3035.png","1536x1536-width":911,"1536x1536-height":565,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0eb6e5f5727e2344c4e9a0204588d6ea_f84a3035.png","2048x2048-width":911,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0eb6e5f5727e2344c4e9a0204588d6ea_f84a3035.png","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":186,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0eb6e5f5727e2344c4e9a0204588d6ea_f84a3035.png","gform-image-choice-md-width":400,"gform-image-choice-md-height":248,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0eb6e5f5727e2344c4e9a0204588d6ea_f84a3035.png","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":372}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":162712,"id":162712,"title":"70712576aecd4918262690185a259852_c94d88e0.png","filename":"70712576aecd4918262690185a259852_c94d88e0.png","filesize":608275,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/70712576aecd4918262690185a259852_c94d88e0.png","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/uptown-bnb-2nd-floor\/70712576aecd4918262690185a259852_c94d88e0-png-2\/","alt":"","author":"0","description":"","caption":"","name":"70712576aecd4918262690185a259852_c94d88e0-png-2","status":"inherit","uploaded_to":179302,"date":"2025-04-18 08:40:17","modified":"2025-04-18 13:39:52","menu_order":0,"mime_type":"image\/png","type":"image","subtype":"png","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":753,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/70712576aecd4918262690185a259852_c94d88e0-150x150.png","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/70712576aecd4918262690185a259852_c94d88e0-300x225.png","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/70712576aecd4918262690185a259852_c94d88e0.png","medium_large-width":753,"medium_large-height":565,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/70712576aecd4918262690185a259852_c94d88e0.png","large-width":753,"large-height":565,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/70712576aecd4918262690185a259852_c94d88e0.png","1536x1536-width":753,"1536x1536-height":565,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/70712576aecd4918262690185a259852_c94d88e0.png","2048x2048-width":753,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/70712576aecd4918262690185a259852_c94d88e0.png","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/70712576aecd4918262690185a259852_c94d88e0.png","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/70712576aecd4918262690185a259852_c94d88e0.png","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":162719,"id":162719,"title":"3a988ab5b4545dec05d17687680dbe9d_935ee5cb.png","filename":"3a988ab5b4545dec05d17687680dbe9d_935ee5cb.png","filesize":690201,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3a988ab5b4545dec05d17687680dbe9d_935ee5cb.png","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/uptown-bnb-2nd-floor\/3a988ab5b4545dec05d17687680dbe9d_935ee5cb-png-2\/","alt":"","author":"0","description":"","caption":"","name":"3a988ab5b4545dec05d17687680dbe9d_935ee5cb-png-2","status":"inherit","uploaded_to":179302,"date":"2025-04-18 08:40:19","modified":"2025-04-18 13:39:52","menu_order":0,"mime_type":"image\/png","type":"image","subtype":"png","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":753,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3a988ab5b4545dec05d17687680dbe9d_935ee5cb-150x150.png","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3a988ab5b4545dec05d17687680dbe9d_935ee5cb-300x225.png","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3a988ab5b4545dec05d17687680dbe9d_935ee5cb.png","medium_large-width":753,"medium_large-height":565,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3a988ab5b4545dec05d17687680dbe9d_935ee5cb.png","large-width":753,"large-height":565,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3a988ab5b4545dec05d17687680dbe9d_935ee5cb.png","1536x1536-width":753,"1536x1536-height":565,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3a988ab5b4545dec05d17687680dbe9d_935ee5cb.png","2048x2048-width":753,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3a988ab5b4545dec05d17687680dbe9d_935ee5cb.png","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3a988ab5b4545dec05d17687680dbe9d_935ee5cb.png","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3a988ab5b4545dec05d17687680dbe9d_935ee5cb.png","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":162726,"id":162726,"title":"035e34d63879d7bfee8d310f9ef9dc48_0f2de464.png","filename":"035e34d63879d7bfee8d310f9ef9dc48_0f2de464.png","filesize":343737,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/035e34d63879d7bfee8d310f9ef9dc48_0f2de464.png","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/uptown-bnb-2nd-floor\/035e34d63879d7bfee8d310f9ef9dc48_0f2de464-png-2\/","alt":"","author":"0","description":"","caption":"","name":"035e34d63879d7bfee8d310f9ef9dc48_0f2de464-png-2","status":"inherit","uploaded_to":179302,"date":"2025-04-18 08:40:20","modified":"2025-04-18 13:39:52","menu_order":0,"mime_type":"image\/png","type":"image","subtype":"png","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":502,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/035e34d63879d7bfee8d310f9ef9dc48_0f2de464-150x150.png","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/035e34d63879d7bfee8d310f9ef9dc48_0f2de464-267x300.png","medium-width":267,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/035e34d63879d7bfee8d310f9ef9dc48_0f2de464.png","medium_large-width":502,"medium_large-height":565,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/035e34d63879d7bfee8d310f9ef9dc48_0f2de464.png","large-width":502,"large-height":565,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/035e34d63879d7bfee8d310f9ef9dc48_0f2de464.png","1536x1536-width":502,"1536x1536-height":565,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/035e34d63879d7bfee8d310f9ef9dc48_0f2de464.png","2048x2048-width":502,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/035e34d63879d7bfee8d310f9ef9dc48_0f2de464.png","gform-image-choice-sm-width":267,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/035e34d63879d7bfee8d310f9ef9dc48_0f2de464.png","gform-image-choice-md-width":355,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/035e34d63879d7bfee8d310f9ef9dc48_0f2de464.png","gform-image-choice-lg-width":502,"gform-image-choice-lg-height":565}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"","filotto_fill":"","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""}},"filotto_layout":"","filotto_fill":"","button_icon":"none","tcm_content":false,"style":"primary","icon":{"button_icon":"none"},"target":"_self","hero_type":"images","hero_buttons":false,"function":"link","target_modal":"","latitude":"45.703130","longitude":"9.664934","accessibilitycontent":{"tcm_content":false},"startingprice":"","gpxmap":"","id_madeep":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"iu_kids":true,"iu_shortprice":"","iu_addr_postalcode":"24129","iu_addr_city":"Bergamo","iu_addr_province":"BG","iu_phone":"+390354890227","iu_cell":"","iu_email":"info@uptownbnb.it","iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_gpxtrack":"","size":"full","id_visit_manza":"5770","iu_motor_accessibility":"notsure","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""},"max_elements":"","show_total":false,"see_all":false,"order_by":"","order_way":"","id_east":"","id_ristora":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"validfrom":"","validto":"","only_ambassadors":false,"id_eppen":"","hours":"","accessibilityicons":[],"description":"<p>Do dyspozycji naszych go\u015bci oddajemy 2 komfortowe pokoje: pok\u00f3j dwuosobowy z \u0142\u00f3\u017ckiem ma\u0142\u017ce\u0144skim oraz 1 wi\u0119kszy pok\u00f3j trzyosobowy z \u0142\u00f3\u017ckiem ma\u0142\u017ce\u0144skim i pojedynczym, przeznaczony dla rodzin lub grup 3-osobowych.<br \/>\nMamy niesamowit\u0105 stref\u0119 \u015bniadaniow\u0105, w kt\u00f3rej nasi go\u015bcie mog\u0105 podziwia\u0107 z g\u00f3ry pi\u0119kny Piazza Angelini i zabytki historycznego centrum, kt\u00f3re prowadz\u0105 prosto do Piazza Vecchia. Nasze \u015bniadania s\u0105 w wi\u0119kszo\u015bci wega\u0144skie lub wegetaria\u0144skie, ale szanujemy wszystkie tradycje kulinarne i oferujemy kilka mi\u0119so\u017cernych rozwi\u0105za\u0144 dla mi\u0142o\u015bnik\u00f3w solidnych \u015bniada\u0144, wszystkie \u015bci\u015ble 0 km i ekologiczne.<\/p>\n","hero_title":"UpTown B'n'B - 2 pi\u0119tro","hero_text":"<p>Up Town B&#8217;n&#8217;B to pierwszy wynajem w sercu Bergamo Alta, ca\u0142kowicie zrealizowany zgodnie z filozofi\u0105 ekologicznego wyposa\u017cenia i Km 0. Z obu stron roztacza si\u0119 zapieraj\u0105cy dech w piersiach widok na place Mercato delle Scarpe i Piazzetta Luigi Angelini. <\/p>\n","indepth":"<p>UpTown B&#8217;n&#8217;B to nowoczesny obiekt, w kt\u00f3rym mo\u017cesz cieszy\u0107 si\u0119 kulturalnym weekendem, sp\u0119dzi\u0107 noc w podr\u00f3\u017cy s\u0142u\u017cbowej, zarezerwowa\u0107 ca\u0142e mieszkanie, gdy przyje\u017cd\u017casz z ca\u0142\u0105 rodzin\u0105, wybra\u0107, kt\u00f3re \u015bniadania chcesz i o kt\u00f3rej godzinie. To nowy spos\u00f3b sp\u0119dzania wakacji, w 100% konfigurowalne do\u015bwiadczenie, w kt\u00f3rym nasi go\u015bcie mog\u0105 czu\u0107 si\u0119 swobodnie.<\/p>\n","howtogetthere":"<p>Staramy si\u0119 promowa\u0107 korzystanie z transportu publicznego i zr\u00f3wnowa\u017con\u0105 mobilno\u015b\u0107, jeste\u015bmy \u0142atwo dost\u0119pni autobusem i kolejk\u0105 linow\u0105, bezpo\u015brednio po\u0142\u0105czeni z centralnym dworcem kolejowym i lotniskiem Orio al Serio.Z lotniska Orio al Serio: linia 1 autobus lotniskowy i kolejka linowaZ dworca centralnego: linia 1A i 1 kolejka linowaZ dolnej kolejki linowej: 2 min.<\/p>\n","price":"<p>\u015arednia cena 30 \u20ac za osob\u0119\/noc<\/p>\n","time":"<p>Zameldowanie: od 15:00 do 00:00Wymeldowanie: do 12:00<\/p>\n","iu_addr_streetnumber":"Piazzetta Luigi Angelini, 15","iu_website":"http:\/\/uptownbnb.it","url":""},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/182180","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/182180\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media\/162665"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media?parent=182180"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/categories?post=182180"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/tags?post=182180"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/aggr?post=182180"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/area?post=182180"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/kind?post=182180"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/zona?post=182180"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}