{"id":19831,"date":"2024-05-08T11:03:31","date_gmt":"2024-05-08T09:03:31","guid":{"rendered":"https:\/\/visitstg2.visitbergamo.net\/oggetto\/via-porta-dipinta\/"},"modified":"2025-02-16T09:46:51","modified_gmt":"2025-02-16T08:46:51","slug":"via-porta-dipinta","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/via-porta-dipinta\/","title":{"rendered":"\u00dcber die Porta Dipinta"},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":3416,"template":"","categories":[],"tags":[],"aggr":[],"area":[867],"kind":[18680],"zona":[18760],"class_list":["post-19831","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","area-bergamo","kind-poi-de","zona-bergamo-de"],"acf":{"hero_text":"","filotto_title":"","filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"scroll","filotto_fill":"manual","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""}},"indepth":"","howtogetthere":"","timerange":"","cancellationpolicy":"","moredetails":"","whatsincluded":"","whatsnotincluded":"","price":"","time":"","latitude":"","longitude":"","startingprice":"","gpxmap":"","iu_motor_accessibility":"no","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_shortprice":"","iu_addr_postalcode":"","iu_addr_city":"Bergamo","iu_addr_province":"","iu_phone":"","iu_cell":"","iu_website":"","iu_email":"","iu_document":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_bookingurl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"","iu_languages":"","iu_minpeople":"","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","id_madeep":"","id_visit_manza":"10272","url":"","url_youtube":"","cta":{"style":"","text":"","icon":{"button_icon":"none"},"function":"","url":"","target":"","url_youtube":"","target_modal":""},"button_icon":"none","tcm_content":[{"acf_fc_layout":"title","title_tag":"h3","title_text":"Das Datenblatt"},{"acf_fc_layout":"text","text":""}],"description":"<div class=\"page\" title=\"Seite 41\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p style=\"text-align: justify;\"><span>Diese wichtige Zufahrtsstra\u00dfe zur Stadt hat ihren Namen von einer mit Fresken bemalten T\u00fcr in der mittelalterlichen Stadtmauer, die im 19. Jahrhundert abgerissen wurde.<br \/>\n19. JAHRHUNDERT. <\/span><\/p>\n<p style=\"text-align: justify;\"><span>In der Kirche von San Michele al Pozzo Bianco aus dem 15.<br \/>\nJahrhundert befinden sich Fresken, die das Leben Marias von Lorenzo Lotto aus dem Jahr 1525 darstellen.<br \/>\nDer venezianische Maler, der von 1514 bis 1525 in Bergamo lebte, wohnte in einem der nicht mehr erhaltenen H\u00e4user der Familie Bonghi, die den kleinen Platz \u00fcberblicken.    <\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n","slides":[{"image":{"ID":3416,"id":3416,"title":"ebd97b302f5d6bd55cdd0892c326a4ec_a55c3d28.jpg","filename":"ebd97b302f5d6bd55cdd0892c326a4ec_a55c3d28.jpg","filesize":562316,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ebd97b302f5d6bd55cdd0892c326a4ec_a55c3d28.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/via-porta-dipinta\/ebd97b302f5d6bd55cdd0892c326a4ec_a55c3d28-jpg-2\/","alt":"Stradina panoramica in Via della Citt\u00e0 Alta di Bergamo con edifici storici","author":"0","description":"Vista suggestiva di via Porta Dipinta in salita, Citt\u00e0 Alta di Bergamo, incorniciata da edifici storici e alberi maestosi, ideale per una passeggiata tra arte, architettura e natura.","caption":"","name":"ebd97b302f5d6bd55cdd0892c326a4ec_a55c3d28-jpg-2","status":"inherit","uploaded_to":19831,"date":"2024-05-08 08:35:51","modified":"2025-04-10 15:46:20","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1550,"height":600,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ebd97b302f5d6bd55cdd0892c326a4ec_a55c3d28-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ebd97b302f5d6bd55cdd0892c326a4ec_a55c3d28-300x116.jpg","medium-width":300,"medium-height":116,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ebd97b302f5d6bd55cdd0892c326a4ec_a55c3d28-768x297.jpg","medium_large-width":768,"medium_large-height":297,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ebd97b302f5d6bd55cdd0892c326a4ec_a55c3d28-1024x396.jpg","large-width":1024,"large-height":396,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ebd97b302f5d6bd55cdd0892c326a4ec_a55c3d28-1536x595.jpg","1536x1536-width":1536,"1536x1536-height":595,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ebd97b302f5d6bd55cdd0892c326a4ec_a55c3d28.jpg","2048x2048-width":1550,"2048x2048-height":600,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ebd97b302f5d6bd55cdd0892c326a4ec_a55c3d28.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":116,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ebd97b302f5d6bd55cdd0892c326a4ec_a55c3d28.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":155,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ebd97b302f5d6bd55cdd0892c326a4ec_a55c3d28.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":232}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"gestrichene T\u00fcr","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":3423,"id":3423,"title":"0511ee6de7225a953571f7b2143ea461_64057690.jpg","filename":"0511ee6de7225a953571f7b2143ea461_64057690.jpg","filesize":457573,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/0511ee6de7225a953571f7b2143ea461_64057690.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/via-porta-dipinta\/0511ee6de7225a953571f7b2143ea461_64057690-jpg-2\/","alt":"Facciate storiche in via Porta Dipinta, in Citt\u00e0 Alta di Bergamo, con portoni ad arco e persiane in legno","author":"0","description":"Dettaglio architettonico delle antiche case in pietra della Citt\u00e0 Alta di Bergamo, con portoni in legno e finestre con persiane, che raccontano secoli di storia e tradizione.","caption":"","name":"0511ee6de7225a953571f7b2143ea461_64057690-jpg-2","status":"inherit","uploaded_to":19831,"date":"2024-05-08 08:35:52","modified":"2025-04-10 15:48:38","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1550,"height":600,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/0511ee6de7225a953571f7b2143ea461_64057690-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/0511ee6de7225a953571f7b2143ea461_64057690-300x116.jpg","medium-width":300,"medium-height":116,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/0511ee6de7225a953571f7b2143ea461_64057690-768x297.jpg","medium_large-width":768,"medium_large-height":297,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/0511ee6de7225a953571f7b2143ea461_64057690-1024x396.jpg","large-width":1024,"large-height":396,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/0511ee6de7225a953571f7b2143ea461_64057690-1536x595.jpg","1536x1536-width":1536,"1536x1536-height":595,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/0511ee6de7225a953571f7b2143ea461_64057690.jpg","2048x2048-width":1550,"2048x2048-height":600,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/0511ee6de7225a953571f7b2143ea461_64057690.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":116,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/0511ee6de7225a953571f7b2143ea461_64057690.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":155,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/0511ee6de7225a953571f7b2143ea461_64057690.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":232}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"gestrichene T\u00fcr","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":3429,"id":3429,"title":"89b147089aea885284283a45b7d31ecc_55c0d701.jpg","filename":"89b147089aea885284283a45b7d31ecc_55c0d701.jpg","filesize":428522,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/89b147089aea885284283a45b7d31ecc_55c0d701.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/via-porta-dipinta\/89b147089aea885284283a45b7d31ecc_55c0d701-jpg-2\/","alt":"Edifici storici su Via Porta Dipinta in Citt\u00e0 Alta a Bergamo, Italia","author":"0","description":"Scorcio di edifici storici su Via Porta Dipinta in Citt\u00e0 Alta a Bergamo, Italia.","caption":"","name":"89b147089aea885284283a45b7d31ecc_55c0d701-jpg-2","status":"inherit","uploaded_to":19831,"date":"2024-05-08 08:35:52","modified":"2025-04-10 16:02:07","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1550,"height":600,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/89b147089aea885284283a45b7d31ecc_55c0d701-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/89b147089aea885284283a45b7d31ecc_55c0d701-300x116.jpg","medium-width":300,"medium-height":116,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/89b147089aea885284283a45b7d31ecc_55c0d701-768x297.jpg","medium_large-width":768,"medium_large-height":297,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/89b147089aea885284283a45b7d31ecc_55c0d701-1024x396.jpg","large-width":1024,"large-height":396,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/89b147089aea885284283a45b7d31ecc_55c0d701-1536x595.jpg","1536x1536-width":1536,"1536x1536-height":595,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/89b147089aea885284283a45b7d31ecc_55c0d701.jpg","2048x2048-width":1550,"2048x2048-height":600,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/89b147089aea885284283a45b7d31ecc_55c0d701.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":116,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/89b147089aea885284283a45b7d31ecc_55c0d701.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":155,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/89b147089aea885284283a45b7d31ecc_55c0d701.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":232}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"gestrichene T\u00fcr","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":3435,"id":3435,"title":"f389c25531a5e7d28b472db6c47fb6e3_d889c014.jpg","filename":"f389c25531a5e7d28b472db6c47fb6e3_d889c014.jpg","filesize":427738,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/f389c25531a5e7d28b472db6c47fb6e3_d889c014.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/via-porta-dipinta\/f389c25531a5e7d28b472db6c47fb6e3_d889c014-jpg-2\/","alt":"Via Porta Dipinta in Citt\u00e0 Alta a Bergamo, Italia","author":"0","description":"Una vivace strada acciottolata, Via Porta Dipinta, serpeggia tra edifici storici color ocra a Bergamo","caption":"","name":"f389c25531a5e7d28b472db6c47fb6e3_d889c014-jpg-2","status":"inherit","uploaded_to":19831,"date":"2024-05-08 08:35:52","modified":"2025-04-10 15:55:21","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1550,"height":600,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/f389c25531a5e7d28b472db6c47fb6e3_d889c014-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/f389c25531a5e7d28b472db6c47fb6e3_d889c014-300x116.jpg","medium-width":300,"medium-height":116,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/f389c25531a5e7d28b472db6c47fb6e3_d889c014-768x297.jpg","medium_large-width":768,"medium_large-height":297,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/f389c25531a5e7d28b472db6c47fb6e3_d889c014-1024x396.jpg","large-width":1024,"large-height":396,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/f389c25531a5e7d28b472db6c47fb6e3_d889c014-1536x595.jpg","1536x1536-width":1536,"1536x1536-height":595,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/f389c25531a5e7d28b472db6c47fb6e3_d889c014.jpg","2048x2048-width":1550,"2048x2048-height":600,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/f389c25531a5e7d28b472db6c47fb6e3_d889c014.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":116,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/f389c25531a5e7d28b472db6c47fb6e3_d889c014.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":155,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/f389c25531a5e7d28b472db6c47fb6e3_d889c014.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":232}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"gestrichene T\u00fcr","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":3441,"id":3441,"title":"1fc1e518660cb5956c3955d0eaa0f502_bf2bc045.jpg","filename":"1fc1e518660cb5956c3955d0eaa0f502_bf2bc045.jpg","filesize":653990,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/1fc1e518660cb5956c3955d0eaa0f502_bf2bc045.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/via-porta-dipinta\/1fc1e518660cb5956c3955d0eaa0f502_bf2bc045-jpg-2\/","alt":"Veduta aerea di via Porta Dipinta in Citt\u00e0 Alta a Bergamo - San Michele al Pozzo Bianco","author":"0","description":"Una vista dall'alto mostra le case e le strade di Citt\u00e0 Alta a Bergamo, in Italia, circondate dal verde. Le case hanno tetti rossi e sono raggruppate vicine l'una all'altra.","caption":"","name":"1fc1e518660cb5956c3955d0eaa0f502_bf2bc045-jpg-2","status":"inherit","uploaded_to":19831,"date":"2024-05-08 08:35:53","modified":"2025-04-10 15:59:40","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1550,"height":600,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/1fc1e518660cb5956c3955d0eaa0f502_bf2bc045-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/1fc1e518660cb5956c3955d0eaa0f502_bf2bc045-300x116.jpg","medium-width":300,"medium-height":116,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/1fc1e518660cb5956c3955d0eaa0f502_bf2bc045-768x297.jpg","medium_large-width":768,"medium_large-height":297,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/1fc1e518660cb5956c3955d0eaa0f502_bf2bc045-1024x396.jpg","large-width":1024,"large-height":396,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/1fc1e518660cb5956c3955d0eaa0f502_bf2bc045-1536x595.jpg","1536x1536-width":1536,"1536x1536-height":595,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/1fc1e518660cb5956c3955d0eaa0f502_bf2bc045.jpg","2048x2048-width":1550,"2048x2048-height":600,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/1fc1e518660cb5956c3955d0eaa0f502_bf2bc045.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":116,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/1fc1e518660cb5956c3955d0eaa0f502_bf2bc045.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":155,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/1fc1e518660cb5956c3955d0eaa0f502_bf2bc045.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":232}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"via porta dipinta - s.\nmichele am weissen brunnen ","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"buttons":[{"style":"primary","text":"Kontakt","icon":{"button_icon":"none"},"function":"link","url":"","select_post":null,"target":"_blank","url_youtube":"","target_modal":""}],"filotto_layout":"scroll","hero_title":"\u00dcber die Porta Dipinta","iu_addr_streetnumber":"via porta dipinta","filotto_fill":"manual","hero_type":"images","filotto_items":false,"accessibilitycontent":{"tcm_content":[{"acf_fc_layout":"title","title_tag":"h3","title_text":"Das Datenblatt"},{"acf_fc_layout":"text","text":""}]},"gallery":{"gallery_items":false},"iu_timetable":false,"poi_data":{"description":"<div class=\"page\" title=\"Seite 41\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p style=\"text-align: justify;\"><span>Diese wichtige Zufahrtsstra\u00dfe zur Stadt hat ihren Namen von einer mit Fresken bemalten T\u00fcr in der mittelalterlichen Stadtmauer, die im 19. Jahrhundert abgerissen wurde.<br \/>\n19. JAHRHUNDERT. <\/span><\/p>\n<p style=\"text-align: justify;\"><span>In der Kirche von San Michele al Pozzo Bianco aus dem 15.<br \/>\nJahrhundert befinden sich Fresken, die das Leben Marias von Lorenzo Lotto aus dem Jahr 1525 darstellen.<br \/>\nDer venezianische Maler, der von 1514 bis 1525 in Bergamo lebte, wohnte in einem der nicht mehr erhaltenen H\u00e4user der Familie Bonghi, die den kleinen Platz \u00fcberblicken.    <\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n","indepth":"","howtogetthere":"","price":"","time":"","latitude":"","longitude":"","id_visit_manza":"10272","iu_motor_accessibility":"no","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_kids":false,"iu_shortprice":"","iu_addr_streetnumber":"via porta dipinta","iu_addr_postalcode":"","iu_addr_city":"Bergamo","iu_addr_province":"","iu_phone":"","iu_cell":"","iu_website":"","iu_email":"","iu_document_label":"","iu_document":false,"iu_timetable":false},"size":"full","hero_buttons_group":{"buttons":[{"style":"primary","text":"Kontakt","icon":{"button_icon":"none"},"function":"link","url":"","select_post":null,"target":"_blank","url_youtube":"","target_modal":""}]},"featured_video":false,"filotto_sub":"","or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"order_by":"","order_way":"","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""},"style":"","text":"","icon":{"button_icon":"none"},"function":"","target":"","target_modal":"","iu_document_label":"","modules":false,"hero_buttons":false,"iu_kids":false,"is_an_ambassador":false},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/19831","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/types\/oggetto"}],"author":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/19831\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media\/3416"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media?parent=19831"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/categories?post=19831"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/tags?post=19831"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/aggr?post=19831"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/area?post=19831"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/kind?post=19831"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/zona?post=19831"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}