{"id":19854,"date":"2024-05-08T11:03:39","date_gmt":"2024-05-08T09:03:39","guid":{"rendered":"https:\/\/visitstg2.visitbergamo.net\/oggetto\/torre-di-adalberto\/"},"modified":"2025-02-16T09:47:11","modified_gmt":"2025-02-16T08:47:11","slug":"torre-di-adalberto","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/torre-di-adalberto\/","title":{"rendered":"Turm von Adalbert"},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":3734,"template":"","categories":[],"tags":[],"aggr":[],"area":[867],"kind":[18680],"zona":[18760],"class_list":["post-19854","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","area-bergamo","kind-poi-de","zona-bergamo-de"],"acf":{"hero_text":"","filotto_title":"","filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"scroll","filotto_fill":"manual","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""}},"indepth":"","howtogetthere":"","timerange":"","cancellationpolicy":"","moredetails":"","whatsincluded":"","whatsnotincluded":"","price":"","time":"","latitude":"45.706106","longitude":"9.658867","startingprice":"","gpxmap":"","iu_motor_accessibility":"no","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_shortprice":"","iu_addr_postalcode":"24129","iu_addr_city":"Bergamo","iu_phone":"","iu_cell":"","iu_website":"","iu_email":"","iu_document":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_bookingurl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"","iu_languages":"","iu_minpeople":"","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","id_madeep":"","id_visit_manza":"10281","url":"","url_youtube":"","cta":{"style":"","text":"","icon":{"button_icon":"none"},"function":"","url":"","target":"","url_youtube":"","target_modal":""},"button_icon":"none","tcm_content":[{"acf_fc_layout":"title","title_tag":"h3","title_text":"Das Datenblatt"},{"acf_fc_layout":"text","text":""}],"description":"<div class=\"page\" title=\"Seite 119\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p style=\"text-align: justify;\"><span>Von der sp\u00e4ten karolingischen Zeit bis zum Ende des 11. Jahrhunderts, als die Macht an die Kommune \u00fcberging, wurde die Herrschaft \u00fcber Bergamo zunehmend von den Bisch\u00f6fen ausge\u00fcbt.<\/p>\n<p>Im 11. Jahrhundert, als die Macht an die Kommune \u00fcberging, wurde die Herrschaft \u00fcber Bergamo zunehmend von den Bisch\u00f6fen ausge\u00fcbt. Bischof Adalbert, nach der teilweisen Zerst\u00f6rung der Verteidigungsanlagen durch K\u00f6nig  <\/span><span>Arnolfo im Jahr 894, baute 904 das Forum wieder auf.<\/span><span>rtifikationen der Stadt.<br \/>\nAuf der Grundlage dieser Annahmen haben lokale Historiker auch den Bau des Turms, der eigentlich ein Adelssitz aus dem 12.<br \/>\nDer Turm ist einer der wenigen \u00dcberlebenden unter den Dutzenden, die es einst in der Oberstadt gab.    <\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n","slides":[{"image":{"ID":3734,"id":3734,"title":"1f892dcdcc3abc7b57bce6135020fc32_ec28bd83.jpg","filename":"1f892dcdcc3abc7b57bce6135020fc32_ec28bd83.jpg","filesize":457656,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/1f892dcdcc3abc7b57bce6135020fc32_ec28bd83.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/torre-di-adalberto\/1f892dcdcc3abc7b57bce6135020fc32_ec28bd83-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"1f892dcdcc3abc7b57bce6135020fc32_ec28bd83-jpg-2","status":"inherit","uploaded_to":19854,"date":"2024-05-08 08:36:25","modified":"2024-05-08 12:24:45","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1550,"height":600,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/1f892dcdcc3abc7b57bce6135020fc32_ec28bd83-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/1f892dcdcc3abc7b57bce6135020fc32_ec28bd83-300x116.jpg","medium-width":300,"medium-height":116,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/1f892dcdcc3abc7b57bce6135020fc32_ec28bd83-768x297.jpg","medium_large-width":768,"medium_large-height":297,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/1f892dcdcc3abc7b57bce6135020fc32_ec28bd83-1024x396.jpg","large-width":1024,"large-height":396,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/1f892dcdcc3abc7b57bce6135020fc32_ec28bd83-1536x595.jpg","1536x1536-width":1536,"1536x1536-height":595,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/1f892dcdcc3abc7b57bce6135020fc32_ec28bd83.jpg","2048x2048-width":1550,"2048x2048-height":600,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/1f892dcdcc3abc7b57bce6135020fc32_ec28bd83.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":116,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/1f892dcdcc3abc7b57bce6135020fc32_ec28bd83.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":155,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/1f892dcdcc3abc7b57bce6135020fc32_ec28bd83.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":232}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"turm von adalbert","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":3740,"id":3740,"title":"cfecc933b99c703ffdc5d77a4c0ee56f_cd9186af.jpg","filename":"cfecc933b99c703ffdc5d77a4c0ee56f_cd9186af.jpg","filesize":682731,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/cfecc933b99c703ffdc5d77a4c0ee56f_cd9186af.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/torre-di-adalberto\/cfecc933b99c703ffdc5d77a4c0ee56f_cd9186af-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"cfecc933b99c703ffdc5d77a4c0ee56f_cd9186af-jpg-2","status":"inherit","uploaded_to":19854,"date":"2024-05-08 08:36:25","modified":"2024-05-08 12:24:45","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1550,"height":600,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/cfecc933b99c703ffdc5d77a4c0ee56f_cd9186af-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/cfecc933b99c703ffdc5d77a4c0ee56f_cd9186af-300x116.jpg","medium-width":300,"medium-height":116,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/cfecc933b99c703ffdc5d77a4c0ee56f_cd9186af-768x297.jpg","medium_large-width":768,"medium_large-height":297,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/cfecc933b99c703ffdc5d77a4c0ee56f_cd9186af-1024x396.jpg","large-width":1024,"large-height":396,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/cfecc933b99c703ffdc5d77a4c0ee56f_cd9186af-1536x595.jpg","1536x1536-width":1536,"1536x1536-height":595,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/cfecc933b99c703ffdc5d77a4c0ee56f_cd9186af.jpg","2048x2048-width":1550,"2048x2048-height":600,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/cfecc933b99c703ffdc5d77a4c0ee56f_cd9186af.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":116,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/cfecc933b99c703ffdc5d77a4c0ee56f_cd9186af.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":155,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/cfecc933b99c703ffdc5d77a4c0ee56f_cd9186af.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":232}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"turm von adalbert","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":3746,"id":3746,"title":"bc039432a2a3e0a6dcaa79ce805bbc35_125137b9.jpg","filename":"bc039432a2a3e0a6dcaa79ce805bbc35_125137b9.jpg","filesize":575427,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/bc039432a2a3e0a6dcaa79ce805bbc35_125137b9.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/torre-di-adalberto\/bc039432a2a3e0a6dcaa79ce805bbc35_125137b9-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"bc039432a2a3e0a6dcaa79ce805bbc35_125137b9-jpg-2","status":"inherit","uploaded_to":19854,"date":"2024-05-08 08:36:25","modified":"2024-05-08 12:24:45","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1550,"height":597,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/bc039432a2a3e0a6dcaa79ce805bbc35_125137b9-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/bc039432a2a3e0a6dcaa79ce805bbc35_125137b9-300x116.jpg","medium-width":300,"medium-height":116,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/bc039432a2a3e0a6dcaa79ce805bbc35_125137b9-768x296.jpg","medium_large-width":768,"medium_large-height":296,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/bc039432a2a3e0a6dcaa79ce805bbc35_125137b9-1024x394.jpg","large-width":1024,"large-height":394,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/bc039432a2a3e0a6dcaa79ce805bbc35_125137b9-1536x592.jpg","1536x1536-width":1536,"1536x1536-height":592,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/bc039432a2a3e0a6dcaa79ce805bbc35_125137b9.jpg","2048x2048-width":1550,"2048x2048-height":597,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/bc039432a2a3e0a6dcaa79ce805bbc35_125137b9.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":116,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/bc039432a2a3e0a6dcaa79ce805bbc35_125137b9.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":154,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/bc039432a2a3e0a6dcaa79ce805bbc35_125137b9.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":231}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"turm von adalbert","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":3752,"id":3752,"title":"3d052d38b862de222167a15c317c2505_ca6065a8.jpg","filename":"3d052d38b862de222167a15c317c2505_ca6065a8.jpg","filesize":613511,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/3d052d38b862de222167a15c317c2505_ca6065a8.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/torre-di-adalberto\/3d052d38b862de222167a15c317c2505_ca6065a8-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"3d052d38b862de222167a15c317c2505_ca6065a8-jpg-2","status":"inherit","uploaded_to":19854,"date":"2024-05-08 08:36:26","modified":"2024-05-08 12:24:45","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1550,"height":600,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/3d052d38b862de222167a15c317c2505_ca6065a8-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/3d052d38b862de222167a15c317c2505_ca6065a8-300x116.jpg","medium-width":300,"medium-height":116,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/3d052d38b862de222167a15c317c2505_ca6065a8-768x297.jpg","medium_large-width":768,"medium_large-height":297,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/3d052d38b862de222167a15c317c2505_ca6065a8-1024x396.jpg","large-width":1024,"large-height":396,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/3d052d38b862de222167a15c317c2505_ca6065a8-1536x595.jpg","1536x1536-width":1536,"1536x1536-height":595,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/3d052d38b862de222167a15c317c2505_ca6065a8.jpg","2048x2048-width":1550,"2048x2048-height":600,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/3d052d38b862de222167a15c317c2505_ca6065a8.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":116,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/3d052d38b862de222167a15c317c2505_ca6065a8.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":155,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/3d052d38b862de222167a15c317c2505_ca6065a8.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":232}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"turm von adalbert","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":3758,"id":3758,"title":"9907e1b0e080905c5e122ab7973ccaa4_bee5fd26.jpg","filename":"9907e1b0e080905c5e122ab7973ccaa4_bee5fd26.jpg","filesize":634825,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/9907e1b0e080905c5e122ab7973ccaa4_bee5fd26.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/torre-di-adalberto\/9907e1b0e080905c5e122ab7973ccaa4_bee5fd26-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"9907e1b0e080905c5e122ab7973ccaa4_bee5fd26-jpg-2","status":"inherit","uploaded_to":19854,"date":"2024-05-08 08:36:26","modified":"2024-05-08 12:24:45","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1550,"height":599,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/9907e1b0e080905c5e122ab7973ccaa4_bee5fd26-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/9907e1b0e080905c5e122ab7973ccaa4_bee5fd26-300x116.jpg","medium-width":300,"medium-height":116,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/9907e1b0e080905c5e122ab7973ccaa4_bee5fd26-768x297.jpg","medium_large-width":768,"medium_large-height":297,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/9907e1b0e080905c5e122ab7973ccaa4_bee5fd26-1024x396.jpg","large-width":1024,"large-height":396,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/9907e1b0e080905c5e122ab7973ccaa4_bee5fd26-1536x594.jpg","1536x1536-width":1536,"1536x1536-height":594,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/9907e1b0e080905c5e122ab7973ccaa4_bee5fd26.jpg","2048x2048-width":1550,"2048x2048-height":599,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/9907e1b0e080905c5e122ab7973ccaa4_bee5fd26.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":116,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/9907e1b0e080905c5e122ab7973ccaa4_bee5fd26.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":155,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/9907e1b0e080905c5e122ab7973ccaa4_bee5fd26.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":232}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"turm von adalbert","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"buttons":[{"style":"primary","text":"Kontakt","icon":{"button_icon":"none"},"function":"link","url":"","select_post":null,"target":"_blank","url_youtube":"","target_modal":""}],"filotto_layout":"scroll","hero_title":"Turm von Adalbert","iu_addr_streetnumber":"Piazza Lorenzo Mascheroni, 5","iu_addr_province":"Bergamo","filotto_fill":"manual","hero_type":"images","filotto_items":false,"accessibilitycontent":{"tcm_content":[{"acf_fc_layout":"title","title_tag":"h3","title_text":"Das Datenblatt"},{"acf_fc_layout":"text","text":""}]},"gallery":{"gallery_items":false},"iu_kids":false,"iu_timetable":false,"poi_data":{"description":"<div class=\"page\" title=\"Seite 119\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p style=\"text-align: justify;\"><span>Von der sp\u00e4ten karolingischen Zeit bis zum Ende des 11. Jahrhunderts, als die Macht an die Kommune \u00fcberging, wurde die Herrschaft \u00fcber Bergamo zunehmend von den Bisch\u00f6fen ausge\u00fcbt.<\/p>\n<p>Im 11. Jahrhundert, als die Macht an die Kommune \u00fcberging, wurde die Herrschaft \u00fcber Bergamo zunehmend von den Bisch\u00f6fen ausge\u00fcbt. Bischof Adalbert, nach der teilweisen Zerst\u00f6rung der Verteidigungsanlagen durch K\u00f6nig  <\/span><span>Arnolfo im Jahr 894, baute 904 das Forum wieder auf.<\/span><span>rtifikationen der Stadt.<br \/>\nAuf der Grundlage dieser Annahmen haben lokale Historiker auch den Bau des Turms, der eigentlich ein Adelssitz aus dem 12.<br \/>\nDer Turm ist einer der wenigen \u00dcberlebenden unter den Dutzenden, die es einst in der Oberstadt gab.    <\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n","indepth":"","howtogetthere":"","price":"","time":"","latitude":"45.706106","longitude":"9.658867","id_visit_manza":"10281","iu_motor_accessibility":"no","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_kids":false,"iu_shortprice":"","iu_addr_streetnumber":"Piazza Lorenzo Mascheroni, 5","iu_addr_postalcode":"24129","iu_addr_city":"Bergamo","iu_addr_province":"Bergamo","iu_phone":"","iu_cell":"","iu_website":"","iu_email":"","iu_document_label":"","iu_document":false,"iu_timetable":false},"size":"full","featured_video":false,"is_an_ambassador":false,"filotto_sub":"","or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"order_by":"","order_way":"","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""},"style":"","text":"","icon":{"button_icon":"none"},"function":"","target":"","target_modal":"","iu_document_label":""},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/19854","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/types\/oggetto"}],"author":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/19854\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media\/3734"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media?parent=19854"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/categories?post=19854"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/tags?post=19854"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/aggr?post=19854"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/area?post=19854"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/kind?post=19854"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/zona?post=19854"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}