{"id":19871,"date":"2024-05-08T11:03:44","date_gmt":"2024-05-08T09:03:44","guid":{"rendered":"https:\/\/visitstg2.visitbergamo.net\/oggetto\/palazzo-frizzoni\/"},"modified":"2025-02-16T09:47:25","modified_gmt":"2025-02-16T08:47:25","slug":"palazzo-frizzoni","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/palazzo-frizzoni\/","title":{"rendered":"Frizzoni Palast"},"excerpt":{"rendered":"<p>Entdecken Sie, was sich hinter den Mauern des Geb\u00e4udes verbirgt, das das Herz des politischen und administrativen Lebens von Bergamo ist: Der Palazzo Frizzoni beherbergt die wichtigsten institutionellen B\u00fcros der Stadtverwaltung.<\/p>\n","protected":false},"author":3,"featured_media":4034,"template":"","categories":[],"tags":[],"aggr":[],"area":[867],"kind":[18680],"zona":[18760],"class_list":["post-19871","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","area-bergamo","kind-poi-de","zona-bergamo-de"],"acf":{"filotto_title":"","filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"scroll","filotto_fill":"manual","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""}},"howtogetthere":"","timerange":"","cancellationpolicy":"","moredetails":"","whatsincluded":"","whatsnotincluded":"","price":"","time":"","latitude":"45.694436","longitude":"9.668445","startingprice":"","gpxmap":"","iu_motor_accessibility":"no","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_shortprice":"","iu_addr_streetnumber":"","iu_addr_postalcode":"","iu_addr_city":"Bergamo","iu_addr_province":"","iu_phone":"","iu_cell":"","iu_email":"","iu_document":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_bookingurl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"","iu_languages":"","iu_minpeople":"","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","id_madeep":"","id_visit_manza":"3130","url_youtube":"","cta":{"style":"","text":"","icon":{"button_icon":"none"},"function":"","url":"http:\/\/www.comune.bergamo.it\/","target":"","url_youtube":"","target_modal":""},"button_icon":"none","tcm_content":[{"acf_fc_layout":"title","title_tag":"h3","title_text":"Das Datenblatt"},{"acf_fc_layout":"text","text":""}],"description":"<p>Der Palast tr\u00e4gt den Namen seines M\u00e4zens, Enrico Frizzoni, der ihn testamentarisch als Rathaus vorgesehen hatte.<br \/>\nDer von Rodolfo Vantini entworfene Palast wurde zwischen 1836 und 1840 im neoklassischen Stil erbaut. Die zw\u00f6lf korinthischen Pilaster, die die Fenster der Fassade unterteilen, erinnern an die griechisch-r\u00f6mische Architektur, ebenso wie der Portikus mit den acht ionischen S\u00e4ulen, den Sie vorfinden, wenn Sie den Eingang passieren. <\/p>\n<p>Anl\u00e4sslich der institutionellen Feierlichkeiten haben Sie auch die M\u00f6glichkeit, das Innere des Geb\u00e4udes zu besichtigen!<br \/>\nAm Ende der gro\u00dfen Treppe finden Sie den Saal, der f\u00fcr die Ratssitzungen genutzt wird.<br \/>\nWenn Sie stattdessen den Spiegelsaal betreten, k\u00f6nnen Sie den herrlichen Mosaikboden bewundern, in dessen Mitte sich das Frizzoni-Wappen befindet, das aus zwei mit einem Band verbundenen Pfeilen besteht.  <\/p>\n<p>Im Erdgeschoss, in der Galleria dei Cardinali, finden Sie Portr\u00e4ts von Kardin\u00e4len aus Bergamo, darunter Angelo Roncalli, der Papst Johannes XXIII. wurde. <strong>Der Palazzo Frizzoni<\/strong> ist auch eine Gem\u00e4ldegalerie: Er beherbergt 80 Gem\u00e4lde der Accademia Carrara.<\/p><\/p>\n","buttons":[{"style":"primary","text":"Kontakt","icon":{"button_icon":"none"},"function":"link","url":"http:\/\/www.comune.bergamo.it\/","select_post":null,"target":"_blank","url_youtube":"","target_modal":""}],"filotto_layout":"scroll","url":"http:\/\/www.comune.bergamo.it\/","hero_title":"Frizzoni Palast","hero_text":"<p>Entdecken Sie, was sich hinter den Mauern des Geb\u00e4udes verbirgt, das das Herz des politischen und administrativen Lebens von Bergamo ist: Palazzo Frizzoni beherbergt die wichtigsten institutionellen B\u00fcros der Stadtverwaltung.<\/p>\n","indepth":"<p>Am Eingang des Geb\u00e4udes wurde k\u00fcrzlich der erste Baby-Pit-Stop in der Gemeinde Bergamo eingeweiht: Auch wenn Sie in der Innenstadt unterwegs sind, finden M\u00fctter hier Wickeltische, gem\u00fctliche Pl\u00e4tze zum Stillen, Sessel zum Ausruhen und Spiele f\u00fcr ihre Babys.<\/p>\n<p>Der Park ist von Montag bis Freitag von 9 Uhr bis 17 Uhr ge\u00f6ffnet.<br \/>\nDer Eintritt ist f\u00fcr Kinder von 0 bis 10 Jahren in Begleitung gestattet. <\/p>\n","iu_website":"http:\/\/www.comune.bergamo.it\/","filotto_fill":"manual","hero_type":"images","filotto_items":false,"accessibilitycontent":{"tcm_content":[{"acf_fc_layout":"title","title_tag":"h3","title_text":"Das Datenblatt"},{"acf_fc_layout":"text","text":""}]},"gallery":{"gallery_items":false},"iu_kids":false,"iu_timetable":false,"poi_data":{"description":"<p>Der Palast tr\u00e4gt den Namen seines M\u00e4zens, Enrico Frizzoni, der ihn testamentarisch als Rathaus vorgesehen hatte.<br \/>\nDer von Rodolfo Vantini entworfene Palast wurde zwischen 1836 und 1840 im neoklassischen Stil erbaut. Die zw\u00f6lf korinthischen Pilaster, die die Fenster der Fassade unterteilen, erinnern an die griechisch-r\u00f6mische Architektur, ebenso wie der Portikus mit den acht ionischen S\u00e4ulen, den Sie vorfinden, wenn Sie den Eingang passieren. <\/p>\n<p>Anl\u00e4sslich der institutionellen Feierlichkeiten haben Sie auch die M\u00f6glichkeit, das Innere des Geb\u00e4udes zu besichtigen!<br \/>\nAm Ende der gro\u00dfen Treppe finden Sie den Saal, der f\u00fcr die Ratssitzungen genutzt wird.<br \/>\nWenn Sie stattdessen den Spiegelsaal betreten, k\u00f6nnen Sie den herrlichen Mosaikboden bewundern, in dessen Mitte sich das Frizzoni-Wappen befindet, das aus zwei mit einem Band verbundenen Pfeilen besteht.  <\/p>\n<p>Im Erdgeschoss, in der Galleria dei Cardinali, finden Sie Portr\u00e4ts von Kardin\u00e4len aus Bergamo, darunter Angelo Roncalli, der Papst Johannes XXIII. wurde. <strong>Der Palazzo Frizzoni<\/strong> ist auch eine Gem\u00e4ldegalerie: Er beherbergt 80 Gem\u00e4lde der Accademia Carrara.<\/p><\/p>\n","indepth":"<p>Am Eingang des Geb\u00e4udes wurde k\u00fcrzlich der erste Baby-Pit-Stop in der Gemeinde Bergamo eingeweiht: Auch wenn Sie in der Innenstadt unterwegs sind, finden M\u00fctter hier Wickeltische, gem\u00fctliche Pl\u00e4tze zum Stillen, Sessel zum Ausruhen und Spiele f\u00fcr ihre Babys.<\/p>\n<p>Der Park ist von Montag bis Freitag von 9 Uhr bis 17 Uhr ge\u00f6ffnet.<br \/>\nDer Eintritt ist f\u00fcr Kinder von 0 bis 10 Jahren in Begleitung gestattet. <\/p>\n","howtogetthere":"","price":"","time":"","latitude":"45.694436","longitude":"9.668445","id_visit_manza":"3130","iu_motor_accessibility":"no","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_kids":false,"iu_shortprice":"","iu_addr_streetnumber":"","iu_addr_postalcode":"","iu_addr_city":"Bergamo","iu_addr_province":"","iu_phone":"","iu_cell":"","iu_website":"http:\/\/www.comune.bergamo.it\/","iu_email":"","iu_document_label":"","iu_document":false,"iu_timetable":false},"size":"full","featured_video":false,"is_an_ambassador":false,"slides":[{"image":{"ID":4034,"id":4034,"title":"997b1fcb8b0f79825f3114875de6903c_de188523.jpg","filename":"997b1fcb8b0f79825f3114875de6903c_de188523-e1738574176815.jpg","filesize":585003,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/997b1fcb8b0f79825f3114875de6903c_de188523-e1738574176815.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/palazzo-frizzoni\/997b1fcb8b0f79825f3114875de6903c_de188523-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"997b1fcb8b0f79825f3114875de6903c_de188523-jpg-2","status":"inherit","uploaded_to":19871,"date":"2024-05-08 08:36:56","modified":"2024-05-08 12:24:51","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1560,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/997b1fcb8b0f79825f3114875de6903c_de188523-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/997b1fcb8b0f79825f3114875de6903c_de188523-300x109.jpg","medium-width":300,"medium-height":109,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/997b1fcb8b0f79825f3114875de6903c_de188523-768x278.jpg","medium_large-width":768,"medium_large-height":278,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/997b1fcb8b0f79825f3114875de6903c_de188523-1024x371.jpg","large-width":1024,"large-height":371,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/997b1fcb8b0f79825f3114875de6903c_de188523-1536x556.jpg","1536x1536-width":1536,"1536x1536-height":556,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/997b1fcb8b0f79825f3114875de6903c_de188523-e1738574176815.jpg","2048x2048-width":1560,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/997b1fcb8b0f79825f3114875de6903c_de188523-e1738574176815.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":109,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/997b1fcb8b0f79825f3114875de6903c_de188523-e1738574176815.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":145,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/997b1fcb8b0f79825f3114875de6903c_de188523-e1738574176815.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":217}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":116811,"id":116811,"title":"_OTR6314 palazzo frizzoni","filename":"OTR6314-palazzo-frizzoni-scaled-e1738574204808.jpg","filesize":1324055,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/OTR6314-palazzo-frizzoni-scaled-e1738574204808.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/palazzo-frizzoni\/_otr6314-palazzo-frizzoni-2\/","alt":"","author":"8","description":"","caption":"","name":"_otr6314-palazzo-frizzoni-2","status":"inherit","uploaded_to":19871,"date":"2025-02-03 09:15:33","modified":"2025-02-03 09:15:33","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1706,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/OTR6314-palazzo-frizzoni-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/OTR6314-palazzo-frizzoni-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/OTR6314-palazzo-frizzoni-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/OTR6314-palazzo-frizzoni-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/OTR6314-palazzo-frizzoni-1536x1024.jpg","1536x1536-width":1536,"1536x1536-height":1024,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/OTR6314-palazzo-frizzoni-2048x1365.jpg","2048x2048-width":2048,"2048x2048-height":1365,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/OTR6314-palazzo-frizzoni-300x300.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/OTR6314-palazzo-frizzoni-400x400.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/OTR6314-palazzo-frizzoni-600x600.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":116818,"id":116818,"title":"_OTR6318 palazzo frizzoni","filename":"OTR6318-palazzo-frizzoni-scaled-e1738574859141.jpg","filesize":1066979,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/OTR6318-palazzo-frizzoni-scaled-e1738574859141.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/palazzo-frizzoni\/_otr6318-palazzo-frizzoni-2\/","alt":"","author":"8","description":"","caption":"","name":"_otr6318-palazzo-frizzoni-2","status":"inherit","uploaded_to":19871,"date":"2025-02-03 09:15:38","modified":"2025-02-03 09:15:38","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1635,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/OTR6318-palazzo-frizzoni-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/OTR6318-palazzo-frizzoni-300x192.jpg","medium-width":300,"medium-height":192,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/OTR6318-palazzo-frizzoni-768x491.jpg","medium_large-width":768,"medium_large-height":491,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/OTR6318-palazzo-frizzoni-1024x654.jpg","large-width":1024,"large-height":654,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/OTR6318-palazzo-frizzoni-1536x981.jpg","1536x1536-width":1536,"1536x1536-height":981,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/OTR6318-palazzo-frizzoni-2048x1308.jpg","2048x2048-width":2048,"2048x2048-height":1308,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/OTR6318-palazzo-frizzoni-300x300.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/OTR6318-palazzo-frizzoni-400x400.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/OTR6318-palazzo-frizzoni-600x600.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":116825,"id":116825,"title":"_OTR6322_1 palazzo frizzoni","filename":"OTR6322_1-palazzo-frizzoni-scaled-e1738574902342.jpg","filesize":889756,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/OTR6322_1-palazzo-frizzoni-scaled-e1738574902342.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/palazzo-frizzoni\/_otr6322_1-palazzo-frizzoni-2\/","alt":"","author":"8","description":"","caption":"","name":"_otr6322_1-palazzo-frizzoni-2","status":"inherit","uploaded_to":19871,"date":"2025-02-03 09:15:42","modified":"2025-02-03 09:15:42","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1671,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/OTR6322_1-palazzo-frizzoni-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/OTR6322_1-palazzo-frizzoni-300x196.jpg","medium-width":300,"medium-height":196,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/OTR6322_1-palazzo-frizzoni-768x501.jpg","medium_large-width":768,"medium_large-height":501,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/OTR6322_1-palazzo-frizzoni-1024x669.jpg","large-width":1024,"large-height":669,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/OTR6322_1-palazzo-frizzoni-1536x1003.jpg","1536x1536-width":1536,"1536x1536-height":1003,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/OTR6322_1-palazzo-frizzoni-2048x1337.jpg","2048x2048-width":2048,"2048x2048-height":1337,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/OTR6322_1-palazzo-frizzoni-300x300.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/OTR6322_1-palazzo-frizzoni-400x400.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/OTR6322_1-palazzo-frizzoni-600x600.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":116832,"id":116832,"title":"_PH10002piazza matteotti_palazzo Frizzoni","filename":"PH10002piazza-matteotti_palazzo-Frizzoni-scaled-e1738574928609.jpg","filesize":1275466,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/PH10002piazza-matteotti_palazzo-Frizzoni-scaled-e1738574928609.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/palazzo-frizzoni\/_ph10002piazza-matteotti_palazzo-frizzoni-2\/","alt":"","author":"8","description":"","caption":"","name":"_ph10002piazza-matteotti_palazzo-frizzoni-2","status":"inherit","uploaded_to":19871,"date":"2025-02-03 09:15:46","modified":"2025-02-03 09:15:46","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1706,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/PH10002piazza-matteotti_palazzo-Frizzoni-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/PH10002piazza-matteotti_palazzo-Frizzoni-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/PH10002piazza-matteotti_palazzo-Frizzoni-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/PH10002piazza-matteotti_palazzo-Frizzoni-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/PH10002piazza-matteotti_palazzo-Frizzoni-1536x1024.jpg","1536x1536-width":1536,"1536x1536-height":1024,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/PH10002piazza-matteotti_palazzo-Frizzoni-2048x1365.jpg","2048x2048-width":2048,"2048x2048-height":1365,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/PH10002piazza-matteotti_palazzo-Frizzoni-300x300.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/PH10002piazza-matteotti_palazzo-Frizzoni-400x400.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/PH10002piazza-matteotti_palazzo-Frizzoni-600x600.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"filotto_sub":"","or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"order_by":"","order_way":"","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""},"style":"","text":"","icon":{"button_icon":"none"},"function":"","target":"","target_modal":"","iu_document_label":""},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/19871","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/types\/oggetto"}],"author":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/19871\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media\/4034"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media?parent=19871"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/categories?post=19871"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/tags?post=19871"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/aggr?post=19871"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/area?post=19871"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/kind?post=19871"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/zona?post=19871"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}