{"id":19896,"date":"2024-05-08T11:03:53","date_gmt":"2024-05-08T09:03:53","guid":{"rendered":"https:\/\/visitstg2.visitbergamo.net\/oggetto\/buergerturm-campanone\/"},"modified":"2025-04-13T16:51:01","modified_gmt":"2025-04-13T14:51:01","slug":"buergerturm-campanone","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/buergerturm-campanone\/","title":{"rendered":"Stadtturm &#8211; Glocke"},"excerpt":{"rendered":"<p>Vom h\u00f6chsten Turm der Stadt haben Sie einen unvergesslichen Blick.<\/p>\n","protected":false},"author":97,"featured_media":4400,"template":"","categories":[],"tags":[],"aggr":[],"area":[867],"kind":[18680],"zona":[18760],"class_list":["post-19896","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","area-bergamo","kind-poi-de","zona-bergamo-de"],"acf":{"hero_buttons":false,"filotto_title":"","filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"scroll","filotto_fill":"manual","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""}},"howtogetthere":"","timerange":"","cancellationpolicy":"","moredetails":"","whatsincluded":"","whatsnotincluded":"","latitude":"45.704278","longitude":"9.663136","startingprice":"","gpxmap":"","iu_motor_accessibility":"yes","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_kids":true,"iu_addr_postalcode":"24129","iu_addr_city":"Bergamo","iu_phone":"+39 035247116","iu_cell":"","iu_email":"info@museodellestorie.bergamo.it","iu_document":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_bookingurl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"","iu_languages":"","iu_minpeople":"","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","id_madeep":"","id_visit_manza":"74","url_youtube":"","iu_shortprice":"\u20ac1 - \u20ac5","iu_timetable":[{"day":{"value":"monday","label":"Luned\u00ec"},"open":false,"time":false},{"day":{"value":"tuesday","label":"Marted\u00ec"},"open":true,"time":[{"opening":"10:00 am","closing":"6:00 pm"}]},{"day":{"value":"wednesday","label":"Mercoled\u00ec"},"open":true,"time":[{"opening":"10:00 am","closing":"6:00 pm"}]},{"day":{"value":"thursday","label":"Gioved\u00ec"},"open":true,"time":[{"opening":"10:00 am","closing":"6:00 pm"}]},{"day":{"value":"friday","label":"Venerd\u00ec"},"open":true,"time":[{"opening":"10:00 am","closing":"6:00 pm"}]},{"day":{"value":"saturday","label":"Sabato"},"open":true,"time":[{"opening":"10:00 am","closing":"7:00 pm"}]},{"day":{"value":"sunday","label":"Domenica"},"open":true,"time":[{"opening":"10:00 am","closing":"7:00 pm"}]}],"button_icon":"none","tcm_content":[{"acf_fc_layout":"title","title_tag":"h3","title_text":"Das Datenblatt"},{"acf_fc_layout":"text","text":""}],"description":"<p class=\"textbox\" dir=\"ltr\">Im Herzen der <a href=\"https:\/\/visit.valueservice.cloud\/de\/oggetto\/piazza-vecchia\/\" target=\"_blank\" rel=\"noopener\">Piazza Vecchia<\/a> in <strong>Bergamo<\/strong> steht der <strong>Stadtturm<\/strong>, bekannt als <strong>Campanone<\/strong>.<\/p>\n<p class=\"textbox\" dir=\"ltr\">Aus einer <strong>H\u00f6he von 52,76 Metern<\/strong> bietet er einen atemberaubenden <strong>Panoramablick<\/strong>.<\/p>\n","slides":[{"image":{"ID":4400,"id":4400,"title":"997e8bcebb979e1113efd2155af2778f_826e3adc.jpg","filename":"997e8bcebb979e1113efd2155af2778f_826e3adc.jpg","filesize":607869,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/997e8bcebb979e1113efd2155af2778f_826e3adc.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/buergerturm-campanone\/997e8bcebb979e1113efd2155af2778f_826e3adc-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"997e8bcebb979e1113efd2155af2778f_826e3adc-jpg-2","status":"inherit","uploaded_to":19896,"date":"2024-05-08 08:37:38","modified":"2024-05-08 12:25:01","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1920,"height":1229,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/997e8bcebb979e1113efd2155af2778f_826e3adc-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/997e8bcebb979e1113efd2155af2778f_826e3adc-300x192.jpg","medium-width":300,"medium-height":192,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/997e8bcebb979e1113efd2155af2778f_826e3adc-768x492.jpg","medium_large-width":768,"medium_large-height":492,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/997e8bcebb979e1113efd2155af2778f_826e3adc-1024x655.jpg","large-width":1024,"large-height":655,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/997e8bcebb979e1113efd2155af2778f_826e3adc-1536x983.jpg","1536x1536-width":1536,"1536x1536-height":983,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/997e8bcebb979e1113efd2155af2778f_826e3adc.jpg","2048x2048-width":1920,"2048x2048-height":1229,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/997e8bcebb979e1113efd2155af2778f_826e3adc.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":192,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/997e8bcebb979e1113efd2155af2778f_826e3adc.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":256,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/997e8bcebb979e1113efd2155af2778f_826e3adc.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":384}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"Novaliglocke","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":4406,"id":4406,"title":"605436fc12deb546949b1a9e5d30d8c2_8856698b.jpg","filename":"605436fc12deb546949b1a9e5d30d8c2_8856698b.jpg","filesize":333163,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/605436fc12deb546949b1a9e5d30d8c2_8856698b.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/buergerturm-campanone\/605436fc12deb546949b1a9e5d30d8c2_8856698b-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"605436fc12deb546949b1a9e5d30d8c2_8856698b-jpg-2","status":"inherit","uploaded_to":19896,"date":"2024-05-08 08:37:39","modified":"2024-05-08 12:25:01","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":728,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/605436fc12deb546949b1a9e5d30d8c2_8856698b-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/605436fc12deb546949b1a9e5d30d8c2_8856698b-300x138.jpg","medium-width":300,"medium-height":138,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/605436fc12deb546949b1a9e5d30d8c2_8856698b-768x354.jpg","medium_large-width":768,"medium_large-height":354,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/605436fc12deb546949b1a9e5d30d8c2_8856698b-1024x472.jpg","large-width":1024,"large-height":472,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/605436fc12deb546949b1a9e5d30d8c2_8856698b-1536x708.jpg","1536x1536-width":1536,"1536x1536-height":708,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/605436fc12deb546949b1a9e5d30d8c2_8856698b.jpg","2048x2048-width":1580,"2048x2048-height":728,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/605436fc12deb546949b1a9e5d30d8c2_8856698b.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":138,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/605436fc12deb546949b1a9e5d30d8c2_8856698b.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":184,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/605436fc12deb546949b1a9e5d30d8c2_8856698b.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":276}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"gro\u00dfe Glocke","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":4412,"id":4412,"title":"f5957f8ce3d66d2ae92adb584287d255_8847498b.jpg","filename":"f5957f8ce3d66d2ae92adb584287d255_8847498b-scaled.jpg","filesize":676495,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/f5957f8ce3d66d2ae92adb584287d255_8847498b-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/buergerturm-campanone\/f5957f8ce3d66d2ae92adb584287d255_8847498b-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"f5957f8ce3d66d2ae92adb584287d255_8847498b-jpg-2","status":"inherit","uploaded_to":19896,"date":"2024-05-08 08:37:39","modified":"2024-05-08 12:25:01","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1714,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/f5957f8ce3d66d2ae92adb584287d255_8847498b-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/f5957f8ce3d66d2ae92adb584287d255_8847498b-300x201.jpg","medium-width":300,"medium-height":201,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/f5957f8ce3d66d2ae92adb584287d255_8847498b-768x514.jpg","medium_large-width":768,"medium_large-height":514,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/f5957f8ce3d66d2ae92adb584287d255_8847498b-1024x685.jpg","large-width":1024,"large-height":685,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/f5957f8ce3d66d2ae92adb584287d255_8847498b-1536x1028.jpg","1536x1536-width":1536,"1536x1536-height":1028,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/f5957f8ce3d66d2ae92adb584287d255_8847498b-2048x1371.jpg","2048x2048-width":2048,"2048x2048-height":1371,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/f5957f8ce3d66d2ae92adb584287d255_8847498b-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":201,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/f5957f8ce3d66d2ae92adb584287d255_8847498b-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":268,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/f5957f8ce3d66d2ae92adb584287d255_8847498b-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":402}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":33724,"id":33724,"title":"_DSC5016vista citta\u0300 alta_ragazza","filename":"DSC5016vista-citta-alta_ragazza.jpg","filesize":577211,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/DSC5016vista-citta-alta_ragazza.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/buergerturm-campanone\/_dsc5016vista-citta-alta_ragazza-2\/","alt":"","author":"6","description":"","caption":"","name":"_dsc5016vista-citta-alta_ragazza-2","status":"inherit","uploaded_to":19896,"date":"2024-05-15 12:27:45","modified":"2024-05-15 12:27:45","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1920,"height":1281,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/DSC5016vista-citta-alta_ragazza-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/DSC5016vista-citta-alta_ragazza-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/DSC5016vista-citta-alta_ragazza-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/DSC5016vista-citta-alta_ragazza-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/DSC5016vista-citta-alta_ragazza-1536x1025.jpg","1536x1536-width":1536,"1536x1536-height":1025,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/DSC5016vista-citta-alta_ragazza.jpg","2048x2048-width":1920,"2048x2048-height":1281,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/DSC5016vista-citta-alta_ragazza.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/DSC5016vista-citta-alta_ragazza.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/DSC5016vista-citta-alta_ragazza.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"buttons":[{"style":"primary","text":"Kontakt","icon":{"button_icon":"none"},"function":"link","url":"http:\/\/www.museodellestorie.bergamo.it","select_post":null,"target":"_blank","url_youtube":"","target_modal":""}],"filotto_layout":"scroll","url":"http:\/\/www.museodellestorie.bergamo.it","hero_title":"Stadtturm - Glocke","hero_text":"<p class=\"textbox\" dir=\"ltr\">Vom h\u00f6chsten Turm der Stadt haben Sie einen unvergesslichen Blick.<\/p>\n","indepth":"<p>An der Spitze des Turms, der zu Fu\u00df (230 Stufen) oder bequemer mit dem Aufzug erreicht werden kann, befindet sich <strong>die gr\u00f6\u00dfte Glocke der Lombardei<\/strong>.<\/p>\n<h3>Kuriosit\u00e4ten<\/h3>\n<p>Auch heute noch schl\u00e4gt der <strong>Campanone<\/strong> jeden Abend um 22 Uhr seine <strong>hundert Glockenschl\u00e4ge<\/strong>, die an die Schlie\u00dfung der Stadttore entlang der Mauern w\u00e4hrend der venezianischen Herrschaft erinnern.<\/p>\n","price":"<p>EINTRITT IN DEN CAMPANONE + PALAZZO DEL PODEST\u00c0<strong>Voll 5\u20ac<\/strong><strong>Erm\u00e4\u00dfigt 3\u20ac <\/strong>Freunde des Museo delle storie di Bergamo, Studenten bis 26 Jahre, Mitglieder des Italian Touring Club, FAI-Mitglieder, Gruppen von mindestens 15 Personen<strong>Erm\u00e4\u00dfigt 1\u20ac<\/strong> Kinder und Jugendliche von 11 bis 17 Jahren<strong>Freikarte:<\/strong> Kinder von 0 bis 10 Jahren, Behinderte, ICOM-Mitglieder, Journalisten, qualifizierte F\u00fchrer, Abbonamento Musei Lombardia<\/p>\n","time":"<p><em> <\/em><\/p>\n<p>D<strong>i-Fr<\/strong> | 10-18<strong>Sa-So und Feiertage <\/strong>| 10-19 8.<strong>Dezember, 26. Dezember &#038; 6. Januar <\/strong>| 10-19<strong>31. Dezember<\/strong> | 10-17 1<strong>. Januar<\/strong> | 14-19 2<strong>. Januar<\/strong> | 10-18 Montags, 25. Dezember geschlossen<\/p>\n","iu_addr_streetnumber":"Alter Platz","iu_addr_province":"Bergamo","iu_website":"http:\/\/www.museodellestorie.bergamo.it","filotto_fill":"manual","filotto_items":false,"hero_type":"images","accessibilitycontent":{"tcm_content":[{"acf_fc_layout":"title","title_tag":"h3","title_text":"Das Datenblatt"},{"acf_fc_layout":"text","text":""}]},"gallery":{"gallery_items":false},"poi_data":{"description":"<p class=\"textbox\" dir=\"ltr\">Im Herzen der <a href=\"https:\/\/visit.valueservice.cloud\/de\/oggetto\/piazza-vecchia\/\" target=\"_blank\" rel=\"noopener\">Piazza Vecchia<\/a> in <strong>Bergamo<\/strong> steht der <strong>Stadtturm<\/strong>, bekannt als <strong>Campanone<\/strong>.<\/p>\n<p class=\"textbox\" dir=\"ltr\">Aus einer <strong>H\u00f6he von 52,76 Metern<\/strong> bietet er einen atemberaubenden <strong>Panoramablick<\/strong>.<\/p>\n","indepth":"<p>An der Spitze des Turms, der zu Fu\u00df (230 Stufen) oder bequemer mit dem Aufzug erreicht werden kann, befindet sich <strong>die gr\u00f6\u00dfte Glocke der Lombardei<\/strong>.<\/p>\n<h3>Kuriosit\u00e4ten<\/h3>\n<p>Auch heute noch schl\u00e4gt der <strong>Campanone<\/strong> jeden Abend um 22 Uhr seine <strong>hundert Glockenschl\u00e4ge<\/strong>, die an die Schlie\u00dfung der Stadttore entlang der Mauern w\u00e4hrend der venezianischen Herrschaft erinnern.<\/p>\n","howtogetthere":"","price":"<p>EINTRITT IN DEN CAMPANONE + PALAZZO DEL PODEST\u00c0<strong>Voll 5\u20ac<\/strong><strong>Erm\u00e4\u00dfigt 3\u20ac <\/strong>Freunde des Museo delle storie di Bergamo, Studenten bis 26 Jahre, Mitglieder des Italian Touring Club, FAI-Mitglieder, Gruppen von mindestens 15 Personen<strong>Erm\u00e4\u00dfigt 1\u20ac<\/strong> Kinder und Jugendliche von 11 bis 17 Jahren<strong>Freikarte:<\/strong> Kinder von 0 bis 10 Jahren, Behinderte, ICOM-Mitglieder, Journalisten, qualifizierte F\u00fchrer, Abbonamento Musei Lombardia<\/p>\n","time":"<p><em> <\/em><\/p>\n<p>D<strong>i-Fr<\/strong> | 10-18<strong>Sa-So und Feiertage <\/strong>| 10-19 8.<strong>Dezember, 26. Dezember &#038; 6. Januar <\/strong>| 10-19<strong>31. Dezember<\/strong> | 10-17 1<strong>. Januar<\/strong> | 14-19 2<strong>. Januar<\/strong> | 10-18 Montags, 25. Dezember geschlossen<\/p>\n","latitude":"45.704278","longitude":"9.663136","id_visit_manza":"74","iu_motor_accessibility":"yes","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_kids":true,"iu_shortprice":"\u20ac1 - \u20ac5","iu_addr_streetnumber":"Alter Platz","iu_addr_postalcode":"24129","iu_addr_city":"Bergamo","iu_addr_province":"Bergamo","iu_phone":"+39 035247116","iu_cell":"","iu_website":"http:\/\/www.museodellestorie.bergamo.it","iu_email":"info@museodellestorie.bergamo.it","iu_document_label":"","iu_document":false,"iu_timetable":[{"day":{"value":"monday","label":"Luned\u00ec"},"open":false,"time":false},{"day":{"value":"tuesday","label":"Marted\u00ec"},"open":true,"time":[{"opening":"10:00 am","closing":"6:00 pm"}]},{"day":{"value":"wednesday","label":"Mercoled\u00ec"},"open":true,"time":[{"opening":"10:00 am","closing":"6:00 pm"}]},{"day":{"value":"thursday","label":"Gioved\u00ec"},"open":true,"time":[{"opening":"10:00 am","closing":"6:00 pm"}]},{"day":{"value":"friday","label":"Venerd\u00ec"},"open":true,"time":[{"opening":"10:00 am","closing":"6:00 pm"}]},{"day":{"value":"saturday","label":"Sabato"},"open":true,"time":[{"opening":"10:00 am","closing":"7:00 pm"}]},{"day":{"value":"sunday","label":"Domenica"},"open":true,"time":[{"opening":"10:00 am","closing":"7:00 pm"}]}]},"size":"full","featured_video":false,"filotto_sub":"","or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"order_by":"","order_way":"","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""},"iu_document_label":"","modules":false,"is_an_ambassador":false},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/19896","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/types\/oggetto"}],"author":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/users\/97"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/19896\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media\/4400"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media?parent=19896"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/categories?post=19896"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/tags?post=19896"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/aggr?post=19896"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/area?post=19896"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/kind?post=19896"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/zona?post=19896"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}