{"id":20037,"date":"2024-05-08T11:04:45","date_gmt":"2024-05-08T09:04:45","guid":{"rendered":"https:\/\/visitstg2.visitbergamo.net\/oggetto\/santalessandro-tor\/"},"modified":"2025-02-16T09:50:08","modified_gmt":"2025-02-16T08:50:08","slug":"porta-santalessandro","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/porta-santalessandro\/","title":{"rendered":"Porta Sant&#8217;Alessandro"},"excerpt":{"rendered":"<p>Perfekt eingebettet in die venezianischen Mauern aus dem 16. Jahrhundert, an der Spitze der Oberstadt gelegen, \u00f6ffnet sich dieses imposante Tor auf eine wunderbare Panoramaterrasse.  <\/p>\n","protected":false},"author":3,"featured_media":6974,"template":"","categories":[],"tags":[],"aggr":[],"area":[867],"kind":[18680],"zona":[18760],"class_list":["post-20037","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","area-bergamo","kind-poi-de","zona-bergamo-de"],"acf":{"filotto_title":"","filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"scroll","filotto_fill":"manual","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""}},"howtogetthere":"","timerange":"","cancellationpolicy":"","moredetails":"","whatsincluded":"","whatsnotincluded":"","price":"","time":"","latitude":"45.706595","longitude":"9.658158","startingprice":"","gpxmap":"","iu_motor_accessibility":"no","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_shortprice":"","iu_addr_streetnumber":"","iu_addr_postalcode":"24129","iu_addr_city":"Bergamo","iu_addr_province":"","iu_phone":"","iu_cell":"","iu_website":"","iu_email":"","iu_document":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_bookingurl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"","iu_languages":"","iu_minpeople":"","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","id_madeep":"","id_visit_manza":"6568","url":"","url_youtube":"","cta":{"style":"","text":"","icon":{"button_icon":"none"},"function":"","url":"","target":"","url_youtube":"","target_modal":""},"button_icon":"none","tcm_content":[{"acf_fc_layout":"title","title_tag":"h3","title_text":"Das Datenblatt"},{"acf_fc_layout":"text","text":""}],"description":"<p>Das nach Westen ausgerichtete Tor der Mura Venete wird das Tor von <strong>Sant&#8217;Alessandro<\/strong> genannt und war der Eingang zur Stadt f\u00fcr diejenigen, die aus Lecco und Como anreisten.<br \/>\nSein Name leitet sich von der nahe gelegenen Basilika ab, die dem Schutzpatron von Bergamo geweiht war und 1561 dem Erdboden gleichgemacht wurde, wie eine Gedenktafel neben der einzigen erhaltenen S\u00e4ule der Basilika zeigt, um den Bau der Stadtmauer zu erm\u00f6glichen.<br \/>\nWenn man durch das Tor geht, trifft man noch immer auf die &#8216;St. Alexanders S\u00e4ule&#8217;, die genau die Stelle markiert, an der die sp\u00e4ter abgerissene Kathedrale stand.    <\/p>\n","slides":[{"image":{"ID":6974,"id":6974,"title":"cc176814adb11890354f70fba3e87fad_6c237b98.jpg","filename":"cc176814adb11890354f70fba3e87fad_6c237b98.jpg","filesize":479039,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/cc176814adb11890354f70fba3e87fad_6c237b98.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/porta-santalessandro\/cc176814adb11890354f70fba3e87fad_6c237b98-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"cc176814adb11890354f70fba3e87fad_6c237b98-jpg-2","status":"inherit","uploaded_to":20037,"date":"2024-05-08 08:43:13","modified":"2024-08-29 08:50:31","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1550,"height":598,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/cc176814adb11890354f70fba3e87fad_6c237b98-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/cc176814adb11890354f70fba3e87fad_6c237b98-300x116.jpg","medium-width":300,"medium-height":116,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/cc176814adb11890354f70fba3e87fad_6c237b98-768x296.jpg","medium_large-width":768,"medium_large-height":296,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/cc176814adb11890354f70fba3e87fad_6c237b98-1024x395.jpg","large-width":1024,"large-height":395,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/cc176814adb11890354f70fba3e87fad_6c237b98-1536x593.jpg","1536x1536-width":1536,"1536x1536-height":593,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/cc176814adb11890354f70fba3e87fad_6c237b98.jpg","2048x2048-width":1550,"2048x2048-height":598,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/cc176814adb11890354f70fba3e87fad_6c237b98.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":116,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/cc176814adb11890354f70fba3e87fad_6c237b98.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":154,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/cc176814adb11890354f70fba3e87fad_6c237b98.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":231}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"t\u00fcr s.\nalexander ","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":6980,"id":6980,"title":"3d59984305e8ae31e76cec2145a61138_71bcf51e.jpg","filename":"3d59984305e8ae31e76cec2145a61138_71bcf51e.jpg","filesize":646339,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/3d59984305e8ae31e76cec2145a61138_71bcf51e.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/porta-santalessandro\/3d59984305e8ae31e76cec2145a61138_71bcf51e-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"3d59984305e8ae31e76cec2145a61138_71bcf51e-jpg-2","status":"inherit","uploaded_to":20037,"date":"2024-05-08 08:43:14","modified":"2024-08-29 08:50:40","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1550,"height":598,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/3d59984305e8ae31e76cec2145a61138_71bcf51e-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/3d59984305e8ae31e76cec2145a61138_71bcf51e-300x116.jpg","medium-width":300,"medium-height":116,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/3d59984305e8ae31e76cec2145a61138_71bcf51e-768x296.jpg","medium_large-width":768,"medium_large-height":296,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/3d59984305e8ae31e76cec2145a61138_71bcf51e-1024x395.jpg","large-width":1024,"large-height":395,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/3d59984305e8ae31e76cec2145a61138_71bcf51e-1536x593.jpg","1536x1536-width":1536,"1536x1536-height":593,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/3d59984305e8ae31e76cec2145a61138_71bcf51e.jpg","2048x2048-width":1550,"2048x2048-height":598,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/3d59984305e8ae31e76cec2145a61138_71bcf51e.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":116,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/3d59984305e8ae31e76cec2145a61138_71bcf51e.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":154,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/3d59984305e8ae31e76cec2145a61138_71bcf51e.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":231}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"t\u00fcr s.\nalexander ","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":6986,"id":6986,"title":"0a2b4cb1c3ede3305a5e31d52fdde23f_b2594322.jpg","filename":"0a2b4cb1c3ede3305a5e31d52fdde23f_b2594322.jpg","filesize":658810,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/0a2b4cb1c3ede3305a5e31d52fdde23f_b2594322.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/porta-santalessandro\/0a2b4cb1c3ede3305a5e31d52fdde23f_b2594322-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"0a2b4cb1c3ede3305a5e31d52fdde23f_b2594322-jpg-2","status":"inherit","uploaded_to":20037,"date":"2024-05-08 08:43:14","modified":"2024-08-29 08:50:50","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1920,"height":836,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/0a2b4cb1c3ede3305a5e31d52fdde23f_b2594322-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/0a2b4cb1c3ede3305a5e31d52fdde23f_b2594322-300x131.jpg","medium-width":300,"medium-height":131,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/0a2b4cb1c3ede3305a5e31d52fdde23f_b2594322-768x334.jpg","medium_large-width":768,"medium_large-height":334,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/0a2b4cb1c3ede3305a5e31d52fdde23f_b2594322-1024x446.jpg","large-width":1024,"large-height":446,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/0a2b4cb1c3ede3305a5e31d52fdde23f_b2594322-1536x669.jpg","1536x1536-width":1536,"1536x1536-height":669,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/0a2b4cb1c3ede3305a5e31d52fdde23f_b2594322.jpg","2048x2048-width":1920,"2048x2048-height":836,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/0a2b4cb1c3ede3305a5e31d52fdde23f_b2594322.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":131,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/0a2b4cb1c3ede3305a5e31d52fdde23f_b2594322.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":174,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/0a2b4cb1c3ede3305a5e31d52fdde23f_b2594322.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":261}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"Porta sant'Alessandro Detail","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":6992,"id":6992,"title":"e3856fa18a26423b3145f0a7368ea04d_43b421d0.jpg","filename":"e3856fa18a26423b3145f0a7368ea04d_43b421d0.jpg","filesize":472522,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/e3856fa18a26423b3145f0a7368ea04d_43b421d0.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/porta-santalessandro\/e3856fa18a26423b3145f0a7368ea04d_43b421d0-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"e3856fa18a26423b3145f0a7368ea04d_43b421d0-jpg-2","status":"inherit","uploaded_to":20037,"date":"2024-05-08 08:43:15","modified":"2024-05-08 12:25:58","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1550,"height":600,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/e3856fa18a26423b3145f0a7368ea04d_43b421d0-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/e3856fa18a26423b3145f0a7368ea04d_43b421d0-300x116.jpg","medium-width":300,"medium-height":116,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/e3856fa18a26423b3145f0a7368ea04d_43b421d0-768x297.jpg","medium_large-width":768,"medium_large-height":297,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/e3856fa18a26423b3145f0a7368ea04d_43b421d0-1024x396.jpg","large-width":1024,"large-height":396,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/e3856fa18a26423b3145f0a7368ea04d_43b421d0-1536x595.jpg","1536x1536-width":1536,"1536x1536-height":595,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/e3856fa18a26423b3145f0a7368ea04d_43b421d0.jpg","2048x2048-width":1550,"2048x2048-height":600,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/e3856fa18a26423b3145f0a7368ea04d_43b421d0.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":116,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/e3856fa18a26423b3145f0a7368ea04d_43b421d0.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":155,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/e3856fa18a26423b3145f0a7368ea04d_43b421d0.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":232}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"t\u00fcr s.\nalexander ","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":6998,"id":6998,"title":"d5d7643c88291d45ad4fbfba6f7aea23_40d058fa.jpg","filename":"d5d7643c88291d45ad4fbfba6f7aea23_40d058fa.jpg","filesize":535358,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/d5d7643c88291d45ad4fbfba6f7aea23_40d058fa.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/porta-santalessandro\/d5d7643c88291d45ad4fbfba6f7aea23_40d058fa-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"d5d7643c88291d45ad4fbfba6f7aea23_40d058fa-jpg-2","status":"inherit","uploaded_to":20037,"date":"2024-05-08 08:43:15","modified":"2024-08-29 08:51:12","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1550,"height":596,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/d5d7643c88291d45ad4fbfba6f7aea23_40d058fa-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/d5d7643c88291d45ad4fbfba6f7aea23_40d058fa-300x115.jpg","medium-width":300,"medium-height":115,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/d5d7643c88291d45ad4fbfba6f7aea23_40d058fa-768x295.jpg","medium_large-width":768,"medium_large-height":295,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/d5d7643c88291d45ad4fbfba6f7aea23_40d058fa-1024x394.jpg","large-width":1024,"large-height":394,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/d5d7643c88291d45ad4fbfba6f7aea23_40d058fa-1536x591.jpg","1536x1536-width":1536,"1536x1536-height":591,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/d5d7643c88291d45ad4fbfba6f7aea23_40d058fa.jpg","2048x2048-width":1550,"2048x2048-height":596,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/d5d7643c88291d45ad4fbfba6f7aea23_40d058fa.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":115,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/d5d7643c88291d45ad4fbfba6f7aea23_40d058fa.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":154,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/d5d7643c88291d45ad4fbfba6f7aea23_40d058fa.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":231}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"t\u00fcr s.\nalexander ","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":7004,"id":7004,"title":"6a03cea45feb89ab41ead85a19894ac1_85aa956e.jpg","filename":"6a03cea45feb89ab41ead85a19894ac1_85aa956e.jpg","filesize":466883,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/6a03cea45feb89ab41ead85a19894ac1_85aa956e.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/porta-santalessandro\/6a03cea45feb89ab41ead85a19894ac1_85aa956e-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"6a03cea45feb89ab41ead85a19894ac1_85aa956e-jpg-2","status":"inherit","uploaded_to":20037,"date":"2024-05-08 08:43:15","modified":"2024-08-29 08:51:28","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1550,"height":598,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/6a03cea45feb89ab41ead85a19894ac1_85aa956e-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/6a03cea45feb89ab41ead85a19894ac1_85aa956e-300x116.jpg","medium-width":300,"medium-height":116,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/6a03cea45feb89ab41ead85a19894ac1_85aa956e-768x296.jpg","medium_large-width":768,"medium_large-height":296,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/6a03cea45feb89ab41ead85a19894ac1_85aa956e-1024x395.jpg","large-width":1024,"large-height":395,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/6a03cea45feb89ab41ead85a19894ac1_85aa956e-1536x593.jpg","1536x1536-width":1536,"1536x1536-height":593,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/6a03cea45feb89ab41ead85a19894ac1_85aa956e.jpg","2048x2048-width":1550,"2048x2048-height":598,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/6a03cea45feb89ab41ead85a19894ac1_85aa956e.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":116,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/6a03cea45feb89ab41ead85a19894ac1_85aa956e.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":154,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/6a03cea45feb89ab41ead85a19894ac1_85aa956e.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":231}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"t\u00fcr s.\nalexander ","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"buttons":[{"style":"primary","text":"Kontakt","icon":{"button_icon":"none"},"function":"link","url":"","select_post":null,"target":"_blank","url_youtube":"","target_modal":""}],"filotto_layout":"scroll","hero_title":"Porta Sant'Alessandro","hero_text":"<p>Perfekt eingebettet in die venezianischen Mauern aus dem 16. Jahrhundert, an der Spitze der Oberstadt gelegen, \u00f6ffnet sich dieses imposante Tor auf eine wunderbare Panoramaterrasse.<\/p>\n","indepth":"<p>Es ist wahrscheinlich, dass die<strong> Porta Sant&#8217;Alessandro<\/strong>, wie die anderen vier Tore der Verteidigungsmauern, in \u00dcbereinstimmung mit den bereits in r\u00f6mischer Zeit vorhandenen Durchg\u00e4ngen gebaut wurde, die entlang der Kardinalachsen ausgerichtet waren und w\u00e4hrend der mittelalterlichen Barbareneinf\u00e4lle wiederholt abgerissen und wieder aufgebaut wurden. <br \/>Heute befindet sich dieses massive Tor in dem Bereich von Citt\u00e0 Alta, der als Colle Aperto bekannt ist, eine Bezeichnung, die im fr\u00fchen 19. Jahrhundert entstand, als das Gebiet, das von der Viale delle Mura zur <strong>Porta Sant&#8217;Alessandro<\/strong> f\u00fchrte, eingeebnet wurde.<br \/>\nDer Platz bietet eine bezaubernde Perspektive sowohl auf den monumentalen Teil als auch auf die Landschaft. <\/p>\n<h3>Kuriosit\u00e4ten<\/h3>\n<p>Genau wie die anderen Eing\u00e4nge zur Stadt in der Vergangenheit wurde auch dieser Zugang jede Nacht um 22 Uhr geschlossen, um die Sicherheit der Stadt zu gew\u00e4hrleisten.<\/p>\n","filotto_fill":"manual","hero_type":"images","filotto_items":false,"accessibilitycontent":{"tcm_content":[{"acf_fc_layout":"title","title_tag":"h3","title_text":"Das Datenblatt"},{"acf_fc_layout":"text","text":""}]},"gallery":{"gallery_items":false},"iu_kids":false,"iu_timetable":false,"poi_data":{"description":"<p>Das nach Westen ausgerichtete Tor der Mura Venete wird das Tor von <strong>Sant&#8217;Alessandro<\/strong> genannt und war der Eingang zur Stadt f\u00fcr diejenigen, die aus Lecco und Como anreisten.<br \/>\nSein Name leitet sich von der nahe gelegenen Basilika ab, die dem Schutzpatron von Bergamo geweiht war und 1561 dem Erdboden gleichgemacht wurde, wie eine Gedenktafel neben der einzigen erhaltenen S\u00e4ule der Basilika zeigt, um den Bau der Stadtmauer zu erm\u00f6glichen.<br \/>\nWenn man durch das Tor geht, trifft man noch immer auf die &#8216;St. Alexanders S\u00e4ule&#8217;, die genau die Stelle markiert, an der die sp\u00e4ter abgerissene Kathedrale stand.    <\/p>\n","indepth":"<p>Es ist wahrscheinlich, dass die<strong> Porta Sant&#8217;Alessandro<\/strong>, wie die anderen vier Tore der Verteidigungsmauern, in \u00dcbereinstimmung mit den bereits in r\u00f6mischer Zeit vorhandenen Durchg\u00e4ngen gebaut wurde, die entlang der Kardinalachsen ausgerichtet waren und w\u00e4hrend der mittelalterlichen Barbareneinf\u00e4lle wiederholt abgerissen und wieder aufgebaut wurden. <br \/>Heute befindet sich dieses massive Tor in dem Bereich von Citt\u00e0 Alta, der als Colle Aperto bekannt ist, eine Bezeichnung, die im fr\u00fchen 19. Jahrhundert entstand, als das Gebiet, das von der Viale delle Mura zur <strong>Porta Sant&#8217;Alessandro<\/strong> f\u00fchrte, eingeebnet wurde.<br \/>\nDer Platz bietet eine bezaubernde Perspektive sowohl auf den monumentalen Teil als auch auf die Landschaft. <\/p>\n<h3>Kuriosit\u00e4ten<\/h3>\n<p>Genau wie die anderen Eing\u00e4nge zur Stadt in der Vergangenheit wurde auch dieser Zugang jede Nacht um 22 Uhr geschlossen, um die Sicherheit der Stadt zu gew\u00e4hrleisten.<\/p>\n","howtogetthere":"","price":"","time":"","latitude":"45.706595","longitude":"9.658158","id_visit_manza":"6568","iu_motor_accessibility":"no","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_kids":false,"iu_shortprice":"","iu_addr_streetnumber":"","iu_addr_postalcode":"24129","iu_addr_city":"Bergamo","iu_addr_province":"","iu_phone":"","iu_cell":"","iu_website":"","iu_email":"","iu_document_label":"","iu_document":false,"iu_timetable":false},"size":"full","featured_video":false,"is_an_ambassador":false,"filotto_sub":"","or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"order_by":"","order_way":"","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""},"style":"","text":"","icon":{"button_icon":"none"},"function":"","target":"","target_modal":"","iu_document_label":""},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/20037","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/types\/oggetto"}],"author":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/20037\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media\/6974"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media?parent=20037"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/categories?post=20037"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/tags?post=20037"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/aggr?post=20037"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/area?post=20037"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/kind?post=20037"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/zona?post=20037"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}