{"id":20044,"date":"2024-05-08T11:04:48","date_gmt":"2024-05-08T09:04:48","guid":{"rendered":"https:\/\/visitstg2.visitbergamo.net\/oggetto\/das-geburtshaus-des-donizetti\/"},"modified":"2025-02-16T09:50:18","modified_gmt":"2025-02-16T08:50:18","slug":"das-geburtshaus-des-donizetti","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/das-geburtshaus-des-donizetti\/","title":{"rendered":"Donizetti Geburtshaus"},"excerpt":{"rendered":"<p>&#8220;Meine Geburt war allerdings noch geheimer, denn ich wurde (sic) unterirdisch in Borgo Canale geboren. Ich ging eine Kellertreppe hinunter, wo der Schatten des Lichts niemals eindrang. Und wie eine Eule flog ich davon&#8230;&#8221; steht auf einer Marmortafel in dem Haus, in dem Gaetano Donizetti geboren wurde.  <\/p>\n","protected":false},"author":3,"featured_media":7094,"template":"","categories":[],"tags":[],"aggr":[],"area":[867],"kind":[18680],"zona":[18760],"class_list":["post-20044","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","area-bergamo","kind-poi-de","zona-bergamo-de"],"acf":{"filotto_title":"","filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"scroll","filotto_fill":"manual","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""}},"howtogetthere":"","timerange":"","cancellationpolicy":"","moredetails":"","whatsincluded":"","whatsnotincluded":"","price":"","latitude":"45.706316","longitude":"9.656118","startingprice":"","gpxmap":"","iu_motor_accessibility":"no","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_shortprice":"","iu_addr_postalcode":"","iu_addr_city":"Bergamo","iu_addr_province":"","iu_phone":"+39 035 4160618","iu_cell":"+39 035 244483","iu_email":"biglietteria@fondazioneteatrodonizetti.org","iu_document":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_bookingurl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"","iu_languages":"","iu_minpeople":"","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","id_madeep":"","id_visit_manza":"939","url_youtube":"","cta":{"style":"","text":"","icon":{"button_icon":"none"},"function":"","url":"http:\/\/www.teatrodonizetti.it\/it\/casa-natale-di-gaetano-donizetti","target":"","url_youtube":"","target_modal":""},"iu_timetable":[{"day":{"value":"sunday","label":"Domenica"},"open":true,"time":[{"opening":"10:00 am","closing":"1:00 pm"},{"opening":"2:00 pm","closing":"5:00 pm"}]}],"button_icon":"none","tcm_content":[{"acf_fc_layout":"title","title_tag":"h3","title_text":"Das Datenblatt"},{"acf_fc_layout":"text","text":""}],"description":"<p style=\"text-align: justify;\">Mit diesen Worten beschreibt einer der f\u00fcnf bedeutendsten Komponisten aller Zeiten sein Elternhaus in einem Brief an Simone Mayr.  <br \/>Donizettis Geburtshaus, das zum Nationaldenkmal erkl\u00e4rt wurde, befindet sich hier in Bergamo, in Borgo Canale, wo die Geb\u00e4ude zu jener Zeit eher bauf\u00e4llig und \u00e4rmlich waren.  <br \/>Die Familie des Komponisten wohnte im Souterrain des Geb\u00e4udes, das man heute auch im Erdgeschoss besichtigen kann, zu dem man \u00fcber eine schmale Treppe gelangt.<\/p>\n<p>Der Raum war sehr spartanisch und bestand aus zwei Zimmern, die als K\u00fcche und Schlafzimmer dienten, sowie dem Brunnen und dem Eisschrank. Donizettis Schicksal scheint besiegelt zu sein: In seinem Leben webte er Noten und schuf unsterbliche Kompositionen, so wie seine Eltern Stoffe webten.<br \/>\nDie Eltern des Maestro waren n\u00e4mlich Schneider und geh\u00f6rten zu jenem bescheidenen Teil der Bev\u00f6lkerung, der seinen Lebensunterhalt mit der Arbeit f\u00fcr die Herren der reichen Pal\u00e4ste in der Oberstadt verdiente.<br \/>\nDonizetti machte seine bescheidene Herkunft wieder gut, indem er weltber\u00fchmt wurde und seiner Stadt Glanz verlieh.   <\/p>\n","slides":[{"image":{"ID":7094,"id":7094,"title":"56fc68720818d57ae3552836084fc0f6_1c684a79.jpg","filename":"56fc68720818d57ae3552836084fc0f6_1c684a79.jpg","filesize":241044,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/56fc68720818d57ae3552836084fc0f6_1c684a79.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/das-geburtshaus-des-donizetti\/56fc68720818d57ae3552836084fc0f6_1c684a79-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"56fc68720818d57ae3552836084fc0f6_1c684a79-jpg-2","status":"inherit","uploaded_to":20044,"date":"2024-05-08 08:43:24","modified":"2024-08-30 11:53:01","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1920,"height":1280,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/56fc68720818d57ae3552836084fc0f6_1c684a79-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/56fc68720818d57ae3552836084fc0f6_1c684a79-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/56fc68720818d57ae3552836084fc0f6_1c684a79-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/56fc68720818d57ae3552836084fc0f6_1c684a79-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/56fc68720818d57ae3552836084fc0f6_1c684a79-1536x1024.jpg","1536x1536-width":1536,"1536x1536-height":1024,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/56fc68720818d57ae3552836084fc0f6_1c684a79.jpg","2048x2048-width":1920,"2048x2048-height":1280,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/56fc68720818d57ae3552836084fc0f6_1c684a79.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/56fc68720818d57ae3552836084fc0f6_1c684a79.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/56fc68720818d57ae3552836084fc0f6_1c684a79.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"donizetti geburtshaus 1","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":7100,"id":7100,"title":"bc1da9b9efff65ef3533d19a5e54dd94_e7edf5ec.jpg","filename":"bc1da9b9efff65ef3533d19a5e54dd94_e7edf5ec.jpg","filesize":253399,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/bc1da9b9efff65ef3533d19a5e54dd94_e7edf5ec.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/das-geburtshaus-des-donizetti\/bc1da9b9efff65ef3533d19a5e54dd94_e7edf5ec-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"bc1da9b9efff65ef3533d19a5e54dd94_e7edf5ec-jpg-2","status":"inherit","uploaded_to":20044,"date":"2024-05-08 08:43:25","modified":"2024-08-30 11:53:18","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1920,"height":1280,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/bc1da9b9efff65ef3533d19a5e54dd94_e7edf5ec-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/bc1da9b9efff65ef3533d19a5e54dd94_e7edf5ec-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/bc1da9b9efff65ef3533d19a5e54dd94_e7edf5ec-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/bc1da9b9efff65ef3533d19a5e54dd94_e7edf5ec-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/bc1da9b9efff65ef3533d19a5e54dd94_e7edf5ec-1536x1024.jpg","1536x1536-width":1536,"1536x1536-height":1024,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/bc1da9b9efff65ef3533d19a5e54dd94_e7edf5ec.jpg","2048x2048-width":1920,"2048x2048-height":1280,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/bc1da9b9efff65ef3533d19a5e54dd94_e7edf5ec.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/bc1da9b9efff65ef3533d19a5e54dd94_e7edf5ec.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/bc1da9b9efff65ef3533d19a5e54dd94_e7edf5ec.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"donizetti geburtshaus 2","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":7106,"id":7106,"title":"96491a8cc309ee8edc8c42fee93017bf_0a67de26.jpg","filename":"96491a8cc309ee8edc8c42fee93017bf_0a67de26.jpg","filesize":254154,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/96491a8cc309ee8edc8c42fee93017bf_0a67de26.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/das-geburtshaus-des-donizetti\/96491a8cc309ee8edc8c42fee93017bf_0a67de26-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"96491a8cc309ee8edc8c42fee93017bf_0a67de26-jpg-2","status":"inherit","uploaded_to":20044,"date":"2024-05-08 08:43:26","modified":"2024-08-30 11:53:25","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1920,"height":1280,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/96491a8cc309ee8edc8c42fee93017bf_0a67de26-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/96491a8cc309ee8edc8c42fee93017bf_0a67de26-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/96491a8cc309ee8edc8c42fee93017bf_0a67de26-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/96491a8cc309ee8edc8c42fee93017bf_0a67de26-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/96491a8cc309ee8edc8c42fee93017bf_0a67de26-1536x1024.jpg","1536x1536-width":1536,"1536x1536-height":1024,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/96491a8cc309ee8edc8c42fee93017bf_0a67de26.jpg","2048x2048-width":1920,"2048x2048-height":1280,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/96491a8cc309ee8edc8c42fee93017bf_0a67de26.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/96491a8cc309ee8edc8c42fee93017bf_0a67de26.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/96491a8cc309ee8edc8c42fee93017bf_0a67de26.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"donizetti geburtshaus 3","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"buttons":[{"style":"primary","text":"Kontakt","icon":{"button_icon":"none"},"function":"link","url":"http:\/\/www.teatrodonizetti.it\/it\/casa-natale-di-gaetano-donizetti","select_post":null,"target":"_blank","url_youtube":"","target_modal":""}],"filotto_layout":"scroll","url":"http:\/\/www.teatrodonizetti.it\/it\/casa-natale-di-gaetano-donizetti","hero_title":"Donizetti Geburtshaus","hero_text":"<p>&#8220;Meine Geburt war allerdings noch geheimer, denn ich wurde (sic) unterirdisch in Borgo Canale geboren. Ich ging eine Kellertreppe hinunter, wo der Schatten des Lichts niemals eindrang. Und wie eine Eule flog ich davon&#8230;&#8221; steht auf einer Marmortafel in dem Haus, in dem Gaetano Donizetti geboren wurde.<\/p>\n","indepth":"<p>Seit einiger Zeit k\u00f6nnen Sie dank des Projekts Impronte sonore einen Tag im Hause Donizetti nacherleben: eine multimediale Reise, die durch Kl\u00e4nge das Leben einer typischen Familie aus dem 18.  <\/p>\n","time":"<p><span style=\"text-decoration: underline;\">Sonntag<\/span>: 10 &#8211; 13 Uhr | 14 &#8211; 17 Uhr<\/p>\n","iu_addr_streetnumber":"Via Borgo Canale, 14","iu_website":"http:\/\/www.teatrodonizetti.it\/it\/casa-natale-di-gaetano-donizetti","filotto_fill":"manual","hero_type":"images","filotto_items":false,"accessibilitycontent":{"tcm_content":[{"acf_fc_layout":"title","title_tag":"h3","title_text":"Das Datenblatt"},{"acf_fc_layout":"text","text":""}]},"gallery":{"gallery_items":false},"iu_kids":false,"poi_data":{"description":"<p style=\"text-align: justify;\">Mit diesen Worten beschreibt einer der f\u00fcnf bedeutendsten Komponisten aller Zeiten sein Elternhaus in einem Brief an Simone Mayr.  <br \/>Donizettis Geburtshaus, das zum Nationaldenkmal erkl\u00e4rt wurde, befindet sich hier in Bergamo, in Borgo Canale, wo die Geb\u00e4ude zu jener Zeit eher bauf\u00e4llig und \u00e4rmlich waren.  <br \/>Die Familie des Komponisten wohnte im Souterrain des Geb\u00e4udes, das man heute auch im Erdgeschoss besichtigen kann, zu dem man \u00fcber eine schmale Treppe gelangt.<\/p>\n<p>Der Raum war sehr spartanisch und bestand aus zwei Zimmern, die als K\u00fcche und Schlafzimmer dienten, sowie dem Brunnen und dem Eisschrank. Donizettis Schicksal scheint besiegelt zu sein: In seinem Leben webte er Noten und schuf unsterbliche Kompositionen, so wie seine Eltern Stoffe webten.<br \/>\nDie Eltern des Maestro waren n\u00e4mlich Schneider und geh\u00f6rten zu jenem bescheidenen Teil der Bev\u00f6lkerung, der seinen Lebensunterhalt mit der Arbeit f\u00fcr die Herren der reichen Pal\u00e4ste in der Oberstadt verdiente.<br \/>\nDonizetti machte seine bescheidene Herkunft wieder gut, indem er weltber\u00fchmt wurde und seiner Stadt Glanz verlieh.   <\/p>\n","indepth":"<p>Seit einiger Zeit k\u00f6nnen Sie dank des Projekts Impronte sonore einen Tag im Hause Donizetti nacherleben: eine multimediale Reise, die durch Kl\u00e4nge das Leben einer typischen Familie aus dem 18.  <\/p>\n","howtogetthere":"","price":"","time":"<p><span style=\"text-decoration: underline;\">Sonntag<\/span>: 10 &#8211; 13 Uhr | 14 &#8211; 17 Uhr<\/p>\n","latitude":"45.706316","longitude":"9.656118","id_visit_manza":"939","iu_motor_accessibility":"no","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_kids":false,"iu_shortprice":"","iu_addr_streetnumber":"Via Borgo Canale, 14","iu_addr_postalcode":"","iu_addr_city":"Bergamo","iu_addr_province":"","iu_phone":"+39 035 4160618","iu_cell":"+39 035 244483","iu_website":"http:\/\/www.teatrodonizetti.it\/it\/casa-natale-di-gaetano-donizetti","iu_email":"biglietteria@fondazioneteatrodonizetti.org","iu_document_label":"","iu_document":false,"iu_timetable":[{"day":{"value":"sunday","label":"Domenica"},"open":true,"time":[{"opening":"10:00 am","closing":"1:00 pm"},{"opening":"2:00 pm","closing":"5:00 pm"}]}]},"size":"full","featured_video":false,"is_an_ambassador":false,"filotto_sub":"","or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"order_by":"","order_way":"","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""},"style":"","text":"","icon":{"button_icon":"none"},"function":"","target":"","target_modal":"","iu_document_label":""},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/20044","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/types\/oggetto"}],"author":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/20044\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media\/7094"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media?parent=20044"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/categories?post=20044"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/tags?post=20044"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/aggr?post=20044"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/area?post=20044"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/kind?post=20044"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/zona?post=20044"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}