{"id":20056,"date":"2024-05-08T11:04:52","date_gmt":"2024-05-08T09:04:52","guid":{"rendered":"https:\/\/visitstg2.visitbergamo.net\/oggetto\/kirche-s-michele-al-pozzo-bianco\/"},"modified":"2025-02-16T09:50:39","modified_gmt":"2025-02-16T08:50:39","slug":"kirche-s-michele-al-pozzo-bianco","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/kirche-s-michele-al-pozzo-bianco\/","title":{"rendered":"S. Michele al Pozzo Bianco Kirche"},"excerpt":{"rendered":"<p>Eines der \u00e4ltesten und wertvollsten in Bergamo, das sogar in einem lombardischen Testament von 774 n. Chr. erw\u00e4hnt wird. Vielleicht wurde es an der Stelle eines heidnischen Tempels errichtet, der dem Gott Vulkan geweiht war.  <\/p>\n","protected":false},"author":3,"featured_media":7346,"template":"","categories":[],"tags":[],"aggr":[],"area":[867],"kind":[18680],"zona":[18760],"class_list":["post-20056","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","area-bergamo","kind-poi-de","zona-bergamo-de"],"acf":{"filotto_title":"","filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"scroll","filotto_fill":"manual","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""}},"howtogetthere":"","timerange":"","cancellationpolicy":"","moredetails":"","whatsincluded":"","whatsnotincluded":"","price":"","latitude":"45.704006","longitude":"9.669834","startingprice":"","gpxmap":"","iu_motor_accessibility":"no","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_shortprice":"","iu_addr_postalcode":"","iu_addr_city":"Bergamo","iu_addr_province":"","iu_phone":"","iu_cell":"","iu_email":"","iu_document":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_bookingurl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"","iu_languages":"","iu_minpeople":"","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","id_madeep":"","id_visit_manza":"2996","url_youtube":"","cta":{"style":"","text":"","icon":{"button_icon":"none"},"function":"","url":"http:\/\/www.comune.bergamo.it\/servizi\/Menu\/dinamica.aspx?idSezione=3780&idArea=1182&idCat=1195&ID=10441&TipoElemento=pagina","target":"","url_youtube":"","target_modal":""},"iu_timetable":[{"day":{"value":"monday","label":"Luned\u00ec"},"open":true,"time":[{"opening":"9:00 am","closing":"5:00 pm"}]},{"day":{"value":"tuesday","label":"Marted\u00ec"},"open":true,"time":[{"opening":"9:00 am","closing":"5:00 pm"}]},{"day":{"value":"wednesday","label":"Mercoled\u00ec"},"open":true,"time":[{"opening":"9:00 am","closing":"5:00 pm"}]},{"day":{"value":"thursday","label":"Gioved\u00ec"},"open":true,"time":[{"opening":"9:00 am","closing":"5:00 pm"}]},{"day":{"value":"friday","label":"Venerd\u00ec"},"open":true,"time":[{"opening":"9:00 am","closing":"5:00 pm"}]},{"day":{"value":"saturday","label":"Sabato"},"open":true,"time":[{"opening":"9:00 am","closing":"6:00 pm"}]},{"day":{"value":"sunday","label":"Domenica"},"open":true,"time":[{"opening":"9:00 am","closing":"6:00 pm"}]}],"button_icon":"none","tcm_content":[{"acf_fc_layout":"text","text":"<p><strong>REACH:<\/strong><\/p>\n<p>P<strong>arken:<\/strong> in 200 Metern Entfernung (Baluardo San Michele): \u00f6ffentlicher Parkplatz ohne reservierte Parkpl\u00e4tze; es besteht die M\u00f6glichkeit, einen Parkausweis f\u00fcr den Kirchhof San Michele al Pozzo Bianco zu beantragen.<\/p>\n<p>\u00d6ffentliche Verkehrsmittel: <strong> in 250 Metern (Viale delle Mura, Ecke Via Osmano): Bushaltestelle der Linie 1; Stufenh\u00f6he 17 cm; Bus mit manuellem Trittbrett; Gehsteigbreite 105 cm und gepflasterte Passage auf der Via Osmano in 300 Metern (Piazza Mercato delle Scarpe): Standseilbahnstation.<br \/>\nDer Fu\u00dfweg f\u00fchrt bergab (8% Steigung auf einem Fischgr\u00e4tenpflaster aus Stein und Porphyr).<\/strong> <\/p>\n<p>Fu\u00dfweg von den Parkpl\u00e4tzen und der Bushaltestelle: bergauf oder bergab (8-10% Steigung) mit Ausnahme des Abschnitts in der N\u00e4he des Eingangs, der kurz, aber sehr steil ist (mehr als 20%); ausreichend breit und mit Steinplatten und Fischgr\u00e4tporphyr gepflastert; keine taktilen Markierungen.<\/p>\n<p><strong>EINTRITT:<\/strong><\/p>\n<p>Ebener Eingang mit zwei 2 cm hohen Schwellen am Tor; T\u00fcr mit ausreichender Breite.<\/p>\n<p><strong>BESUCHEN:<\/strong><\/p>\n<p>Ebener und begehbarer Innenraum; vor dem Chor und den Kapellen liegt eine 20 cm hohe Stufe. Sichtbare Kunstwerke, Lichter k\u00f6nnen gegen eine Geb\u00fchr am Kircheneingang eingeschaltet werden (Schalterh\u00f6he 150 cm). Krypta wegen steiler, schmaler Treppen nicht zug\u00e4nglich.<\/p>\n<p><strong>DIE TOILETTE ZU BENUTZEN:<\/strong><\/p>\n<p>Es gibt eine barrierefreie Toilette (vorgefertigt) auf dem Parkplatz der St. Michael&#8217;s Bastion<\/p>\n"},{"acf_fc_layout":"title","title_tag":"h3","title_text":"Das Datenblatt"},{"acf_fc_layout":"text","text":"<p>S<strong>YNTHETISCHE BEWERTUNG:<\/strong> Person mit Mobilit\u00e4tseinschr\u00e4nkung: zug\u00e4nglich mit robuster Pflegekraft Person mit Sehbehinderung: zug\u00e4nglich mit Pflegekraft<\/p>\n"},{"acf_fc_layout":"gallery","gallery_items":[{"description":"Parkplatz an der Bastion von San Michele, entlang der Viale delle Mura","image":{"ID":21060,"id":21060,"title":"Parcheggio al baluardo di San Michele, lungo il Viale delle Mura","filename":"4b0b9a4195e9fc1659234b7afb38c665_deea3cef-8.jpg","filesize":537675,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/4b0b9a4195e9fc1659234b7afb38c665_deea3cef-8.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/kirche-s-michele-al-pozzo-bianco\/parcheggio-al-baluardo-di-san-michele-lungo-il-viale-delle-mura-5-2\/","alt":"Parcheggio vicino alla Chiesa di San Michele al Pozzo Bianco","author":"0","description":"Vista del parcheggio pubblico situato nei pressi del Baluardo San Michele, a breve distanza dalla Chiesa.","caption":"","name":"parcheggio-al-baluardo-di-san-michele-lungo-il-viale-delle-mura-5-2","status":"inherit","uploaded_to":20056,"date":"2024-05-08 12:32:49","modified":"2025-04-11 12:28:18","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":676,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/4b0b9a4195e9fc1659234b7afb38c665_deea3cef-8-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/4b0b9a4195e9fc1659234b7afb38c665_deea3cef-8-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/4b0b9a4195e9fc1659234b7afb38c665_deea3cef-8-768x433.jpg","medium_large-width":768,"medium_large-height":433,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/4b0b9a4195e9fc1659234b7afb38c665_deea3cef-8-1024x577.jpg","large-width":1024,"large-height":577,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/4b0b9a4195e9fc1659234b7afb38c665_deea3cef-8.jpg","1536x1536-width":1200,"1536x1536-height":676,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/4b0b9a4195e9fc1659234b7afb38c665_deea3cef-8.jpg","2048x2048-width":1200,"2048x2048-height":676,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/4b0b9a4195e9fc1659234b7afb38c665_deea3cef-8.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/4b0b9a4195e9fc1659234b7afb38c665_deea3cef-8.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/4b0b9a4195e9fc1659234b7afb38c665_deea3cef-8.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},"url_youtube":""},{"description":"Stra\u00dfenkreuzung - Viale delle Mura","image":{"ID":21066,"id":21066,"title":"Attraversamento stradale - Viale delle Mura","filename":"ed7c458e9e6c16deace532108a35a944_f00b1c48-8.jpg","filesize":527016,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ed7c458e9e6c16deace532108a35a944_f00b1c48-8.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/kirche-s-michele-al-pozzo-bianco\/attraversamento-stradale-viale-delle-mura-5-2\/","alt":"Attraversamento pedonale vicino alla fermata dell'autobus per la Chiesa di San Michele","author":"0","description":"Attraversamento pedonale su Viale delle Mura, nei pressi della fermata dell'autobus utile per raggiungere la chiesa","caption":"","name":"attraversamento-stradale-viale-delle-mura-5-2","status":"inherit","uploaded_to":20056,"date":"2024-05-08 12:32:50","modified":"2025-04-11 12:31:00","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":676,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ed7c458e9e6c16deace532108a35a944_f00b1c48-8-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ed7c458e9e6c16deace532108a35a944_f00b1c48-8-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ed7c458e9e6c16deace532108a35a944_f00b1c48-8-768x433.jpg","medium_large-width":768,"medium_large-height":433,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ed7c458e9e6c16deace532108a35a944_f00b1c48-8-1024x577.jpg","large-width":1024,"large-height":577,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ed7c458e9e6c16deace532108a35a944_f00b1c48-8.jpg","1536x1536-width":1200,"1536x1536-height":676,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ed7c458e9e6c16deace532108a35a944_f00b1c48-8.jpg","2048x2048-width":1200,"2048x2048-height":676,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ed7c458e9e6c16deace532108a35a944_f00b1c48-8.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ed7c458e9e6c16deace532108a35a944_f00b1c48-8.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ed7c458e9e6c16deace532108a35a944_f00b1c48-8.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},"url_youtube":""},{"description":"Bushaltestelle an der Viale delle Mura","image":{"ID":21072,"id":21072,"title":"Fermata dell'autobus lungo il Viale delle Mura","filename":"8994b044a453725ccfbd8e7cac3ae68d_e15a6123-8.jpg","filesize":617022,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/8994b044a453725ccfbd8e7cac3ae68d_e15a6123-8.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/kirche-s-michele-al-pozzo-bianco\/fermata-dellautobus-lungo-il-viale-delle-mura-5-2\/","alt":"Fermata dell'autobus per la Chiesa di San Michele al Pozzo Bianco","author":"0","description":"Dettaglio della fermata dell'autobus su Viale delle Mura, indicata come punto di riferimento per chi utilizza i mezzi pubblici, per raggiungere la Chiesa di San Michele al Pozzo Bianco","caption":"","name":"fermata-dellautobus-lungo-il-viale-delle-mura-5-2","status":"inherit","uploaded_to":20056,"date":"2024-05-08 12:32:50","modified":"2025-04-11 12:31:39","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":818,"height":1200,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/8994b044a453725ccfbd8e7cac3ae68d_e15a6123-8-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/8994b044a453725ccfbd8e7cac3ae68d_e15a6123-8-205x300.jpg","medium-width":205,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/8994b044a453725ccfbd8e7cac3ae68d_e15a6123-8-768x1127.jpg","medium_large-width":768,"medium_large-height":1127,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/8994b044a453725ccfbd8e7cac3ae68d_e15a6123-8-698x1024.jpg","large-width":698,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/8994b044a453725ccfbd8e7cac3ae68d_e15a6123-8.jpg","1536x1536-width":818,"1536x1536-height":1200,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/8994b044a453725ccfbd8e7cac3ae68d_e15a6123-8.jpg","2048x2048-width":818,"2048x2048-height":1200,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/8994b044a453725ccfbd8e7cac3ae68d_e15a6123-8.jpg","gform-image-choice-sm-width":205,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/8994b044a453725ccfbd8e7cac3ae68d_e15a6123-8.jpg","gform-image-choice-md-width":273,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/8994b044a453725ccfbd8e7cac3ae68d_e15a6123-8.jpg","gform-image-choice-lg-width":409,"gform-image-choice-lg-height":600}},"url_youtube":""},{"description":"Osmano Stra\u00dfe","image":{"ID":21078,"id":21078,"title":"Via Osmano","filename":"655bd8b21d3b21e45cc381a4ff7a2348_1c79e4ba-8.jpg","filesize":443297,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/655bd8b21d3b21e45cc381a4ff7a2348_1c79e4ba-8.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/kirche-s-michele-al-pozzo-bianco\/via-osmano-5-2\/","alt":"Percorso pedonale acciottolato verso la Chiesa di San Michele al Pozzo Bianco - ","author":"0","description":"Percorso pedonale in acciottolato che conduce alla Chiesa di San Michele, tipico delle vie di Bergamo Alta","caption":"","name":"via-osmano-5-2","status":"inherit","uploaded_to":20056,"date":"2024-05-08 12:32:50","modified":"2025-04-11 12:32:58","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":676,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/655bd8b21d3b21e45cc381a4ff7a2348_1c79e4ba-8-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/655bd8b21d3b21e45cc381a4ff7a2348_1c79e4ba-8-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/655bd8b21d3b21e45cc381a4ff7a2348_1c79e4ba-8-768x433.jpg","medium_large-width":768,"medium_large-height":433,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/655bd8b21d3b21e45cc381a4ff7a2348_1c79e4ba-8-1024x577.jpg","large-width":1024,"large-height":577,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/655bd8b21d3b21e45cc381a4ff7a2348_1c79e4ba-8.jpg","1536x1536-width":1200,"1536x1536-height":676,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/655bd8b21d3b21e45cc381a4ff7a2348_1c79e4ba-8.jpg","2048x2048-width":1200,"2048x2048-height":676,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/655bd8b21d3b21e45cc381a4ff7a2348_1c79e4ba-8.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/655bd8b21d3b21e45cc381a4ff7a2348_1c79e4ba-8.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/655bd8b21d3b21e45cc381a4ff7a2348_1c79e4ba-8.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},"url_youtube":""},{"description":"Eingabe","image":{"ID":21084,"id":21084,"title":"Ingresso","filename":"504e063c0aa13fcbe86f275d056e77ad_d36187d8-8.jpg","filesize":533393,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/504e063c0aa13fcbe86f275d056e77ad_d36187d8-8.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/kirche-s-michele-al-pozzo-bianco\/ingresso-22-2\/","alt":"Cancello d'ingresso della Chiesa di San Michele al Pozzo Bianco a Bergamo Alta","author":"0","description":"Vista frontale del cancello d'ingresso che conduce all'interno della chiesa.","caption":"","name":"ingresso-22-2","status":"inherit","uploaded_to":20056,"date":"2024-05-08 12:32:51","modified":"2025-04-11 12:39:25","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":876,"height":1200,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/504e063c0aa13fcbe86f275d056e77ad_d36187d8-8-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/504e063c0aa13fcbe86f275d056e77ad_d36187d8-8-219x300.jpg","medium-width":219,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/504e063c0aa13fcbe86f275d056e77ad_d36187d8-8-768x1052.jpg","medium_large-width":768,"medium_large-height":1052,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/504e063c0aa13fcbe86f275d056e77ad_d36187d8-8-748x1024.jpg","large-width":748,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/504e063c0aa13fcbe86f275d056e77ad_d36187d8-8.jpg","1536x1536-width":876,"1536x1536-height":1200,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/504e063c0aa13fcbe86f275d056e77ad_d36187d8-8.jpg","2048x2048-width":876,"2048x2048-height":1200,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/504e063c0aa13fcbe86f275d056e77ad_d36187d8-8.jpg","gform-image-choice-sm-width":219,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/504e063c0aa13fcbe86f275d056e77ad_d36187d8-8.jpg","gform-image-choice-md-width":292,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/504e063c0aa13fcbe86f275d056e77ad_d36187d8-8.jpg","gform-image-choice-lg-width":438,"gform-image-choice-lg-height":600}},"url_youtube":""},{"description":"Letzter Abschnitt des Gehwegs (steil) vor dem Eingang","image":{"ID":21090,"id":21090,"title":"Ultimo tratto di marciapiede (ripido) prima dell'ingresso","filename":"3a230c4259bc55cf0baf763b9413a0ac_9b9ecd05-8.jpg","filesize":456115,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/3a230c4259bc55cf0baf763b9413a0ac_9b9ecd05-8.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/kirche-s-michele-al-pozzo-bianco\/ultimo-tratto-di-marciapiede-ripido-prima-dellingresso-5-2\/","alt":"Salita pedonale verso la Chiesa di San Michele al Pozzo Bianco con corrimano","author":"0","description":"Percorso pedonale in salita, attrezzato con corrimano, che porta all'ingresso della chiesa","caption":"Percorso pedonale in salita, attrezzato con corrimano, che porta all'ingresso della chiesa","name":"ultimo-tratto-di-marciapiede-ripido-prima-dellingresso-5-2","status":"inherit","uploaded_to":20056,"date":"2024-05-08 12:32:51","modified":"2025-04-11 12:40:56","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":676,"height":1200,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/3a230c4259bc55cf0baf763b9413a0ac_9b9ecd05-8-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/3a230c4259bc55cf0baf763b9413a0ac_9b9ecd05-8-169x300.jpg","medium-width":169,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/3a230c4259bc55cf0baf763b9413a0ac_9b9ecd05-8.jpg","medium_large-width":676,"medium_large-height":1200,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/3a230c4259bc55cf0baf763b9413a0ac_9b9ecd05-8-577x1024.jpg","large-width":577,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/3a230c4259bc55cf0baf763b9413a0ac_9b9ecd05-8.jpg","1536x1536-width":676,"1536x1536-height":1200,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/3a230c4259bc55cf0baf763b9413a0ac_9b9ecd05-8.jpg","2048x2048-width":676,"2048x2048-height":1200,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/3a230c4259bc55cf0baf763b9413a0ac_9b9ecd05-8.jpg","gform-image-choice-sm-width":169,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/3a230c4259bc55cf0baf763b9413a0ac_9b9ecd05-8.jpg","gform-image-choice-md-width":225,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/3a230c4259bc55cf0baf763b9413a0ac_9b9ecd05-8.jpg","gform-image-choice-lg-width":338,"gform-image-choice-lg-height":600}},"url_youtube":""},{"description":"Eingangst\u00fcr","image":{"ID":21096,"id":21096,"title":"Porta d'ingresso","filename":"a0f4b054df81cd99b1f964c6a2196eac_3c61cedb-8.jpg","filesize":264835,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/a0f4b054df81cd99b1f964c6a2196eac_3c61cedb-8.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/kirche-s-michele-al-pozzo-bianco\/porta-dingresso-17-2\/","alt":"Porta interna della Chiesa di San Michele al Pozzo Bianco che conduce alla navata","author":"0","description":"Dettaglio della porta interna in legno che separa l'atrio dalla navata principale","caption":"","name":"porta-dingresso-17-2","status":"inherit","uploaded_to":20056,"date":"2024-05-08 12:32:51","modified":"2025-04-11 12:41:26","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":676,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/a0f4b054df81cd99b1f964c6a2196eac_3c61cedb-8-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/a0f4b054df81cd99b1f964c6a2196eac_3c61cedb-8-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/a0f4b054df81cd99b1f964c6a2196eac_3c61cedb-8-768x433.jpg","medium_large-width":768,"medium_large-height":433,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/a0f4b054df81cd99b1f964c6a2196eac_3c61cedb-8-1024x577.jpg","large-width":1024,"large-height":577,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/a0f4b054df81cd99b1f964c6a2196eac_3c61cedb-8.jpg","1536x1536-width":1200,"1536x1536-height":676,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/a0f4b054df81cd99b1f964c6a2196eac_3c61cedb-8.jpg","2048x2048-width":1200,"2048x2048-height":676,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/a0f4b054df81cd99b1f964c6a2196eac_3c61cedb-8.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/a0f4b054df81cd99b1f964c6a2196eac_3c61cedb-8.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/a0f4b054df81cd99b1f964c6a2196eac_3c61cedb-8.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},"url_youtube":""},{"description":"Interieur","image":{"ID":21102,"id":21102,"title":"Interno","filename":"c976911547769e844829fee8ba82f48f_93299794-8.jpg","filesize":294407,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/c976911547769e844829fee8ba82f48f_93299794-8.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/kirche-s-michele-al-pozzo-bianco\/interno-22-2\/","alt":"Interno della Chiesa di San Michele al Pozzo Bianco con affreschi e altare","author":"0","description":"Veduta dell'interno della chiesa, con gli affreschi sulle pareti e l'altare principale","caption":"","name":"interno-22-2","status":"inherit","uploaded_to":20056,"date":"2024-05-08 12:32:51","modified":"2025-04-11 12:42:10","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":676,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/c976911547769e844829fee8ba82f48f_93299794-8-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/c976911547769e844829fee8ba82f48f_93299794-8-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/c976911547769e844829fee8ba82f48f_93299794-8-768x433.jpg","medium_large-width":768,"medium_large-height":433,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/c976911547769e844829fee8ba82f48f_93299794-8-1024x577.jpg","large-width":1024,"large-height":577,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/c976911547769e844829fee8ba82f48f_93299794-8.jpg","1536x1536-width":1200,"1536x1536-height":676,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/c976911547769e844829fee8ba82f48f_93299794-8.jpg","2048x2048-width":1200,"2048x2048-height":676,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/c976911547769e844829fee8ba82f48f_93299794-8.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/c976911547769e844829fee8ba82f48f_93299794-8.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/c976911547769e844829fee8ba82f48f_93299794-8.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},"url_youtube":""},{"description":"Kapelle mit Fresken von Lorenzo Lotto","image":{"ID":21108,"id":21108,"title":"Cappella affrescata da Lorenzo Lotto","filename":"6105c5fcbf321ab863decc323ae9bc30_4ade7265-8.jpg","filesize":424762,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/6105c5fcbf321ab863decc323ae9bc30_4ade7265-8.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/kirche-s-michele-al-pozzo-bianco\/cappella-affrescata-da-lorenzo-lotto-5-2\/","alt":"Cappella laterale con cancello in ferro battuto nella Chiesa di San Michele al Pozzo Bianco","author":"0","description":"Dettaglio della cappella laterale protetta da un cancello in ferro battuto all'interno della chiesa. La Cappella contiene gli affreschi di Lorenzo Lotto.","caption":"","name":"cappella-affrescata-da-lorenzo-lotto-5-2","status":"inherit","uploaded_to":20056,"date":"2024-05-08 12:32:52","modified":"2025-04-11 12:45:04","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":739,"height":1200,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/6105c5fcbf321ab863decc323ae9bc30_4ade7265-8-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/6105c5fcbf321ab863decc323ae9bc30_4ade7265-8-185x300.jpg","medium-width":185,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/6105c5fcbf321ab863decc323ae9bc30_4ade7265-8.jpg","medium_large-width":739,"medium_large-height":1200,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/6105c5fcbf321ab863decc323ae9bc30_4ade7265-8-631x1024.jpg","large-width":631,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/6105c5fcbf321ab863decc323ae9bc30_4ade7265-8.jpg","1536x1536-width":739,"1536x1536-height":1200,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/6105c5fcbf321ab863decc323ae9bc30_4ade7265-8.jpg","2048x2048-width":739,"2048x2048-height":1200,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/6105c5fcbf321ab863decc323ae9bc30_4ade7265-8.jpg","gform-image-choice-sm-width":185,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/6105c5fcbf321ab863decc323ae9bc30_4ade7265-8.jpg","gform-image-choice-md-width":246,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/6105c5fcbf321ab863decc323ae9bc30_4ade7265-8.jpg","gform-image-choice-lg-width":370,"gform-image-choice-lg-height":600}},"url_youtube":""},{"description":"Barrierefreie Toilette im Parkhaus","image":{"ID":21114,"id":21114,"title":"Bagno accessibile presso il parcheggio","filename":"6e2f3b895221f01a789de4602e8d29a8_df0c7006-8.jpg","filesize":527611,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/6e2f3b895221f01a789de4602e8d29a8_df0c7006-8.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/kirche-s-michele-al-pozzo-bianco\/bagno-accessibile-presso-il-parcheggio-5-2\/","alt":"Bagno accessibile presso il parcheggio di Baluardo di San Michele","author":"0","description":"Cabina metallica verde e grigia che contiene i servizi igienici accessibili presso ","caption":"","name":"bagno-accessibile-presso-il-parcheggio-5-2","status":"inherit","uploaded_to":20056,"date":"2024-05-08 12:32:52","modified":"2025-04-11 12:48:31","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":676,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/6e2f3b895221f01a789de4602e8d29a8_df0c7006-8-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/6e2f3b895221f01a789de4602e8d29a8_df0c7006-8-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/6e2f3b895221f01a789de4602e8d29a8_df0c7006-8-768x433.jpg","medium_large-width":768,"medium_large-height":433,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/6e2f3b895221f01a789de4602e8d29a8_df0c7006-8-1024x577.jpg","large-width":1024,"large-height":577,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/6e2f3b895221f01a789de4602e8d29a8_df0c7006-8.jpg","1536x1536-width":1200,"1536x1536-height":676,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/6e2f3b895221f01a789de4602e8d29a8_df0c7006-8.jpg","2048x2048-width":1200,"2048x2048-height":676,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/6e2f3b895221f01a789de4602e8d29a8_df0c7006-8.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/6e2f3b895221f01a789de4602e8d29a8_df0c7006-8.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/6e2f3b895221f01a789de4602e8d29a8_df0c7006-8.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},"url_youtube":""}]}],"description":"<p>Wussten Sie, dass der ber\u00fchmte K\u00fcnstler Lorenzo Lotto aus dem 16. Jahrhundert in der &#8216;Casa del Vicario&#8217; neben dieser Kirche lebte?<br \/>\nDie Wohnung ist heute teilweise in die nahe gelegene Orsoline-Nonnenpension integriert. Auch wegen dieser N\u00e4he schuf der venezianische Meister wunderbare Werke in <strong>San Michele al Pozzo bianco<\/strong>, darunter den Freskenzyklus mit Szenen aus dem Leben Mariens, der 1525 in der linken Seitenkapelle gemalt wurde. <\/p>\n<p>Diese Kirche ist ein wahrer Schatz f\u00fcr Kunstliebhaber: Sie enth\u00e4lt einige der \u00e4ltesten Fresken der Provinz Bergamo und ist eine au\u00dfergew\u00f6hnliche Lektion in der Geschichte der lokalen Malerei, die vom fr\u00fchen 13. bis zum Ende des 16.<\/p>\n<p>Der runde Stein, der heute auf dem Kirchhof steht, zeigt die Stelle an, an der sich einst die M\u00fcndung des alten wei\u00dfen Brunnens befand, der der Kirche ihren Namen gab.<\/p>\n","slides":[{"image":{"ID":7346,"id":7346,"title":"742abe27b64ed96aec6f4fc8d1946b93_a7b5fe3f.jpg","filename":"742abe27b64ed96aec6f4fc8d1946b93_a7b5fe3f.jpg","filesize":664038,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/742abe27b64ed96aec6f4fc8d1946b93_a7b5fe3f.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/kirche-s-michele-al-pozzo-bianco\/742abe27b64ed96aec6f4fc8d1946b93_a7b5fe3f-jpg-2\/","alt":"Interno di una chiesa con affreschi e altare dorato, vista frontale.","author":"0","description":"L'immagine mostra l'interno di una chiesa decorata con affreschi sulle pareti e sulla volta. Al centro si trova un altare dorato, circondato da una grata in ferro battuto. Le panche in legno sono disposte in file verso l'altare, mentre l'architettura presenta archi e dettagli artistici.","caption":"","name":"742abe27b64ed96aec6f4fc8d1946b93_a7b5fe3f-jpg-2","status":"inherit","uploaded_to":20056,"date":"2024-05-08 08:44:00","modified":"2025-04-14 09:23:38","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1920,"height":944,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/742abe27b64ed96aec6f4fc8d1946b93_a7b5fe3f-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/742abe27b64ed96aec6f4fc8d1946b93_a7b5fe3f-300x148.jpg","medium-width":300,"medium-height":148,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/742abe27b64ed96aec6f4fc8d1946b93_a7b5fe3f-768x378.jpg","medium_large-width":768,"medium_large-height":378,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/742abe27b64ed96aec6f4fc8d1946b93_a7b5fe3f-1024x503.jpg","large-width":1024,"large-height":503,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/742abe27b64ed96aec6f4fc8d1946b93_a7b5fe3f-1536x755.jpg","1536x1536-width":1536,"1536x1536-height":755,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/742abe27b64ed96aec6f4fc8d1946b93_a7b5fe3f.jpg","2048x2048-width":1920,"2048x2048-height":944,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/742abe27b64ed96aec6f4fc8d1946b93_a7b5fe3f.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":148,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/742abe27b64ed96aec6f4fc8d1946b93_a7b5fe3f.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":197,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/742abe27b64ed96aec6f4fc8d1946b93_a7b5fe3f.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":295}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"san michele al pozzo 7","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":7352,"id":7352,"title":"e0ce569344727475374769a6690fcc15_d8fc9e80.jpg","filename":"e0ce569344727475374769a6690fcc15_d8fc9e80.jpg","filesize":568110,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/e0ce569344727475374769a6690fcc15_d8fc9e80.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/kirche-s-michele-al-pozzo-bianco\/e0ce569344727475374769a6690fcc15_d8fc9e80-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"e0ce569344727475374769a6690fcc15_d8fc9e80-jpg-2","status":"inherit","uploaded_to":20056,"date":"2024-05-08 08:44:01","modified":"2024-05-08 12:26:07","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1920,"height":904,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/e0ce569344727475374769a6690fcc15_d8fc9e80-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/e0ce569344727475374769a6690fcc15_d8fc9e80-300x141.jpg","medium-width":300,"medium-height":141,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/e0ce569344727475374769a6690fcc15_d8fc9e80-768x362.jpg","medium_large-width":768,"medium_large-height":362,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/e0ce569344727475374769a6690fcc15_d8fc9e80-1024x482.jpg","large-width":1024,"large-height":482,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/e0ce569344727475374769a6690fcc15_d8fc9e80-1536x723.jpg","1536x1536-width":1536,"1536x1536-height":723,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/e0ce569344727475374769a6690fcc15_d8fc9e80.jpg","2048x2048-width":1920,"2048x2048-height":904,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/e0ce569344727475374769a6690fcc15_d8fc9e80.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":141,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/e0ce569344727475374769a6690fcc15_d8fc9e80.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":188,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/e0ce569344727475374769a6690fcc15_d8fc9e80.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":283}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"san michele al pozzo 6","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":7358,"id":7358,"title":"6f29f486ad9690d82489499b6cf3284c_e6447c8c.jpg","filename":"6f29f486ad9690d82489499b6cf3284c_e6447c8c.jpg","filesize":464598,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/6f29f486ad9690d82489499b6cf3284c_e6447c8c.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/kirche-s-michele-al-pozzo-bianco\/6f29f486ad9690d82489499b6cf3284c_e6447c8c-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"6f29f486ad9690d82489499b6cf3284c_e6447c8c-jpg-2","status":"inherit","uploaded_to":20056,"date":"2024-05-08 08:44:01","modified":"2024-05-08 12:26:07","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1920,"height":610,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/6f29f486ad9690d82489499b6cf3284c_e6447c8c-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/6f29f486ad9690d82489499b6cf3284c_e6447c8c-300x95.jpg","medium-width":300,"medium-height":95,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/6f29f486ad9690d82489499b6cf3284c_e6447c8c-768x244.jpg","medium_large-width":768,"medium_large-height":244,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/6f29f486ad9690d82489499b6cf3284c_e6447c8c-1024x325.jpg","large-width":1024,"large-height":325,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/6f29f486ad9690d82489499b6cf3284c_e6447c8c-1536x488.jpg","1536x1536-width":1536,"1536x1536-height":488,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/6f29f486ad9690d82489499b6cf3284c_e6447c8c.jpg","2048x2048-width":1920,"2048x2048-height":610,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/6f29f486ad9690d82489499b6cf3284c_e6447c8c.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":95,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/6f29f486ad9690d82489499b6cf3284c_e6447c8c.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":127,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/6f29f486ad9690d82489499b6cf3284c_e6447c8c.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":191}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"san michele al pozzo 5","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":7364,"id":7364,"title":"4eb1aa9cefe4482190f7558e27ea9e94_4d078ed4.jpg","filename":"4eb1aa9cefe4482190f7558e27ea9e94_4d078ed4.jpg","filesize":152680,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/4eb1aa9cefe4482190f7558e27ea9e94_4d078ed4.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/kirche-s-michele-al-pozzo-bianco\/4eb1aa9cefe4482190f7558e27ea9e94_4d078ed4-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"4eb1aa9cefe4482190f7558e27ea9e94_4d078ed4-jpg-2","status":"inherit","uploaded_to":20056,"date":"2024-05-08 08:44:02","modified":"2024-05-08 12:26:07","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":915,"height":528,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/4eb1aa9cefe4482190f7558e27ea9e94_4d078ed4-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/4eb1aa9cefe4482190f7558e27ea9e94_4d078ed4-300x173.jpg","medium-width":300,"medium-height":173,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/4eb1aa9cefe4482190f7558e27ea9e94_4d078ed4-768x443.jpg","medium_large-width":768,"medium_large-height":443,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/4eb1aa9cefe4482190f7558e27ea9e94_4d078ed4.jpg","large-width":915,"large-height":528,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/4eb1aa9cefe4482190f7558e27ea9e94_4d078ed4.jpg","1536x1536-width":915,"1536x1536-height":528,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/4eb1aa9cefe4482190f7558e27ea9e94_4d078ed4.jpg","2048x2048-width":915,"2048x2048-height":528,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/4eb1aa9cefe4482190f7558e27ea9e94_4d078ed4.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":173,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/4eb1aa9cefe4482190f7558e27ea9e94_4d078ed4.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":231,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/4eb1aa9cefe4482190f7558e27ea9e94_4d078ed4.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":346}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"buttons":[{"style":"primary","text":"Kontakt","icon":{"button_icon":"none"},"function":"link","url":"http:\/\/www.comune.bergamo.it\/servizi\/Menu\/dinamica.aspx?idSezione=3780&idArea=1182&idCat=1195&ID=10441&TipoElemento=pagina","select_post":null,"target":"_blank","url_youtube":"","target_modal":""}],"filotto_layout":"scroll","url":"http:\/\/www.comune.bergamo.it\/servizi\/Menu\/dinamica.aspx?idSezione=3780&idArea=1182&idCat=1195&ID=10441&TipoElemento=pagina","hero_title":"S. Michele al Pozzo Bianco Kirche","hero_text":"<p>Eines der \u00e4ltesten und wertvollsten in Bergamo, das sogar in einem lombardischen Testament von 774 n. Chr. erw\u00e4hnt wird. Vielleicht wurde es an der Stelle eines heidnischen Tempels errichtet, der dem Gott Vulkan geweiht war.<\/p>\n","indepth":"<p>Die Kirche stammt aus der Zeit der Langobarden, wurde aber in den folgenden Jahrhunderten mehrmals renoviert, bis hin zur Fassade aus lebendigem Stein, die 1915 ausgef\u00fchrt wurde.<\/p>\n<p>Von der urspr\u00fcnglichen Struktur sind wahrscheinlich nur ein Teil der Krypta, die Au\u00dfenmauer und wenig anderes erhalten; der Rest wurde im 15. Jahrhundert wieder aufgebaut.<\/p>\n<p>Bei den in den 1940er Jahren durchgef\u00fchrten Restaurierungsarbeiten wurden Werke verschiedener K\u00fcnstler aus dem fr\u00fchen Mittelalter gefunden, die von absolutem Wert sind, auch wenn sie manchmal fragmentarisch sind. Als Beweis f\u00fcr die Existenz einer \u00e4lteren Kirche unter dem Rahmen der heutigen aus dem 15. Jahrhundert wurden Gem\u00e4lde aus dem Jahr 1200 und vielleicht sogar noch fr\u00fcher gefunden, die einen eindeutig byzantinischen Charakter haben.<\/p>\n<p>Der Grundriss des Geb\u00e4udes ist rechteckig, mit einem merkw\u00fcrdigen, nicht ganz regelm\u00e4\u00dfigen Umfang.<\/p>\n<p>Im Inneren sehen Sie drei Kapellen: Die mittlere ist \u00fcber drei Stufen zu erreichen und durch zwei kleine Fenster an der Seite k\u00f6nnen Sie in die darunter liegende Krypta sehen, die \u00fcber eine Treppe im zweiten Erker der Kirche auf der linken Seite zu erreichen ist.<\/p>\n","time":"<p>&#8211; 9.00 &#8211; 17.00 Uhr von Oktober bis April &#8211; 9.00 &#8211; 18.00 Uhr von Mai bis September  <\/p>\n<p>(Der Zeitplan kann sich noch \u00e4ndern)<\/p>\n","iu_addr_streetnumber":"Largo San Michele Al Pozzo Bianco","iu_website":"http:\/\/www.comune.bergamo.it\/servizi\/Menu\/dinamica.aspx?idSezione=3780&idArea=1182&idCat=1195&ID=10441&TipoElemento=pagina","filotto_fill":"manual","hero_type":"images","filotto_items":false,"accessibilitycontent":{"tcm_content":[{"acf_fc_layout":"text","text":"<p><strong>REACH:<\/strong><\/p>\n<p>P<strong>arken:<\/strong> in 200 Metern Entfernung (Baluardo San Michele): \u00f6ffentlicher Parkplatz ohne reservierte Parkpl\u00e4tze; es besteht die M\u00f6glichkeit, einen Parkausweis f\u00fcr den Kirchhof San Michele al Pozzo Bianco zu beantragen.<\/p>\n<p>\u00d6ffentliche Verkehrsmittel: <strong> in 250 Metern (Viale delle Mura, Ecke Via Osmano): Bushaltestelle der Linie 1; Stufenh\u00f6he 17 cm; Bus mit manuellem Trittbrett; Gehsteigbreite 105 cm und gepflasterte Passage auf der Via Osmano in 300 Metern (Piazza Mercato delle Scarpe): Standseilbahnstation.<br \/>\nDer Fu\u00dfweg f\u00fchrt bergab (8% Steigung auf einem Fischgr\u00e4tenpflaster aus Stein und Porphyr).<\/strong> <\/p>\n<p>Fu\u00dfweg von den Parkpl\u00e4tzen und der Bushaltestelle: bergauf oder bergab (8-10% Steigung) mit Ausnahme des Abschnitts in der N\u00e4he des Eingangs, der kurz, aber sehr steil ist (mehr als 20%); ausreichend breit und mit Steinplatten und Fischgr\u00e4tporphyr gepflastert; keine taktilen Markierungen.<\/p>\n<p><strong>EINTRITT:<\/strong><\/p>\n<p>Ebener Eingang mit zwei 2 cm hohen Schwellen am Tor; T\u00fcr mit ausreichender Breite.<\/p>\n<p><strong>BESUCHEN:<\/strong><\/p>\n<p>Ebener und begehbarer Innenraum; vor dem Chor und den Kapellen liegt eine 20 cm hohe Stufe. Sichtbare Kunstwerke, Lichter k\u00f6nnen gegen eine Geb\u00fchr am Kircheneingang eingeschaltet werden (Schalterh\u00f6he 150 cm). Krypta wegen steiler, schmaler Treppen nicht zug\u00e4nglich.<\/p>\n<p><strong>DIE TOILETTE ZU BENUTZEN:<\/strong><\/p>\n<p>Es gibt eine barrierefreie Toilette (vorgefertigt) auf dem Parkplatz der St. Michael&#8217;s Bastion<\/p>\n"},{"acf_fc_layout":"title","title_tag":"h3","title_text":"Das Datenblatt"},{"acf_fc_layout":"text","text":"<p>S<strong>YNTHETISCHE BEWERTUNG:<\/strong> Person mit Mobilit\u00e4tseinschr\u00e4nkung: zug\u00e4nglich mit robuster Pflegekraft Person mit Sehbehinderung: zug\u00e4nglich mit Pflegekraft<\/p>\n"},{"acf_fc_layout":"gallery","gallery_items":[{"description":"Parkplatz an der Bastion von San Michele, entlang der Viale delle Mura","image":{"ID":21060,"id":21060,"title":"Parcheggio al baluardo di San Michele, lungo il Viale delle Mura","filename":"4b0b9a4195e9fc1659234b7afb38c665_deea3cef-8.jpg","filesize":537675,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/4b0b9a4195e9fc1659234b7afb38c665_deea3cef-8.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/kirche-s-michele-al-pozzo-bianco\/parcheggio-al-baluardo-di-san-michele-lungo-il-viale-delle-mura-5-2\/","alt":"Parcheggio vicino alla Chiesa di San Michele al Pozzo Bianco","author":"0","description":"Vista del parcheggio pubblico situato nei pressi del Baluardo San Michele, a breve distanza dalla Chiesa.","caption":"","name":"parcheggio-al-baluardo-di-san-michele-lungo-il-viale-delle-mura-5-2","status":"inherit","uploaded_to":20056,"date":"2024-05-08 12:32:49","modified":"2025-04-11 12:28:18","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":676,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/4b0b9a4195e9fc1659234b7afb38c665_deea3cef-8-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/4b0b9a4195e9fc1659234b7afb38c665_deea3cef-8-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/4b0b9a4195e9fc1659234b7afb38c665_deea3cef-8-768x433.jpg","medium_large-width":768,"medium_large-height":433,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/4b0b9a4195e9fc1659234b7afb38c665_deea3cef-8-1024x577.jpg","large-width":1024,"large-height":577,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/4b0b9a4195e9fc1659234b7afb38c665_deea3cef-8.jpg","1536x1536-width":1200,"1536x1536-height":676,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/4b0b9a4195e9fc1659234b7afb38c665_deea3cef-8.jpg","2048x2048-width":1200,"2048x2048-height":676,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/4b0b9a4195e9fc1659234b7afb38c665_deea3cef-8.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/4b0b9a4195e9fc1659234b7afb38c665_deea3cef-8.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/4b0b9a4195e9fc1659234b7afb38c665_deea3cef-8.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},"url_youtube":""},{"description":"Stra\u00dfenkreuzung - Viale delle Mura","image":{"ID":21066,"id":21066,"title":"Attraversamento stradale - Viale delle Mura","filename":"ed7c458e9e6c16deace532108a35a944_f00b1c48-8.jpg","filesize":527016,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ed7c458e9e6c16deace532108a35a944_f00b1c48-8.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/kirche-s-michele-al-pozzo-bianco\/attraversamento-stradale-viale-delle-mura-5-2\/","alt":"Attraversamento pedonale vicino alla fermata dell'autobus per la Chiesa di San Michele","author":"0","description":"Attraversamento pedonale su Viale delle Mura, nei pressi della fermata dell'autobus utile per raggiungere la chiesa","caption":"","name":"attraversamento-stradale-viale-delle-mura-5-2","status":"inherit","uploaded_to":20056,"date":"2024-05-08 12:32:50","modified":"2025-04-11 12:31:00","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":676,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ed7c458e9e6c16deace532108a35a944_f00b1c48-8-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ed7c458e9e6c16deace532108a35a944_f00b1c48-8-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ed7c458e9e6c16deace532108a35a944_f00b1c48-8-768x433.jpg","medium_large-width":768,"medium_large-height":433,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ed7c458e9e6c16deace532108a35a944_f00b1c48-8-1024x577.jpg","large-width":1024,"large-height":577,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ed7c458e9e6c16deace532108a35a944_f00b1c48-8.jpg","1536x1536-width":1200,"1536x1536-height":676,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ed7c458e9e6c16deace532108a35a944_f00b1c48-8.jpg","2048x2048-width":1200,"2048x2048-height":676,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ed7c458e9e6c16deace532108a35a944_f00b1c48-8.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ed7c458e9e6c16deace532108a35a944_f00b1c48-8.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ed7c458e9e6c16deace532108a35a944_f00b1c48-8.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},"url_youtube":""},{"description":"Bushaltestelle an der Viale delle Mura","image":{"ID":21072,"id":21072,"title":"Fermata dell'autobus lungo il Viale delle Mura","filename":"8994b044a453725ccfbd8e7cac3ae68d_e15a6123-8.jpg","filesize":617022,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/8994b044a453725ccfbd8e7cac3ae68d_e15a6123-8.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/kirche-s-michele-al-pozzo-bianco\/fermata-dellautobus-lungo-il-viale-delle-mura-5-2\/","alt":"Fermata dell'autobus per la Chiesa di San Michele al Pozzo Bianco","author":"0","description":"Dettaglio della fermata dell'autobus su Viale delle Mura, indicata come punto di riferimento per chi utilizza i mezzi pubblici, per raggiungere la Chiesa di San Michele al Pozzo Bianco","caption":"","name":"fermata-dellautobus-lungo-il-viale-delle-mura-5-2","status":"inherit","uploaded_to":20056,"date":"2024-05-08 12:32:50","modified":"2025-04-11 12:31:39","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":818,"height":1200,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/8994b044a453725ccfbd8e7cac3ae68d_e15a6123-8-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/8994b044a453725ccfbd8e7cac3ae68d_e15a6123-8-205x300.jpg","medium-width":205,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/8994b044a453725ccfbd8e7cac3ae68d_e15a6123-8-768x1127.jpg","medium_large-width":768,"medium_large-height":1127,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/8994b044a453725ccfbd8e7cac3ae68d_e15a6123-8-698x1024.jpg","large-width":698,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/8994b044a453725ccfbd8e7cac3ae68d_e15a6123-8.jpg","1536x1536-width":818,"1536x1536-height":1200,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/8994b044a453725ccfbd8e7cac3ae68d_e15a6123-8.jpg","2048x2048-width":818,"2048x2048-height":1200,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/8994b044a453725ccfbd8e7cac3ae68d_e15a6123-8.jpg","gform-image-choice-sm-width":205,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/8994b044a453725ccfbd8e7cac3ae68d_e15a6123-8.jpg","gform-image-choice-md-width":273,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/8994b044a453725ccfbd8e7cac3ae68d_e15a6123-8.jpg","gform-image-choice-lg-width":409,"gform-image-choice-lg-height":600}},"url_youtube":""},{"description":"Osmano Stra\u00dfe","image":{"ID":21078,"id":21078,"title":"Via Osmano","filename":"655bd8b21d3b21e45cc381a4ff7a2348_1c79e4ba-8.jpg","filesize":443297,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/655bd8b21d3b21e45cc381a4ff7a2348_1c79e4ba-8.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/kirche-s-michele-al-pozzo-bianco\/via-osmano-5-2\/","alt":"Percorso pedonale acciottolato verso la Chiesa di San Michele al Pozzo Bianco - ","author":"0","description":"Percorso pedonale in acciottolato che conduce alla Chiesa di San Michele, tipico delle vie di Bergamo Alta","caption":"","name":"via-osmano-5-2","status":"inherit","uploaded_to":20056,"date":"2024-05-08 12:32:50","modified":"2025-04-11 12:32:58","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":676,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/655bd8b21d3b21e45cc381a4ff7a2348_1c79e4ba-8-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/655bd8b21d3b21e45cc381a4ff7a2348_1c79e4ba-8-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/655bd8b21d3b21e45cc381a4ff7a2348_1c79e4ba-8-768x433.jpg","medium_large-width":768,"medium_large-height":433,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/655bd8b21d3b21e45cc381a4ff7a2348_1c79e4ba-8-1024x577.jpg","large-width":1024,"large-height":577,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/655bd8b21d3b21e45cc381a4ff7a2348_1c79e4ba-8.jpg","1536x1536-width":1200,"1536x1536-height":676,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/655bd8b21d3b21e45cc381a4ff7a2348_1c79e4ba-8.jpg","2048x2048-width":1200,"2048x2048-height":676,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/655bd8b21d3b21e45cc381a4ff7a2348_1c79e4ba-8.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/655bd8b21d3b21e45cc381a4ff7a2348_1c79e4ba-8.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/655bd8b21d3b21e45cc381a4ff7a2348_1c79e4ba-8.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},"url_youtube":""},{"description":"Eingabe","image":{"ID":21084,"id":21084,"title":"Ingresso","filename":"504e063c0aa13fcbe86f275d056e77ad_d36187d8-8.jpg","filesize":533393,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/504e063c0aa13fcbe86f275d056e77ad_d36187d8-8.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/kirche-s-michele-al-pozzo-bianco\/ingresso-22-2\/","alt":"Cancello d'ingresso della Chiesa di San Michele al Pozzo Bianco a Bergamo Alta","author":"0","description":"Vista frontale del cancello d'ingresso che conduce all'interno della chiesa.","caption":"","name":"ingresso-22-2","status":"inherit","uploaded_to":20056,"date":"2024-05-08 12:32:51","modified":"2025-04-11 12:39:25","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":876,"height":1200,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/504e063c0aa13fcbe86f275d056e77ad_d36187d8-8-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/504e063c0aa13fcbe86f275d056e77ad_d36187d8-8-219x300.jpg","medium-width":219,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/504e063c0aa13fcbe86f275d056e77ad_d36187d8-8-768x1052.jpg","medium_large-width":768,"medium_large-height":1052,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/504e063c0aa13fcbe86f275d056e77ad_d36187d8-8-748x1024.jpg","large-width":748,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/504e063c0aa13fcbe86f275d056e77ad_d36187d8-8.jpg","1536x1536-width":876,"1536x1536-height":1200,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/504e063c0aa13fcbe86f275d056e77ad_d36187d8-8.jpg","2048x2048-width":876,"2048x2048-height":1200,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/504e063c0aa13fcbe86f275d056e77ad_d36187d8-8.jpg","gform-image-choice-sm-width":219,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/504e063c0aa13fcbe86f275d056e77ad_d36187d8-8.jpg","gform-image-choice-md-width":292,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/504e063c0aa13fcbe86f275d056e77ad_d36187d8-8.jpg","gform-image-choice-lg-width":438,"gform-image-choice-lg-height":600}},"url_youtube":""},{"description":"Letzter Abschnitt des Gehwegs (steil) vor dem Eingang","image":{"ID":21090,"id":21090,"title":"Ultimo tratto di marciapiede (ripido) prima dell'ingresso","filename":"3a230c4259bc55cf0baf763b9413a0ac_9b9ecd05-8.jpg","filesize":456115,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/3a230c4259bc55cf0baf763b9413a0ac_9b9ecd05-8.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/kirche-s-michele-al-pozzo-bianco\/ultimo-tratto-di-marciapiede-ripido-prima-dellingresso-5-2\/","alt":"Salita pedonale verso la Chiesa di San Michele al Pozzo Bianco con corrimano","author":"0","description":"Percorso pedonale in salita, attrezzato con corrimano, che porta all'ingresso della chiesa","caption":"Percorso pedonale in salita, attrezzato con corrimano, che porta all'ingresso della chiesa","name":"ultimo-tratto-di-marciapiede-ripido-prima-dellingresso-5-2","status":"inherit","uploaded_to":20056,"date":"2024-05-08 12:32:51","modified":"2025-04-11 12:40:56","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":676,"height":1200,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/3a230c4259bc55cf0baf763b9413a0ac_9b9ecd05-8-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/3a230c4259bc55cf0baf763b9413a0ac_9b9ecd05-8-169x300.jpg","medium-width":169,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/3a230c4259bc55cf0baf763b9413a0ac_9b9ecd05-8.jpg","medium_large-width":676,"medium_large-height":1200,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/3a230c4259bc55cf0baf763b9413a0ac_9b9ecd05-8-577x1024.jpg","large-width":577,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/3a230c4259bc55cf0baf763b9413a0ac_9b9ecd05-8.jpg","1536x1536-width":676,"1536x1536-height":1200,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/3a230c4259bc55cf0baf763b9413a0ac_9b9ecd05-8.jpg","2048x2048-width":676,"2048x2048-height":1200,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/3a230c4259bc55cf0baf763b9413a0ac_9b9ecd05-8.jpg","gform-image-choice-sm-width":169,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/3a230c4259bc55cf0baf763b9413a0ac_9b9ecd05-8.jpg","gform-image-choice-md-width":225,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/3a230c4259bc55cf0baf763b9413a0ac_9b9ecd05-8.jpg","gform-image-choice-lg-width":338,"gform-image-choice-lg-height":600}},"url_youtube":""},{"description":"Eingangst\u00fcr","image":{"ID":21096,"id":21096,"title":"Porta d'ingresso","filename":"a0f4b054df81cd99b1f964c6a2196eac_3c61cedb-8.jpg","filesize":264835,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/a0f4b054df81cd99b1f964c6a2196eac_3c61cedb-8.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/kirche-s-michele-al-pozzo-bianco\/porta-dingresso-17-2\/","alt":"Porta interna della Chiesa di San Michele al Pozzo Bianco che conduce alla navata","author":"0","description":"Dettaglio della porta interna in legno che separa l'atrio dalla navata principale","caption":"","name":"porta-dingresso-17-2","status":"inherit","uploaded_to":20056,"date":"2024-05-08 12:32:51","modified":"2025-04-11 12:41:26","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":676,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/a0f4b054df81cd99b1f964c6a2196eac_3c61cedb-8-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/a0f4b054df81cd99b1f964c6a2196eac_3c61cedb-8-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/a0f4b054df81cd99b1f964c6a2196eac_3c61cedb-8-768x433.jpg","medium_large-width":768,"medium_large-height":433,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/a0f4b054df81cd99b1f964c6a2196eac_3c61cedb-8-1024x577.jpg","large-width":1024,"large-height":577,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/a0f4b054df81cd99b1f964c6a2196eac_3c61cedb-8.jpg","1536x1536-width":1200,"1536x1536-height":676,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/a0f4b054df81cd99b1f964c6a2196eac_3c61cedb-8.jpg","2048x2048-width":1200,"2048x2048-height":676,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/a0f4b054df81cd99b1f964c6a2196eac_3c61cedb-8.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/a0f4b054df81cd99b1f964c6a2196eac_3c61cedb-8.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/a0f4b054df81cd99b1f964c6a2196eac_3c61cedb-8.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},"url_youtube":""},{"description":"Interieur","image":{"ID":21102,"id":21102,"title":"Interno","filename":"c976911547769e844829fee8ba82f48f_93299794-8.jpg","filesize":294407,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/c976911547769e844829fee8ba82f48f_93299794-8.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/kirche-s-michele-al-pozzo-bianco\/interno-22-2\/","alt":"Interno della Chiesa di San Michele al Pozzo Bianco con affreschi e altare","author":"0","description":"Veduta dell'interno della chiesa, con gli affreschi sulle pareti e l'altare principale","caption":"","name":"interno-22-2","status":"inherit","uploaded_to":20056,"date":"2024-05-08 12:32:51","modified":"2025-04-11 12:42:10","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":676,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/c976911547769e844829fee8ba82f48f_93299794-8-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/c976911547769e844829fee8ba82f48f_93299794-8-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/c976911547769e844829fee8ba82f48f_93299794-8-768x433.jpg","medium_large-width":768,"medium_large-height":433,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/c976911547769e844829fee8ba82f48f_93299794-8-1024x577.jpg","large-width":1024,"large-height":577,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/c976911547769e844829fee8ba82f48f_93299794-8.jpg","1536x1536-width":1200,"1536x1536-height":676,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/c976911547769e844829fee8ba82f48f_93299794-8.jpg","2048x2048-width":1200,"2048x2048-height":676,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/c976911547769e844829fee8ba82f48f_93299794-8.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/c976911547769e844829fee8ba82f48f_93299794-8.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/c976911547769e844829fee8ba82f48f_93299794-8.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},"url_youtube":""},{"description":"Kapelle mit Fresken von Lorenzo Lotto","image":{"ID":21108,"id":21108,"title":"Cappella affrescata da Lorenzo Lotto","filename":"6105c5fcbf321ab863decc323ae9bc30_4ade7265-8.jpg","filesize":424762,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/6105c5fcbf321ab863decc323ae9bc30_4ade7265-8.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/kirche-s-michele-al-pozzo-bianco\/cappella-affrescata-da-lorenzo-lotto-5-2\/","alt":"Cappella laterale con cancello in ferro battuto nella Chiesa di San Michele al Pozzo Bianco","author":"0","description":"Dettaglio della cappella laterale protetta da un cancello in ferro battuto all'interno della chiesa. La Cappella contiene gli affreschi di Lorenzo Lotto.","caption":"","name":"cappella-affrescata-da-lorenzo-lotto-5-2","status":"inherit","uploaded_to":20056,"date":"2024-05-08 12:32:52","modified":"2025-04-11 12:45:04","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":739,"height":1200,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/6105c5fcbf321ab863decc323ae9bc30_4ade7265-8-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/6105c5fcbf321ab863decc323ae9bc30_4ade7265-8-185x300.jpg","medium-width":185,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/6105c5fcbf321ab863decc323ae9bc30_4ade7265-8.jpg","medium_large-width":739,"medium_large-height":1200,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/6105c5fcbf321ab863decc323ae9bc30_4ade7265-8-631x1024.jpg","large-width":631,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/6105c5fcbf321ab863decc323ae9bc30_4ade7265-8.jpg","1536x1536-width":739,"1536x1536-height":1200,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/6105c5fcbf321ab863decc323ae9bc30_4ade7265-8.jpg","2048x2048-width":739,"2048x2048-height":1200,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/6105c5fcbf321ab863decc323ae9bc30_4ade7265-8.jpg","gform-image-choice-sm-width":185,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/6105c5fcbf321ab863decc323ae9bc30_4ade7265-8.jpg","gform-image-choice-md-width":246,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/6105c5fcbf321ab863decc323ae9bc30_4ade7265-8.jpg","gform-image-choice-lg-width":370,"gform-image-choice-lg-height":600}},"url_youtube":""},{"description":"Barrierefreie Toilette im Parkhaus","image":{"ID":21114,"id":21114,"title":"Bagno accessibile presso il parcheggio","filename":"6e2f3b895221f01a789de4602e8d29a8_df0c7006-8.jpg","filesize":527611,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/6e2f3b895221f01a789de4602e8d29a8_df0c7006-8.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/kirche-s-michele-al-pozzo-bianco\/bagno-accessibile-presso-il-parcheggio-5-2\/","alt":"Bagno accessibile presso il parcheggio di Baluardo di San Michele","author":"0","description":"Cabina metallica verde e grigia che contiene i servizi igienici accessibili presso ","caption":"","name":"bagno-accessibile-presso-il-parcheggio-5-2","status":"inherit","uploaded_to":20056,"date":"2024-05-08 12:32:52","modified":"2025-04-11 12:48:31","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":676,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/6e2f3b895221f01a789de4602e8d29a8_df0c7006-8-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/6e2f3b895221f01a789de4602e8d29a8_df0c7006-8-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/6e2f3b895221f01a789de4602e8d29a8_df0c7006-8-768x433.jpg","medium_large-width":768,"medium_large-height":433,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/6e2f3b895221f01a789de4602e8d29a8_df0c7006-8-1024x577.jpg","large-width":1024,"large-height":577,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/6e2f3b895221f01a789de4602e8d29a8_df0c7006-8.jpg","1536x1536-width":1200,"1536x1536-height":676,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/6e2f3b895221f01a789de4602e8d29a8_df0c7006-8.jpg","2048x2048-width":1200,"2048x2048-height":676,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/6e2f3b895221f01a789de4602e8d29a8_df0c7006-8.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/6e2f3b895221f01a789de4602e8d29a8_df0c7006-8.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/6e2f3b895221f01a789de4602e8d29a8_df0c7006-8.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},"url_youtube":""}]}]},"gallery":{"gallery_items":false},"poi_data":{"description":"<p>Wussten Sie, dass der ber\u00fchmte K\u00fcnstler Lorenzo Lotto aus dem 16. Jahrhundert in der &#8216;Casa del Vicario&#8217; neben dieser Kirche lebte?<br \/>\nDie Wohnung ist heute teilweise in die nahe gelegene Orsoline-Nonnenpension integriert. Auch wegen dieser N\u00e4he schuf der venezianische Meister wunderbare Werke in <strong>San Michele al Pozzo bianco<\/strong>, darunter den Freskenzyklus mit Szenen aus dem Leben Mariens, der 1525 in der linken Seitenkapelle gemalt wurde. <\/p>\n<p>Diese Kirche ist ein wahrer Schatz f\u00fcr Kunstliebhaber: Sie enth\u00e4lt einige der \u00e4ltesten Fresken der Provinz Bergamo und ist eine au\u00dfergew\u00f6hnliche Lektion in der Geschichte der lokalen Malerei, die vom fr\u00fchen 13. bis zum Ende des 16.<\/p>\n<p>Der runde Stein, der heute auf dem Kirchhof steht, zeigt die Stelle an, an der sich einst die M\u00fcndung des alten wei\u00dfen Brunnens befand, der der Kirche ihren Namen gab.<\/p>\n","indepth":"<p>Die Kirche stammt aus der Zeit der Langobarden, wurde aber in den folgenden Jahrhunderten mehrmals renoviert, bis hin zur Fassade aus lebendigem Stein, die 1915 ausgef\u00fchrt wurde.<\/p>\n<p>Von der urspr\u00fcnglichen Struktur sind wahrscheinlich nur ein Teil der Krypta, die Au\u00dfenmauer und wenig anderes erhalten; der Rest wurde im 15. Jahrhundert wieder aufgebaut.<\/p>\n<p>Bei den in den 1940er Jahren durchgef\u00fchrten Restaurierungsarbeiten wurden Werke verschiedener K\u00fcnstler aus dem fr\u00fchen Mittelalter gefunden, die von absolutem Wert sind, auch wenn sie manchmal fragmentarisch sind. Als Beweis f\u00fcr die Existenz einer \u00e4lteren Kirche unter dem Rahmen der heutigen aus dem 15. Jahrhundert wurden Gem\u00e4lde aus dem Jahr 1200 und vielleicht sogar noch fr\u00fcher gefunden, die einen eindeutig byzantinischen Charakter haben.<\/p>\n<p>Der Grundriss des Geb\u00e4udes ist rechteckig, mit einem merkw\u00fcrdigen, nicht ganz regelm\u00e4\u00dfigen Umfang.<\/p>\n<p>Im Inneren sehen Sie drei Kapellen: Die mittlere ist \u00fcber drei Stufen zu erreichen und durch zwei kleine Fenster an der Seite k\u00f6nnen Sie in die darunter liegende Krypta sehen, die \u00fcber eine Treppe im zweiten Erker der Kirche auf der linken Seite zu erreichen ist.<\/p>\n","howtogetthere":"","price":"","time":"<p>&#8211; 9.00 &#8211; 17.00 Uhr von Oktober bis April &#8211; 9.00 &#8211; 18.00 Uhr von Mai bis September  <\/p>\n<p>(Der Zeitplan kann sich noch \u00e4ndern)<\/p>\n","latitude":"45.704006","longitude":"9.669834","id_visit_manza":"2996","iu_motor_accessibility":"no","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_kids":false,"iu_shortprice":"","iu_addr_streetnumber":"Largo San Michele Al Pozzo Bianco","iu_addr_postalcode":"","iu_addr_city":"Bergamo","iu_addr_province":"","iu_phone":"","iu_cell":"","iu_website":"http:\/\/www.comune.bergamo.it\/servizi\/Menu\/dinamica.aspx?idSezione=3780&idArea=1182&idCat=1195&ID=10441&TipoElemento=pagina","iu_email":"","iu_document_label":"","iu_document":false,"iu_timetable":[{"day":{"value":"monday","label":"Luned\u00ec"},"open":true,"time":[{"opening":"9:00 am","closing":"5:00 pm"}]},{"day":{"value":"tuesday","label":"Marted\u00ec"},"open":true,"time":[{"opening":"9:00 am","closing":"5:00 pm"}]},{"day":{"value":"wednesday","label":"Mercoled\u00ec"},"open":true,"time":[{"opening":"9:00 am","closing":"5:00 pm"}]},{"day":{"value":"thursday","label":"Gioved\u00ec"},"open":true,"time":[{"opening":"9:00 am","closing":"5:00 pm"}]},{"day":{"value":"friday","label":"Venerd\u00ec"},"open":true,"time":[{"opening":"9:00 am","closing":"5:00 pm"}]},{"day":{"value":"saturday","label":"Sabato"},"open":true,"time":[{"opening":"9:00 am","closing":"6:00 pm"}]},{"day":{"value":"sunday","label":"Domenica"},"open":true,"time":[{"opening":"9:00 am","closing":"6:00 pm"}]}]},"size":"full","hero_buttons_group":{"buttons":[{"style":"primary","text":"Kontakt","icon":{"button_icon":"none"},"function":"link","url":"http:\/\/www.comune.bergamo.it\/servizi\/Menu\/dinamica.aspx?idSezione=3780&idArea=1182&idCat=1195&ID=10441&TipoElemento=pagina","select_post":null,"target":"_blank","url_youtube":"","target_modal":""}]},"featured_video":false,"filotto_sub":"","or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"order_by":"","order_way":"","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""},"style":"","text":"","icon":{"button_icon":"none"},"function":"","target":"","target_modal":"","iu_document_label":"","modules":false,"hero_buttons":false,"iu_kids":false,"is_an_ambassador":false},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/20056","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/types\/oggetto"}],"author":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/20056\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media\/7346"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media?parent=20056"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/categories?post=20056"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/tags?post=20056"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/aggr?post=20056"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/area?post=20056"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/kind?post=20056"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/zona?post=20056"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}