{"id":20107,"date":"2024-05-08T11:05:10","date_gmt":"2024-05-08T09:05:10","guid":{"rendered":"https:\/\/visitstg2.visitbergamo.net\/oggetto\/kirche-von-san-martino-della-pigrizia-und-treppe\/"},"modified":"2025-02-16T09:51:30","modified_gmt":"2025-02-16T08:51:30","slug":"kirche-von-san-martino-della-pigrizia-und-treppe","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/kirche-von-san-martino-della-pigrizia-und-treppe\/","title":{"rendered":"Kirche St. Martin der Faulen"},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":8252,"template":"","categories":[173],"tags":[],"aggr":[],"area":[867],"kind":[18680],"zona":[18760],"class_list":["post-20107","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-wohin-man-geht","area-bergamo","kind-poi-de","zona-bergamo-de"],"acf":{"hero_text":"","filotto_title":"","filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"scroll","filotto_fill":"manual","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""}},"howtogetthere":"","timerange":"","cancellationpolicy":"","moredetails":"","whatsincluded":"","whatsnotincluded":"","price":"","time":"","latitude":"45.700048","longitude":"9.641342","startingprice":"","gpxmap":"","iu_motor_accessibility":"no","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_shortprice":"","iu_addr_postalcode":"24129","iu_addr_city":"Bergamo","iu_phone":"","iu_cell":"","iu_website":"","iu_email":"","iu_document":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_bookingurl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"","iu_languages":"","iu_minpeople":"","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","id_madeep":"","id_visit_manza":"10444","url":"","url_youtube":"","cta":{"style":"","text":"","icon":{"button_icon":"none"},"function":"","url":"","target":"","url_youtube":"","target_modal":""},"button_icon":"none","tcm_content":[{"acf_fc_layout":"title","title_tag":"h3","title_text":"Das Datenblatt"},{"acf_fc_layout":"text","text":""}],"description":"<p style=\"text-align: justify;\" dir=\"ltr\"><span><br \/>Auf der landschaftlich reizvollen Strecke, die vom Ortsteil Longuelo nach <strong>Borgo Canale<\/strong> hinauff\u00fchrt, zwischen den beiden herrlichen bergamasker Becken, dem Astino und der Conca d&#8217;Oro, sto\u00dfen Sie unterwegs auf die kleine <strong>Kirche San Martino della Pigrizia<\/strong>.<\/span>Anders als Sie vielleicht denken, hat San Martino nichts mit Faulheit zu tun, ganz im Gegenteil!<br \/>\nDer Name dieses Ortes hat einen rein geografischen Hintergrund: Der Landstrich auf der Seite des Valle d&#8217;Astino ist im Gegensatz zu dem der <span> <strong>Conca d&#8217;Oro<\/strong> von Natur aus weniger der Sonneneinstrahlung ausgesetzt und aus diesem Grund geht der Anbau in diesem Gebiet langsamer voran.<br \/>\nIm Laufe der Zeit begannen die Einheimischen, diesem Teil des Landes den Spitznamen &#8216;Faulheit&#8217; zu geben, um seinen &#8216;faulen&#8217; Charakter zu betonen.<\/span>  <\/p>\n<p style=\"text-align: justify;\" dir=\"ltr\"><span>Die Kirche, die aus dem 9. Jahrhundert stammt und mehrfach umgebaut wurde, verf\u00fcgt \u00fcber einen bronzenen Haupteingang, auf dem die beiden Schutzheiligen, St. Martin und Unsere Liebe Frau von der Reinheit, abgebildet sind, sowie eine kleine obere L\u00fcnette, die die bogenf\u00f6rmige Fassade abschlie\u00dft.  <br \/>An der Seite f\u00fchrt eine kleine Steintreppe zur zweiten Eingangst\u00fcr.<br \/>\nAuch sie ist aus Bronze gefertigt und stellt die Geschichte der kleinen Kirche dar.<br \/>\nDas Innere besteht aus einem einzigen rechteckigen Kirchenschiff, das durch zwei gemauerte B\u00f6gen in drei Joche unterteilt ist, \u00fcber denen die beiden Schr\u00e4gen des freiliegenden Daches auslaufen.<br \/>\nDas Presbyterium besteht aus einer sehr schlichten Kapelle, die von einem Tonnengew\u00f6lbe \u00fcberdacht ist und in deren Mitte sich eine Reihe von Werken befinden, die die Madonna mit Kind und die Heiligen Martin, Johannes der T\u00e4ufer, Karl und Antonius von Padua darstellen.     <\/span><\/p>\n<p style=\"text-align: justify;\" dir=\"ltr\">\n","slides":[{"image":{"ID":8252,"id":8252,"title":"003d587cfb0db5c875720bcbc41373f1_dd58af88.jpg","filename":"003d587cfb0db5c875720bcbc41373f1_dd58af88.jpg","filesize":529944,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/003d587cfb0db5c875720bcbc41373f1_dd58af88.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/kirche-von-san-martino-della-pigrizia-und-treppe\/003d587cfb0db5c875720bcbc41373f1_dd58af88-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"003d587cfb0db5c875720bcbc41373f1_dd58af88-jpg-2","status":"inherit","uploaded_to":20107,"date":"2024-05-08 08:46:06","modified":"2024-08-30 13:09:09","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1550,"height":600,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/003d587cfb0db5c875720bcbc41373f1_dd58af88-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/003d587cfb0db5c875720bcbc41373f1_dd58af88-300x116.jpg","medium-width":300,"medium-height":116,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/003d587cfb0db5c875720bcbc41373f1_dd58af88-768x297.jpg","medium_large-width":768,"medium_large-height":297,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/003d587cfb0db5c875720bcbc41373f1_dd58af88-1024x396.jpg","large-width":1024,"large-height":396,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/003d587cfb0db5c875720bcbc41373f1_dd58af88-1536x595.jpg","1536x1536-width":1536,"1536x1536-height":595,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/003d587cfb0db5c875720bcbc41373f1_dd58af88.jpg","2048x2048-width":1550,"2048x2048-height":600,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/003d587cfb0db5c875720bcbc41373f1_dd58af88.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":116,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/003d587cfb0db5c875720bcbc41373f1_dd58af88.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":155,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/003d587cfb0db5c875720bcbc41373f1_dd58af88.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":232}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"heiliger martin der faulheit","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":8258,"id":8258,"title":"1dffebc6e48dcda529f6b674b35a80b3_e220901a.png","filename":"1dffebc6e48dcda529f6b674b35a80b3_e220901a.png","filesize":1277741,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/1dffebc6e48dcda529f6b674b35a80b3_e220901a.png","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/kirche-von-san-martino-della-pigrizia-und-treppe\/1dffebc6e48dcda529f6b674b35a80b3_e220901a-png-2\/","alt":"","author":"0","description":"","caption":"","name":"1dffebc6e48dcda529f6b674b35a80b3_e220901a-png-2","status":"inherit","uploaded_to":20107,"date":"2024-05-08 08:46:06","modified":"2024-08-30 13:09:22","menu_order":0,"mime_type":"image\/png","type":"image","subtype":"png","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1550,"height":600,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/1dffebc6e48dcda529f6b674b35a80b3_e220901a-150x150.png","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/1dffebc6e48dcda529f6b674b35a80b3_e220901a-300x116.png","medium-width":300,"medium-height":116,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/1dffebc6e48dcda529f6b674b35a80b3_e220901a-768x297.png","medium_large-width":768,"medium_large-height":297,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/1dffebc6e48dcda529f6b674b35a80b3_e220901a-1024x396.png","large-width":1024,"large-height":396,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/1dffebc6e48dcda529f6b674b35a80b3_e220901a-1536x595.png","1536x1536-width":1536,"1536x1536-height":595,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/1dffebc6e48dcda529f6b674b35a80b3_e220901a.png","2048x2048-width":1550,"2048x2048-height":600,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/1dffebc6e48dcda529f6b674b35a80b3_e220901a.png","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":116,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/1dffebc6e48dcda529f6b674b35a80b3_e220901a.png","gform-image-choice-md-width":400,"gform-image-choice-md-height":155,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/1dffebc6e48dcda529f6b674b35a80b3_e220901a.png","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":232}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"heiliger martin der faulheit","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"buttons":[{"style":"primary","text":"Kontakt","icon":{"button_icon":"none"},"function":"link","url":"","select_post":null,"target":"_blank","url_youtube":"","target_modal":""}],"filotto_layout":"scroll","hero_title":"Kirche St. Martin der Faulen","indepth":"<p style=\"text-align: justify;\" dir=\"ltr\"><strong>Die Aufstellung von San Martino<\/strong><\/p>\n<p style=\"text-align: justify;\" dir=\"ltr\">Nicht weit von der Kirche entfernt, in Richtung Oberstadt, befindet sich die Treppe San Martino, die die Via Borgo Canale mit der Via San Martino della Pigrizia verbindet.<br \/>\nEs handelt sich um ein kurzes St\u00fcck, das zun\u00e4chst aus Stufen besteht und nach ein paar Metern in einen Aufstieg auf Kopfsteinpflaster \u00fcbergeht, der zu den Toren von Bergamo Alta f\u00fchrt.<br \/>\nBeim Aufstieg sto\u00dfen Sie auch auf die eindrucksvollen Scorlazzino- und Scorlazzone-Treppen, die zur Burg San Vigilio hinauff\u00fchren und einen einzigartigen Panoramablick bieten.  <\/p>\n","iu_addr_streetnumber":"Via S. Martino della Pigrizia","iu_addr_province":"Bergamo","filotto_fill":"manual","hero_type":"images","filotto_items":false,"accessibilitycontent":{"tcm_content":[{"acf_fc_layout":"title","title_tag":"h3","title_text":"Das Datenblatt"},{"acf_fc_layout":"text","text":""}]},"gallery":{"gallery_items":false},"iu_kids":false,"iu_timetable":false,"poi_data":{"description":"<p style=\"text-align: justify;\" dir=\"ltr\"><span><br \/>Auf der landschaftlich reizvollen Strecke, die vom Ortsteil Longuelo nach <strong>Borgo Canale<\/strong> hinauff\u00fchrt, zwischen den beiden herrlichen bergamasker Becken, dem Astino und der Conca d&#8217;Oro, sto\u00dfen Sie unterwegs auf die kleine <strong>Kirche San Martino della Pigrizia<\/strong>.<\/span>Anders als Sie vielleicht denken, hat San Martino nichts mit Faulheit zu tun, ganz im Gegenteil!<br \/>\nDer Name dieses Ortes hat einen rein geografischen Hintergrund: Der Landstrich auf der Seite des Valle d&#8217;Astino ist im Gegensatz zu dem der <span> <strong>Conca d&#8217;Oro<\/strong> von Natur aus weniger der Sonneneinstrahlung ausgesetzt und aus diesem Grund geht der Anbau in diesem Gebiet langsamer voran.<br \/>\nIm Laufe der Zeit begannen die Einheimischen, diesem Teil des Landes den Spitznamen &#8216;Faulheit&#8217; zu geben, um seinen &#8216;faulen&#8217; Charakter zu betonen.<\/span>  <\/p>\n<p style=\"text-align: justify;\" dir=\"ltr\"><span>Die Kirche, die aus dem 9. Jahrhundert stammt und mehrfach umgebaut wurde, verf\u00fcgt \u00fcber einen bronzenen Haupteingang, auf dem die beiden Schutzheiligen, St. Martin und Unsere Liebe Frau von der Reinheit, abgebildet sind, sowie eine kleine obere L\u00fcnette, die die bogenf\u00f6rmige Fassade abschlie\u00dft.  <br \/>An der Seite f\u00fchrt eine kleine Steintreppe zur zweiten Eingangst\u00fcr.<br \/>\nAuch sie ist aus Bronze gefertigt und stellt die Geschichte der kleinen Kirche dar.<br \/>\nDas Innere besteht aus einem einzigen rechteckigen Kirchenschiff, das durch zwei gemauerte B\u00f6gen in drei Joche unterteilt ist, \u00fcber denen die beiden Schr\u00e4gen des freiliegenden Daches auslaufen.<br \/>\nDas Presbyterium besteht aus einer sehr schlichten Kapelle, die von einem Tonnengew\u00f6lbe \u00fcberdacht ist und in deren Mitte sich eine Reihe von Werken befinden, die die Madonna mit Kind und die Heiligen Martin, Johannes der T\u00e4ufer, Karl und Antonius von Padua darstellen.     <\/span><\/p>\n<p style=\"text-align: justify;\" dir=\"ltr\">\n","indepth":"<p style=\"text-align: justify;\" dir=\"ltr\"><strong>Die Aufstellung von San Martino<\/strong><\/p>\n<p style=\"text-align: justify;\" dir=\"ltr\">Nicht weit von der Kirche entfernt, in Richtung Oberstadt, befindet sich die Treppe San Martino, die die Via Borgo Canale mit der Via San Martino della Pigrizia verbindet.<br \/>\nEs handelt sich um ein kurzes St\u00fcck, das zun\u00e4chst aus Stufen besteht und nach ein paar Metern in einen Aufstieg auf Kopfsteinpflaster \u00fcbergeht, der zu den Toren von Bergamo Alta f\u00fchrt.<br \/>\nBeim Aufstieg sto\u00dfen Sie auch auf die eindrucksvollen Scorlazzino- und Scorlazzone-Treppen, die zur Burg San Vigilio hinauff\u00fchren und einen einzigartigen Panoramablick bieten.  <\/p>\n","howtogetthere":"","price":"","time":"","latitude":"45.700048","longitude":"9.641342","id_visit_manza":"10444","iu_motor_accessibility":"no","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_kids":false,"iu_shortprice":"","iu_addr_streetnumber":"Via S. Martino della Pigrizia","iu_addr_postalcode":"24129","iu_addr_city":"Bergamo","iu_addr_province":"Bergamo","iu_phone":"","iu_cell":"","iu_website":"","iu_email":"","iu_document_label":"","iu_document":false,"iu_timetable":false},"size":"full","featured_video":false,"is_an_ambassador":false,"filotto_sub":"","or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"order_by":"","order_way":"","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""},"style":"","text":"","icon":{"button_icon":"none"},"function":"","target":"","target_modal":"","iu_document_label":""},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/20107","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/types\/oggetto"}],"author":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/20107\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media\/8252"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media?parent=20107"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/categories?post=20107"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/tags?post=20107"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/aggr?post=20107"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/area?post=20107"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/kind?post=20107"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/zona?post=20107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}