{"id":20108,"date":"2024-05-08T11:05:11","date_gmt":"2024-05-08T09:05:11","guid":{"rendered":"https:\/\/visitstg2.visitbergamo.net\/oggetto\/lovere-touristenhafen\/"},"modified":"2025-02-16T09:51:31","modified_gmt":"2025-02-16T08:51:31","slug":"lovere-touristenhafen","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/lovere-touristenhafen\/","title":{"rendered":"Lovere Jachthafen"},"excerpt":{"rendered":"<p>Sind Sie ein sportlicher Typ oder ziehen Sie es vor, am See zu entspannen und dabei ein gutes Glas Wein zu schl\u00fcrfen?<br \/>\nSo oder so, im Porto di Lovere finden Sie, was Sie suchen! <\/p>\n","protected":false},"author":3,"featured_media":8264,"template":"","categories":[173],"tags":[],"aggr":[],"area":[922],"kind":[18680],"zona":[18982],"class_list":["post-20108","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-wohin-man-geht","area-lovere","kind-poi-de","zona-lovere-de"],"acf":{"filotto_title":"","filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"scroll","filotto_fill":"manual","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""}},"indepth":"","howtogetthere":"","timerange":"","cancellationpolicy":"","moredetails":"","whatsincluded":"","whatsnotincluded":"","price":"","time":"","latitude":"45.809074","longitude":"10.069017","startingprice":"","gpxmap":"","iu_motor_accessibility":"no","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_shortprice":"","iu_addr_streetnumber":"","iu_addr_postalcode":"24065","iu_addr_city":"Lovere","iu_phone":"","iu_cell":"","iu_website":"","iu_email":"","iu_document":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_bookingurl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"","iu_languages":"","iu_minpeople":"","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","id_madeep":"","id_visit_manza":"7117","url":"","url_youtube":"","cta":{"style":"","text":"","icon":{"button_icon":"none"},"function":"","url":"","target":"","url_youtube":"","target_modal":""},"iu_timetable":false,"button_icon":"none","tcm_content":[{"acf_fc_layout":"title","title_tag":"h3","title_text":"Das Datenblatt"},{"acf_fc_layout":"text","text":""}],"description":"<p dir=\"ltr\">Der Jachthafen Cornasola in Lovere geh\u00f6rt zu den gr\u00f6\u00dften und modernsten Seehafenanlagen Europas.<br \/>\nSie werden dort Hunderte von Booten an perfekt ausgestatteten Kais festmachen sehen.<br \/>\nRund um die Anlegestelle ist ein riesiges Areal mit zahlreichen Freizeitaktivit\u00e4ten, von Sport bis zu Erfrischungen, entstanden.<br \/>\nSie k\u00f6nnen schwimmen, rudern, segeln, Tennis, Fu\u00dfball und Basketball spielen oder sich in eine der vielen Bars oder Restaurants setzen, um die lokalen Spezialit\u00e4ten zu probieren.   <\/p>\n<p>\u00a0<\/p>\n<p dir=\"ltr\">Der Hafen ist ein echtes Freizeit- und Kulturzentrum: Hier finden Sie auch die Bibliothek, das st\u00e4dtische Kulturzentrum und die Jugendherberge, eine gro\u00dfe Gr\u00fcnfl\u00e4che, die f\u00fcr Kinder und Familien ausgestattet ist, und eine gro\u00dfe Wiese am See, um die Sonne zu genie\u00dfen.<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n","slides":[{"image":false,"video":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/POI_Lungolago_PortoTuristico.mp4","video_mobile":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/POI_Lungolago_PortoTuristico_VERT.mp4","video_with_audio":false,"duration_ms":"","title":"marina lovere","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"buttons":[{"style":"primary","text":"Kontakt","icon":{"button_icon":"none"},"function":"link","url":"","select_post":null,"target":"_blank","url_youtube":"","target_modal":""}],"filotto_layout":"scroll","hero_title":"Lovere Jachthafen","hero_text":"<p><span id=\"docs-internal-guid-3413acb9-5000-0f93-866b-54f73ae3bf5a\">Sind Sie ein sportlicher Typ oder ziehen Sie es vor, am See zu entspannen und dabei ein gutes Glas Wein zu schl\u00fcrfen?<br \/>\nSo oder so, im Porto di Lovere finden Sie, was Sie suchen! <\/span><\/p>\n","iu_addr_province":"Bergamo","size":"full","filotto_fill":"manual","filotto_items":false,"hero_type":"images","accessibilitycontent":{"tcm_content":[{"acf_fc_layout":"title","title_tag":"h3","title_text":"Das Datenblatt"},{"acf_fc_layout":"text","text":""}]},"gallery":{"gallery_items":false},"poi_data":{"description":"<p dir=\"ltr\">Der Jachthafen Cornasola in Lovere geh\u00f6rt zu den gr\u00f6\u00dften und modernsten Seehafenanlagen Europas.<br \/>\nSie werden dort Hunderte von Booten an perfekt ausgestatteten Kais festmachen sehen.<br \/>\nRund um die Anlegestelle ist ein riesiges Areal mit zahlreichen Freizeitaktivit\u00e4ten, von Sport bis zu Erfrischungen, entstanden.<br \/>\nSie k\u00f6nnen schwimmen, rudern, segeln, Tennis, Fu\u00dfball und Basketball spielen oder sich in eine der vielen Bars oder Restaurants setzen, um die lokalen Spezialit\u00e4ten zu probieren.   <\/p>\n<p>\u00a0<\/p>\n<p dir=\"ltr\">Der Hafen ist ein echtes Freizeit- und Kulturzentrum: Hier finden Sie auch die Bibliothek, das st\u00e4dtische Kulturzentrum und die Jugendherberge, eine gro\u00dfe Gr\u00fcnfl\u00e4che, die f\u00fcr Kinder und Familien ausgestattet ist, und eine gro\u00dfe Wiese am See, um die Sonne zu genie\u00dfen.<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n","indepth":"","howtogetthere":"","price":"","time":"","latitude":"45.809074","longitude":"10.069017","id_visit_manza":"7117","iu_motor_accessibility":"no","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_kids":false,"iu_shortprice":"","iu_addr_streetnumber":"","iu_addr_postalcode":"24065","iu_addr_city":"Lovere","iu_addr_province":"Bergamo","iu_phone":"","iu_cell":"","iu_website":"","iu_email":"","iu_document_label":"","iu_document":false,"iu_timetable":false},"hero_buttons_group":{"buttons":[{"style":"primary","text":"Kontakt","icon":{"button_icon":"none"},"function":"link","url":"","select_post":null,"target":"_blank","url_youtube":"","target_modal":""}]},"modules":false,"filotto_sub":"","or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"order_by":"","order_way":"","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""},"style":"","text":"","icon":{"button_icon":"none"},"function":"","target":"","target_modal":"","iu_document_label":"","hero_buttons":[{"style":"primary","text":"Kontakt","icon":{"button_icon":"none"},"function":"link","url":"","select_post":null,"target":"_blank","url_youtube":"","target_modal":""}],"iu_kids":false,"featured_video":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/POI_Lungolago_PortoTuristico_SH.mp4","is_an_ambassador":false},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/20108","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/types\/oggetto"}],"author":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/20108\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media\/8264"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media?parent=20108"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/categories?post=20108"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/tags?post=20108"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/aggr?post=20108"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/area?post=20108"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/kind?post=20108"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/zona?post=20108"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}