{"id":20116,"date":"2024-05-08T11:05:14","date_gmt":"2024-05-08T09:05:14","guid":{"rendered":"https:\/\/visitstg2.visitbergamo.net\/oggetto\/kirche-santalessandro-in-colonna\/"},"modified":"2025-02-16T09:51:38","modified_gmt":"2025-02-16T08:51:38","slug":"kirche-santalessandro-in-colonna","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/kirche-santalessandro-in-colonna\/","title":{"rendered":"Kirche St. Alexander in S\u00e4ule"},"excerpt":{"rendered":"<p>In einer mittelalterlichen Stra\u00dfe in der Unterstadt weist eine einsame 10 Meter hohe S\u00e4ule, die von einem Martyrium zeugt, auf diese alte Kirche hin.<br \/>\nTreten Sie ein und entdecken Sie ihre verborgenen Sch\u00e4tze! <\/p>\n","protected":false},"author":3,"featured_media":8396,"template":"","categories":[173],"tags":[],"aggr":[],"area":[867],"kind":[18680],"zona":[18760],"class_list":["post-20116","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-wohin-man-geht","area-bergamo","kind-poi-de","zona-bergamo-de"],"acf":{"filotto_title":"","filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"scroll","filotto_fill":"manual","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""}},"indepth":"","howtogetthere":"","timerange":"","cancellationpolicy":"","moredetails":"","whatsincluded":"","whatsnotincluded":"","price":"","time":"","latitude":"45.695222","longitude":"9.664549","startingprice":"","gpxmap":"","iu_motor_accessibility":"no","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_shortprice":"","iu_addr_postalcode":"","iu_addr_city":"Bergamo","iu_addr_province":"","iu_phone":"+39 035 249696","iu_cell":"","iu_email":"parrocchia.salessandro@gmail.com","iu_document":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_bookingurl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"","iu_languages":"","iu_minpeople":"","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","id_madeep":"","id_visit_manza":"3024","url_youtube":"","cta":{"style":"","text":"","icon":{"button_icon":"none"},"function":"","url":"http:\/\/santalessandroincolonna.it","target":"","url_youtube":"","target_modal":""},"button_icon":"none","tcm_content":[{"acf_fc_layout":"title","title_tag":"h3","title_text":"Das Datenblatt"},{"acf_fc_layout":"text","text":""}],"description":"<p>Es hei\u00dft, dass <strong>der Heilige Alexander<\/strong>, der Schutzpatron von Bergamo, genau an der Stelle enthauptet wurde, an der heute diese imposante S\u00e4ule steht.<br \/>\nSie wurde 1618 aus Steinfragmenten aus r\u00f6mischer Zeit rekonstruiert und ist das einzige Zeugnis der Kathedrale, die dem Heiligen im 4. Jahrhundert geweiht und sp\u00e4ter abgerissen wurde. <\/p>\n<p>Die Kirche, die Sie heute sehen k\u00f6nnen und auf deren Vorplatz die S\u00e4ule steht, stammt aus dem Jahr 1447, erhielt ihre heutige Struktur jedoch erst im fr\u00fchen 18. Jahrhundert; der Glockenturm hingegen wurde im 20.<\/p>\n<p>Im Inneren finden Sie ein einziges Kirchenschiff mit nicht weniger als vier Kapellen auf jeder Seite: Wenn Sie nicht abergl\u00e4ubisch sind, k\u00f6nnen Sie die Kapelle der Heiligen Jungfrau des Patronats besuchen, die an der Stelle eines alten Friedhofs errichtet wurde.<\/p>\n<p>Dar\u00fcber hinaus erwarten Sie in den Kapellen und Sakristeien zahlreiche Kunstwerke, darunter Lorenzo Lotto&#8217;s pr\u00e4chtiges Gem\u00e4lde &#8216;Beweinung des toten Christus&#8217;, ein seltenes Beispiel f\u00fcr Tempera auf Leinwand, datiert 1520-1521.<\/p>\n","slides":[{"image":{"ID":8396,"id":8396,"title":"ef3c1743bc7ac87a2d608d3ea0e7ab17_752b60f4.jpg","filename":"ef3c1743bc7ac87a2d608d3ea0e7ab17_752b60f4.jpg","filesize":433624,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ef3c1743bc7ac87a2d608d3ea0e7ab17_752b60f4.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/kirche-santalessandro-in-colonna\/ef3c1743bc7ac87a2d608d3ea0e7ab17_752b60f4-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"ef3c1743bc7ac87a2d608d3ea0e7ab17_752b60f4-jpg-2","status":"inherit","uploaded_to":20116,"date":"2024-05-08 08:46:23","modified":"2024-09-29 08:42:35","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1920,"height":1282,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ef3c1743bc7ac87a2d608d3ea0e7ab17_752b60f4-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ef3c1743bc7ac87a2d608d3ea0e7ab17_752b60f4-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ef3c1743bc7ac87a2d608d3ea0e7ab17_752b60f4-768x513.jpg","medium_large-width":768,"medium_large-height":513,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ef3c1743bc7ac87a2d608d3ea0e7ab17_752b60f4-1024x684.jpg","large-width":1024,"large-height":684,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ef3c1743bc7ac87a2d608d3ea0e7ab17_752b60f4-1536x1026.jpg","1536x1536-width":1536,"1536x1536-height":1026,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ef3c1743bc7ac87a2d608d3ea0e7ab17_752b60f4.jpg","2048x2048-width":1920,"2048x2048-height":1282,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ef3c1743bc7ac87a2d608d3ea0e7ab17_752b60f4.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ef3c1743bc7ac87a2d608d3ea0e7ab17_752b60f4.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ef3c1743bc7ac87a2d608d3ea0e7ab17_752b60f4.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":401}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"st. alexander in kolumne","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"buttons":[{"style":"primary","text":"Kontakt","icon":{"button_icon":"none"},"function":"link","url":"http:\/\/santalessandroincolonna.it","select_post":null,"target":"_blank","url_youtube":"","target_modal":""}],"filotto_layout":"scroll","url":"http:\/\/santalessandroincolonna.it","hero_title":"Kirche St. Alexander in S\u00e4ule","hero_text":"<p>In einer mittelalterlichen Stra\u00dfe in der Unterstadt weist eine einsame 10 Meter hohe S\u00e4ule, die von einem Martyrium zeugt, auf diese alte Kirche hin.<br \/>\nTreten Sie ein und entdecken Sie ihre verborgenen Sch\u00e4tze! <\/p>\n","iu_addr_streetnumber":"St. Alexander Stra\u00dfe","iu_website":"http:\/\/santalessandroincolonna.it","filotto_fill":"manual","hero_type":"images","filotto_items":false,"accessibilitycontent":{"tcm_content":[{"acf_fc_layout":"title","title_tag":"h3","title_text":"Das Datenblatt"},{"acf_fc_layout":"text","text":""}]},"gallery":{"gallery_items":false},"iu_kids":false,"iu_timetable":false,"poi_data":{"description":"<p>Es hei\u00dft, dass <strong>der Heilige Alexander<\/strong>, der Schutzpatron von Bergamo, genau an der Stelle enthauptet wurde, an der heute diese imposante S\u00e4ule steht.<br \/>\nSie wurde 1618 aus Steinfragmenten aus r\u00f6mischer Zeit rekonstruiert und ist das einzige Zeugnis der Kathedrale, die dem Heiligen im 4. Jahrhundert geweiht und sp\u00e4ter abgerissen wurde. <\/p>\n<p>Die Kirche, die Sie heute sehen k\u00f6nnen und auf deren Vorplatz die S\u00e4ule steht, stammt aus dem Jahr 1447, erhielt ihre heutige Struktur jedoch erst im fr\u00fchen 18. Jahrhundert; der Glockenturm hingegen wurde im 20.<\/p>\n<p>Im Inneren finden Sie ein einziges Kirchenschiff mit nicht weniger als vier Kapellen auf jeder Seite: Wenn Sie nicht abergl\u00e4ubisch sind, k\u00f6nnen Sie die Kapelle der Heiligen Jungfrau des Patronats besuchen, die an der Stelle eines alten Friedhofs errichtet wurde.<\/p>\n<p>Dar\u00fcber hinaus erwarten Sie in den Kapellen und Sakristeien zahlreiche Kunstwerke, darunter Lorenzo Lotto&#8217;s pr\u00e4chtiges Gem\u00e4lde &#8216;Beweinung des toten Christus&#8217;, ein seltenes Beispiel f\u00fcr Tempera auf Leinwand, datiert 1520-1521.<\/p>\n","indepth":"","howtogetthere":"","price":"","time":"","latitude":"45.695222","longitude":"9.664549","id_visit_manza":"3024","iu_motor_accessibility":"no","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_kids":false,"iu_shortprice":"","iu_addr_streetnumber":"St. Alexander Stra\u00dfe","iu_addr_postalcode":"","iu_addr_city":"Bergamo","iu_addr_province":"","iu_phone":"+39 035 249696","iu_cell":"","iu_website":"http:\/\/santalessandroincolonna.it","iu_email":"parrocchia.salessandro@gmail.com","iu_document_label":"","iu_document":false,"iu_timetable":false},"size":"full","featured_video":false,"is_an_ambassador":false,"filotto_sub":"","or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"order_by":"","order_way":"","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""},"style":"","text":"","icon":{"button_icon":"none"},"function":"","target":"","target_modal":"","iu_document_label":""},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/20116","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/types\/oggetto"}],"author":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/20116\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media\/8396"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media?parent=20116"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/categories?post=20116"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/tags?post=20116"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/aggr?post=20116"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/area?post=20116"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/kind?post=20116"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/zona?post=20116"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}