{"id":20180,"date":"2024-05-08T11:05:37","date_gmt":"2024-05-08T09:05:37","guid":{"rendered":"https:\/\/visitstg2.visitbergamo.net\/oggetto\/crespi-dadda\/"},"modified":"2025-02-16T09:52:41","modified_gmt":"2025-02-16T08:52:41","slug":"crespi-dadda","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/crespi-dadda\/","title":{"rendered":"Crespi D&#8217;Adda"},"excerpt":{"rendered":"<p>Kommen Sie und entdecken Sie dieses Unesco-Kulturerbe! Wenn Sie durch Crespi D&#8217;Adda schlendern, f\u00fchlen Sie sich wie in einem echten Arbeiterdorf am Ende des 19. <\/p>\n","protected":false},"author":3,"featured_media":9374,"template":"","categories":[],"tags":[],"aggr":[],"area":[1070],"kind":[18680],"zona":[19395],"class_list":["post-20180","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","area-capriate-san-gervasio","kind-poi-de","zona-capriate-san-gervasio-de"],"acf":{"filotto_title":"","filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"scroll","filotto_fill":"manual","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""}},"indepth":"","howtogetthere":"","timerange":"","cancellationpolicy":"","moredetails":"","whatsincluded":"","whatsnotincluded":"","price":"","time":"","latitude":"45.596533","longitude":"9.535786","startingprice":"","gpxmap":"","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_shortprice":"","iu_addr_streetnumber":"","iu_addr_postalcode":"","iu_addr_city":"Capriate San Gervasio","iu_addr_province":"","iu_phone":"+39 029091712","iu_cell":"","iu_email":"info@visitcrespi.it","iu_document":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_bookingurl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"","iu_languages":"","iu_minpeople":"","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","id_madeep":"","id_visit_manza":"3047","url_youtube":"","cta":{"style":"","text":"","icon":{"button_icon":"none"},"function":"","url":"https:\/\/www.visitcrespi.it\/","target":"","url_youtube":"","target_modal":""},"iu_timetable":false,"button_icon":"none","iu_kids":false,"iu_motor_accessibility":"notsure","tcm_content":[{"acf_fc_layout":"title","title_tag":"h3","title_text":"Das Datenblatt"},{"acf_fc_layout":"text","text":""}],"description":"<p><strong>Crespi d&#8217;Adda<\/strong> ist ein Beispiel f\u00fcr <strong>Industriearch\u00e4ologie<\/strong> und wurde im Dezember 1995<strong>von der UNESCO<\/strong> zum Weltkulturerbe erkl\u00e4rt. Es ist ein au\u00dfergew\u00f6hnlich gut erhaltenes <strong>Arbeiterdorf<\/strong> mit einem beispielhaften Stadtgrundriss. Entdecken Sie die Geschichte der Familie Crespi und tauchen Sie ein in das Leben des letzten Jahrhunderts.  <\/p>\n<h3>Die Geschichte von Crespi und die Entstehung des Dorfes<\/h3>\n<p>Die Familie <strong>Crespi<\/strong>, eine Weberfamilie, gr\u00fcndete hier 1878 ihr Unternehmen, da sie wusste, dass in der Gegend viele Arbeitskr\u00e4fte zur Verf\u00fcgung standen und sie die M\u00f6glichkeit sah, einen Industriekanal entlang der <strong>Adda<\/strong> zu bauen, um deren Wasserkraft zu nutzen. So entstand <strong>Cristoforo Crespi<\/strong>, der Gr\u00fcnder. Er baute den sogenannten <em>&#8216;palas\u00f2cc&#8217;<\/em>, aber erst mit der Ankunft seines in England ausgebildeten Sohnes Silvio wurde ein Plan f\u00fcr das gesamte Dorf erstellt. Das Prinzip war, jedem eine kleine Villa mit Garten und Gem\u00fcsegarten zur Verf\u00fcgung zu stellen und die notwendigen Dienstleistungen zu erbringen, von den \u00f6ffentlichen B\u00e4dern bis zur Schule, von der Kirche bis zum Sportplatz, vom Erholungszentrum bis zum kleinen Krankenhaus. Und dann das Theater, der Lebensmittelladen, die Feuerwehr, das Waschhaus, das Musikkorps, das Sommerlager, der Hauswirtschaftskurs. Alles von <strong>Silvio Crespi<\/strong> selbst verwaltet, einem au\u00dfergew\u00f6hnlichen Unternehmer und hartn\u00e4ckigen Politiker. Der Grundriss der Stadt ist einfach: Entlang des Flusses liegt die Fabrik mit ihren hohen Schornsteinen und daneben das Schloss der Besitzer. Die Arbeiterh\u00e4user sind an mehreren parallelen Stra\u00dfen angeordnet, im S\u00fcden befindet sich eine Gruppe von sp\u00e4teren Villen f\u00fcr Angestellte und F\u00fchrungskr\u00e4fte. Am Anfang des Dorfes steht die Kirche und daneben die Schule.<\/p>\n<h3>Ein Eintauchen in die Vergangenheit<\/h3>\n<p>Crespi d&#8217;Adda, ein weltweit einzigartiges Zeugnis eines <strong>Industriedorfs am Ende des 19. Jahrhunderts,<\/strong> besticht durch den au\u00dfergew\u00f6hnlichen Erhaltungszustand seiner Geb\u00e4ude und seines Stadtgrundrisses sowie durch seine Lage am Mittellauf des Flusses Adda &#8211; der Wiege der <strong>italienischen industriellen Revolution<\/strong> -, der reich an historischen und k\u00fcnstlerischen Zeugnissen ist. Am bemerkenswertesten ist jedoch die Tatsache, dass es im Gegensatz zu allen anderen \u00e4hnlichen D\u00f6rfern in Italien und auf der ganzen Welt neben der Unversehrtheit der Geb\u00e4ude auch seine sozialen und produktiven Funktionen beibehalten hat und tats\u00e4chlich eine lebendige Gemeinschaft beherbergt, in der die Fabrik bis 2004 in Betrieb war. Ein Tag in Crespi d&#8217;Adda ist nicht nur ein kultureller Besuch, sondern vor allem ein Eintauchen in das letzte Jahrhundert und eine Gelegenheit, in das Leben und die Br\u00e4uche der Vergangenheit einzutauchen. <\/p>\n","slides":[{"image":{"ID":9386,"id":9386,"title":"9b3672e930198356d7638c2d50117bce_a54e8def.jpg","filename":"9b3672e930198356d7638c2d50117bce_a54e8def.jpg","filesize":912407,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/9b3672e930198356d7638c2d50117bce_a54e8def.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/crespi-dadda\/9b3672e930198356d7638c2d50117bce_a54e8def-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"9b3672e930198356d7638c2d50117bce_a54e8def-jpg-2","status":"inherit","uploaded_to":20180,"date":"2024-05-08 08:49:01","modified":"2024-05-08 12:27:02","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1920,"height":1281,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/9b3672e930198356d7638c2d50117bce_a54e8def-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/9b3672e930198356d7638c2d50117bce_a54e8def-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/9b3672e930198356d7638c2d50117bce_a54e8def-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/9b3672e930198356d7638c2d50117bce_a54e8def-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/9b3672e930198356d7638c2d50117bce_a54e8def-1536x1025.jpg","1536x1536-width":1536,"1536x1536-height":1025,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/9b3672e930198356d7638c2d50117bce_a54e8def.jpg","2048x2048-width":1920,"2048x2048-height":1281,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/9b3672e930198356d7638c2d50117bce_a54e8def.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/9b3672e930198356d7638c2d50117bce_a54e8def.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/9b3672e930198356d7638c2d50117bce_a54e8def.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"Cr\u00eapes 1","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":36883,"id":36883,"title":"Nuovo progetto (5)","filename":"Nuovo-progetto-5.jpg","filesize":168177,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/Nuovo-progetto-5.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/crespi-dadda\/nuovo-progetto-5-2\/","alt":"","author":"6","description":"","caption":"","name":"nuovo-progetto-5-2","status":"inherit","uploaded_to":20180,"date":"2024-05-22 12:44:26","modified":"2024-05-22 12:45:41","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1560,"height":720,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/Nuovo-progetto-5-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/Nuovo-progetto-5-300x138.jpg","medium-width":300,"medium-height":138,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/Nuovo-progetto-5-768x354.jpg","medium_large-width":768,"medium_large-height":354,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/Nuovo-progetto-5-1024x473.jpg","large-width":1024,"large-height":473,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/Nuovo-progetto-5-1536x709.jpg","1536x1536-width":1536,"1536x1536-height":709,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/Nuovo-progetto-5.jpg","2048x2048-width":1560,"2048x2048-height":720,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/Nuovo-progetto-5.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":138,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/Nuovo-progetto-5.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":185,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/Nuovo-progetto-5.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":277}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"Cr\u00eapes 5","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":9374,"id":9374,"title":"74a537899689d25146715ed7b7ec65a8_383d6a74.jpg","filename":"74a537899689d25146715ed7b7ec65a8_383d6a74.jpg","filesize":1323254,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/74a537899689d25146715ed7b7ec65a8_383d6a74.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/crespi-dadda\/74a537899689d25146715ed7b7ec65a8_383d6a74-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"74a537899689d25146715ed7b7ec65a8_383d6a74-jpg-2","status":"inherit","uploaded_to":20180,"date":"2024-05-08 08:49:00","modified":"2024-05-08 12:27:02","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1920,"height":1280,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/74a537899689d25146715ed7b7ec65a8_383d6a74-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/74a537899689d25146715ed7b7ec65a8_383d6a74-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/74a537899689d25146715ed7b7ec65a8_383d6a74-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/74a537899689d25146715ed7b7ec65a8_383d6a74-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/74a537899689d25146715ed7b7ec65a8_383d6a74-1536x1024.jpg","1536x1536-width":1536,"1536x1536-height":1024,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/74a537899689d25146715ed7b7ec65a8_383d6a74.jpg","2048x2048-width":1920,"2048x2048-height":1280,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/74a537899689d25146715ed7b7ec65a8_383d6a74.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/74a537899689d25146715ed7b7ec65a8_383d6a74.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/74a537899689d25146715ed7b7ec65a8_383d6a74.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"Cr\u00eapes 2","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":36889,"id":36889,"title":"Nuovo progetto (7)","filename":"Nuovo-progetto-7.jpg","filesize":173677,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/Nuovo-progetto-7.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/crespi-dadda\/nuovo-progetto-7-2\/","alt":"","author":"6","description":"","caption":"","name":"nuovo-progetto-7-2","status":"inherit","uploaded_to":20180,"date":"2024-05-22 12:45:17","modified":"2024-05-22 12:45:30","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1560,"height":720,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/Nuovo-progetto-7-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/Nuovo-progetto-7-300x138.jpg","medium-width":300,"medium-height":138,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/Nuovo-progetto-7-768x354.jpg","medium_large-width":768,"medium_large-height":354,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/Nuovo-progetto-7-1024x473.jpg","large-width":1024,"large-height":473,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/Nuovo-progetto-7-1536x709.jpg","1536x1536-width":1536,"1536x1536-height":709,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/Nuovo-progetto-7.jpg","2048x2048-width":1560,"2048x2048-height":720,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/Nuovo-progetto-7.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":138,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/Nuovo-progetto-7.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":185,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/Nuovo-progetto-7.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":277}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"Cr\u00eapes 6","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":9404,"id":9404,"title":"3caf626e4fe61bb66f00f730f5e0b4c4_6488bf61.jpg","filename":"3caf626e4fe61bb66f00f730f5e0b4c4_6488bf61.jpg","filesize":1398883,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/3caf626e4fe61bb66f00f730f5e0b4c4_6488bf61.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/crespi-dadda\/3caf626e4fe61bb66f00f730f5e0b4c4_6488bf61-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"3caf626e4fe61bb66f00f730f5e0b4c4_6488bf61-jpg-2","status":"inherit","uploaded_to":20180,"date":"2024-05-08 08:49:03","modified":"2024-05-08 12:27:02","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1920,"height":1280,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/3caf626e4fe61bb66f00f730f5e0b4c4_6488bf61-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/3caf626e4fe61bb66f00f730f5e0b4c4_6488bf61-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/3caf626e4fe61bb66f00f730f5e0b4c4_6488bf61-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/3caf626e4fe61bb66f00f730f5e0b4c4_6488bf61-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/3caf626e4fe61bb66f00f730f5e0b4c4_6488bf61-1536x1024.jpg","1536x1536-width":1536,"1536x1536-height":1024,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/3caf626e4fe61bb66f00f730f5e0b4c4_6488bf61.jpg","2048x2048-width":1920,"2048x2048-height":1280,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/3caf626e4fe61bb66f00f730f5e0b4c4_6488bf61.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/3caf626e4fe61bb66f00f730f5e0b4c4_6488bf61.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/3caf626e4fe61bb66f00f730f5e0b4c4_6488bf61.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"Cr\u00eapes 4","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"buttons":[{"style":"primary","text":"Kontakt","icon":{"button_icon":"none"},"function":"link","url":"https:\/\/www.visitcrespi.it\/","select_post":null,"target":"_blank","url_youtube":"","target_modal":""}],"filotto_layout":"scroll","url":"https:\/\/www.visitcrespi.it\/","hero_title":"Crespi D'Adda","hero_text":"<p>Kommen Sie und entdecken Sie dieses Unesco-Kulturerbe!<br \/>\nWenn Sie durch Crespi D&#8217;Adda spazieren, f\u00fchlen Sie sich wie in einem echten Arbeiterdorf des sp\u00e4ten 19. Jahrhunderts. <\/p>\n","iu_website":"https:\/\/www.visitcrespi.it\/","filotto_fill":"manual","filotto_items":false,"hero_type":"images","accessibilitycontent":{"tcm_content":[{"acf_fc_layout":"title","title_tag":"h3","title_text":"Das Datenblatt"},{"acf_fc_layout":"text","text":""}]},"gallery":{"gallery_items":false},"poi_data":{"description":"<p><strong>Crespi d&#8217;Adda<\/strong> ist ein Beispiel f\u00fcr <strong>Industriearch\u00e4ologie<\/strong> und wurde im Dezember 1995<strong>von der UNESCO<\/strong> zum Weltkulturerbe erkl\u00e4rt. Es ist ein au\u00dfergew\u00f6hnlich gut erhaltenes <strong>Arbeiterdorf<\/strong> mit einem beispielhaften Stadtgrundriss. Entdecken Sie die Geschichte der Familie Crespi und tauchen Sie ein in das Leben des letzten Jahrhunderts.  <\/p>\n<h3>Die Geschichte von Crespi und die Entstehung des Dorfes<\/h3>\n<p>Die Familie <strong>Crespi<\/strong>, eine Weberfamilie, gr\u00fcndete hier 1878 ihr Unternehmen, da sie wusste, dass in der Gegend viele Arbeitskr\u00e4fte zur Verf\u00fcgung standen und sie die M\u00f6glichkeit sah, einen Industriekanal entlang der <strong>Adda<\/strong> zu bauen, um deren Wasserkraft zu nutzen. So entstand <strong>Cristoforo Crespi<\/strong>, der Gr\u00fcnder. Er baute den sogenannten <em>&#8216;palas\u00f2cc&#8217;<\/em>, aber erst mit der Ankunft seines in England ausgebildeten Sohnes Silvio wurde ein Plan f\u00fcr das gesamte Dorf erstellt. Das Prinzip war, jedem eine kleine Villa mit Garten und Gem\u00fcsegarten zur Verf\u00fcgung zu stellen und die notwendigen Dienstleistungen zu erbringen, von den \u00f6ffentlichen B\u00e4dern bis zur Schule, von der Kirche bis zum Sportplatz, vom Erholungszentrum bis zum kleinen Krankenhaus. Und dann das Theater, der Lebensmittelladen, die Feuerwehr, das Waschhaus, das Musikkorps, das Sommerlager, der Hauswirtschaftskurs. Alles von <strong>Silvio Crespi<\/strong> selbst verwaltet, einem au\u00dfergew\u00f6hnlichen Unternehmer und hartn\u00e4ckigen Politiker. Der Grundriss der Stadt ist einfach: Entlang des Flusses liegt die Fabrik mit ihren hohen Schornsteinen und daneben das Schloss der Besitzer. Die Arbeiterh\u00e4user sind an mehreren parallelen Stra\u00dfen angeordnet, im S\u00fcden befindet sich eine Gruppe von sp\u00e4teren Villen f\u00fcr Angestellte und F\u00fchrungskr\u00e4fte. Am Anfang des Dorfes steht die Kirche und daneben die Schule.<\/p>\n<h3>Ein Eintauchen in die Vergangenheit<\/h3>\n<p>Crespi d&#8217;Adda, ein weltweit einzigartiges Zeugnis eines <strong>Industriedorfs am Ende des 19. Jahrhunderts,<\/strong> besticht durch den au\u00dfergew\u00f6hnlichen Erhaltungszustand seiner Geb\u00e4ude und seines Stadtgrundrisses sowie durch seine Lage am Mittellauf des Flusses Adda &#8211; der Wiege der <strong>italienischen industriellen Revolution<\/strong> -, der reich an historischen und k\u00fcnstlerischen Zeugnissen ist. Am bemerkenswertesten ist jedoch die Tatsache, dass es im Gegensatz zu allen anderen \u00e4hnlichen D\u00f6rfern in Italien und auf der ganzen Welt neben der Unversehrtheit der Geb\u00e4ude auch seine sozialen und produktiven Funktionen beibehalten hat und tats\u00e4chlich eine lebendige Gemeinschaft beherbergt, in der die Fabrik bis 2004 in Betrieb war. Ein Tag in Crespi d&#8217;Adda ist nicht nur ein kultureller Besuch, sondern vor allem ein Eintauchen in das letzte Jahrhundert und eine Gelegenheit, in das Leben und die Br\u00e4uche der Vergangenheit einzutauchen. <\/p>\n","indepth":"","howtogetthere":"","price":"","time":"","latitude":"45.596533","longitude":"9.535786","id_visit_manza":"3047","iu_motor_accessibility":"notsure","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_kids":false,"iu_shortprice":"","iu_addr_streetnumber":"","iu_addr_postalcode":"","iu_addr_city":"Capriate San Gervasio","iu_addr_province":"","iu_phone":"+39 029091712","iu_cell":"","iu_website":"https:\/\/www.visitcrespi.it\/","iu_email":"info@visitcrespi.it","iu_document_label":"","iu_document":false,"iu_timetable":false},"filotto_sub":"","or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"order_by":"","order_way":"","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""},"style":"","text":"","icon":{"button_icon":"none"},"function":"","target":"","target_modal":"","iu_document_label":""},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/20180","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/types\/oggetto"}],"author":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/20180\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media\/9374"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media?parent=20180"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/categories?post=20180"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/tags?post=20180"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/aggr?post=20180"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/area?post=20180"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/kind?post=20180"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/zona?post=20180"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}