{"id":35925,"date":"2025-06-08T14:55:52","date_gmt":"2025-06-08T12:55:52","guid":{"rendered":"https:\/\/visitstg2.visitbergamo.net\/oggetto\/einzel-kanuverleih\/"},"modified":"2025-05-12T19:49:26","modified_gmt":"2025-05-12T17:49:26","slug":"einzel-kanuverleih","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/einzel-kanuverleih\/","title":{"rendered":"Einzel-Kanuverleih"},"excerpt":{"rendered":"<p>Kaufen Sie Ihren innerhalb von 12 Monaten einl\u00f6sbaren Gutschein .<\/p>\n","protected":false},"author":0,"featured_media":183968,"template":"","categories":[524],"tags":[],"aggr":[],"area":[],"kind":[18703],"zona":[],"class_list":["post-35925","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-erlebnisse","kind-esperienza-de"],"acf":{"buttons":[{"style":"primary","text":"Kaufen","icon":{"button_icon":"none"},"function":"content","url":"","select_post":"","target":"_self","url_youtube":"","target_modal":"buyExp"},{"style":"primary","text":"Kontakt","icon":{"button_icon":"none"},"function":"content","url":"","select_post":"","target":"_self","url_youtube":"","target_modal":"modalContact"}],"hero_type":"images","video_youtube_url":"","video_vimeo_url":"","size":"full","hero_title":"Einzel-Kanuverleih","hero_text":"<p>Kaufen Sie Ihren innerhalb von 12 Monaten einl\u00f6sbaren Gutschein .<\/p>\n","slides":[{"image":{"ID":183968,"id":183968,"title":"ec_service_1542_4","filename":"ec_service_1542_4.jpg","filesize":101919,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_1542_4.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/einzel-kanuverleih\/ec_service_1542_4-2-2\/","alt":"","author":"0","description":"","caption":"","name":"ec_service_1542_4-2-2","status":"inherit","uploaded_to":35925,"date":"2025-04-22 17:48:16","modified":"2025-05-12 17:49:28","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":900,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_1542_4-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_1542_4-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_1542_4-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_1542_4-1024x768.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_1542_4.jpg","1536x1536-width":1200,"1536x1536-height":900,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_1542_4.jpg","2048x2048-width":1200,"2048x2048-height":900,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_1542_4.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_1542_4.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_1542_4.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":34748,"id":34748,"title":"ec_service_1542_4_2.jpg","filename":"ec_service_1542_4_2.jpg","filesize":101968,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_1542_4_2.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/einzel-kanuverleih\/ec_service_1542_4_2-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"ec_service_1542_4_2-jpg-2","status":"inherit","uploaded_to":35925,"date":"2024-05-21 11:40:29","modified":"2025-05-12 17:49:28","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":900,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_1542_4_2-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_1542_4_2-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_1542_4_2-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_1542_4_2-1024x768.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_1542_4_2.jpg","1536x1536-width":1200,"1536x1536-height":900,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_1542_4_2.jpg","2048x2048-width":1200,"2048x2048-height":900,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_1542_4_2.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_1542_4_2.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_1542_4_2.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"hero_buttons_group":{"buttons":[{"style":"primary","text":"Kaufen","icon":{"button_icon":"none"},"function":"content","url":"","select_post":"","target":"_self","url_youtube":"","target_modal":"buyExp"},{"style":"primary","text":"Kontakt","icon":{"button_icon":"none"},"function":"content","url":"","select_post":"","target":"_self","url_youtube":"","target_modal":"modalContact"}]},"hero_buttons":false,"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"scroll","filotto_fill":"manual","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"random","order_way":"asc"}},"description":"<p>Sportaction bietet einen Kanuverleih, um die atemberaubende Landschaft des Iseosees zu erleben.<br \/>\nIm Notfall steht ein Rettungsdienst mit Schlauchboot zur Verf\u00fcgung<\/p>\n","indepth":"<p>Sportaction bietet einen Kanuverleih, um die atemberaubende Landschaft des Iseosees zu erleben.<br \/>\nIm Notfall steht ein Rettungsdienst mit Schlauchboot zur Verf\u00fcgung<\/p>\n","howtogetthere":"","timerange":"","seasonality":"","pairings":"","curiosities":"","awards":"","cancellationpolicy":"<p>Das Erlebnis kann an einem anderen Datum nachgeholt werden, wenn die Reservierung 24 Stunden vor der Aktivit\u00e4t storniert wird oder bei schlechtem Wetter<\/p>\n","moredetails":"<p>Reservierungen:<br \/>\nMit einer Reservierung kaufen Sie einen Gutschein, der innerhalb von 12 Monaten eingel\u00f6st werden kann, auch als Geschenk. Sie k\u00f6nnen sich dann f\u00fcr den gew\u00e4hlten Termin an das Sportaction Sekretariat wenden (Kontakt in der Auftragsbest\u00e4tigung, die Sie erhalten).<\/p>\n<p>Achtung:<br \/>\nMinderj\u00e4hrige k\u00f6nnen das SUP nur in Begleitung eines Erwachsenen mieten.<\/p>\n<p>Preisangaben:<br \/>\nDer Preis beinhaltet die Anmietung von 1 Stunde.<\/p>\n<p>Startpunkt:<br \/>\nSSD Sportaction ar.l.<br \/>\nStandort Gr\u00e9 &#8211; Solto Collina<\/p>\n","whatsincluded":"<p>Einzel-Kanuverleih (1 Platz)<\/p>\n","whatsnotincluded":"<p>&#8211; Alles, was nicht in &#8220;Was ist enthalten&#8221; angegeben ist<\/p>\n","price":"","time":"","service_icons":[],"services":"","parking":"","restaurant":"","breakfast":"","internet":"","children":"","pets":"","latitude":"45.79244230","longitude":"10.05588430","startingprice":"12.00","gpxmap":"","iu_kids":false,"iu_shortprice":"","iu_company_name":"","registered_office":"","iu_addr_streetnumber":"Via Gr\u00e8","iu_addr_postalcode":"24060","iu_addr_city":"Solto Collina","iu_addr_province":"Bergamo","iu_phone":"","iu_cell":"","iu_website":"","iu_email":"","iu_vat":"","iu_document_label":"","iu_document":false,"iu_documents":false,"iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"Sportaction, localit\u00e0 Gre , Solto Collina","iu_bookingurl":"https:\/\/back-services.com\/newfront\/services.htm?channelid=652&lang=deu&no_qr=si&styleid=3073&ecomid=1542&serviceid=4","iu_videourl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"1h","iu_languages":"","iu_minpeople":"","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"iu_stars":"","iu_rooms":"","iu_beds":"","id_madeep":"652_1542_4","id_visit_manza":"","id_east":"","id_ristora":"","id_eppen":"","style":"primary","text":"","button_icon":"none","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"validfrom":"01\/01\/2023","validto":"31\/12\/2028","hours":"","ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":"","review":false,"modules":false,"filotto_layout":"scroll","filotto_fill":"manual","filotto_items":false,"iu_motor_accessibility":"no","iu_visual_accessibility":"no","iu_auditory_accessibility":"no","iu_cognitive_accessibility":"no","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"random","order_way":"asc"},"or_filter":false,"max_elements":"","show_total":false,"see_all":false,"order_by":"random","order_way":"asc","featured_video":false,"is_an_ambassador":false,"only_ambassadors":false},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/35925","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/35925\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media\/183968"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media?parent=35925"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/categories?post=35925"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/tags?post=35925"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/aggr?post=35925"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/area?post=35925"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/kind?post=35925"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/zona?post=35925"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}