{"id":35950,"date":"2025-06-08T14:56:54","date_gmt":"2025-06-08T12:56:54","guid":{"rendered":"https:\/\/visitstg2.visitbergamo.net\/oggetto\/micheles-kitchen\/"},"modified":"2025-05-12T19:51:10","modified_gmt":"2025-05-12T17:51:10","slug":"micheles-kitchen","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/micheles-kitchen\/","title":{"rendered":"Michele&#8217;s Kitchen"},"excerpt":{"rendered":"<p>Kochkurs und Abendessen in einem Haus einer Familie aus Bergamo .<\/p>\n","protected":false},"author":0,"featured_media":184136,"template":"","categories":[524,521],"tags":[],"aggr":[],"area":[],"kind":[18703],"zona":[],"class_list":["post-35950","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-erlebnisse","category-esperienze","kind-esperienza-de"],"acf":{"buttons":[{"style":"primary","text":"Kaufen","icon":{"button_icon":"none"},"function":"content","url":"","select_post":"","target":"_self","url_youtube":"","target_modal":"buyExp"},{"style":"primary","text":"Kontakt","icon":{"button_icon":"none"},"function":"content","url":"","select_post":"","target":"_self","url_youtube":"","target_modal":"modalContact"}],"hero_type":"images","video_youtube_url":"","video_vimeo_url":"","size":"full","hero_title":"Michele's Kitchen","hero_text":"<p>Kochkurs und Abendessen in einem Haus einer Familie aus Bergamo .<\/p>\n","slides":[{"image":{"ID":184136,"id":184136,"title":"ec_service_2982_1","filename":"ec_service_2982_1.jpg","filesize":125141,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_2982_1.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/micheles-kitchen\/ec_service_2982_1-2-2\/","alt":"","author":"0","description":"","caption":"","name":"ec_service_2982_1-2-2","status":"inherit","uploaded_to":35950,"date":"2025-04-22 17:48:58","modified":"2025-05-12 17:51:12","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":647,"height":1151,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_2982_1-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_2982_1-169x300.jpg","medium-width":169,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_2982_1.jpg","medium_large-width":647,"medium_large-height":1151,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_2982_1-576x1024.jpg","large-width":576,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_2982_1.jpg","1536x1536-width":647,"1536x1536-height":1151,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_2982_1.jpg","2048x2048-width":647,"2048x2048-height":1151,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_2982_1.jpg","gform-image-choice-sm-width":169,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_2982_1.jpg","gform-image-choice-md-width":225,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_2982_1.jpg","gform-image-choice-lg-width":337,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":34946,"id":34946,"title":"ec_service_2982_1_2.jpg","filename":"ec_service_2982_1_2.jpg","filesize":217639,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_2982_1_2.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/micheles-kitchen\/ec_service_2982_1_2-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"ec_service_2982_1_2-jpg-2","status":"inherit","uploaded_to":35950,"date":"2024-05-21 11:41:43","modified":"2025-05-12 17:51:12","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":828,"height":1056,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_2982_1_2-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_2982_1_2-235x300.jpg","medium-width":235,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_2982_1_2-768x979.jpg","medium_large-width":768,"medium_large-height":979,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_2982_1_2-803x1024.jpg","large-width":803,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_2982_1_2.jpg","1536x1536-width":828,"1536x1536-height":1056,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_2982_1_2.jpg","2048x2048-width":828,"2048x2048-height":1056,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_2982_1_2.jpg","gform-image-choice-sm-width":235,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_2982_1_2.jpg","gform-image-choice-md-width":314,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_2982_1_2.jpg","gform-image-choice-lg-width":470,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":34952,"id":34952,"title":"Screenshot","filename":"ec_service_2982_1_3.jpg","filesize":126694,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_2982_1_3.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/micheles-kitchen\/screenshot-2\/","alt":"","author":"0","description":"Screenshot","caption":"","name":"screenshot-2","status":"inherit","uploaded_to":35950,"date":"2024-05-21 11:41:44","modified":"2025-05-12 17:51:12","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":741,"height":888,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_2982_1_3-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_2982_1_3-250x300.jpg","medium-width":250,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_2982_1_3.jpg","medium_large-width":741,"medium_large-height":888,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_2982_1_3.jpg","large-width":741,"large-height":888,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_2982_1_3.jpg","1536x1536-width":741,"1536x1536-height":888,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_2982_1_3.jpg","2048x2048-width":741,"2048x2048-height":888,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_2982_1_3.jpg","gform-image-choice-sm-width":250,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_2982_1_3.jpg","gform-image-choice-md-width":334,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_2982_1_3.jpg","gform-image-choice-lg-width":501,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":34958,"id":34958,"title":"ec_service_2982_1_4.jpg","filename":"ec_service_2982_1_4.jpg","filesize":776350,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_2982_1_4.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/micheles-kitchen\/ec_service_2982_1_4-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"ec_service_2982_1_4-jpg-2","status":"inherit","uploaded_to":35950,"date":"2024-05-21 11:41:44","modified":"2025-05-12 17:51:12","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":828,"height":971,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_2982_1_4-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_2982_1_4-256x300.jpg","medium-width":256,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_2982_1_4-768x901.jpg","medium_large-width":768,"medium_large-height":901,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_2982_1_4.jpg","large-width":828,"large-height":971,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_2982_1_4.jpg","1536x1536-width":828,"1536x1536-height":971,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_2982_1_4.jpg","2048x2048-width":828,"2048x2048-height":971,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_2982_1_4.jpg","gform-image-choice-sm-width":256,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_2982_1_4.jpg","gform-image-choice-md-width":341,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_2982_1_4.jpg","gform-image-choice-lg-width":512,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":34964,"id":34964,"title":"ec_service_2982_1_5.jpg","filename":"ec_service_2982_1_5.jpg","filesize":94536,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_2982_1_5.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/micheles-kitchen\/ec_service_2982_1_5-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"ec_service_2982_1_5-jpg-2","status":"inherit","uploaded_to":35950,"date":"2024-05-21 11:41:45","modified":"2025-05-12 17:51:12","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":809,"height":1200,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_2982_1_5-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_2982_1_5-202x300.jpg","medium-width":202,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_2982_1_5-768x1139.jpg","medium_large-width":768,"medium_large-height":1139,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_2982_1_5-690x1024.jpg","large-width":690,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_2982_1_5.jpg","1536x1536-width":809,"1536x1536-height":1200,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_2982_1_5.jpg","2048x2048-width":809,"2048x2048-height":1200,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_2982_1_5.jpg","gform-image-choice-sm-width":202,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_2982_1_5.jpg","gform-image-choice-md-width":270,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_2982_1_5.jpg","gform-image-choice-lg-width":405,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":34970,"id":34970,"title":"ec_service_2982_1_6.jpg","filename":"ec_service_2982_1_6.jpg","filesize":175448,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_2982_1_6.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/micheles-kitchen\/ec_service_2982_1_6-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"ec_service_2982_1_6-jpg-2","status":"inherit","uploaded_to":35950,"date":"2024-05-21 11:41:45","modified":"2025-05-12 17:51:12","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":1600,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_2982_1_6-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_2982_1_6-225x300.jpg","medium-width":225,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_2982_1_6-768x1024.jpg","medium_large-width":768,"medium_large-height":1024,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_2982_1_6-768x1024.jpg","large-width":768,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_2982_1_6-1152x1536.jpg","1536x1536-width":1152,"1536x1536-height":1536,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_2982_1_6.jpg","2048x2048-width":1200,"2048x2048-height":1600,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_2982_1_6.jpg","gform-image-choice-sm-width":225,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_2982_1_6.jpg","gform-image-choice-md-width":300,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_2982_1_6.jpg","gform-image-choice-lg-width":450,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":34976,"id":34976,"title":"ec_service_2982_1_7.jpg","filename":"ec_service_2982_1_7.jpg","filesize":863150,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_2982_1_7.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/micheles-kitchen\/ec_service_2982_1_7-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"ec_service_2982_1_7-jpg-2","status":"inherit","uploaded_to":35950,"date":"2024-05-21 11:41:46","modified":"2025-05-12 17:51:12","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":828,"height":826,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_2982_1_7-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_2982_1_7-300x300.jpg","medium-width":300,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_2982_1_7-768x766.jpg","medium_large-width":768,"medium_large-height":766,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_2982_1_7.jpg","large-width":828,"large-height":826,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_2982_1_7.jpg","1536x1536-width":828,"1536x1536-height":826,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_2982_1_7.jpg","2048x2048-width":828,"2048x2048-height":826,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_2982_1_7.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_2982_1_7.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_2982_1_7.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":34982,"id":34982,"title":"ec_service_2982_1_8.jpg","filename":"ec_service_2982_1_8.jpg","filesize":447613,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_2982_1_8.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/micheles-kitchen\/ec_service_2982_1_8-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"ec_service_2982_1_8-jpg-2","status":"inherit","uploaded_to":35950,"date":"2024-05-21 11:41:47","modified":"2025-05-12 17:51:12","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":638,"height":1126,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_2982_1_8-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_2982_1_8-170x300.jpg","medium-width":170,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_2982_1_8.jpg","medium_large-width":638,"medium_large-height":1126,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_2982_1_8-580x1024.jpg","large-width":580,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_2982_1_8.jpg","1536x1536-width":638,"1536x1536-height":1126,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_2982_1_8.jpg","2048x2048-width":638,"2048x2048-height":1126,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_2982_1_8.jpg","gform-image-choice-sm-width":170,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_2982_1_8.jpg","gform-image-choice-md-width":227,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_2982_1_8.jpg","gform-image-choice-lg-width":340,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"hero_buttons_group":{"buttons":[{"style":"primary","text":"Kaufen","icon":{"button_icon":"none"},"function":"content","url":"","select_post":"","target":"_self","url_youtube":"","target_modal":"buyExp"},{"style":"primary","text":"Kontakt","icon":{"button_icon":"none"},"function":"content","url":"","select_post":"","target":"_self","url_youtube":"","target_modal":"modalContact"}]},"hero_buttons":false,"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"scroll","filotto_fill":"manual","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"random","order_way":"asc"}},"description":"<p>WAS SIE TUN WERDEN<br \/>\n-Sie werden einen lustigen Nachmittag verbringen und lernen, wie man ein typisch italienisches Gericht zubereitet<br \/>\n-Sie werden ein italienisches Men\u00fc probieren, einschlie\u00dflich des von Ihnen zubereiteten Gerichts<br \/>\n-Wenn Sie nach Hause zur\u00fcckkehren, k\u00f6nnen Sie die Erfahrung noch einmal erleben, indem Sie das dank Micheles Lehren gelernte Gericht wiederholen<\/p>\n<p>WAS SIE ERWARTET<br \/>\nMichele hei\u00dft Sie in seinem Haus in Bergamo willkommen.<br \/>\nEr erwartet Sie mit einem Begr\u00fc\u00dfungscocktail und bespricht dann das Men\u00fc, das Sie zubereiten werden.<br \/>\nSie k\u00f6nnen w\u00e4hlen, ob Sie einen sch\u00f6nen Teller mit frischer Pasta zubereiten m\u00f6chten: Tagliatelle, Casoncelli, Lasagne mit verschiedenen Saucen (Bolognese, Pesto, Fisch) oder warum nicht? Vielleicht die typischen Casoncelli nach bergamaskischer Art: Ravioli gef\u00fcllt mit Fleisch, gew\u00fcrzt mit Butter, Salbei und Speck.<br \/>\nWenn Sie keine Pasta m\u00f6gen, k\u00f6nnen Sie sich entscheiden, einen zweiten Gang mit Fleisch oder Fisch oder die zeitlose italienische Pizza zuzubereiten! <\/p>\n<p>Das beinhaltet Ihr Abendmen\u00fc:<br \/>\n&#8211; Aperitif (Prosecco und Snacks)<br \/>\n&#8211; Vorspeisen (lokale Salami und K\u00e4se, Gem\u00fcse)<br \/>\n&#8211; das von Ihnen zubereitete Gericht (1 Gericht Ihrer Wahl zwischen Pasta, Pizza, Fleisch, Fisch, etc.)<br \/>\n&#8211; Wein<br \/>\n&#8211; Desserts (1 Wahl zwischen sizilianischen Cannoli, Tiramisu, Panna Cotta, Bab\u00e0, Strudel, Profitteroles)<br \/>\n&#8211; Kaffee und Lik\u00f6re<\/p>\n<p>Nach 2-3 Stunden Arbeit k\u00f6nnen Sie sich endlich hinsetzen, um Ihre k\u00f6stlichen Zubereitungen zusammen mit einem ausgezeichneten italienischen Wein zu probieren.<br \/>\nW\u00e4hrend des Abendessens erz\u00e4hlt Michele Ihnen die Herkunft und Geschichte der von Ihnen ausgew\u00e4hlten Gerichte und erkl\u00e4rt Ihnen die Weinauswahl.<\/p>\n<p>Das Abendessen endet mit einem k\u00f6stlichen typisch italienischen Lik\u00f6r (Limoncello, Grappa, Lakritzlik\u00f6r oder ein Amaro) und einem unvermeidlichen guten Espresso.<\/p>\n<p>Der Kochkurs von Michele&#8217;s Kitchen ist sehr praktisch: Michele zeigt Ihnen die verschiedenen Schritte der Zubereitung der Gerichte und Sie k\u00f6nnen seinen Anweisungen von Ihrem Arbeitsplatz aus folgen.<br \/>\nEin Nachmittag mit gutem Essen und Spa\u00df erwartet Sie! Und wenn Sie wieder zu Hause sind, k\u00f6nnen Sie dank der Lehren, die Michele Ihnen hinterlassen hat, Abendessen oder Mittagessen made in Italy organisieren. Sie werden einen tollen Eindruck hinterlassen!<\/p>\n","indepth":"","howtogetthere":"","timerange":"<p>Das ganze Jahr<\/p>\n","seasonality":"","pairings":"","curiosities":"","awards":"","cancellationpolicy":"<p>Bei Nichterscheinen werden 100% des Betrages einbehalten.<\/p>\n<p>Eine Stornierung ist kostenlos, wenn sie innerhalb von 72 Stunden vor dem Service erfolgt.<br \/>\nWenn die Stornierung innerhalb der letzten 48 Stunden erfolgt, wird die Leistung zu 50% zur\u00fcckerstattet.<br \/>\nErfolgt die Stornierung nicht innerhalb von 48 Stunden vor dem Service, wird Ihnen der volle Betrag in Rechnung gestellt.<\/p>\n","moredetails":"<p>Das Erlebnis findet in der Via Rillosi, 7 in Bergamo, c\/o dem Hausdes Erlebnisanbieters Michele Ripepi statt.<\/p>\n<p>Das Erlebnis findet am Nachmittag ab 16.30 Uhr statt und dauert ca. 4 Stunden.<\/p>\n<p>Auf Anfrage und mit separatem Angebot ist es m\u00f6glich, Besuche von lokalen M\u00e4rkten oder Gesch\u00e4ften in Bergamo zu organisieren, wo Sie die Zutaten f\u00fcr den Kochkurs kaufen k\u00f6nnen.<\/p>\n<p>F\u00fcr Gruppen von mehr als 6 Personen wenden Sie sich direkt an den Anbieter.<\/p>\n","whatsincluded":"<p>&#8211; Kochkurs<br \/>\n-Verkostung typischer lokaler Produkte und zubereiteter Gerichte am Tisch.<\/p>\n","whatsnotincluded":"<p>-Transport, um den Ort zu erreichen, an dem die Erfahrung stattfindet<\/p>\n","price":"","time":"","service_icons":[],"services":"","parking":"","restaurant":"","breakfast":"","internet":"","children":"","pets":"","latitude":"45.69273420","longitude":"9.65030060","startingprice":"100.00","gpxmap":"","iu_kids":false,"iu_shortprice":"","iu_company_name":"","registered_office":"","iu_addr_streetnumber":"Via Giuseppe Rillosi, 7","iu_addr_postalcode":"24128","iu_addr_city":"Bergamo","iu_addr_province":"Bergamo","iu_phone":"","iu_cell":"","iu_website":"","iu_email":"","iu_vat":"","iu_document_label":"","iu_document":false,"iu_documents":false,"iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"Michele Ripepi, Via Giuseppe Rillosi, 7, Bergamo","iu_bookingurl":"https:\/\/back-services.com\/newfront\/services.htm?channelid=652&lang=deu&no_qr=si&styleid=3073&ecomid=2982&serviceid=1","iu_videourl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"4h","iu_languages":"Franz\u00f6sisch - Englisch - Italienisch","iu_minpeople":"Mindestens 2 Personen","iu_maxpeople":"Maximal 5 Personen","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"iu_stars":"","iu_rooms":"","iu_beds":"","id_madeep":"652_2982_1","id_visit_manza":"","id_east":"","id_ristora":"","id_eppen":"","style":"primary","text":"","button_icon":"none","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"validfrom":"03\/09\/2021","validto":"31\/12\/2025","hours":"","ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":"","review":false,"modules":false,"filotto_layout":"scroll","filotto_fill":"manual","filotto_items":false,"iu_motor_accessibility":"no","iu_visual_accessibility":"no","iu_auditory_accessibility":"no","iu_cognitive_accessibility":"no","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"random","order_way":"asc"},"or_filter":false,"max_elements":"","show_total":false,"see_all":false,"order_by":"random","order_way":"asc","only_ambassadors":false},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/35950","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/35950\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media\/184136"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media?parent=35950"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/categories?post=35950"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/tags?post=35950"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/aggr?post=35950"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/area?post=35950"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/kind?post=35950"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/zona?post=35950"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}