{"id":35954,"date":"2025-06-08T14:57:04","date_gmt":"2025-06-08T12:57:04","guid":{"rendered":"https:\/\/visitstg2.visitbergamo.net\/oggetto\/ebike-tour-in-presolana-dem-dolomitenberg-in-der-region-bergamo\/"},"modified":"2025-05-12T19:51:28","modified_gmt":"2025-05-12T17:51:28","slug":"ebike-tour-in-presolana-dem-dolomitenberg-in-der-region-bergamo","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/ebike-tour-in-presolana-dem-dolomitenberg-in-der-region-bergamo\/","title":{"rendered":"Ebike-Tour in Presolana, dem Dolomitenberg in der Region Bergamo."},"excerpt":{"rendered":"<p>E-Bike-Verleih und Begleitung mit MTB-F\u00fchrer inbegriffen.<br \/>\nKaufen Sie Ihren Gutschein, der innerhalb von 12 Monaten eingel\u00f6st werden kann.<\/p>\n","protected":false},"author":0,"featured_media":1040,"template":"","categories":[524],"tags":[17226,17262],"aggr":[],"area":[],"kind":[18703],"zona":[],"class_list":["post-35954","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-erlebnisse","tag-im-freien-de","tag-rad-tourismus-de","kind-esperienza-de"],"acf":{"buttons":[{"style":"primary","text":"Kaufen","icon":{"button_icon":"none"},"function":"content","url":"","select_post":"","target":"_self","url_youtube":"","target_modal":"buyExp"},{"style":"primary","text":"Kontakt","icon":{"button_icon":"none"},"function":"content","url":"","select_post":"","target":"_self","url_youtube":"","target_modal":"modalContact"}],"hero_type":"images","video_youtube_url":"","video_vimeo_url":"","size":"full","hero_title":"Ebike-Tour in Presolana, dem Dolomitenberg in der Region Bergamo.","hero_text":"<p>E-Bike-Verleih und Begleitung mit MTB-F\u00fchrer inbegriffen.<br \/>\nKaufen Sie Ihren Gutschein, der innerhalb von 12 Monaten eingel\u00f6st werden kann.<\/p>\n","slides":[{"image":{"ID":1040,"id":1040,"title":"ec_service_3182_7","filename":"ec_service_3182_7.jpg","filesize":31684,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/04\/ec_service_3182_7.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/ebike-tour-in-presolana-dem-dolomitenberg-in-der-region-bergamo\/ec_service_3182_7-2\/","alt":"","author":"4","description":"","caption":"","name":"ec_service_3182_7-2","status":"inherit","uploaded_to":35954,"date":"2024-04-16 09:26:06","modified":"2025-05-12 17:51:29","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":428,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/04\/ec_service_3182_7-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/04\/ec_service_3182_7-300x107.jpg","medium-width":300,"medium-height":107,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/04\/ec_service_3182_7-768x274.jpg","medium_large-width":768,"medium_large-height":274,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/04\/ec_service_3182_7-1024x365.jpg","large-width":1024,"large-height":365,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/04\/ec_service_3182_7.jpg","1536x1536-width":1200,"1536x1536-height":428,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/04\/ec_service_3182_7.jpg","2048x2048-width":1200,"2048x2048-height":428,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/04\/ec_service_3182_7.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":107,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/04\/ec_service_3182_7.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":143,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/04\/ec_service_3182_7.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":214}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":35042,"id":35042,"title":"ec_service_3182_7_2.jpg","filename":"ec_service_3182_7_2.jpg","filesize":104431,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_3182_7_2.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/ebike-tour-in-presolana-dem-dolomitenberg-in-der-region-bergamo\/ec_service_3182_7_2-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"ec_service_3182_7_2-jpg-2","status":"inherit","uploaded_to":35954,"date":"2024-05-21 11:41:56","modified":"2025-05-12 17:51:29","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":573,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_3182_7_2-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_3182_7_2-300x143.jpg","medium-width":300,"medium-height":143,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_3182_7_2-768x367.jpg","medium_large-width":768,"medium_large-height":367,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_3182_7_2-1024x489.jpg","large-width":1024,"large-height":489,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_3182_7_2.jpg","1536x1536-width":1200,"1536x1536-height":573,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_3182_7_2.jpg","2048x2048-width":1200,"2048x2048-height":573,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_3182_7_2.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":143,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_3182_7_2.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":191,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_3182_7_2.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":287}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":35048,"id":35048,"title":"ec_service_3182_7_3.jpg","filename":"ec_service_3182_7_3.jpg","filesize":82740,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_3182_7_3.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/ebike-tour-in-presolana-dem-dolomitenberg-in-der-region-bergamo\/ec_service_3182_7_3-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"ec_service_3182_7_3-jpg-2","status":"inherit","uploaded_to":35954,"date":"2024-05-21 11:41:57","modified":"2025-05-12 17:51:29","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":388,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_3182_7_3-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_3182_7_3-300x97.jpg","medium-width":300,"medium-height":97,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_3182_7_3-768x248.jpg","medium_large-width":768,"medium_large-height":248,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_3182_7_3-1024x331.jpg","large-width":1024,"large-height":331,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_3182_7_3.jpg","1536x1536-width":1200,"1536x1536-height":388,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_3182_7_3.jpg","2048x2048-width":1200,"2048x2048-height":388,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_3182_7_3.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":97,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_3182_7_3.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":129,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_3182_7_3.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":194}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":35054,"id":35054,"title":"ec_service_3182_7_4.jpg","filename":"ec_service_3182_7_4.jpg","filesize":69802,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_3182_7_4.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/ebike-tour-in-presolana-dem-dolomitenberg-in-der-region-bergamo\/ec_service_3182_7_4-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"ec_service_3182_7_4-jpg-2","status":"inherit","uploaded_to":35954,"date":"2024-05-21 11:41:57","modified":"2025-05-12 17:51:29","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":457,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_3182_7_4-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_3182_7_4-300x114.jpg","medium-width":300,"medium-height":114,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_3182_7_4-768x292.jpg","medium_large-width":768,"medium_large-height":292,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_3182_7_4-1024x390.jpg","large-width":1024,"large-height":390,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_3182_7_4.jpg","1536x1536-width":1200,"1536x1536-height":457,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_3182_7_4.jpg","2048x2048-width":1200,"2048x2048-height":457,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_3182_7_4.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":114,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_3182_7_4.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":152,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_3182_7_4.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":229}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"hero_buttons_group":{"buttons":[{"style":"primary","text":"Kaufen","icon":{"button_icon":"none"},"function":"content","url":"","select_post":"","target":"_self","url_youtube":"","target_modal":"buyExp"},{"style":"primary","text":"Kontakt","icon":{"button_icon":"none"},"function":"content","url":"","select_post":"","target":"_self","url_youtube":"","target_modal":"modalContact"}]},"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"scroll","filotto_fill":"manual","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"random","order_way":"asc"}},"description":"<p>&#8211; Zusammen mit einem MTB-F\u00fchrer fahren Sie in einem einzigartigen naturalistischen Kontext<br \/>\n&#8211; Von Presolana bis zum Monte Pora durchqueren Sie W\u00e4lder und Pfade mit atemberaubenden Ausblicken<\/p>\n<p>WAS SIE ERWARTET<br \/>\nTreffpunkt am Presolana-Pass, vor dem Gesch\u00e4ft &#8220;Verzeroli Sport&#8221;, Sie werden Ihren MTB-F\u00fchrer, der Sie nach der Lieferung Ihres E-Bikes zu einem aufregenden Bergausflug im Zeichen der Natur und des Spa\u00dfes mitnimmt, treffen.<\/p>\n<p>Vom Presolana-Pass steigt man in Richtung Colle Vareno auf und erreicht dann den Monte Pora und den Monte Alto.<br \/>\nEs erwarten Sie wirklich einzigartige Szenarien: Presolana tr\u00e4gt den Spitznamen &#8220;K\u00f6nigin der Orobie&#8221;: der einzige Berg der Dolomiten im Bergamo-Gebiet. Vom Monte Pora hat man neben einem herrlichen Blick auf die Presolana auch einen herrlichen Blick auf den Iseosee.<br \/>\nUnterwegs treffen Sie auf zahlreiche Schutzh\u00fctten, falls Sie eine Pause einlegen m\u00f6chten, haben Sie die Qual der Wahl!<\/p>\n","indepth":"","howtogetthere":"","timerange":"<p>Das ganze Jahr<\/p>\n","seasonality":"","pairings":"","curiosities":"","awards":"","cancellationpolicy":"<p>Kostenlose Stornierung bis 2 Tage vor der Tour.<br \/>\nNach Ablauf dieser Frist erfolgt keine R\u00fcckerstattung des gezahlten Betrags.<br \/>\nKeine R\u00fcckerstattung bei Nichterscheinen.<\/p>\n","moredetails":"<p>Reservierungen:<br \/>\nMit einer Reservierung kaufen Sie einen Gutschein, der innerhalb von 12 Monaten eingel\u00f6st werden kann, auch als Geschenk. Sie k\u00f6nnen dann E-bike Italy f\u00fcr das gew\u00e4hlte Datum kontaktieren, um den Treffpunkt zu vereinbaren und Einzelheiten zum Fahrradverleih (Gr\u00f6\u00dfe und Typ des E-Bikes) zu erfahren. Die Kontaktdaten von E-Bike Italy finden Sie in der Auftragsbest\u00e4tigung, die Sie unmittelbar nach dem Kauf erhalten.<\/p>\n<p>Treffpunkt:<br \/>\nVia Cantoniera, 74 Castione della Presolana (BG), vor dem Gesch\u00e4ft &#8220;Verzeroli Sport&#8221;.<\/p>\n<p>Gesamtkilometer der Tour: ca. 30<br \/>\nDauer der Tour: ca. 4 Stunden<\/p>\n<p>Bequeme und sportliche Kleidung mit geschlossenen Schuhen (Turn- oder Trekkingschuhe) wird empfohlen und es empfiehlt sich, einen Rucksack mit Trinkflasche mitzubringen.<\/p>\n","whatsincluded":"<p>&#8211; Begleitung durch gepr\u00fcften MTB-F\u00fchrer<br \/>\n&#8211; E-Bike-Verleih inklusive Helm<br \/>\n&#8211; Haftplichtversicherung<\/p>\n","whatsnotincluded":"<p>-Anreise zum Startpunkt der Tour und R\u00fcckfahrt nach Hause<br \/>\n&#8211; Mahlzeiten<br \/>\n-Alles, was nicht ausdr\u00fccklich unter &#8220;Was enthalten ist&#8221; angegeben ist<\/p>\n","price":"","time":"","service_icons":[],"services":"","parking":"","restaurant":"","breakfast":"","internet":"","children":"","pets":"","latitude":"45.92970900","longitude":"10.09320800","startingprice":"75.00","gpxmap":"","iu_kids":false,"iu_shortprice":"","iu_company_name":"","registered_office":"","iu_addr_streetnumber":"Via Cantoniera, 74","iu_addr_postalcode":"24020","iu_addr_city":"Cantoniera della Presolana","iu_addr_province":"Bergamo","iu_phone":"","iu_cell":"","iu_website":"","iu_email":"","iu_vat":"","iu_document_label":"","iu_document":false,"iu_documents":false,"iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"E-Bike Italy, Via San Alessandro, 14A, Albino","iu_bookingurl":"https:\/\/back-services.com\/newfront\/services.htm?channelid=652&lang=deu&no_qr=si&styleid=3073&ecomid=3182&serviceid=7","iu_videourl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"4h","iu_languages":"Italienisch - Englisch","iu_minpeople":"Mindestens 1 Person","iu_maxpeople":"Maximal 10 Personen","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"iu_stars":"","iu_rooms":"","iu_beds":"","id_madeep":"652_3182_7","id_visit_manza":"","id_east":"","id_ristora":"","id_eppen":"","style":"primary","text":"","button_icon":"none","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"validfrom":"24\/04\/2021","hours":"","ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":"","modules":false,"filotto_layout":"scroll","filotto_fill":"manual","filotto_items":false,"iu_motor_accessibility":"no","iu_visual_accessibility":"no","iu_auditory_accessibility":"no","iu_cognitive_accessibility":"no","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"random","order_way":"asc"},"or_filter":false,"max_elements":"","show_total":false,"see_all":false,"order_by":"random","order_way":"asc","featured_video":false,"only_ambassadors":false,"hero_buttons":false,"experience_data":{"description":"<p>&#8211; Zusammen mit einem MTB-F\u00fchrer fahren Sie in einem einzigartigen naturalistischen Kontext<br \/>\n&#8211; Von Presolana bis zum Monte Pora durchqueren Sie W\u00e4lder und Pfade mit atemberaubenden Ausblicken<\/p>\n<p>WAS SIE ERWARTET<br \/>\nTreffpunkt am Presolana-Pass, vor dem Gesch\u00e4ft &#8220;Verzeroli Sport&#8221;, Sie werden Ihren MTB-F\u00fchrer, der Sie nach der Lieferung Ihres E-Bikes zu einem aufregenden Bergausflug im Zeichen der Natur und des Spa\u00dfes mitnimmt, treffen.<\/p>\n<p>Vom Presolana-Pass steigt man in Richtung Colle Vareno auf und erreicht dann den Monte Pora und den Monte Alto.<br \/>\nEs erwarten Sie wirklich einzigartige Szenarien: Presolana tr\u00e4gt den Spitznamen &#8220;K\u00f6nigin der Orobie&#8221;: der einzige Berg der Dolomiten im Bergamo-Gebiet. Vom Monte Pora hat man neben einem herrlichen Blick auf die Presolana auch einen herrlichen Blick auf den Iseosee.<br \/>\nUnterwegs treffen Sie auf zahlreiche Schutzh\u00fctten, falls Sie eine Pause einlegen m\u00f6chten, haben Sie die Qual der Wahl!<\/p>\n","indepth":"","latitude":"45.92970900","longitude":"10.09320800","iu_motor_accessibility":"no","iu_visual_accessibility":"no","iu_auditory_accessibility":"no","iu_cognitive_accessibility":"no","iu_addr_streetnumber":"Via Cantoniera, 74","iu_addr_postalcode":"24020","iu_addr_city":"Cantoniera della Presolana","iu_addr_province":"Bergamo","timerange":"<p>Das ganze Jahr<\/p>\n","cancellationpolicy":"<p>Kostenlose Stornierung bis 2 Tage vor der Tour.<br \/>\nNach Ablauf dieser Frist erfolgt keine R\u00fcckerstattung des gezahlten Betrags.<br \/>\nKeine R\u00fcckerstattung bei Nichterscheinen.<\/p>\n","moredetails":"<p>Reservierungen:<br \/>\nMit einer Reservierung kaufen Sie einen Gutschein, der innerhalb von 12 Monaten eingel\u00f6st werden kann, auch als Geschenk. Sie k\u00f6nnen dann E-bike Italy f\u00fcr das gew\u00e4hlte Datum kontaktieren, um den Treffpunkt zu vereinbaren und Einzelheiten zum Fahrradverleih (Gr\u00f6\u00dfe und Typ des E-Bikes) zu erfahren. Die Kontaktdaten von E-Bike Italy finden Sie in der Auftragsbest\u00e4tigung, die Sie unmittelbar nach dem Kauf erhalten.<\/p>\n<p>Treffpunkt:<br \/>\nVia Cantoniera, 74 Castione della Presolana (BG), vor dem Gesch\u00e4ft &#8220;Verzeroli Sport&#8221;.<\/p>\n<p>Gesamtkilometer der Tour: ca. 30<br \/>\nDauer der Tour: ca. 4 Stunden<\/p>\n<p>Bequeme und sportliche Kleidung mit geschlossenen Schuhen (Turn- oder Trekkingschuhe) wird empfohlen und es empfiehlt sich, einen Rucksack mit Trinkflasche mitzubringen.<\/p>\n","whatsincluded":"<p>&#8211; Begleitung durch gepr\u00fcften MTB-F\u00fchrer<br \/>\n&#8211; E-Bike-Verleih inklusive Helm<br \/>\n&#8211; Haftplichtversicherung<\/p>\n","whatsnotincluded":"<p>-Anreise zum Startpunkt der Tour und R\u00fcckfahrt nach Hause<br \/>\n&#8211; Mahlzeiten<br \/>\n-Alles, was nicht ausdr\u00fccklich unter &#8220;Was enthalten ist&#8221; angegeben ist<\/p>\n","startingprice":"75.00","id_madeep":"652_3182_7","iu_minpeople":"Mindestens 1 Person","iu_maxpeople":"Maximal 10 Personen","iu_languages":"Italienisch - Englisch","iu_duration":"4h","iu_difficulty":"","iu_bookingurl":"https:\/\/back-services.com\/newfront\/services.htm?channelid=652&lang=deu&no_qr=si&styleid=3073&ecomid=3182&serviceid=7","iu_manager":"E-Bike Italy, Via San Alessandro, 14A, Albino","review":false,"validfrom":"24\/04\/2021","validto":"31\/12\/2025"},"is_an_ambassador":false,"validto":"31\/12\/2025"},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/35954","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/35954\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media\/1040"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media?parent=35954"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/categories?post=35954"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/tags?post=35954"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/aggr?post=35954"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/area?post=35954"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/kind?post=35954"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/zona?post=35954"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}