{"id":73984,"date":"2025-05-12T11:13:45","date_gmt":"2025-05-12T09:13:45","guid":{"rendered":"https:\/\/visitstg2.visitbergamo.net\/oggetto\/al-sorriso\/"},"modified":"2025-05-12T20:15:06","modified_gmt":"2025-05-12T18:15:06","slug":"al-sorriso","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/al-sorriso\/","title":{"rendered":"Al Sorriso"},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":80993,"template":"","categories":[854],"tags":[],"aggr":[],"area":[877],"kind":[18720],"zona":[],"class_list":["post-73984","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-essen","area-curno","kind-ristorante-de"],"acf":{"buttons":false,"hero_type":"images","video_youtube_url":"","video_vimeo_url":"","size":"full","hero_title":"Al Sorriso","hero_text":"","slides":[{"image":{"ID":80993,"id":80993,"title":"ecom_2691_general","filename":"ecom_2691_general.jpeg","filesize":122257,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/10\/ecom_2691_general.jpeg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/al-sorriso\/ecom_2691_general-2\/","alt":"","author":"3","description":"","caption":"","name":"ecom_2691_general-2","status":"inherit","uploaded_to":73984,"date":"2024-10-02 09:22:48","modified":"2025-05-12 18:15:07","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1024,"height":768,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/10\/ecom_2691_general-150x150.jpeg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/10\/ecom_2691_general-300x225.jpeg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/10\/ecom_2691_general-768x576.jpeg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/10\/ecom_2691_general.jpeg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/10\/ecom_2691_general.jpeg","1536x1536-width":1024,"1536x1536-height":768,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/10\/ecom_2691_general.jpeg","2048x2048-width":1024,"2048x2048-height":768,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/10\/ecom_2691_general.jpeg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/10\/ecom_2691_general.jpeg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/10\/ecom_2691_general.jpeg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"Al Sorriso","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"hero_buttons_group":{"buttons":false},"hero_buttons":false,"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":false,"filotto_fill":false,"filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":0,"show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":false,"order_way":false}},"description":"<p>Seit \u00fcber 30 Jahren bietet das Restaurant-Pizzeria Al Sorriso ein einzigartiges kulinarisches Erlebnis, eine Reise durch typisch mediterrane Aromen mit bedeutenden Einfl\u00fcssen aus Bergamo, die gekonnt mit stets frischen und hochwertigen Zutaten kombiniert werden. Jedes Gericht wird zu einem angenehmen Moment, den man sich merken wird.&#13;<br \/>\nVon den Vorspeisen bis zum Dessert, einschlie\u00dflich der Weine aus dem Keller, der Pizzen und der Crocchiarelle (knusprige Stangen): Al Sorriso bietet eine gro\u00dfe Auswahl an Gerichten, die sowohl zum Mitnehmen als auch zur Lieferung verf\u00fcgbar sind.<\/p>\n","indepth":"","howtogetthere":"","timerange":"","seasonality":"","pairings":"","curiosities":"","awards":"","cancellationpolicy":"","moredetails":"","whatsincluded":"","whatsnotincluded":"","price":"","time":"","service_icons":[],"services":"","parking":"","restaurant":"","breakfast":"","internet":"","children":"","pets":"","latitude":"45.6944093","longitude":"9.5993586","startingprice":"","gpxmap":"","iu_motor_accessibility":"notsure","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_kids":false,"iu_shortprice":"","iu_company_name":"","registered_office":"","iu_addr_streetnumber":"Via Lecco","iu_addr_postalcode":"24035","iu_addr_city":"Curno","iu_addr_province":"Curno","iu_phone":"","iu_cell":"","iu_website":"","iu_email":"info@ristorantealsorriso.it","iu_vat":"","iu_document_label":"","iu_document":false,"iu_documents":false,"iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_bookingurl":"","iu_videourl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"","iu_languages":"","iu_minpeople":"","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","iu_reservation":true,"iu_takeaway":false,"iu_delivery":false,"iu_stars":"","iu_rooms":"","iu_beds":"","id_madeep":"","id_visit_manza":"","id_east":"","id_ristora":"55","id_eppen":"","style":"primary","text":"","button_icon":"none","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"validfrom":"","validto":"","hours":"","ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":""},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/73984","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/73984\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media\/80993"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media?parent=73984"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/categories?post=73984"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/tags?post=73984"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/aggr?post=73984"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/area?post=73984"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/kind?post=73984"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/zona?post=73984"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}