{"id":74017,"date":"2025-05-12T11:18:06","date_gmt":"2025-05-12T09:18:06","guid":{"rendered":"https:\/\/visitstg2.visitbergamo.net\/oggetto\/locanda-dellannunciata\/"},"modified":"2025-05-12T20:19:12","modified_gmt":"2025-05-12T18:19:12","slug":"locanda-dellannunciata","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/locanda-dellannunciata\/","title":{"rendered":"Locanda dell&#8217;Annunciata"},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":81489,"template":"","categories":[854],"tags":[],"aggr":[],"area":[1052],"kind":[18720],"zona":[],"class_list":["post-74017","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-essen","area-palazzago","kind-ristorante-de"],"acf":{"buttons":false,"hero_type":"images","video_youtube_url":"","video_vimeo_url":"","size":"full","hero_title":"Locanda dell'Annunciata","hero_text":"","slides":[{"image":{"ID":81489,"id":81489,"title":"ecom_2885_general","filename":"ecom_2885_general.jpeg","filesize":102456,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/10\/ecom_2885_general.jpeg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/locanda-dellannunciata\/ecom_2885_general-2\/","alt":"","author":"3","description":"","caption":"","name":"ecom_2885_general-2","status":"inherit","uploaded_to":74017,"date":"2024-10-02 09:28:55","modified":"2025-05-12 18:19:13","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":899,"height":633,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/10\/ecom_2885_general-150x150.jpeg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/10\/ecom_2885_general-300x211.jpeg","medium-width":300,"medium-height":211,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/10\/ecom_2885_general-768x541.jpeg","medium_large-width":768,"medium_large-height":541,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/10\/ecom_2885_general.jpeg","large-width":899,"large-height":633,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/10\/ecom_2885_general.jpeg","1536x1536-width":899,"1536x1536-height":633,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/10\/ecom_2885_general.jpeg","2048x2048-width":899,"2048x2048-height":633,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/10\/ecom_2885_general.jpeg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":211,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/10\/ecom_2885_general.jpeg","gform-image-choice-md-width":400,"gform-image-choice-md-height":282,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/10\/ecom_2885_general.jpeg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":422}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"Locanda dell'Annunciata","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"hero_buttons_group":{"buttons":false},"hero_buttons":false,"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":false,"filotto_fill":false,"filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":0,"show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":false,"order_way":false}},"description":"<p>Osteria della Locanda dell&#8217;Annunciata wurde 2013 durch die Zusammenarbeit zweier alter Freunde, Giampo und Silvana, gegr\u00fcndet, die durch ihre Leidenschaft f\u00fcr die italienische K\u00fcche und gute Tafel verbunden sind. In einem alten b\u00fcrgerlichen Landhaus, das in den 1920er Jahren bereits eine Einkehrm\u00f6glichkeit war und noch fr\u00fcher, \u00fcber Jahrhunderte hinweg, ein Augustinerkloster war, werden traditionelle Gerichte mit Fantasie neu interpretiert. Diese Gerichte werden dann alten und neuen Freunden angeboten, die glauben, dass gutes Essen aus der Vergangenheit ein Genuss f\u00fcr K\u00f6rper und Geist ist und dass es sich auch heute noch lohnt, es zu probieren, denn wie Mr. Sykes sagen w\u00fcrde, wird es nicht mehr wie fr\u00fcher sein, aber es ist etwas.<\/p>\n","indepth":"","howtogetthere":"","timerange":"","seasonality":"","pairings":"","curiosities":"","awards":"","cancellationpolicy":"","moredetails":"","whatsincluded":"","whatsnotincluded":"","price":"","time":"","service_icons":[],"services":"","parking":"","restaurant":"","breakfast":"","internet":"","children":"","pets":"","latitude":"45.7507531","longitude":"9.5410885","startingprice":"","gpxmap":"","iu_motor_accessibility":"notsure","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_kids":false,"iu_shortprice":"","iu_company_name":"","registered_office":"","iu_addr_streetnumber":"Via Annunciata,","iu_addr_postalcode":"24030","iu_addr_city":"Palazzago","iu_addr_province":"Palazzago","iu_phone":"","iu_cell":"","iu_website":"","iu_email":"info@locandadellannunciata.it","iu_vat":"","iu_document_label":"","iu_document":false,"iu_documents":false,"iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_bookingurl":"","iu_videourl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"","iu_languages":"","iu_minpeople":"","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","iu_reservation":true,"iu_takeaway":true,"iu_delivery":true,"iu_stars":"","iu_rooms":"","iu_beds":"","id_madeep":"","id_visit_manza":"","id_east":"","id_ristora":"103","id_eppen":"","style":"primary","text":"","button_icon":"none","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"validfrom":"","validto":"","hours":"","ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":""},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/74017","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/74017\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media\/81489"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media?parent=74017"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/categories?post=74017"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/tags?post=74017"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/aggr?post=74017"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/area?post=74017"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/kind?post=74017"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/zona?post=74017"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}