{"id":81528,"date":"2025-05-12T10:59:40","date_gmt":"2025-05-12T08:59:40","guid":{"rendered":"https:\/\/visitstg2.visitbergamo.net\/oggetto\/loro\/"},"modified":"2025-05-12T20:18:56","modified_gmt":"2025-05-12T18:18:56","slug":"loro","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/loro\/","title":{"rendered":"LoRo"},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":81476,"template":"","categories":[854],"tags":[],"aggr":[],"area":[],"kind":[18720],"zona":[],"class_list":["post-81528","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-essen","kind-ristorante-de"],"acf":{"buttons":false,"hero_type":"images","video_youtube_url":"","video_vimeo_url":"","size":"full","hero_title":"LoRo","hero_text":"","slides":[{"image":{"ID":81476,"id":81476,"title":"loro.jpg","filename":"loro.jpg","filesize":116433,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/10\/loro.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/loro\/loro-jpg-2\/","alt":"","author":"3","description":"","caption":"","name":"loro-jpg-2","status":"inherit","uploaded_to":81528,"date":"2024-10-02 09:28:50","modified":"2025-05-12 18:18:57","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":898,"height":393,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/10\/loro-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/10\/loro-300x131.jpg","medium-width":300,"medium-height":131,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/10\/loro-768x336.jpg","medium_large-width":768,"medium_large-height":336,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/10\/loro.jpg","large-width":898,"large-height":393,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/10\/loro.jpg","1536x1536-width":898,"1536x1536-height":393,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/10\/loro.jpg","2048x2048-width":898,"2048x2048-height":393,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/10\/loro.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":131,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/10\/loro.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":175,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/10\/loro.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":263}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"LoRo","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"hero_buttons_group":{"buttons":false},"hero_buttons":false,"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":false,"filotto_fill":false,"filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":0,"show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":false,"order_way":false}},"description":"<p>Zwei Degustationsmen\u00fcs \u2013 eines f\u00fcr Fischgerichte und eines f\u00fcr Fleischspezialit\u00e4ten \u2013 sowie eine gro\u00dfe \u00e0 la carte Speisekarte, aus der man frei w\u00e4hlen kann.&#13;<br \/>\nIm Mittelpunkt steht die Exzellenz der Rohstoffe und die besondere Sorgfalt bei den Gartechniken, sodass jede Zutat und jeder Geschmack respektiert und voll zur Geltung gebracht wird.&#13;<br \/>\nHier profitieren die Gerichte von einer dynamischen Kreativit\u00e4t, die die glorreiche italienische Gastronomietradition mit Geschmack modernisiert.&#13;<br \/>\nDer gut sortierte Weinkeller, unter der fachkundigen Leitung des Sommeliers Francesco Longhi, begleitet die kulinarischen Kreationen mit Meisterhaftigkeit.&#13;<br \/>\nNeben dem Hauptrestaurant gibt es auch ein Bistro f\u00fcr informellere Mittag- und Abendessen, eine Feinkost und eine Speisekammer, in der man die besten Produkte der italienischen Spitzenk\u00fcche kaufen kann.&#13;<br \/>\n&#13;<br \/>\nDER CHEF&#13;<br \/>\nPierantonio Rocchetti&#13;<br \/>\nGeboren 1977, ist Pierantonio Rocchetti der Chefkoch und Inhaber des Hauses, das sich in einem rustikalen Geb\u00e4ude aus dem 17. Jahrhundert am Stadtrand von Trescore Balneario befindet.&#13;<br \/>\nSeit 2011 h\u00e4lt das Restaurant erfolgreich seinen Michelin-Stern. Der Name des Restaurants ist ein Akronym der Nachnamen von Rocchetti selbst und seinem Partner Francesco Longhi, der den Service und den Weinkeller leitet.&#13;<br \/>\nDas Duo ist unzertrennlich: Die beiden begannen schon in jungen Jahren zusammenzuarbeiten, nach ersten Erfahrungen in renommierten Restaurants der Bergamo-Region.&#13;<br \/>\nDie K\u00fcche von Rocchetti basiert auf einem grundlegenden Prinzip: Respekt vor den Rohstoffen, den Aromen und den G\u00e4sten.<\/p>\n","indepth":"","howtogetthere":"","timerange":"","seasonality":"","pairings":"","curiosities":"","awards":"","cancellationpolicy":"","moredetails":"","whatsincluded":"","whatsnotincluded":"","price":"","time":"","service_icons":[],"services":"","parking":"","restaurant":"","breakfast":"","internet":"","children":"","pets":"","latitude":"45.694190191873","longitude":"9.8327662309345","startingprice":"","gpxmap":"","iu_motor_accessibility":"notsure","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_kids":false,"iu_shortprice":"","iu_company_name":"","registered_office":"","iu_addr_streetnumber":"via Bruse","iu_addr_postalcode":"24069","iu_addr_city":"Trescore Balneario","iu_addr_province":"Trescore Balneario","iu_phone":"","iu_cell":"","iu_website":"","iu_email":"info@loroandco.com","iu_vat":"","iu_document_label":"","iu_document":false,"iu_documents":false,"iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_bookingurl":"","iu_videourl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"","iu_languages":"","iu_minpeople":"","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"iu_stars":"","iu_rooms":"","iu_beds":"","id_madeep":"","id_visit_manza":"","id_east":"","id_ristora":"354","id_eppen":"","style":"primary","text":"","button_icon":"none","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"validfrom":"","validto":"","hours":"","ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":""},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/81528","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/81528\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media\/81476"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media?parent=81528"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/categories?post=81528"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/tags?post=81528"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/aggr?post=81528"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/area?post=81528"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/kind?post=81528"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/zona?post=81528"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}