{"id":81800,"date":"2025-05-12T11:01:50","date_gmt":"2025-05-12T09:01:50","guid":{"rendered":"https:\/\/visitstg2.visitbergamo.net\/oggetto\/ristofante\/"},"modified":"2025-05-12T20:21:25","modified_gmt":"2025-05-12T18:21:25","slug":"ristofante","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/ristofante\/","title":{"rendered":"RistoFante"},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":81732,"template":"","categories":[854,823],"tags":[],"aggr":[],"area":[],"kind":[18720],"zona":[],"class_list":["post-81800","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-essen","category-mangiare","kind-ristorante-de"],"acf":{"buttons":false,"hero_type":"images","video_youtube_url":"","video_vimeo_url":"","size":"full","hero_title":"RistoFante","hero_text":"","slides":[{"image":{"ID":81732,"id":81732,"title":"ristofante.jpg","filename":"ristofante.jpg","filesize":99189,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/10\/ristofante.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/ristofante\/ristofante-jpg-2\/","alt":"","author":"3","description":"","caption":"","name":"ristofante-jpg-2","status":"inherit","uploaded_to":81800,"date":"2024-10-02 09:32:03","modified":"2025-05-12 18:21:26","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":898,"height":393,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/10\/ristofante-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/10\/ristofante-300x131.jpg","medium-width":300,"medium-height":131,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/10\/ristofante-768x336.jpg","medium_large-width":768,"medium_large-height":336,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/10\/ristofante.jpg","large-width":898,"large-height":393,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/10\/ristofante.jpg","1536x1536-width":898,"1536x1536-height":393,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/10\/ristofante.jpg","2048x2048-width":898,"2048x2048-height":393,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/10\/ristofante.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":131,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/10\/ristofante.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":175,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/10\/ristofante.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":263}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"RistoFante","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"hero_buttons_group":{"buttons":false},"hero_buttons":false,"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":false,"filotto_fill":false,"filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":0,"show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":false,"order_way":false}},"description":"<p>Der Chef&#13;<br \/>\nGianbattista \u201cTitta\u201d Manzini&#13;<br \/>\nSeit 30 Jahren widmet sich der Chefkoch Giambattista Manzini, den alle &#8220;Titta&#8221; nennen, mit Leidenschaft der K\u00fcche und ihren verschiedenen Facetten. Mit besonderem Augenmerk auf lokale und maximal frische Produkte respektiert er den Lauf der Jahreszeiten und deren Fr\u00fcchte, sodass er seine Interpretation der regionalen K\u00fcche bestm\u00f6glich zum Ausdruck bringen kann. Bei Ristofante ist das Angebot sehr umfangreich und immer von h\u00f6chster Qualit\u00e4t: Auf der Speisekarte finden sich Bergamasker Polenta oder sogar Bergamasker Sushi sowie Fleisch, Pilze, frische Pasta und vor allem Fisch.&#13;<br \/>\n&#13;<br \/>\nDas Restaurant&#13;<br \/>\nAn der Spitze der K\u00fcche steht Titta selbst, w\u00e4hrend Silvia den Gastraum mit gro\u00dfer Sorgfalt betreut und die G\u00e4ste in einem zarten und eleganten Ambiente empf\u00e4ngt, das aus zwei S\u00e4len und einem privaten Raum besteht. In der sch\u00f6nen Jahreszeit empf\u00e4ngt der wunderbare Garten die G\u00e4ste und bietet die ideale Location, um Tittas Kreationen im Freien zu genie\u00dfen.&#13;<br \/>\n&#13;<\/p>\n","indepth":"","howtogetthere":"","timerange":"","seasonality":"","pairings":"","curiosities":"","awards":"","cancellationpolicy":"","moredetails":"","whatsincluded":"","whatsnotincluded":"","price":"","time":"","service_icons":[],"services":"","parking":"","restaurant":"","breakfast":"","internet":"","children":"","pets":"","latitude":"45.732386186718","longitude":"9.7292638211","startingprice":"","gpxmap":"","iu_motor_accessibility":"notsure","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_kids":false,"iu_shortprice":"","iu_company_name":"","registered_office":"","iu_addr_streetnumber":"Via G. Mazzini,","iu_addr_postalcode":"24022","iu_addr_city":"Alzano Lombardo","iu_addr_province":"Alzano Lombardo","iu_phone":"","iu_cell":"","iu_website":"","iu_email":"ristofante@ristofante.it","iu_vat":"","iu_document_label":"","iu_document":false,"iu_documents":false,"iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_bookingurl":"","iu_videourl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"","iu_languages":"","iu_minpeople":"","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"iu_stars":"","iu_rooms":"","iu_beds":"","id_madeep":"","id_visit_manza":"","id_east":"","id_ristora":"343","id_eppen":"","style":"primary","text":"","button_icon":"none","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"validfrom":"","validto":"","hours":"","ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":""},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/81800","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/81800\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media\/81732"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media?parent=81800"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/categories?post=81800"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/tags?post=81800"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/aggr?post=81800"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/area?post=81800"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/kind?post=81800"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/zona?post=81800"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}