{"id":81806,"date":"2025-05-12T11:02:26","date_gmt":"2025-05-12T09:02:26","guid":{"rendered":"https:\/\/visitstg2.visitbergamo.net\/oggetto\/ristorante-miranda\/"},"modified":"2025-05-12T20:22:03","modified_gmt":"2025-05-12T18:22:03","slug":"ristorante-miranda","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/ristorante-miranda\/","title":{"rendered":"Ristorante Miranda"},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":81780,"template":"","categories":[854,823],"tags":[],"aggr":[],"area":[],"kind":[18720],"zona":[],"class_list":["post-81806","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-essen","category-mangiare","kind-ristorante-de"],"acf":{"buttons":false,"hero_type":"images","video_youtube_url":"","video_vimeo_url":"","size":"full","hero_title":"Ristorante Miranda","hero_text":"","slides":[{"image":{"ID":81780,"id":81780,"title":"1619464401-img0803.webp","filename":"1619464401-img0803.webp","filesize":106254,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/10\/1619464401-img0803.webp","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/ristorante-miranda\/1619464401-img0803-webp-2\/","alt":"","author":"3","description":"","caption":"","name":"1619464401-img0803-webp-2","status":"inherit","uploaded_to":81806,"date":"2024-10-02 09:32:23","modified":"2025-05-12 18:22:03","menu_order":0,"mime_type":"image\/webp","type":"image","subtype":"webp","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1347,"height":590,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/10\/1619464401-img0803-150x150.webp","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/10\/1619464401-img0803-300x131.webp","medium-width":300,"medium-height":131,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/10\/1619464401-img0803-768x336.webp","medium_large-width":768,"medium_large-height":336,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/10\/1619464401-img0803-1024x449.webp","large-width":1024,"large-height":449,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/10\/1619464401-img0803.webp","1536x1536-width":1347,"1536x1536-height":590,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/10\/1619464401-img0803.webp","2048x2048-width":1347,"2048x2048-height":590,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/10\/1619464401-img0803.webp","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":131,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/10\/1619464401-img0803.webp","gform-image-choice-md-width":400,"gform-image-choice-md-height":175,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/10\/1619464401-img0803.webp","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":263}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"Ristorante Miranda","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"hero_buttons_group":{"buttons":false},"hero_buttons":false,"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":false,"filotto_fill":false,"filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":0,"show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":false,"order_way":false}},"description":"<p>DAS RESTAURANT&#13;<br \/>\n&#13;<br \/>\n1959 erwarb Oreste das ehemalige Zuhause eines der bekanntesten italienischen K\u00fcnstler seiner Zeit, Aligi Sassu, und verwandelte es in ein Hotelrestaurant. Der Ort ist bezaubernd, eingebettet in ein Paradies aus Frieden und Ruhe, mit Blick auf den Iseosee. Das Miranda besitzt einen Olivenhain im Park seines Hotels, aus dem ein delikates \u00d6l gewonnen wird, das in den Gerichten verwendet wird.&#13;<br \/>\n&#13;<br \/>\nDER RESTAURATEUR&#13;<br \/>\n&#13;<br \/>\nSergio, der schon von klein auf im Service half, hat das Erbe seines Gro\u00dfvaters Oreste angetreten und repr\u00e4sentiert die dritte Generation dieser Familie von Gastronomen. Die Tradition der Veredelung hochwertiger Rohstoffe bleibt ein st\u00e4ndiges und wertvolles Gut in der K\u00fcche dieses Restaurants, das die Geschichte und Geschichten des Sees erz\u00e4hlt. Echtheit wird an erster Stelle gesetzt, auch dank der besonderen Aufmerksamkeit f\u00fcr regionale Produkte, die vom See und kleinen lokalen Unternehmen geliefert werden. Die Weinkarte mit \u00fcber 200 Etiketten ist sehr umfangreich und sorgf\u00e4ltig zusammengestellt.<\/p>\n","indepth":"","howtogetthere":"","timerange":"","seasonality":"","pairings":"","curiosities":"","awards":"","cancellationpolicy":"","moredetails":"","whatsincluded":"","whatsnotincluded":"","price":"","time":"","service_icons":[],"services":"","parking":"","restaurant":"","breakfast":"","internet":"","children":"","pets":"","latitude":"45.78063","longitude":"10.04514","startingprice":"","gpxmap":"","iu_motor_accessibility":"notsure","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_kids":false,"iu_shortprice":"","iu_company_name":"","registered_office":"","iu_addr_streetnumber":"Via Cornello","iu_addr_postalcode":"24060","iu_addr_city":"Riva di Solto","iu_addr_province":"Riva di Solto","iu_phone":"","iu_cell":"","iu_website":"","iu_email":"info@hotelristorantemiranda.com","iu_vat":"","iu_document_label":"","iu_document":false,"iu_documents":false,"iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_bookingurl":"","iu_videourl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"","iu_languages":"","iu_minpeople":"","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"iu_stars":"","iu_rooms":"","iu_beds":"","id_madeep":"","id_visit_manza":"","id_east":"","id_ristora":"325","id_eppen":"","style":"primary","text":"","button_icon":"none","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"validfrom":"","validto":"","hours":"","ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":""},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/81806","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/81806\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media\/81780"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media?parent=81806"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/categories?post=81806"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/tags?post=81806"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/aggr?post=81806"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/area?post=81806"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/kind?post=81806"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/zona?post=81806"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}