{"id":82058,"date":"2025-05-12T11:03:54","date_gmt":"2025-05-12T09:03:54","guid":{"rendered":"https:\/\/visitstg2.visitbergamo.net\/oggetto\/trattoria-visconti\/"},"modified":"2025-05-12T20:23:51","modified_gmt":"2025-05-12T18:23:51","slug":"trattoria-visconti","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/trattoria-visconti\/","title":{"rendered":"Trattoria Visconti"},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":82026,"template":"","categories":[854,823],"tags":[],"aggr":[],"area":[],"kind":[18720],"zona":[],"class_list":["post-82058","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-essen","category-mangiare","kind-ristorante-de"],"acf":{"buttons":false,"hero_type":"images","video_youtube_url":"","video_vimeo_url":"","size":"full","hero_title":"Trattoria Visconti","hero_text":"","slides":[{"image":{"ID":82026,"id":82026,"title":"1621971157-img1570.webp","filename":"1621971157-img1570.webp","filesize":102554,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/10\/1621971157-img1570.webp","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/trattoria-visconti\/1621971157-img1570-webp-2\/","alt":"","author":"3","description":"","caption":"","name":"1621971157-img1570-webp-2","status":"inherit","uploaded_to":82058,"date":"2024-10-02 09:35:38","modified":"2025-05-12 18:23:51","menu_order":0,"mime_type":"image\/webp","type":"image","subtype":"webp","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":898,"height":393,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/10\/1621971157-img1570-150x150.webp","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/10\/1621971157-img1570-300x131.webp","medium-width":300,"medium-height":131,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/10\/1621971157-img1570-768x336.webp","medium_large-width":768,"medium_large-height":336,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/10\/1621971157-img1570.webp","large-width":898,"large-height":393,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/10\/1621971157-img1570.webp","1536x1536-width":898,"1536x1536-height":393,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/10\/1621971157-img1570.webp","2048x2048-width":898,"2048x2048-height":393,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/10\/1621971157-img1570.webp","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":131,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/10\/1621971157-img1570.webp","gform-image-choice-md-width":400,"gform-image-choice-md-height":175,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/10\/1621971157-img1570.webp","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":263}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"Trattoria Visconti","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"hero_buttons_group":{"buttons":false},"hero_buttons":false,"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":false,"filotto_fill":false,"filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":0,"show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":false,"order_way":false}},"description":"<p>DAS RESTAURANT&#13;<br \/>\n&#13;<br \/>\nDie Pr\u00e4senz eines Weinausschanks reicht bis ins sp\u00e4te 19. Jahrhundert zur\u00fcck, aber es war erst in den 1930er Jahren, dass Leone Visconti, der Gro\u00dfvater der heutigen Inhaberin Maria Fiorella, zum Besitzer wurde. Zun\u00e4chst kochte Gro\u00dfmutter Adelina einige einfache Gerichte f\u00fcr die Arbeiter und t\u00e4glichen Kunden sowie aufwendigere Mahlzeiten, um Feste, Taufen und Hochzeiten zu feiern. Im Laufe der Zeit verwandelte sich dieses Lokal und wurde zu einem der Tempel der traditionellen Bergamasker K\u00fcche, einem eleganten und raffinierten Lokal, das eine authentische K\u00fcche mit Zutaten aus der Region anbietet.&#13;<br \/>\n&#13;<br \/>\nDER RESTAURATEUR&#13;<br \/>\n&#13;<br \/>\nDie Geschichte der Trattoria Visconti ist eine Familiengeschichte, in der jedes Mitglied seine Rolle gefunden hat: Daniele, im Speisesaal zusammen mit seiner Mutter Fiorella und seinem Vater Giorgio, ist das Gesicht des Restaurants und verantwortlich f\u00fcr den reichen Weinkeller, der neben Wein auch eine Auswahl an Craft-Bieren umfasst. In der K\u00fcche steht Roberto, der j\u00fcngste Sohn, der ein saisonales Men\u00fc anbietet, in dem traditionelle Gerichte neu interpretiert werden, ohne ihre Bedeutung und Erinnerung zu verf\u00e4lschen. Fast alle Produkte stammen aus dem gro\u00dfen Gem\u00fcsegarten hinter dem Restaurant, wo sich auch ein kleines Feld mit einheimischem Bergamasker Mais f\u00fcr hausgemachte Polenta und ein kleiner Obstgarten befinden. Hier bem\u00fcht man sich, so weit wie m\u00f6glich autark zu sein. F\u00fcr den Rest werden die umliegenden Produzenten einbezogen.<\/p>\n","indepth":"","howtogetthere":"","timerange":"","seasonality":"","pairings":"","curiosities":"","awards":"","cancellationpolicy":"","moredetails":"","whatsincluded":"","whatsnotincluded":"","price":"","time":"","service_icons":[],"services":"","parking":"","restaurant":"","breakfast":"","internet":"","children":"","pets":"","latitude":"45.71833","longitude":"9.54739","startingprice":"","gpxmap":"","iu_motor_accessibility":"notsure","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_kids":false,"iu_shortprice":"","iu_company_name":"","registered_office":"","iu_addr_streetnumber":"Via De Gasperi","iu_addr_postalcode":"24030","iu_addr_city":"Ambivere","iu_addr_province":"Ambivere","iu_phone":"","iu_cell":"","iu_website":"","iu_email":"info@trattoriavisconti.it","iu_vat":"","iu_document_label":"","iu_document":false,"iu_documents":false,"iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_bookingurl":"","iu_videourl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"","iu_languages":"","iu_minpeople":"","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"iu_stars":"","iu_rooms":"","iu_beds":"","id_madeep":"","id_visit_manza":"","id_east":"","id_ristora":"332","id_eppen":"","style":"primary","text":"","button_icon":"none","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"validfrom":"","validto":"","hours":"","ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":""},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/82058","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/82058\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media\/82026"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media?parent=82058"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/categories?post=82058"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/tags?post=82058"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/aggr?post=82058"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/area?post=82058"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/kind?post=82058"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/zona?post=82058"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}