{"id":84859,"date":"2025-05-12T10:36:51","date_gmt":"2025-05-12T08:36:51","guid":{"rendered":"https:\/\/visitstg2.visitbergamo.net\/oggetto\/roter-safran-fino\/"},"modified":"2025-03-04T13:59:20","modified_gmt":"2025-03-04T12:59:20","slug":"roter-safran-fino","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/roter-safran-fino\/","title":{"rendered":"Roter Safran Fino"},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":40526,"template":"","categories":[854],"tags":[],"aggr":[],"area":[901],"kind":[18715],"zona":[],"class_list":["post-84859","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-essen","area-zanica","kind-produttore-de"],"acf":{"iu_shortprice":"","button_icon":"none","target":"_self","function":"link","style":"primary","icon":{"button_icon":"none"},"target_modal":"","latitude":"45.6354738","longitude":"9.678121","startingprice":"","gpxmap":"","id_madeep":"","iu_addr_postalcode":"24050","iu_addr_city":"Zanica","iu_phone":"+39 342 7633956","iu_cell":"","iu_email":"zafferanorossofino@gmail.com","iu_manager":"","id_visit_manza":"","iu_motor_accessibility":"no","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","id_east":"161564316","id_ristora":"","validfrom":"","validto":"","iu_addr_province":"Bergamo","size":"full","filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":false,"filotto_fill":false,"filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":0,"show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":false,"order_way":false}},"hero_type":"images","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"iu_startingdate":"","iu_closingdate":"","iu_gpxtrack":"","url":"","iu_bookingurl":"","id_eppen":"","iu_videourl":"","description":"<p>Dank ihrer Leidenschaft f\u00fcr den nachhaltigen Anbau hat das Unternehmen den Schwerpunkt auf die Fruchtfolge und den Umweltschutz gelegt. Von der anf\u00e4nglichen Produktion im eigenen Garten haben sie eine &#8220;Welt der Bl\u00fctenstempel&#8221; geschaffen, die sie mit den Menschen teilen, die ihre Rezepte mit Safran bereichern m\u00f6chten. Durch Besuche und Erfahrungen in den Safranhainen in Mittel- und Norditalien hat das Unternehmen die Kunst des Anbaus verfeinert.  <\/p>\n","hero_title":"Roter Safran Fino","iu_addr_streetnumber":"Via Padre Turoldo 19","iu_website":"http:\/\/www.zafferanorossofino.com","text":"","url_youtube":"","hero_buttons":false,"iu_kids":false,"iu_timetable":false,"iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"featured_video":false,"hours":"","service_icons":[],"iu_company_name":"","iu_vat":"","iu_stars":"","iu_rooms":"","iu_beds":"","ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":"","registered_office":"","slides":[{"image":{"ID":40526,"id":40526,"title":"1691755916-mg_2382.jpg","filename":"1691755916-mg_2382.jpg","filesize":241563,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1691755916-mg_2382.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/roter-safran-fino\/1691755916-mg_2382-jpg-2\/","alt":"","author":"3","description":"","caption":"","name":"1691755916-mg_2382-jpg-2","status":"inherit","uploaded_to":84859,"date":"2024-06-17 14:43:22","modified":"2024-10-08 15:17:01","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1400,"height":612,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1691755916-mg_2382-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1691755916-mg_2382-300x131.jpg","medium-width":300,"medium-height":131,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1691755916-mg_2382-768x336.jpg","medium_large-width":768,"medium_large-height":336,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1691755916-mg_2382-1024x448.jpg","large-width":1024,"large-height":448,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1691755916-mg_2382.jpg","1536x1536-width":1400,"1536x1536-height":612,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1691755916-mg_2382.jpg","2048x2048-width":1400,"2048x2048-height":612,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1691755916-mg_2382.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":131,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1691755916-mg_2382.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":175,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1691755916-mg_2382.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":262}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":64766,"id":64766,"title":"1691755921-mg_1945.jpg","filename":"1691755921-mg_1945.jpg","filesize":268715,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1691755921-mg_1945.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/roter-safran-fino\/1691755921-mg_1945-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"1691755921-mg_1945-jpg-2","status":"inherit","uploaded_to":84859,"date":"2024-06-25 10:00:03","modified":"2024-10-08 15:17:01","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1400,"height":612,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1691755921-mg_1945-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1691755921-mg_1945-300x131.jpg","medium-width":300,"medium-height":131,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1691755921-mg_1945-768x336.jpg","medium_large-width":768,"medium_large-height":336,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1691755921-mg_1945-1024x448.jpg","large-width":1024,"large-height":448,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1691755921-mg_1945.jpg","1536x1536-width":1400,"1536x1536-height":612,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1691755921-mg_1945.jpg","2048x2048-width":1400,"2048x2048-height":612,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1691755921-mg_1945.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":131,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1691755921-mg_1945.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":175,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1691755921-mg_1945.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":262}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":64772,"id":64772,"title":"1691755927-mg_2382.jpg","filename":"1691755927-mg_2382.jpg","filesize":241563,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1691755927-mg_2382.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/roter-safran-fino\/1691755927-mg_2382-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"1691755927-mg_2382-jpg-2","status":"inherit","uploaded_to":84859,"date":"2024-06-25 10:00:06","modified":"2024-10-08 15:17:01","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1400,"height":612,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1691755927-mg_2382-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1691755927-mg_2382-300x131.jpg","medium-width":300,"medium-height":131,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1691755927-mg_2382-768x336.jpg","medium_large-width":768,"medium_large-height":336,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1691755927-mg_2382-1024x448.jpg","large-width":1024,"large-height":448,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1691755927-mg_2382.jpg","1536x1536-width":1400,"1536x1536-height":612,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1691755927-mg_2382.jpg","2048x2048-width":1400,"2048x2048-height":612,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1691755927-mg_2382.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":131,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1691755927-mg_2382.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":175,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1691755927-mg_2382.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":262}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":64778,"id":64778,"title":"btr","filename":"1691755931-img_20201025_153023.jpg","filesize":389149,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1691755931-img_20201025_153023.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/roter-safran-fino\/btr-2\/","alt":"","author":"0","description":"btr","caption":"","name":"btr-2","status":"inherit","uploaded_to":84859,"date":"2024-06-25 10:00:08","modified":"2024-10-08 15:17:01","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1400,"height":612,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1691755931-img_20201025_153023-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1691755931-img_20201025_153023-300x131.jpg","medium-width":300,"medium-height":131,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1691755931-img_20201025_153023-768x336.jpg","medium_large-width":768,"medium_large-height":336,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1691755931-img_20201025_153023-1024x448.jpg","large-width":1024,"large-height":448,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1691755931-img_20201025_153023.jpg","1536x1536-width":1400,"1536x1536-height":612,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1691755931-img_20201025_153023.jpg","2048x2048-width":1400,"2048x2048-height":612,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1691755931-img_20201025_153023.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":131,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1691755931-img_20201025_153023.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":175,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1691755931-img_20201025_153023.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":262}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":64784,"id":64784,"title":"rbthdr","filename":"1691755935-img_20210620_094951.jpg","filesize":293676,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1691755935-img_20210620_094951.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/roter-safran-fino\/rbthdr-2\/","alt":"","author":"0","description":"rbthdr","caption":"","name":"rbthdr-2","status":"inherit","uploaded_to":84859,"date":"2024-06-25 10:00:11","modified":"2024-10-08 15:17:01","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1400,"height":612,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1691755935-img_20210620_094951-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1691755935-img_20210620_094951-300x131.jpg","medium-width":300,"medium-height":131,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1691755935-img_20210620_094951-768x336.jpg","medium_large-width":768,"medium_large-height":336,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1691755935-img_20210620_094951-1024x448.jpg","large-width":1024,"large-height":448,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1691755935-img_20210620_094951.jpg","1536x1536-width":1400,"1536x1536-height":612,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1691755935-img_20210620_094951.jpg","2048x2048-width":1400,"2048x2048-height":612,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1691755935-img_20210620_094951.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":131,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1691755935-img_20210620_094951.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":175,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1691755935-img_20210620_094951.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":262}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":64790,"id":64790,"title":"1691755939-raccolta-zafferano.jpg","filename":"1691755939-raccolta-zafferano.jpg","filesize":414675,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1691755939-raccolta-zafferano.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/roter-safran-fino\/1691755939-raccolta-zafferano-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"1691755939-raccolta-zafferano-jpg-2","status":"inherit","uploaded_to":84859,"date":"2024-06-25 10:00:13","modified":"2024-10-08 15:17:01","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1400,"height":612,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1691755939-raccolta-zafferano-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1691755939-raccolta-zafferano-300x131.jpg","medium-width":300,"medium-height":131,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1691755939-raccolta-zafferano-768x336.jpg","medium_large-width":768,"medium_large-height":336,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1691755939-raccolta-zafferano-1024x448.jpg","large-width":1024,"large-height":448,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1691755939-raccolta-zafferano.jpg","1536x1536-width":1400,"1536x1536-height":612,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1691755939-raccolta-zafferano.jpg","2048x2048-width":1400,"2048x2048-height":612,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1691755939-raccolta-zafferano.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":131,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1691755939-raccolta-zafferano.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":175,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1691755939-raccolta-zafferano.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":262}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":64796,"id":64796,"title":"1691755943-zafferaneto-zafferano-rosso-fino.jpg","filename":"1691755943-zafferaneto-zafferano-rosso-fino.jpg","filesize":420504,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1691755943-zafferaneto-zafferano-rosso-fino.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/roter-safran-fino\/1691755943-zafferaneto-zafferano-rosso-fino-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"1691755943-zafferaneto-zafferano-rosso-fino-jpg-2","status":"inherit","uploaded_to":84859,"date":"2024-06-25 10:00:15","modified":"2024-10-08 15:17:01","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1400,"height":612,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1691755943-zafferaneto-zafferano-rosso-fino-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1691755943-zafferaneto-zafferano-rosso-fino-300x131.jpg","medium-width":300,"medium-height":131,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1691755943-zafferaneto-zafferano-rosso-fino-768x336.jpg","medium_large-width":768,"medium_large-height":336,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1691755943-zafferaneto-zafferano-rosso-fino-1024x448.jpg","large-width":1024,"large-height":448,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1691755943-zafferaneto-zafferano-rosso-fino.jpg","1536x1536-width":1400,"1536x1536-height":612,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1691755943-zafferaneto-zafferano-rosso-fino.jpg","2048x2048-width":1400,"2048x2048-height":612,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1691755943-zafferaneto-zafferano-rosso-fino.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":131,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1691755943-zafferaneto-zafferano-rosso-fino.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":175,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1691755943-zafferaneto-zafferano-rosso-fino.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":262}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}]},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/84859","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/84859\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media\/40526"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media?parent=84859"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/categories?post=84859"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/tags?post=84859"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/aggr?post=84859"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/area?post=84859"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/kind?post=84859"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/zona?post=84859"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}