{"id":84908,"date":"2024-06-05T19:53:57","date_gmt":"2024-06-05T17:53:57","guid":{"rendered":"https:\/\/visitstg2.visitbergamo.net\/oggetto\/erreichbare-route-zu-den-massi-di-cemmo\/"},"modified":"2024-10-09T09:30:47","modified_gmt":"2024-10-09T07:30:47","slug":"erreichbare-route-zu-den-massi-di-cemmo","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/erreichbare-route-zu-den-massi-di-cemmo\/","title":{"rendered":"Erreichbare Route zu den Massi di Cemmo"},"excerpt":{"rendered":"","protected":false},"author":8,"featured_media":37858,"template":"","categories":[],"tags":[],"aggr":[],"area":[],"kind":[18685],"zona":[],"class_list":["post-84908","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","kind-itinerario-de"],"acf":{"featured_video":false,"is_an_ambassador":false,"modules":[{"acf_fc_layout":"two_columns_module","tcm_title":{"title_text":"Routen-Statistiken"},"tcm_ui":[{"label":"Durchschnittliche Reisezeit","value":"40 Minuten von der Via Santo Stefano entfernt - 2 Minuten vom Parkplatz der Anlage Massi di Cemmo"},{"label":"L\u00e4nge","value":"1 km"},{"label":"Positiver H\u00f6henunterschied","value":"30 m"},{"label":"Technische Schwierigkeiten","value":"mittel (signifikanter Unterschied in der H\u00f6he)"},{"label":"Negative H\u00f6hendifferenz","value":"0 m"},{"label":"Maximale H\u00f6he","value":"218 m \u00fc. NN"},{"label":"Minimale H\u00f6he","value":"215 m \u00fc. NN"},{"label":"Art der Route","value":"linear"}],"tcm_content":[{"acf_fc_layout":"text","text":"<h2>\n            <span style=\"font-weight: 400;\">Entdecken Sie die Vorgeschichte im Valle Camonica<\/span><br \/>\n          <\/h2>\n<p>          <span style=\"font-weight: 400;\">Die nahe gelegene Provinz Brescia bietet zahlreiche M\u00f6glichkeiten f\u00fcr Abenteuer, vor allem wenn Sie von der Vorgeschichte der Menschheit fasziniert sind.<br \/>\nStaunen Sie \u00fcber die Parks und Museen des   <strong>UNESCO-St\u00e4tte Nr.<br \/>\n94 <\/strong>Die<strong>&#8220;Arte Rupestre della Valle Camonica<\/strong>&#8220;<strong>(Felskunst des<\/strong> <strong>Camonica-Tals<\/strong>) ist voll von Zeugnissen aus dem Leben der <strong>alten Camuni<\/strong>.<br \/>\nSie selbst werden Ihnen durch die Gravuren, die sie auf dem Stein hinterlassen haben, von ihrem Leben und ihrem Glauben erz\u00e4hlen! <\/span><\/p>\n<p>          <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-37849 size-full\" src=\"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/cemmo3.jpeg\" alt=\"\" width=\"512\" height=\"274\" srcset=\"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/cemmo3.jpeg 512w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/cemmo3-300x161.jpeg 300w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/p>\n"}]},{"acf_fc_layout":"two_columns_module","tcm_title":{"title_text":"Technische Details"},"tcm_ui":[{"label":"Geeignet f\u00fcr Ger\u00e4te","value":"Rollst\u00fchle mit Begleitperson \/ elektrischer Rollstuhl"},{"label":"Wegpflasterung","value":"Asphalt, stabilisierter Boden (Baustellenzugang)"},{"label":"Toiletten","value":"im Graffiti Park - oder vor Ort nach Reservierung"},{"label":"Orientierungs- oder Informationsschilder","value":"arch\u00e4ologische St\u00e4tte Massi di Cemmo"},{"label":"Vorhandensein von B\u00e4umen oder schattigen Bereichen","value":"sonnige Route"},{"label":"Trinkwasser-Brunnen","value":"nicht anwesend"}],"tcm_content":[{"acf_fc_layout":"text","text":"<h2><span style=\"font-weight: 400;\">Erreichbare Route zu den Massi di Cemmo<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">In <strong>Capo di Ponte<\/strong> finden Sie vor allem drei arch\u00e4ologische Parks und einen <\/span><b>Rundgang zu den Massi di Cemmo<\/b><span style=\"font-weight: 400;\">  nun <strong>auch f\u00fcr mobilit\u00e4tseingeschr\u00e4nkte<\/strong> Personen vollst\u00e4ndig <strong>zug\u00e4nglich<\/strong>.<br \/>\nDie Route wurde dank des S.T.A.I.-Projekts (2023) erm\u00f6glicht, in Zusammenarbeit mit   <\/span><span style=\"font-weight: 400;\">Sol.Co.<br \/>\nCamunia <\/span><span style=\"font-weight: 400;\">.<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">Geschichte von Capo di Ponte und den Massi di Cemmo<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">\u00dcberreste menschlicher Siedlungen aus der Zeit um 4000 v. Chr., einer Zeit, in der sich J\u00e4gerst\u00e4mme in der Gegend niederlie\u00dfen, angezogen von der reichen Tierwelt. Cemmo selbst war dank seiner g\u00fcnstigen geografischen Lage das erste bewohnte Gebiet im Tal. In den umliegenden W\u00e4ldern fanden kollektive Rituale statt, von denen uns Tausende von Felsgravuren Zeugnis ablegen. Im Laufe der Jahrtausende hat die Bedeutung des Ortes nicht nachgelassen und es gibt Hinweise auf weitere Bl\u00fctezeiten, wie das sp\u00e4te Mittelalter, als er Sitz der Podest\u00e0 des Tals war, und das 14.<br \/>\n<\/span><span style=\"font-weight: 400;\">Ein Ort mit vielen Facetten, den Sie nicht verpassen sollten!<\/span><\/p>\n"}]},{"acf_fc_layout":"two_columns_module","tcm_title":{"title_text":"B\u00fchne"},"tcm_ui":false,"tcm_content":[{"acf_fc_layout":"text","text":"<h2><span style=\"font-weight: 400;\">Wie man zu den Massi di Cemmo kommt<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Capo di Ponte ist in etwa 1\u00bd Stunden mit dem Auto von Bergamo und in 35 Minuten von Lovere am Iseosee aus erreichbar.<br \/>\nMit dem Zug dauert es von Bergamo aus 3h30 und Sie m\u00fcssen in Brescia umsteigen.<br \/>\nSie k\u00f6nnen die Stadt auch mit dem Bus vom Flughafen Mailand-Bergamo aus erreichen, und zwar mit der direkten Linie BS1 von Arriva, die etwas mehr als 2 Stunden braucht (Haltestelle Bahnhof Capo di Ponte).<br \/>\nWenn Sie den Bahnhof verlassen und das Geb\u00e4ude hinter sich lassen, biegen Sie links ab und gehen Sie 500 Meter die Via Nazionale entlang, dann biegen Sie in die Via Briscioli ein.   <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Der begehbare Weg zu den Massi di Cemmo kann in seiner l\u00e4ngeren Version vom <strong>Graffiti-Park<\/strong> aus starten oder in seiner k\u00fcrzeren und direkteren Version direkt in der N\u00e4he der arch\u00e4ologischen St\u00e4tte.<br \/>\n<\/span><span style=\"font-weight: 400;\">Wenn Sie sich f\u00fcr den Weg vom <\/span><b>Graffiti-Park<\/b><span style=\"font-weight: 400;\">einem sch\u00f6nen Hotel-Restaurant am Ortseingang direkt an der Via Briscioli, steht Ihnen ein Parkplatz mit Behinderten- und Busparkpl\u00e4tzen zur Verf\u00fcgung.<br \/>\nVon hier aus k\u00f6nnen Sie die Massi di Cemmo entweder durch das historische Zentrum von Capo di Ponte oder \u00fcber die gro\u00dfe Fahrzeugbr\u00fccke \u00fcber den Fluss Oglio erreichen.<br \/>\nIm ersten Fall finden Sie mehrere Kopfsteinpflasterabschnitte und am Ende einen steilen Abhang auf unebenem Untergrund, der die Anwesenheit einer Begleitperson erfordert, falls Sie sich mit einem Rollstuhl fortbewegen.  <\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-37855 aligncenter\" src=\"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/cemmo.jpeg\" alt=\"\" width=\"522\" height=\"274\" srcset=\"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/cemmo.jpeg 522w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/cemmo-300x157.jpeg 300w\" sizes=\"auto, (max-width: 522px) 100vw, 522px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">Wenn Sie hingegen vom Graffiti-Park aus anreisen m\u00f6chten, wenden Sie sich mit dem R\u00fccken zum Hoteleingang und biegen links in die Via Briscioli in Richtung Altstadt ein.<br \/>\nNach 50 Metern biegen Sie links in die Via Santo Stefano ein, wo Sie nach etwa 10 Metern auf den ersten Abhang sto\u00dfen. Fahren Sie weiter geradeaus auf dem Asphaltweg, vorbei an der Br\u00fccke \u00fcber den Fluss Oglio und der Kreuzung mit dem Vallecamonica-Radweg.<br \/>\nNach 600 Metern, auf denen Sie den gr\u00f6\u00dften H\u00f6henunterschied der Strecke \u00fcberwinden &#8211; eine Strecke von etwa 20 Metern &#8211; k\u00f6nnen Sie rechts in die Via Martiri della Libert\u00e0 einbiegen, die die letzte gerade Strecke in Richtung <strong>Massi di Cemmo<\/strong> darstellt.<br \/>\nFahren Sie weitere 400 Meter geradeaus, \u00fcberqueren Sie die Via Marconi und halten Sie das Ristorante la Pieve zu Ihrer Rechten. Am Ende der Via Pieve San Siro haben Sie nach 30 Metern die arch\u00e4ologische St\u00e4tte erreicht.   <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Angesichts des H\u00f6henunterschieds in der Via Santo Stefano und des unebenen Bodens im historischen Zentrum wurde eigens ein <strong>Behindertenparkplatz neben dem Gel\u00e4nde von Massi di Cemmo<\/strong> angelegt.<br \/>\nDer Parkplatz hat einen stabilen Boden und ist mit einem direkten Durchgang, ebenfalls auf einem stabilen Boden, zum Eingangstor ausgestattet.<br \/>\nEs ist also m\u00f6glich, die St\u00e4tte direkt mit dem eigenen Fahrzeug zu besuchen und eventuelle Schwierigkeiten auf den Zufahrtswegen zu \u00fcberwinden.    <\/span><\/p>\n"}]}],"slides":[{"image":{"ID":37845,"id":37845,"title":"cemmo2","filename":"cemmo2.jpeg","filesize":42648,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/cemmo2.jpeg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/erreichbare-route-zu-den-massi-di-cemmo\/cemmo2-2\/","alt":"","author":"8","description":"","caption":"","name":"cemmo2-2","status":"inherit","uploaded_to":84908,"date":"2024-06-05 17:53:09","modified":"2024-10-07 09:06:55","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":511,"height":274,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/cemmo2-150x150.jpeg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/cemmo2-300x161.jpeg","medium-width":300,"medium-height":161,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/cemmo2.jpeg","medium_large-width":511,"medium_large-height":274,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/cemmo2.jpeg","large-width":511,"large-height":274,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/cemmo2.jpeg","1536x1536-width":511,"1536x1536-height":274,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/cemmo2.jpeg","2048x2048-width":511,"2048x2048-height":274,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/cemmo2.jpeg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":161,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/cemmo2.jpeg","gform-image-choice-md-width":400,"gform-image-choice-md-height":214,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/cemmo2.jpeg","gform-image-choice-lg-width":511,"gform-image-choice-lg-height":274}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"filotto_layout":"scroll","hero_title":"Erreichbare Route zu den Massi di Cemmo","hero_text":"<p>          <b>Vom Graffiti-Park (Capo di Ponte) oder direkt von der Website<\/b><\/p>\n","size":"full","filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"scroll","filotto_fill":"manual","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""}},"filotto_fill":"manual","filotto_items":false,"hero_type":"images","filotto_title":"","filotto_sub":"","or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"order_by":"","order_way":"","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""}},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/84908","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/types\/oggetto"}],"author":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/users\/8"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/84908\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media\/37858"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media?parent=84908"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/categories?post=84908"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/tags?post=84908"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/aggr?post=84908"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/area?post=84908"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/kind?post=84908"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/zona?post=84908"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}