{"id":85394,"date":"2025-05-12T20:24:47","date_gmt":"2025-05-12T18:24:47","guid":{"rendered":"https:\/\/visitstg2.visitbergamo.net\/oggetto\/bramata-mehl-fuer-polenta\/"},"modified":"2024-10-08T15:02:30","modified_gmt":"2024-10-08T13:02:30","slug":"bramata-mehl-fuer-polenta","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/bramata-mehl-fuer-polenta\/","title":{"rendered":"Bramata-Mehl f\u00fcr Polenta"},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":66859,"template":"","categories":[854],"tags":[],"aggr":[],"area":[],"kind":[18711],"zona":[],"class_list":["post-85394","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-essen","kind-prodotto-tipico-de"],"acf":{"iu_shortprice":"","button_icon":"none","function":"link","latitude":"","longitude":"","startingprice":"","gpxmap":"","iu_addr_postalcode":"","iu_addr_city":"","iu_phone":"","iu_cell":"","iu_email":"","id_visit_manza":"","iu_motor_accessibility":"","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","id_east":"5201811","id_ristora":"","description":"<p>Bergamasker Bramata-Mehl wird durch das Mahlen von glasigem Mais oder gemahlenen glasigen Samen auf eine eher grobe Korngr\u00f6\u00dfe gewonnen, weshalb es auch rau im Mund ist.<br \/>\nEs hat eine goldgelbe Farbe, sehr intensiv mit einigen helleren Streifen und orangefarbenen, manchmal roten Reflexen.<br \/>\nEr hat ein Aroma von gut gebackener Brotkruste.  <\/p>\n","target":"_self","hero_title":"Bramata-Mehl f\u00fcr Polenta","size":"full","seasonality":"<p>Der Mais wird im Oktober geerntet und dann getrocknet.<br \/>\nDas Mehl wird das ganze Jahr \u00fcber hergestellt und konsumiert. <\/p>\n","pairings":"<p>Nicht nur Polenta.<br \/>\nMaismehl wird f\u00fcr die Herstellung von Nudeln verwendet, insbesondere f\u00fcr traditionelle Formen wie *Foiade* &#8211; breite Nudeln, Brot, Gnocchi, aber auch f\u00fcr S\u00fc\u00dfigkeiten.<br \/>\nEs war das Gericht der Hirten w\u00e4hrend der Transhumanz, die es mit Milch und deren Derivaten genossen.<br \/>\nTypisch ist das *Chiss\u00f6l*: ein Polentak\u00fcgelchen mit einem St\u00fcck Taleggio-K\u00e4se im Inneren, das \u00fcber der Glut platziert wird; eine Zubereitung, die oft als Willkommensgru\u00df in lokalen Restaurants angeboten wird.<br \/>\nNeben dem K\u00e4se, dem Hauptnahrungsmittel der Region, wird die bergamasker Polenta auch zu Wurstwaren, Wild, insbesondere V\u00f6geln, und Nutztieren serviert.<br \/>\nUnz\u00e4hlige Rezepte sehen sie in Kombination mit: *L\u00f6anghina, Salami, gekochte Salami, Kaninchen, gef\u00fclltes Huhn, Rippchen mit Wirsing, Schmorfleisch, Braten, aber auch Gem\u00fcse und Pilze, oder als einzelnes Gericht, angereichert mit lokalen K\u00e4sesorten und Butter aus den Bergen.     <\/p>\n","curiosities":"<p>Die Polenta bergamasca ist einzigartig: Sie muss aufrecht stehen und mit einem Messer geschnitten werden.<br \/>\nJahrhundertelang war sie das Hauptnahrungsmittel der weniger wohlhabenden lokalen Bev\u00f6lkerung, so dass die Bergamasker &#8216;polentoni&#8217; genannt wurden.<br \/>\nHeute ist sie aufgrund ihrer organoleptischen und ern\u00e4hrungsphysiologischen Qualit\u00e4ten die K\u00f6nigin auf den Tischen der Restaurants in aller Welt.<br \/>\nDie *Farina integrale e bramata della Bergamasc*a kann nur im gesamten Verwaltungsgebiet der Provinz Bergamo hergestellt werden.<br \/>\nBei zahlreichen Festen und Messen in der Region spielt sie eine wichtige Rolle in der Gastronomie.    <\/p>\n","awards":"<p>Das Polentamehl aus Bergamo hat vom Ministerium f\u00fcr Agrarpolitik die Anerkennung als traditionelles Lebensmittel (PAT) erhalten.<br \/>\nDie Bezeichnung <em>Farina integrale e bramata della Bergamasca (Vollkorn- und Bramatamehl <\/em>) ist ausschlie\u00dflich dem Produkt vorbehalten, das die Bedingungen und Anforderungen erf\u00fcllt, die in den Produktionsvorschriften der von der Handelskammer Bergamo eingef\u00fchrten Marke Bergamo, Stadt der tausend&#8230; Geschm\u00e4cker festgelegt sind<em>.<\/em> <\/p>\n","filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":false,"filotto_fill":false,"filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":0,"show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":false,"order_way":false}},"style":"primary","hero_type":"images","target_modal":"","id_madeep":"","iu_addr_province":"","iu_manager":"","validfrom":"","validto":"","icon":{"button_icon":"none"},"cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"iu_startingdate":"","iu_closingdate":"","iu_gpxtrack":"","url":"","iu_bookingurl":"","id_eppen":"","text":"","url_youtube":"","hero_buttons":false,"iu_kids":false,"iu_timetable":false,"iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"buttons":false,"hero_text":"","hours":"","service_icons":[],"iu_company_name":"","iu_vat":"","iu_stars":"","iu_rooms":"","iu_beds":"","ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":"","time":"","registered_office":"","slides":[{"image":{"ID":66859,"id":66859,"title":"1623999886-polentabergamascadsc9955.jpg","filename":"1623999886-polentabergamascadsc9955.jpg","filesize":382764,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1623999886-polentabergamascadsc9955.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/i-casoncelli-e-la-polenta\/1623999886-polentabergamascadsc9955-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"1623999886-polentabergamascadsc9955-jpg-2","status":"inherit","uploaded_to":80871,"date":"2024-06-25 10:32:00","modified":"2024-10-04 14:54:26","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1400,"height":1400,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1623999886-polentabergamascadsc9955-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1623999886-polentabergamascadsc9955-300x300.jpg","medium-width":300,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1623999886-polentabergamascadsc9955-768x768.jpg","medium_large-width":768,"medium_large-height":768,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1623999886-polentabergamascadsc9955-1024x1024.jpg","large-width":1024,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1623999886-polentabergamascadsc9955.jpg","1536x1536-width":1400,"1536x1536-height":1400,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1623999886-polentabergamascadsc9955.jpg","2048x2048-width":1400,"2048x2048-height":1400,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1623999886-polentabergamascadsc9955.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1623999886-polentabergamascadsc9955.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1623999886-polentabergamascadsc9955.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":70275,"id":70275,"title":"1623999910-polentabergamascadsc9958.jpg","filename":"1623999910-polentabergamascadsc9958.jpg","filesize":465349,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999910-polentabergamascadsc9958.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/bramata-mehl-fuer-polenta\/1623999910-polentabergamascadsc9958-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"1623999910-polentabergamascadsc9958-jpg-2","status":"inherit","uploaded_to":85394,"date":"2024-07-08 17:04:47","modified":"2024-10-07 10:06:02","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1400,"height":1400,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999910-polentabergamascadsc9958-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999910-polentabergamascadsc9958-300x300.jpg","medium-width":300,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999910-polentabergamascadsc9958-768x768.jpg","medium_large-width":768,"medium_large-height":768,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999910-polentabergamascadsc9958-1024x1024.jpg","large-width":1024,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999910-polentabergamascadsc9958.jpg","1536x1536-width":1400,"1536x1536-height":1400,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999910-polentabergamascadsc9958.jpg","2048x2048-width":1400,"2048x2048-height":1400,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999910-polentabergamascadsc9958.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999910-polentabergamascadsc9958.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999910-polentabergamascadsc9958.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":70281,"id":70281,"title":"1623999916-polentabergamascadsc9960.jpg","filename":"1623999916-polentabergamascadsc9960.jpg","filesize":227886,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999916-polentabergamascadsc9960.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/bramata-mehl-fuer-polenta\/1623999916-polentabergamascadsc9960-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"1623999916-polentabergamascadsc9960-jpg-2","status":"inherit","uploaded_to":85394,"date":"2024-07-08 17:04:49","modified":"2024-10-07 10:06:02","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1400,"height":1400,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999916-polentabergamascadsc9960-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999916-polentabergamascadsc9960-300x300.jpg","medium-width":300,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999916-polentabergamascadsc9960-768x768.jpg","medium_large-width":768,"medium_large-height":768,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999916-polentabergamascadsc9960-1024x1024.jpg","large-width":1024,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999916-polentabergamascadsc9960.jpg","1536x1536-width":1400,"1536x1536-height":1400,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999916-polentabergamascadsc9960.jpg","2048x2048-width":1400,"2048x2048-height":1400,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999916-polentabergamascadsc9960.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999916-polentabergamascadsc9960.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999916-polentabergamascadsc9960.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":70287,"id":70287,"title":"1623999919-polentabergamascadsc9963.jpg","filename":"1623999919-polentabergamascadsc9963.jpg","filesize":276307,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999919-polentabergamascadsc9963.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/bramata-mehl-fuer-polenta\/1623999919-polentabergamascadsc9963-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"1623999919-polentabergamascadsc9963-jpg-2","status":"inherit","uploaded_to":85394,"date":"2024-07-08 17:04:51","modified":"2024-10-07 10:06:02","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1400,"height":1400,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999919-polentabergamascadsc9963-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999919-polentabergamascadsc9963-300x300.jpg","medium-width":300,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999919-polentabergamascadsc9963-768x768.jpg","medium_large-width":768,"medium_large-height":768,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999919-polentabergamascadsc9963-1024x1024.jpg","large-width":1024,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999919-polentabergamascadsc9963.jpg","1536x1536-width":1400,"1536x1536-height":1400,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999919-polentabergamascadsc9963.jpg","2048x2048-width":1400,"2048x2048-height":1400,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999919-polentabergamascadsc9963.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999919-polentabergamascadsc9963.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999919-polentabergamascadsc9963.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":70293,"id":70293,"title":"1623999922-polentabergamascadsc9967.jpg","filename":"1623999922-polentabergamascadsc9967.jpg","filesize":507303,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999922-polentabergamascadsc9967.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/bramata-mehl-fuer-polenta\/1623999922-polentabergamascadsc9967-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"1623999922-polentabergamascadsc9967-jpg-2","status":"inherit","uploaded_to":85394,"date":"2024-07-08 17:04:52","modified":"2024-10-07 10:06:02","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1400,"height":1400,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999922-polentabergamascadsc9967-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999922-polentabergamascadsc9967-300x300.jpg","medium-width":300,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999922-polentabergamascadsc9967-768x768.jpg","medium_large-width":768,"medium_large-height":768,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999922-polentabergamascadsc9967-1024x1024.jpg","large-width":1024,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999922-polentabergamascadsc9967.jpg","1536x1536-width":1400,"1536x1536-height":1400,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999922-polentabergamascadsc9967.jpg","2048x2048-width":1400,"2048x2048-height":1400,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999922-polentabergamascadsc9967.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999922-polentabergamascadsc9967.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999922-polentabergamascadsc9967.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":70299,"id":70299,"title":"1623999925-polentabergamascadsc9972.jpg","filename":"1623999925-polentabergamascadsc9972.jpg","filesize":346239,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999925-polentabergamascadsc9972.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/bramata-mehl-fuer-polenta\/1623999925-polentabergamascadsc9972-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"1623999925-polentabergamascadsc9972-jpg-2","status":"inherit","uploaded_to":85394,"date":"2024-07-08 17:04:54","modified":"2024-10-07 10:06:02","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1400,"height":1400,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999925-polentabergamascadsc9972-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999925-polentabergamascadsc9972-300x300.jpg","medium-width":300,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999925-polentabergamascadsc9972-768x768.jpg","medium_large-width":768,"medium_large-height":768,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999925-polentabergamascadsc9972-1024x1024.jpg","large-width":1024,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999925-polentabergamascadsc9972.jpg","1536x1536-width":1400,"1536x1536-height":1400,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999925-polentabergamascadsc9972.jpg","2048x2048-width":1400,"2048x2048-height":1400,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999925-polentabergamascadsc9972.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999925-polentabergamascadsc9972.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999925-polentabergamascadsc9972.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":70305,"id":70305,"title":"1623999936-polentabramatadsc9935.jpg","filename":"1623999936-polentabramatadsc9935.jpg","filesize":373890,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999936-polentabramatadsc9935.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/bramata-mehl-fuer-polenta\/1623999936-polentabramatadsc9935-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"1623999936-polentabramatadsc9935-jpg-2","status":"inherit","uploaded_to":85394,"date":"2024-07-08 17:04:57","modified":"2024-10-07 10:06:02","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1400,"height":1400,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999936-polentabramatadsc9935-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999936-polentabramatadsc9935-300x300.jpg","medium-width":300,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999936-polentabramatadsc9935-768x768.jpg","medium_large-width":768,"medium_large-height":768,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999936-polentabramatadsc9935-1024x1024.jpg","large-width":1024,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999936-polentabramatadsc9935.jpg","1536x1536-width":1400,"1536x1536-height":1400,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999936-polentabramatadsc9935.jpg","2048x2048-width":1400,"2048x2048-height":1400,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999936-polentabramatadsc9935.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999936-polentabramatadsc9935.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999936-polentabramatadsc9935.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":70311,"id":70311,"title":"1623999942-polentabramatadsc9937.jpg","filename":"1623999942-polentabramatadsc9937.jpg","filesize":573929,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999942-polentabramatadsc9937.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/bramata-mehl-fuer-polenta\/1623999942-polentabramatadsc9937-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"1623999942-polentabramatadsc9937-jpg-2","status":"inherit","uploaded_to":85394,"date":"2024-07-08 17:04:58","modified":"2024-10-07 10:06:02","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1400,"height":1400,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999942-polentabramatadsc9937-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999942-polentabramatadsc9937-300x300.jpg","medium-width":300,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999942-polentabramatadsc9937-768x768.jpg","medium_large-width":768,"medium_large-height":768,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999942-polentabramatadsc9937-1024x1024.jpg","large-width":1024,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999942-polentabramatadsc9937.jpg","1536x1536-width":1400,"1536x1536-height":1400,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999942-polentabramatadsc9937.jpg","2048x2048-width":1400,"2048x2048-height":1400,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999942-polentabramatadsc9937.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999942-polentabramatadsc9937.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999942-polentabramatadsc9937.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":70317,"id":70317,"title":"1623999946-polentabramatadsc9939.jpg","filename":"1623999946-polentabramatadsc9939.jpg","filesize":355021,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999946-polentabramatadsc9939.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/bramata-mehl-fuer-polenta\/1623999946-polentabramatadsc9939-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"1623999946-polentabramatadsc9939-jpg-2","status":"inherit","uploaded_to":85394,"date":"2024-07-08 17:05:00","modified":"2024-10-07 10:06:02","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1400,"height":1400,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999946-polentabramatadsc9939-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999946-polentabramatadsc9939-300x300.jpg","medium-width":300,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999946-polentabramatadsc9939-768x768.jpg","medium_large-width":768,"medium_large-height":768,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999946-polentabramatadsc9939-1024x1024.jpg","large-width":1024,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999946-polentabramatadsc9939.jpg","1536x1536-width":1400,"1536x1536-height":1400,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999946-polentabramatadsc9939.jpg","2048x2048-width":1400,"2048x2048-height":1400,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999946-polentabramatadsc9939.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999946-polentabramatadsc9939.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999946-polentabramatadsc9939.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":70323,"id":70323,"title":"1623999949-polentabramatadsc9942.jpg","filename":"1623999949-polentabramatadsc9942.jpg","filesize":225015,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999949-polentabramatadsc9942.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/bramata-mehl-fuer-polenta\/1623999949-polentabramatadsc9942-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"1623999949-polentabramatadsc9942-jpg-2","status":"inherit","uploaded_to":85394,"date":"2024-07-08 17:05:02","modified":"2024-10-07 10:06:02","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1400,"height":1400,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999949-polentabramatadsc9942-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999949-polentabramatadsc9942-300x300.jpg","medium-width":300,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999949-polentabramatadsc9942-768x768.jpg","medium_large-width":768,"medium_large-height":768,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999949-polentabramatadsc9942-1024x1024.jpg","large-width":1024,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999949-polentabramatadsc9942.jpg","1536x1536-width":1400,"1536x1536-height":1400,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999949-polentabramatadsc9942.jpg","2048x2048-width":1400,"2048x2048-height":1400,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999949-polentabramatadsc9942.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999949-polentabramatadsc9942.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999949-polentabramatadsc9942.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":70329,"id":70329,"title":"1623999953-polentabramatadsc9946.jpg","filename":"1623999953-polentabramatadsc9946.jpg","filesize":189602,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999953-polentabramatadsc9946.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/bramata-mehl-fuer-polenta\/1623999953-polentabramatadsc9946-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"1623999953-polentabramatadsc9946-jpg-2","status":"inherit","uploaded_to":85394,"date":"2024-07-08 17:05:04","modified":"2024-10-07 10:06:02","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1400,"height":1400,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999953-polentabramatadsc9946-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999953-polentabramatadsc9946-300x300.jpg","medium-width":300,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999953-polentabramatadsc9946-768x768.jpg","medium_large-width":768,"medium_large-height":768,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999953-polentabramatadsc9946-1024x1024.jpg","large-width":1024,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999953-polentabramatadsc9946.jpg","1536x1536-width":1400,"1536x1536-height":1400,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999953-polentabramatadsc9946.jpg","2048x2048-width":1400,"2048x2048-height":1400,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999953-polentabramatadsc9946.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999953-polentabramatadsc9946.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999953-polentabramatadsc9946.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":70335,"id":70335,"title":"1623999956-polentabramatadsc9951.jpg","filename":"1623999956-polentabramatadsc9951.jpg","filesize":227820,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999956-polentabramatadsc9951.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/bramata-mehl-fuer-polenta\/1623999956-polentabramatadsc9951-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"1623999956-polentabramatadsc9951-jpg-2","status":"inherit","uploaded_to":85394,"date":"2024-07-08 17:05:06","modified":"2024-10-07 10:06:02","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1400,"height":1400,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999956-polentabramatadsc9951-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999956-polentabramatadsc9951-300x300.jpg","medium-width":300,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999956-polentabramatadsc9951-768x768.jpg","medium_large-width":768,"medium_large-height":768,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999956-polentabramatadsc9951-1024x1024.jpg","large-width":1024,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999956-polentabramatadsc9951.jpg","1536x1536-width":1400,"1536x1536-height":1400,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999956-polentabramatadsc9951.jpg","2048x2048-width":1400,"2048x2048-height":1400,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999956-polentabramatadsc9951.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999956-polentabramatadsc9951.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999956-polentabramatadsc9951.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":70341,"id":70341,"title":"1623999959-polentabramatadsc9953.jpg","filename":"1623999959-polentabramatadsc9953.jpg","filesize":521064,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999959-polentabramatadsc9953.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/bramata-mehl-fuer-polenta\/1623999959-polentabramatadsc9953-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"1623999959-polentabramatadsc9953-jpg-2","status":"inherit","uploaded_to":85394,"date":"2024-07-08 17:05:08","modified":"2024-10-07 10:06:02","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1400,"height":1400,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999959-polentabramatadsc9953-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999959-polentabramatadsc9953-300x300.jpg","medium-width":300,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999959-polentabramatadsc9953-768x768.jpg","medium_large-width":768,"medium_large-height":768,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999959-polentabramatadsc9953-1024x1024.jpg","large-width":1024,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999959-polentabramatadsc9953.jpg","1536x1536-width":1400,"1536x1536-height":1400,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999959-polentabramatadsc9953.jpg","2048x2048-width":1400,"2048x2048-height":1400,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999959-polentabramatadsc9953.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999959-polentabramatadsc9953.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999959-polentabramatadsc9953.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}]},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/85394","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/85394\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media\/66859"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media?parent=85394"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/categories?post=85394"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/tags?post=85394"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/aggr?post=85394"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/area?post=85394"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/kind?post=85394"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/zona?post=85394"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}