{"id":85409,"date":"2025-05-12T20:24:47","date_gmt":"2025-05-12T18:24:47","guid":{"rendered":"https:\/\/visitstg2.visitbergamo.net\/oggetto\/wurst-nach-bergamo-art-loanghina\/"},"modified":"2024-10-08T15:02:04","modified_gmt":"2024-10-08T13:02:04","slug":"wurst-nach-bergamo-art-loanghina","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/wurst-nach-bergamo-art-loanghina\/","title":{"rendered":"Wurst nach Bergamo-Art (Loanghina)"},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":66831,"template":"","categories":[854],"tags":[],"aggr":[],"area":[],"kind":[18711],"zona":[],"class_list":["post-85409","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-essen","kind-prodotto-tipico-de"],"acf":{"iu_shortprice":"","button_icon":"none","function":"link","latitude":"","longitude":"","startingprice":"","gpxmap":"","iu_addr_postalcode":"","iu_addr_city":"","iu_phone":"","iu_cell":"","iu_email":"","id_visit_manza":"","iu_motor_accessibility":"","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","id_east":"5201799","id_ristora":"","description":"<p>Es wird schwer sein, der Loangh\u00ecna zu widerstehen, denn Sie k\u00f6nnen sie ganz einfach zubereiten: Wenn Sie gekochtes Fleisch lieben, f\u00fcgen Sie sie hinzu, um Ihre So\u00dfe zu bereichern, oder verwenden Sie sie in Nudelf\u00fcllungen oder Flans, um ihr Charakter und Geschmack zu verleihen. Um es auf gesunde Weise zuzubereiten, grillen Sie es, damit es w\u00e4hrend des Garens sein Fett verliert: Sie k\u00f6nnen es in St\u00fccke schneiden oder aufrollen und mit einem Zahnstocher fixieren. Geben Sie dazu eine gro\u00dfz\u00fcgige Portion Polenta bergamasca und Sie werden eine Mischung von Aromen riechen, die vom Teller aufsteigt und Sie dazu verleitet, sie sofort zu essen! Ein weiteres typisches Gericht, in dem Loangh\u00ecna vorkommt, ist Polenta e os\u00e8i. Sie finden sie auch in vielen anderen Rezepten, darunter Risotto alla bergamasca und Pollo alla casalinga, d.h. Huhn gef\u00fcllt mit ger\u00f6steten Kastanien, Pflaumen und Loangh\u00ecna. Wenn Sie es vorziehen, die Wurst im Gehen zu genie\u00dfen, sollten Sie wissen, dass sie auch als Stra\u00dfenessen in einem Sandwich serviert wird.<br \/>\nDie Wurst besteht zu etwa 70 Prozent aus mageren Teilen (Keule, Nacken, Schulter und Bankabschnitte) und zu etwa 30 Prozent aus gemahlenen Fettteilen (Kinnriemen, Hals, Bauchspeck). Jeder Schweinemetzger f\u00fcgt der Mischung Zutaten nach Belieben hinzu, wie Wein, Fleischbr\u00fche, Salz, Grana Padano D.O.P., Gew\u00fcrze und Aromen. Die homogene Mischung wird in einen Darm gef\u00fcllt; das Endprodukt ist schlauchf\u00f6rmig und hat einen kleinen Durchmesser.<\/p>\n","target":"_self","hero_title":"Wurst nach Bergamo-Art (Loanghina)","size":"full","curiosities":"<p>Die Associazione norcini bergamaschi zeigt Ihnen, wie Sie die Grundrezepte f\u00fcr die bergamasche loanghine zubereiten k\u00f6nnen.<br \/>\nDas \u00e4lteste, typisch f\u00fcr das untere Bergamasker Gebiet, enth\u00e4lt auch Grana Padano D.O.P. K\u00e4se und Br\u00fche als Zutaten und sollte daher innerhalb k\u00fcrzester Zeit verzehrt werden.<br \/>\nAssociazione Norcini bergamaschi, via Dante Allighieri, 27.<br \/>\nCalcinate (BG).<br \/>\nTel. 00393384645479 <\/p>\n","filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":false,"filotto_fill":false,"filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":0,"show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":false,"order_way":false}},"style":"primary","hero_type":"images","target_modal":"","id_madeep":"","iu_addr_province":"","iu_manager":"","validfrom":"","validto":"","icon":{"button_icon":"none"},"cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"iu_startingdate":"","iu_closingdate":"","iu_gpxtrack":"","url":"","iu_bookingurl":"","id_eppen":"","text":"","url_youtube":"","hero_buttons":false,"iu_kids":false,"iu_timetable":false,"iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"buttons":false,"hero_text":"","hours":"","service_icons":[],"iu_company_name":"","iu_vat":"","iu_stars":"","iu_rooms":"","iu_beds":"","ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":"","time":"","registered_office":"","slides":[{"image":{"ID":66831,"id":66831,"title":"1623999750-loanghinadsc9874.jpg","filename":"1623999750-loanghinadsc9874.jpg","filesize":278789,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1623999750-loanghinadsc9874.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/wurst-nach-bergamo-art-loanghina\/1623999750-loanghinadsc9874-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"1623999750-loanghinadsc9874-jpg-2","status":"inherit","uploaded_to":85409,"date":"2024-06-25 10:31:50","modified":"2024-10-07 10:06:28","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1400,"height":1400,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1623999750-loanghinadsc9874-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1623999750-loanghinadsc9874-300x300.jpg","medium-width":300,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1623999750-loanghinadsc9874-768x768.jpg","medium_large-width":768,"medium_large-height":768,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1623999750-loanghinadsc9874-1024x1024.jpg","large-width":1024,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1623999750-loanghinadsc9874.jpg","1536x1536-width":1400,"1536x1536-height":1400,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1623999750-loanghinadsc9874.jpg","2048x2048-width":1400,"2048x2048-height":1400,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1623999750-loanghinadsc9874.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1623999750-loanghinadsc9874.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1623999750-loanghinadsc9874.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":70179,"id":70179,"title":"1623999761-loanghinadsc9875.jpg","filename":"1623999761-loanghinadsc9875.jpg","filesize":210048,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999761-loanghinadsc9875.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/wurst-nach-bergamo-art-loanghina\/1623999761-loanghinadsc9875-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"1623999761-loanghinadsc9875-jpg-2","status":"inherit","uploaded_to":85409,"date":"2024-07-08 17:04:13","modified":"2024-10-07 10:06:28","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1400,"height":1400,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999761-loanghinadsc9875-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999761-loanghinadsc9875-300x300.jpg","medium-width":300,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999761-loanghinadsc9875-768x768.jpg","medium_large-width":768,"medium_large-height":768,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999761-loanghinadsc9875-1024x1024.jpg","large-width":1024,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999761-loanghinadsc9875.jpg","1536x1536-width":1400,"1536x1536-height":1400,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999761-loanghinadsc9875.jpg","2048x2048-width":1400,"2048x2048-height":1400,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999761-loanghinadsc9875.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999761-loanghinadsc9875.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999761-loanghinadsc9875.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":70185,"id":70185,"title":"1623999766-loanghinadsc9881.jpg","filename":"1623999766-loanghinadsc9881.jpg","filesize":195859,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999766-loanghinadsc9881.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/wurst-nach-bergamo-art-loanghina\/1623999766-loanghinadsc9881-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"1623999766-loanghinadsc9881-jpg-2","status":"inherit","uploaded_to":85409,"date":"2024-07-08 17:04:16","modified":"2024-10-07 10:06:28","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1400,"height":1400,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999766-loanghinadsc9881-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999766-loanghinadsc9881-300x300.jpg","medium-width":300,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999766-loanghinadsc9881-768x768.jpg","medium_large-width":768,"medium_large-height":768,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999766-loanghinadsc9881-1024x1024.jpg","large-width":1024,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999766-loanghinadsc9881.jpg","1536x1536-width":1400,"1536x1536-height":1400,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999766-loanghinadsc9881.jpg","2048x2048-width":1400,"2048x2048-height":1400,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999766-loanghinadsc9881.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999766-loanghinadsc9881.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999766-loanghinadsc9881.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":70191,"id":70191,"title":"1623999769-loanghinadsc9882.jpg","filename":"1623999769-loanghinadsc9882.jpg","filesize":242748,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999769-loanghinadsc9882.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/wurst-nach-bergamo-art-loanghina\/1623999769-loanghinadsc9882-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"1623999769-loanghinadsc9882-jpg-2","status":"inherit","uploaded_to":85409,"date":"2024-07-08 17:04:18","modified":"2024-10-07 10:06:28","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1400,"height":1400,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999769-loanghinadsc9882-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999769-loanghinadsc9882-300x300.jpg","medium-width":300,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999769-loanghinadsc9882-768x768.jpg","medium_large-width":768,"medium_large-height":768,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999769-loanghinadsc9882-1024x1024.jpg","large-width":1024,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999769-loanghinadsc9882.jpg","1536x1536-width":1400,"1536x1536-height":1400,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999769-loanghinadsc9882.jpg","2048x2048-width":1400,"2048x2048-height":1400,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999769-loanghinadsc9882.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999769-loanghinadsc9882.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1623999769-loanghinadsc9882.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}]},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/85409","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/85409\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media\/66831"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media?parent=85409"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/categories?post=85409"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/tags?post=85409"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/aggr?post=85409"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/area?post=85409"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/kind?post=85409"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/zona?post=85409"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}