{"id":85449,"date":"2025-05-12T20:24:47","date_gmt":"2025-05-12T18:24:47","guid":{"rendered":"https:\/\/visitstg2.visitbergamo.net\/oggetto\/moscato-di-scanzo-docg\/"},"modified":"2025-03-11T14:01:37","modified_gmt":"2025-03-11T13:01:37","slug":"moscato-di-scanzo-docg","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/moscato-di-scanzo-docg\/","title":{"rendered":"Moscato di Scanzo DOCG"},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":66258,"template":"","categories":[854],"tags":[],"aggr":[],"area":[],"kind":[18711],"zona":[],"class_list":["post-85449","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-essen","kind-prodotto-tipico-de"],"acf":{"iu_shortprice":"","button_icon":"none","function":"link","latitude":"","longitude":"","startingprice":"","gpxmap":"","iu_addr_postalcode":"","iu_addr_city":"","iu_phone":"","iu_cell":"","iu_email":"","id_visit_manza":"","iu_motor_accessibility":"","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","id_east":"143394205","id_ristora":"","target":"_self","size":"full","filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":false,"filotto_fill":false,"filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":0,"show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":false,"order_way":false}},"style":"primary","hero_type":"images","target_modal":"","id_madeep":"","iu_addr_province":"","iu_manager":"","validfrom":"","validto":"","icon":{"button_icon":"none"},"cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"iu_startingdate":"","iu_closingdate":"","iu_gpxtrack":"","url":"","iu_bookingurl":"","id_eppen":"","text":"","url_youtube":"","hero_buttons":false,"iu_kids":false,"iu_timetable":false,"iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"description":"<p>Der Moscato di Scanzo ist ein rotbeeriger Moscato Passito und einer der exklusivsten DOCG-Weine Italiens: Seine Trauben werden auf einer Fl\u00e4che von nur 31 Hektar in der Gemeinde Scanzorosciate angebaut. Das besondere Mikroklima und die kalkig-mergelige Formation, auf der die Reben wachsen, machen die Trauben einzigartig und sorgen f\u00fcr eine hohe Mineralit\u00e4t bei geringer Wasserverf\u00fcgbarkeit. Diese Eigenschaften sind von grundlegender Bedeutung und machen die Trauben gesund, duftend und aromareich.  <\/p>\n<p>Die Produktionsvorschriften sind sehr streng: die manuelle Ernte findet zwischen Ende September und Mitte Oktober statt und die sorgf\u00e4ltig ausgew\u00e4hlten Trauben werden mindestens 21 Tage lang auf Gestellen in bel\u00fcfteten R\u00e4umen nat\u00fcrlich getrocknet. Da der Moscato kein Holz vertr\u00e4gt, wird er in Glas- und Stahlbeh\u00e4ltern gereift. Er kann mindestens zwei Jahre nach der Ernte vermarktet werden, und zwar ab dem 1. November.    <\/p>\n<p>Er hat eine warme, rubinrote Farbe mit violetten Reflexen. Mit seinem ausgewogenen und eleganten Geschmack, m\u00e4\u00dfig s\u00fc\u00df, passt er ideal zu Bergamasker D.O.C. Blauschimmelk\u00e4se wie Strachitunt und Gorgonzola, aber auch zu Bitto, reifem Formai de Mut und Ziegenk\u00e4se. Er passt auch sehr gut zu dunkler Schokolade und trockenem Geb\u00e4ck.  <\/p>\n","hero_title":"Moscato di Scanzo DOCG","curiosities":"<p>Das Konsortium zum Schutz des Moscato di Scanzo garantiert seine Qualit\u00e4t und unterstreicht seine Exzellenz mit seinem Markenzeichen. Das Logo des Konsortiums f\u00fcr den Moscato di Scanzo D.O.C.G. zeigt zwei Pers\u00f6nlichkeiten: Simone da Scanzo und Alberico da Rosciate, nach denen das Gebiet benannt wurde, in dem dieser Wein hergestellt wird. <\/p>\n","buttons":false,"hero_text":"","hours":"","service_icons":[],"iu_company_name":"","iu_vat":"","iu_stars":"","iu_rooms":"","iu_beds":"","ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":"","time":"","registered_office":"","slides":[{"image":{"ID":66258,"id":66258,"title":"1668007845-moscato-di-scanzo-docg.jpg","filename":"1668007845-moscato-di-scanzo-docg.jpg","filesize":295380,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1668007845-moscato-di-scanzo-docg.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/moscato-di-scanzo-docg\/1668007845-moscato-di-scanzo-docg-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"1668007845-moscato-di-scanzo-docg-jpg-2","status":"inherit","uploaded_to":85449,"date":"2024-06-25 10:27:54","modified":"2024-10-07 10:08:39","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1488,"height":1920,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1668007845-moscato-di-scanzo-docg-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1668007845-moscato-di-scanzo-docg-233x300.jpg","medium-width":233,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1668007845-moscato-di-scanzo-docg-768x991.jpg","medium_large-width":768,"medium_large-height":991,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1668007845-moscato-di-scanzo-docg-794x1024.jpg","large-width":794,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1668007845-moscato-di-scanzo-docg-1190x1536.jpg","1536x1536-width":1190,"1536x1536-height":1536,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1668007845-moscato-di-scanzo-docg.jpg","2048x2048-width":1488,"2048x2048-height":1920,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1668007845-moscato-di-scanzo-docg.jpg","gform-image-choice-sm-width":233,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1668007845-moscato-di-scanzo-docg.jpg","gform-image-choice-md-width":310,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1668007845-moscato-di-scanzo-docg.jpg","gform-image-choice-lg-width":465,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}]},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/85449","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/85449\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media\/66258"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media?parent=85449"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/categories?post=85449"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/tags?post=85449"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/aggr?post=85449"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/area?post=85449"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/kind?post=85449"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/zona?post=85449"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}